{"id":184409,"date":"2024-11-26T17:39:27","date_gmt":"2024-11-26T16:39:27","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=184409"},"modified":"2024-11-26T17:39:27","modified_gmt":"2024-11-26T16:39:27","slug":"reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/","title":{"rendered":"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez"},"content":{"rendered":"<p>La misionera asturiana <strong>\u00c1ngela Vicenta Guti\u00e9rrez Bada<\/strong>, sor \u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana de Cooperaci\u00f3n al Desarrollo del <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/actualidad.asturias.es\/\" target=\"_blank\" rel=\"noopener\"><strong>Principado de Asturias<\/strong><\/a><\/span>. El galard\u00f3n est\u00e1 dotado con 6.000 euros y se entregar\u00e1 el <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/candas365.es\/noticias\/category\/agenda\/\"><strong>10 de diciembre<\/strong><\/a><\/span>, con motivo de la celebraci\u00f3n de <strong>D\u00eda Internacional de los Derechos Humanos.<\/strong><\/p>\n<figure id=\"attachment_184410\" aria-describedby=\"caption-attachment-184410\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-184410\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez-650x380.jpg\" alt=\"misionera asturiana \u00c1ngela Guti\u00e9rrez\" width=\"650\" height=\"380\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez-650x380.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez-360x210.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez-768x449.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez-150x88.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez-450x263.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez.jpg 1112w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-184410\" class=\"wp-caption-text\">Foto: Prensa Gobierno de Asturias<\/figcaption><\/figure>\n<p>El jurado ha elegido a sor \u00c1ngela, entre las ocho candidaturas presentadas, \u201cpor su contribuci\u00f3n a restaurar la dignidad de las personas con enfermedades mentales, principalmente mujeres, en la Rep\u00fablica Democr\u00e1tica del Congo, pa\u00eds en el que estas personas est\u00e1n estigmatizadas y en el que se registra un agravamiento de la violencia sexual sobre las mujeres\u201d. Igualmente, ha destacado la \u201clabor esencial\u201d de Guti\u00e9rrez en la puesta en marcha del mayor complejo sanitario del continente africano, dedicado a la enfermedad mental.<\/p>\n<p><strong>Sor \u00c1ngela, nacida en Panes (Pe\u00f1amellera Baja), lleg\u00f3 en 1989 junto con otras dos religiosas a Kinshasa, capital del pa\u00eds africano, con el fin de proporcionar asistencia social y sanitaria a personas con enfermedades mentales.<\/strong> En 1991 crearon el Centro de Salud Mental T\u00e9lema, que en el dialecto local significa poner en pie a la persona. Se trata de la \u00fanica instituci\u00f3n psiqui\u00e1trica de d\u00eda para personas con enfermedades mentales de Kinshasa y el mayor centro del continente africano.<\/p>\n<p><strong>T\u00e9lema dispone de una log\u00edstica completa para el ingreso, diagn\u00f3stico, tratamiento y seguimiento de personas enfermas.<\/strong> Tambi\u00e9n se les proporciona terapia ocupacional y formaci\u00f3n abierta a j\u00f3venes sin recursos con la finalidad de que rehagan sus vidas, por ejemplo, a trav\u00e9s de la costura, una habilidad que puede brindarles oportunidades de empleo, empoderamiento econ\u00f3mico y creatividad.<\/p>\n<p>Actualmente, la proyecci\u00f3n econ\u00f3mica del proyecto se dirige hacia la puesta en marcha de una piscifactor\u00eda donde las mujeres aprenden t\u00e9cnicas avanzadas para el cuidado de los peces, la gesti\u00f3n de estanques y la reproducci\u00f3n responsable de las especies. Adem\u00e1s, se enfatiza la importancia de pr\u00e1cticas sostenibles que no solo maximizan la producci\u00f3n, sino que tambi\u00e9n preservan el medio ambiente local.<\/p>\n<p>La enfermedad mental en \u00c1frica afecta m\u00e1s a las mujeres que a los hombres, ya que ellas sufren desde ni\u00f1as la violencia estructural de una sociedad profundamente machista. Muchas de ellas, tras ser abandonadas, son v\u00edctimas de violaciones, a menudo quedan embarazadas y dan a luz en la calle.<\/p>\n<p><strong>La labor de sor \u00c1ngela consiste tambi\u00e9n en contactar y trabajar con las familias de las personas con enfermedad mental para lograr la reunificaci\u00f3n<\/strong>. Adem\u00e1s, incluye la sensibilizaci\u00f3n de la poblaci\u00f3n congole\u00f1a y la lucha contra la carga de superstici\u00f3n que condiciona la percepci\u00f3n de las personas enfermas.<\/p>\n<p>El Premio Derechos Humanos se puso en marcha en 2021 con el objetivo de reconocer a personas o entidades que se hayan distinguido por su lucha a favor de la libertad y los derechos humanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La misionera asturiana \u00c1ngela Vicenta Guti\u00e9rrez Bada, sor \u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana de Cooperaci\u00f3n al Desarrollo del Principado de Asturias. El galard\u00f3n est\u00e1 dotado con 6.000 euros y se entregar\u00e1 el 10 de diciembre, con motivo de la celebraci\u00f3n de D\u00eda Internacional de los<\/p>\n","protected":false},"author":1,"featured_media":184410,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[380],"class_list":{"0":"post-184409","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-asturias","8":"tag-asturias"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"La misionera asturiana \u00c1ngela Vicenta Guti\u00e9rrez Bada, sor \u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La misionera asturiana \u00c1ngela Vicenta Guti\u00e9rrez Bada, sor \u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1112\" \/>\n\t\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-11-26T16:39:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-11-26T16:39:27+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La misionera asturiana \u00c1ngela Vicenta Guti\u00e9rrez Bada, sor \u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#listItem\",\"name\":\"Reconocimiento y premio para la misionera asturiana \\u00c1ngela Guti\\u00e9rrez\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#listItem\",\"position\":3,\"name\":\"Reconocimiento y premio para la misionera asturiana \\u00c1ngela Guti\\u00e9rrez\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#newsarticle\",\"name\":\"Reconocimiento y premio para la misionera asturiana \\u00c1ngela Guti\\u00e9rrez | Cand\\u00e1s 365\",\"headline\":\"Reconocimiento y premio para la misionera asturiana \\u00c1ngela Guti\\u00e9rrez\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/misionera-asturiana-Angela-Gutierrez.jpg\",\"width\":1112,\"height\":650,\"caption\":\"Foto: Prensa Gobierno de Asturias\"},\"datePublished\":\"2024-11-26T17:39:27+01:00\",\"dateModified\":\"2024-11-26T17:39:27+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#webpage\"},\"articleSection\":\"Asturias, Asturias\",\"dateline\":\"Publicado el noviembre 26, 2024.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/\",\"name\":\"Reconocimiento y premio para la misionera asturiana \\u00c1ngela Guti\\u00e9rrez | Cand\\u00e1s 365\",\"description\":\"La misionera asturiana \\u00c1ngela Vicenta Guti\\u00e9rrez Bada, sor \\u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/misionera-asturiana-Angela-Gutierrez.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#mainImage\",\"width\":1112,\"height\":650,\"caption\":\"Foto: Prensa Gobierno de Asturias\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\\\/#mainImage\"},\"datePublished\":\"2024-11-26T17:39:27+01:00\",\"dateModified\":\"2024-11-26T17:39:27+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez | Cand\u00e1s 365","description":"La misionera asturiana \u00c1ngela Vicenta Guti\u00e9rrez Bada, sor \u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana","canonical_url":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#listItem","name":"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#listItem","position":3,"name":"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#newsarticle","name":"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez | Cand\u00e1s 365","headline":"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez.jpg","width":1112,"height":650,"caption":"Foto: Prensa Gobierno de Asturias"},"datePublished":"2024-11-26T17:39:27+01:00","dateModified":"2024-11-26T17:39:27+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#webpage"},"articleSection":"Asturias, Asturias","dateline":"Publicado el noviembre 26, 2024."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#webpage","url":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/","name":"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez | Cand\u00e1s 365","description":"La misionera asturiana \u00c1ngela Vicenta Guti\u00e9rrez Bada, sor \u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez.jpg","@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#mainImage","width":1112,"height":650,"caption":"Foto: Prensa Gobierno de Asturias"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/#mainImage"},"datePublished":"2024-11-26T17:39:27+01:00","dateModified":"2024-11-26T17:39:27+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez | Cand\u00e1s 365","og:description":"La misionera asturiana \u00c1ngela Vicenta Guti\u00e9rrez Bada, sor \u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana","og:url":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez.jpg","og:image:width":1112,"og:image:height":650,"article:published_time":"2024-11-26T16:39:27+00:00","article:modified_time":"2024-11-26T16:39:27+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez | Cand\u00e1s 365","twitter:description":"La misionera asturiana \u00c1ngela Vicenta Guti\u00e9rrez Bada, sor \u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/11\/misionera-asturiana-Angela-Gutierrez.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"184409","title":null,"description":"La misionera asturiana \u00c1ngela Vicenta Guti\u00e9rrez Bada, sor \u00c1ngela, ha sido galardonada con el III Premio Derechos Humanos que convoca la Agencia Asturiana","keywords":null,"keyphrases":{"focus":{"keyphrase":"\u00c1ngela","score":93,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"misionera asturiana","score":80,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-03 08:39:17","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-11-26 16:29:01","updated":"2025-09-03 08:39:17"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tReconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Reconocimiento y premio para la misionera asturiana \u00c1ngela Guti\u00e9rrez","link":"https:\/\/candas365.es\/noticias\/reconocimiento-y-premio-para-la-misionera-asturiana-angela-gutierrez\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/184409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=184409"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/184409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/184410"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=184409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=184409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=184409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}