{"id":182038,"date":"2024-06-25T21:54:15","date_gmt":"2024-06-25T19:54:15","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=182038"},"modified":"2024-06-25T21:54:15","modified_gmt":"2024-06-25T19:54:15","slug":"ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/","title":{"rendered":"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb"},"content":{"rendered":"<p><strong>Ione Belarra<\/strong> afirm\u00f3 que el PSOE ha elegido a un nuevo <a href=\"https:\/\/candas365.es\/noticias\/tag\/politica\/\"><span style=\"color: #ff6600;\"><strong>socio de Gobierno<\/strong><\/span><\/a>, las declaraciones las ha realizado despu\u00e9s de que el PSOE y el PP haya pactado para la renovaci\u00f3n del Consejo General del Poder Judicial (CGPJ). \u201cInaugura una nueva legislatura\u201d, y consider\u00f3 que \u201cno responde a lo que las urnas votaron el 23 de julio\u201d.<\/p>\n<figure id=\"attachment_182040\" aria-describedby=\"caption-attachment-182040\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-182040\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra-650x440.jpg\" alt=\"Ione Belarra\" width=\"650\" height=\"440\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra-650x440.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra-360x243.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra-768x519.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra-150x101.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra-450x304.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra.jpg 995w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-182040\" class=\"wp-caption-text\">Ione Belarra en imagen de archivo | Foto de Dani Gago<\/figcaption><\/figure>\n<p>En declaraciones a los medios de comunicaci\u00f3n en el Congreso, Ione Belarra sostuvo que con el acuerdo entre el PSOE y el PP para la renovaci\u00f3n del CGPJ se env\u00eda una mensaje \u201cmuy peligroso a la ciudadan\u00eda espa\u00f1ola\u201d que ser\u00eda que \u201cla democracia no puede llegar a la justicia, no puede llegar a los poderes profundos del Estado\u201d.<\/p>\n<blockquote><p>Belarra lament\u00f3 el pacto y esgrimi\u00f3 que despu\u00e9s de sus cinco d\u00edas de reflexi\u00f3n, el presidente del Ejecutivo, Pedro S\u00e1nchez, \u201cdijo que el Partido Popular es el \u2018lawfare\u2019 en Espa\u00f1a\u201d.<\/p><\/blockquote>\n<p>Ese punto de inflexi\u00f3n consider\u00f3, \u201cten\u00eda que haber implicado la democratizaci\u00f3n de la justicia con la mayor\u00eda plurinacional y democr\u00e1tica, y en vez de eso lo que vemos es una rendici\u00f3n ante el Partido Popular, ante el representante del \u2018lawfare\u2019\u201d.<\/p>\n<p>\u201cDesde nuestro punto de vista esto inaugura una nueva legislatura, esto supone la construcci\u00f3n de una gran coalici\u00f3n entre el Partido Popular y el Partido Socialista y pensamos que esa elecci\u00f3n desde luego no responde a lo que las urnas votaron el 23 de julio y no se va a hacer desde luego con la complicidad y el silencio desde Podemos\u201d, enfatiz\u00f3.<\/p>\n<p>Belarra dijo que su partido constata con el citado acuerdo que <strong>\u201cel Partido Socialista ha elegido nuevo socio de Gobierno, que es el Partido Popular, porque es con quien pacta todo lo realmente importante, que son las cuestiones de Estado, como el Consejo General del Poder Judicial\u201d.<\/strong><\/p>\n<p>Sobre la propuesta de PP y PSOE para reformar el sistema de elecci\u00f3n del \u00f3rgano de gobierno de los jueces, la secretaria general del Podemos asegur\u00f3 que \u201cestamos ante un hecho sin precedentes\u201d, ya que \u201cparece que el Consejo General del Poder Judicial se va a arrogar la capacidad legislativa, por lo tanto me parece grav\u00edsimo y me parece un ataque a la democracia\u201d.<\/p>\n<p>(<a href=\"https:\/\/www.servimedia.es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>SERVIMEDIA<\/strong><\/span><\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ione Belarra afirm\u00f3 que el PSOE ha elegido a un nuevo socio de Gobierno, las declaraciones las ha realizado despu\u00e9s de que el PSOE y el PP haya pactado para la renovaci\u00f3n del Consejo General del Poder Judicial (CGPJ). \u201cInaugura una nueva legislatura\u201d, y consider\u00f3 que \u201cno responde a lo que las urnas votaron el<\/p>\n","protected":false},"author":1,"featured_media":182040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[555,470],"class_list":{"0":"post-182038","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-podemos","9":"tag-politica"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ione Belarra afirm\u00f3 que el PSOE ha elegido a un nuevo socio de Gobierno, las declaraciones las ha realizado despu\u00e9s de que el PSOE y el PP haya pactado para la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Ione Belarra afirm\u00f3 que el PSOE ha elegido a un nuevo socio de Gobierno, las declaraciones las ha realizado despu\u00e9s de que el PSOE y el PP haya pactado para la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"995\" \/>\n\t\t<meta property=\"og:image:height\" content=\"673\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-06-25T19:54:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-06-25T19:54:15+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ione Belarra afirm\u00f3 que el PSOE ha elegido a un nuevo socio de Gobierno, las declaraciones las ha realizado despu\u00e9s de que el PSOE y el PP haya pactado para la\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#listItem\",\"name\":\"Ione Belarra: \\u00abEl PSOE ha elegido nuevo socio de Gobierno\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#listItem\",\"position\":3,\"name\":\"Ione Belarra: \\u00abEl PSOE ha elegido nuevo socio de Gobierno\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#newsarticle\",\"name\":\"Ione Belarra: \\u00abEl PSOE ha elegido nuevo socio de Gobierno\\u00bb | Cand\\u00e1s 365\",\"headline\":\"Ione Belarra: \\u00abEl PSOE ha elegido nuevo socio de Gobierno\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Ione-Belarra.jpg\",\"width\":995,\"height\":673,\"caption\":\"Ione Belarra en imagen de archivo | Foto de Dani Gago\"},\"datePublished\":\"2024-06-25T21:54:15+02:00\",\"dateModified\":\"2024-06-25T21:54:15+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#webpage\"},\"articleSection\":\"Actualidad, Podemos, pol\\u00edtica\",\"dateline\":\"Publicado el junio 25, 2024.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/\",\"name\":\"Ione Belarra: \\u00abEl PSOE ha elegido nuevo socio de Gobierno\\u00bb | Cand\\u00e1s 365\",\"description\":\"Ione Belarra afirm\\u00f3 que el PSOE ha elegido a un nuevo socio de Gobierno, las declaraciones las ha realizado despu\\u00e9s de que el PSOE y el PP haya pactado para la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Ione-Belarra.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#mainImage\",\"width\":995,\"height\":673,\"caption\":\"Ione Belarra en imagen de archivo | Foto de Dani Gago\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\\\/#mainImage\"},\"datePublished\":\"2024-06-25T21:54:15+02:00\",\"dateModified\":\"2024-06-25T21:54:15+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb | Cand\u00e1s 365","description":"Ione Belarra afirm\u00f3 que el PSOE ha elegido a un nuevo socio de Gobierno, las declaraciones las ha realizado despu\u00e9s de que el PSOE y el PP haya pactado para la","canonical_url":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#listItem","name":"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#listItem","position":3,"name":"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#newsarticle","name":"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb | Cand\u00e1s 365","headline":"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra.jpg","width":995,"height":673,"caption":"Ione Belarra en imagen de archivo | Foto de Dani Gago"},"datePublished":"2024-06-25T21:54:15+02:00","dateModified":"2024-06-25T21:54:15+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#webpage"},"articleSection":"Actualidad, Podemos, pol\u00edtica","dateline":"Publicado el junio 25, 2024."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#webpage","url":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/","name":"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb | Cand\u00e1s 365","description":"Ione Belarra afirm\u00f3 que el PSOE ha elegido a un nuevo socio de Gobierno, las declaraciones las ha realizado despu\u00e9s de que el PSOE y el PP haya pactado para la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra.jpg","@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#mainImage","width":995,"height":673,"caption":"Ione Belarra en imagen de archivo | Foto de Dani Gago"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/#mainImage"},"datePublished":"2024-06-25T21:54:15+02:00","dateModified":"2024-06-25T21:54:15+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb | Cand\u00e1s 365","og:description":"Ione Belarra afirm\u00f3 que el PSOE ha elegido a un nuevo socio de Gobierno, las declaraciones las ha realizado despu\u00e9s de que el PSOE y el PP haya pactado para la","og:url":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra.jpg","og:image:width":995,"og:image:height":673,"article:published_time":"2024-06-25T19:54:15+00:00","article:modified_time":"2024-06-25T19:54:15+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb | Cand\u00e1s 365","twitter:description":"Ione Belarra afirm\u00f3 que el PSOE ha elegido a un nuevo socio de Gobierno, las declaraciones las ha realizado despu\u00e9s de que el PSOE y el PP haya pactado para la","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/06\/Ione-Belarra.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"182038","title":null,"description":"Ione Belarra afirm\u00f3 que el PSOE ha elegido a un nuevo socio de Gobierno, las declaraciones las ha realizado despu\u00e9s de que el PSOE y el PP haya pactado para la","keywords":null,"keyphrases":{"focus":{"keyphrase":"Belarra","score":93,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Ione Belarra","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-02 12:21:15","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-06-25 19:42:47","updated":"2025-09-02 12:21:15"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tIone Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Ione Belarra: \u00abEl PSOE ha elegido nuevo socio de Gobierno\u00bb","link":"https:\/\/candas365.es\/noticias\/ione-belarra-el-psoe-ha-elegido-nuevo-socio-de-gobierno\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/182038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=182038"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/182038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/182040"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=182038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=182038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=182038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}