{"id":181081,"date":"2024-05-15T17:57:18","date_gmt":"2024-05-15T15:57:18","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=181081"},"modified":"2024-05-15T18:04:57","modified_gmt":"2024-05-15T16:04:57","slug":"europeas-2024-el-objetivo-de-teresa-ribera","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/","title":{"rendered":"Europeas 2024: El objetivo de Teresa Ribera"},"content":{"rendered":"<p>La cabeza de lista del PSOE a las<span style=\"color: #ff6600;\"> <a style=\"color: #ff6600;\" href=\"https:\/\/candas365.es\/noticias\/tag\/elecciones\/\"><strong>elecciones al Parlamento Europeo<\/strong><\/a><\/span>,\u00a0 Teresa Ribera, afirm\u00f3 el mi\u00e9rcoles que <strong>su objetivo es ganar a la ultraderecha y a la \u201cderecha cobarde\u201d<\/strong>, y acus\u00f3 al PP de ir a Bruselas solo a \u201chablar mal de Espa\u00f1a y del Gobierno\u201d.<\/p>\n<figure id=\"attachment_181082\" aria-describedby=\"caption-attachment-181082\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-181082\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera-650x447.jpg\" alt=\"Teresa Ribera\" width=\"650\" height=\"447\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera-650x447.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera-360x248.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera-768x528.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera-150x103.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera-450x309.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera.jpg 976w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-181082\" class=\"wp-caption-text\">Teresa Ribera, este mi\u00e9rcoles en Sevilla | Foto del PSOE<\/figcaption><\/figure>\n<p>Durante la presentaci\u00f3n de la candidatura socialista para los comicios del 9 de junio, celebrada en Sevilla, Teresa Ribera defendi\u00f3 los avances logrados por el Gobierno presidido por Pedro S\u00e1nchez como la defensa de los derechos, las libertades, las pol\u00edticas sociales, las mejoras de las condiciones laborales o el salario m\u00ednimo.<\/p>\n<p>Ribera apost\u00f3 por \u201cuna Europa mucho m\u00e1s social\u201d y subray\u00f3 la importancia de la defensa del orden internacional \u201cporque Europa es un basti\u00f3n de democracia y derechos, pero solamente se conservan si se defienden\u201d.<\/p>\n<p>Por eso, argument\u00f3, \u201cnecesitamos un equipo potente, convencido, audaz, valiente, que no tiene ning\u00fan problema en defender sus principios ante quien haga falta, que sale a ganar\u201d.<\/p>\n<p>\u201cVamos a ganar a la ultraderecha, vamos a ganar a aquellos que levantan el brazo en Roma y en Mil\u00e1n\u201d, y a aquellos que \u201cdefienden las bombas frente a la paz, que aspiran a hacer implosionar a Europa desde dentro\u201d.<\/p>\n<p>Asimismo, ret\u00f3 a los presentes a vencer tambi\u00e9n a \u201cla derecha cobarde\u201d que, denunci\u00f3, \u201cno tienen ning\u00fan problema en pactar con la ultraderecha y sacrificar derechos de las personas y pol\u00edticas sociales, adem\u00e1s de denigrar a las mujeres\u201d.<\/p>\n<p>Aquellos, a\u00f1adi\u00f3, \u201cque no tienen ning\u00fan problema para rehacer su discurso o inventarse conflictos, cuando las urnas han dejado perfectamente claro que queremos paz, progreso, derechos y mejor vida para el conjunto de la mayor\u00eda social\u201d.<\/p>\n<p>\u201cDebemos defender a Europa frente a las agresiones de Putin, que nos ha mostrado que los conflictos ahora son no solamente esa versi\u00f3n cruenta y espantosa de las bombas, tambi\u00e9n la utilizaci\u00f3n de la energ\u00eda, del alimento, de la informaci\u00f3n y la desinformaci\u00f3n como armas de guerra\u201d, remarc\u00f3.<\/p>\n<h2>ATAQUE AL PP<\/h2>\n<p>Dirigi\u00e9ndose al Partido Popular, critic\u00f3 que la formaci\u00f3n liderada por Alberto N\u00fa\u00f1ez Feij\u00f3o \u201csigue predicando \u2018cuanto peor mejor\u2019, sigue buscando conspiraciones, sigue renegando de los resultados electorales en las urnas y luego dicen que son dem\u00f3cratas\u201d.<\/p>\n<p>Un PP, a\u00f1adi\u00f3, que asegura que \u201cson europe\u00edstas y en realidad no conocen Bruselas para defender los intereses de Espa\u00f1a, ni los de la agricultura, ni los de las ciudades, ni los de las personas, solo conocen Bruselas para ir a protestar, poner zancadillas, hablar mal de Espa\u00f1a, del Gobierno\u201d.<\/p>\n<p>Finalmente, acus\u00f3 a los populares de utilizar \u201ct\u00e9cnicas de desinformaci\u00f3n y fango, a las que desgraciadamente nos tienen muy acostumbrados\u201d.<\/p>\n<p>(<a href=\"https:\/\/www.servimedia.es\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>SERVIMEDIA<\/strong><\/span><\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cabeza de lista del PSOE a las elecciones al Parlamento Europeo,\u00a0 Teresa Ribera, afirm\u00f3 el mi\u00e9rcoles que su objetivo es ganar a la ultraderecha y a la \u201cderecha cobarde\u201d, y acus\u00f3 al PP de ir a Bruselas solo a \u201chablar mal de Espa\u00f1a y del Gobierno\u201d. Durante la presentaci\u00f3n de la candidatura socialista para<\/p>\n","protected":false},"author":1,"featured_media":181082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[413,470,494],"class_list":{"0":"post-181081","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-elecciones","9":"tag-politica","10":"tag-psoe"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"La cabeza de lista del PSOE a las elecciones al Parlamento Europeo, Teresa Ribera, afirm\u00f3 el mi\u00e9rcoles que su objetivo es ganar a la ultraderecha y a la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Europeas 2024: El objetivo de Teresa Ribera | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La cabeza de lista del PSOE a las elecciones al Parlamento Europeo, Teresa Ribera, afirm\u00f3 el mi\u00e9rcoles que su objetivo es ganar a la ultraderecha y a la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"976\" \/>\n\t\t<meta property=\"og:image:height\" content=\"671\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-05-15T15:57:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-05-15T16:04:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Europeas 2024: El objetivo de Teresa Ribera | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La cabeza de lista del PSOE a las elecciones al Parlamento Europeo, Teresa Ribera, afirm\u00f3 el mi\u00e9rcoles que su objetivo es ganar a la ultraderecha y a la\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#listItem\",\"name\":\"Europeas 2024: El objetivo de Teresa Ribera\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#listItem\",\"position\":3,\"name\":\"Europeas 2024: El objetivo de Teresa Ribera\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#newsarticle\",\"name\":\"Europeas 2024: El objetivo de Teresa Ribera | Cand\\u00e1s 365\",\"headline\":\"Europeas 2024: El objetivo de Teresa Ribera\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Teresa-Ribera.jpg\",\"width\":976,\"height\":671,\"caption\":\"Teresa Ribera, este mi\\u00e9rcoles en Sevilla | Foto del PSOE\"},\"datePublished\":\"2024-05-15T17:57:18+02:00\",\"dateModified\":\"2024-05-15T18:04:57+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#webpage\"},\"articleSection\":\"Actualidad, Elecciones, pol\\u00edtica, PSOE\",\"dateline\":\"Publicado el mayo 15, 2024.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/\",\"name\":\"Europeas 2024: El objetivo de Teresa Ribera | Cand\\u00e1s 365\",\"description\":\"La cabeza de lista del PSOE a las elecciones al Parlamento Europeo, Teresa Ribera, afirm\\u00f3 el mi\\u00e9rcoles que su objetivo es ganar a la ultraderecha y a la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Teresa-Ribera.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#mainImage\",\"width\":976,\"height\":671,\"caption\":\"Teresa Ribera, este mi\\u00e9rcoles en Sevilla | Foto del PSOE\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/europeas-2024-el-objetivo-de-teresa-ribera\\\/#mainImage\"},\"datePublished\":\"2024-05-15T17:57:18+02:00\",\"dateModified\":\"2024-05-15T18:04:57+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Europeas 2024: El objetivo de Teresa Ribera | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Europeas 2024: El objetivo de Teresa Ribera | Cand\u00e1s 365","description":"La cabeza de lista del PSOE a las elecciones al Parlamento Europeo, Teresa Ribera, afirm\u00f3 el mi\u00e9rcoles que su objetivo es ganar a la ultraderecha y a la","canonical_url":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#listItem","name":"Europeas 2024: El objetivo de Teresa Ribera"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#listItem","position":3,"name":"Europeas 2024: El objetivo de Teresa Ribera","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#newsarticle","name":"Europeas 2024: El objetivo de Teresa Ribera | Cand\u00e1s 365","headline":"Europeas 2024: El objetivo de Teresa Ribera","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera.jpg","width":976,"height":671,"caption":"Teresa Ribera, este mi\u00e9rcoles en Sevilla | Foto del PSOE"},"datePublished":"2024-05-15T17:57:18+02:00","dateModified":"2024-05-15T18:04:57+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#webpage"},"articleSection":"Actualidad, Elecciones, pol\u00edtica, PSOE","dateline":"Publicado el mayo 15, 2024."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#webpage","url":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/","name":"Europeas 2024: El objetivo de Teresa Ribera | Cand\u00e1s 365","description":"La cabeza de lista del PSOE a las elecciones al Parlamento Europeo, Teresa Ribera, afirm\u00f3 el mi\u00e9rcoles que su objetivo es ganar a la ultraderecha y a la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera.jpg","@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#mainImage","width":976,"height":671,"caption":"Teresa Ribera, este mi\u00e9rcoles en Sevilla | Foto del PSOE"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/#mainImage"},"datePublished":"2024-05-15T17:57:18+02:00","dateModified":"2024-05-15T18:04:57+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Europeas 2024: El objetivo de Teresa Ribera | Cand\u00e1s 365","og:description":"La cabeza de lista del PSOE a las elecciones al Parlamento Europeo, Teresa Ribera, afirm\u00f3 el mi\u00e9rcoles que su objetivo es ganar a la ultraderecha y a la","og:url":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera.jpg","og:image:width":976,"og:image:height":671,"article:published_time":"2024-05-15T15:57:18+00:00","article:modified_time":"2024-05-15T16:04:57+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Europeas 2024: El objetivo de Teresa Ribera | Cand\u00e1s 365","twitter:description":"La cabeza de lista del PSOE a las elecciones al Parlamento Europeo, Teresa Ribera, afirm\u00f3 el mi\u00e9rcoles que su objetivo es ganar a la ultraderecha y a la","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Teresa-Ribera.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"181081","title":null,"description":"La cabeza de lista del PSOE a las elecciones al Parlamento Europeo, Teresa Ribera, afirm\u00f3 el mi\u00e9rcoles que su objetivo es ganar a la ultraderecha y a la","keywords":null,"keyphrases":{"focus":{"keyphrase":"Teresa Ribera","score":91,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Teresa Ribera","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-02 10:13:40","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-05-15 15:51:44","updated":"2025-09-02 10:13:40"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEuropeas 2024: El objetivo de Teresa Ribera\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Europeas 2024: El objetivo de Teresa Ribera","link":"https:\/\/candas365.es\/noticias\/europeas-2024-el-objetivo-de-teresa-ribera\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/181081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=181081"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/181081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/181082"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=181081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=181081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=181081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}