{"id":180746,"date":"2024-05-09T17:03:37","date_gmt":"2024-05-09T15:03:37","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=180746"},"modified":"2024-05-09T17:03:37","modified_gmt":"2024-05-09T15:03:37","slug":"educacion-infantil-en-asturias-el-nuevo-decreto-del-principado","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/","title":{"rendered":"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado"},"content":{"rendered":"<p>La Consejer\u00eda de Educaci\u00f3n del <a href=\"https:\/\/actualidad.asturias.es\/\"><span style=\"color: #ff6600;\"><strong>Principado<\/strong><\/span><\/a> ofrece a todos los interesados en BOPA la informaci\u00f3n sobre el nuevo decreto regulador de los requisitos de los centros, tanto p\u00fablicos como privados, que oferten el primer ciclo de Infantil, as\u00ed como la organizaci\u00f3n y el funcionamiento de los equipamientos p\u00fablicos que impartan este ciclo para alumnado de 0 a 3 a\u00f1os.<\/p>\n<figure id=\"attachment_180747\" aria-describedby=\"caption-attachment-180747\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-180747\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias-650x471.jpg\" alt=\"Educaci\u00f3n Infantil Asturias\" width=\"650\" height=\"471\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias-650x471.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias-360x261.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias-768x556.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias-150x109.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias-450x326.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias.jpg 893w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-180747\" class=\"wp-caption-text\">Foto: Prensa Gobierno de Asturias<\/figcaption><\/figure>\n<p><strong>Las principales novedades son la dotaci\u00f3n de dos educadores por aula, la posibilidad de ocupar m\u00e1s de una planta en los edificios destinados a estas ense\u00f1anzas y la regulaci\u00f3n de los horarios.<\/strong><\/p>\n<p>En el cap\u00edtulo de plantilla, cabe destacar que cada unidad deber\u00e1 estar atendida por dos profesionales. No obstante, se incluye alguna excepci\u00f3n, como los periodos con baja asistencia de alumnado, en los que podr\u00e1 estar presente un solo profesional.<\/p>\n<p>Asimismo, en las unidades que no superen el 50% de la ratio, se contar\u00e1 con un profesional por unidad y un apoyo equivalente a ocho horas por cada tres clases. Con car\u00e1cter general, el n\u00famero m\u00e1ximo de ni\u00f1os y ni\u00f1as por aula ser\u00e1 de 8 de 0 a\u00f1os (beb\u00e9s), 13 de un a\u00f1o y 18 de dos a\u00f1os. Por necesidades organizativas, la propuesta de decreto permite crear unidades mixtas que agrupen a menores de distintas edades.<\/p>\n<p>La nueva norma \u2013impulsada con motivo de la puesta en marcha de la red auton\u00f3mica, p\u00fablica y gratuita de <a href=\"https:\/\/candas365.es\/noticias\/carreno-muestra-su-intencion-de-incorporarse-a-les-escuelines\/\"><span style=\"color: #ff6600;\"><strong>Les Escuelines<\/strong><\/span><\/a>\/As Escol\u00edas- establece que los centros destinados a estas ense\u00f1anzas se ubicar\u00e1n, de forma general, en planta baja. No obstante, se podr\u00e1 ocupar m\u00e1s de un piso cuando concurran determinadas circunstancias, entre ellas, en zonas de alta densidad de poblaci\u00f3n, suelos en pleno centro urbano o barrios sin locales disponibles para el desarrollo exclusivo en planta baja, o en la rehabilitaci\u00f3n de edificios con alg\u00fan tipo de protecci\u00f3n urban\u00edstica.<\/p>\n<p>El decreto, que deber\u00e1 someterse a negociaci\u00f3n con la Direcci\u00f3n General de la Funci\u00f3n P\u00fablica, incluye tambi\u00e9n los horarios. As\u00ed, se establece un m\u00e1ximo de diez horas de actividad diaria de los centros, que deber\u00e1n estar abiertos, como m\u00ednimo, hasta las cuatro de la tarde.<\/p>\n<p>En cuanto al alumnado, no podr\u00e1 permanecer en las escuelas m\u00e1s de ocho horas al d\u00eda, lo que proporcionar\u00e1 cierta flexibilidad a las familias. Adem\u00e1s, el horario de apertura y cierre se adaptar\u00e1 a la demanda de, al menos, un 10% del alumnado matriculado. Las unidades ser\u00e1n, con car\u00e1cter general, a jornada completa, aunque se podr\u00e1 establecer la media jornada cuando as\u00ed lo requiera la matr\u00edcula existente.<\/p>\n<p>Por otro lado, se mantiene la dotaci\u00f3n inicial de tres unidades por centro, si bien podr\u00e1n existir escuelas con menos clases, en funci\u00f3n de las necesidades de puestos escolares o de las caracter\u00edsticas f\u00edsicas de los edificios.<\/p>\n<h2>Atenci\u00f3n a la diversidad<\/h2>\n<p>Respecto a la atenci\u00f3n a la diversidad, el alumnado de 0 a 3 a\u00f1os estar\u00e1 supervisado por el \u00c1rea III del equipo regional, en colaboraci\u00f3n con las unidades de atenci\u00f3n temprana y los equipos de orientaci\u00f3n del sector en el que se encuentre ubicada la escuela. Ese seguimiento servir\u00e1 para detectar y asesorar en aquellos casos que requieran una respuesta educativa diferente a la ordinaria.<\/p>\n<p>El decreto incluye tambi\u00e9n un apartado en el proceso de admisi\u00f3n para reservar un n\u00famero determinado de plazas para el alumnado que reciba intervenci\u00f3n de las unidades de atenci\u00f3n temprana dependientes de la Consejer\u00eda de Derechos Sociales y Bienestar.<\/p>\n<p>En cuanto a la autonom\u00eda pedag\u00f3gica, cada centro seguir\u00e1 el Programa Educativo y la Programaci\u00f3n General Anual (PGA), al igual que ocurre con el resto de etapas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Consejer\u00eda de Educaci\u00f3n del Principado ofrece a todos los interesados en BOPA la informaci\u00f3n sobre el nuevo decreto regulador de los requisitos de los centros, tanto p\u00fablicos como privados, que oferten el primer ciclo de Infantil, as\u00ed como la organizaci\u00f3n y el funcionamiento de los equipamientos p\u00fablicos que impartan este ciclo para alumnado de<\/p>\n","protected":false},"author":1,"featured_media":180747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[380,419],"class_list":{"0":"post-180746","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-asturias","8":"tag-asturias","9":"tag-educacion"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Consejer\u00eda de Educaci\u00f3n del Principado ofrece a todos los interesados en BOPA la informaci\u00f3n sobre el nuevo decreto regulador de los requisitos de los\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La Consejer\u00eda de Educaci\u00f3n del Principado ofrece a todos los interesados en BOPA la informaci\u00f3n sobre el nuevo decreto regulador de los requisitos de los\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"893\" \/>\n\t\t<meta property=\"og:image:height\" content=\"647\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-05-09T15:03:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-05-09T15:03:37+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Consejer\u00eda de Educaci\u00f3n del Principado ofrece a todos los interesados en BOPA la informaci\u00f3n sobre el nuevo decreto regulador de los requisitos de los\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#listItem\",\"name\":\"Educaci\\u00f3n Infantil en Asturias: El nuevo decreto del Principado\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#listItem\",\"position\":3,\"name\":\"Educaci\\u00f3n Infantil en Asturias: El nuevo decreto del Principado\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#newsarticle\",\"name\":\"Educaci\\u00f3n Infantil en Asturias: El nuevo decreto del Principado | Cand\\u00e1s 365\",\"headline\":\"Educaci\\u00f3n Infantil en Asturias: El nuevo decreto del Principado\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Educacion-Infantil-Asturias.jpg\",\"width\":893,\"height\":647,\"caption\":\"Foto: Prensa Gobierno de Asturias\"},\"datePublished\":\"2024-05-09T17:03:37+02:00\",\"dateModified\":\"2024-05-09T17:03:37+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#webpage\"},\"articleSection\":\"Asturias, Asturias, educaci\\u00f3n\",\"dateline\":\"Publicado el mayo 9, 2024.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/\",\"name\":\"Educaci\\u00f3n Infantil en Asturias: El nuevo decreto del Principado | Cand\\u00e1s 365\",\"description\":\"La Consejer\\u00eda de Educaci\\u00f3n del Principado ofrece a todos los interesados en BOPA la informaci\\u00f3n sobre el nuevo decreto regulador de los requisitos de los\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Educacion-Infantil-Asturias.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#mainImage\",\"width\":893,\"height\":647,\"caption\":\"Foto: Prensa Gobierno de Asturias\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\\\/#mainImage\"},\"datePublished\":\"2024-05-09T17:03:37+02:00\",\"dateModified\":\"2024-05-09T17:03:37+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado | Cand\u00e1s 365","description":"La Consejer\u00eda de Educaci\u00f3n del Principado ofrece a todos los interesados en BOPA la informaci\u00f3n sobre el nuevo decreto regulador de los requisitos de los","canonical_url":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#listItem","name":"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#listItem","position":3,"name":"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#newsarticle","name":"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado | Cand\u00e1s 365","headline":"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias.jpg","width":893,"height":647,"caption":"Foto: Prensa Gobierno de Asturias"},"datePublished":"2024-05-09T17:03:37+02:00","dateModified":"2024-05-09T17:03:37+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#webpage"},"articleSection":"Asturias, Asturias, educaci\u00f3n","dateline":"Publicado el mayo 9, 2024."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#webpage","url":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/","name":"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado | Cand\u00e1s 365","description":"La Consejer\u00eda de Educaci\u00f3n del Principado ofrece a todos los interesados en BOPA la informaci\u00f3n sobre el nuevo decreto regulador de los requisitos de los","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias.jpg","@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#mainImage","width":893,"height":647,"caption":"Foto: Prensa Gobierno de Asturias"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/#mainImage"},"datePublished":"2024-05-09T17:03:37+02:00","dateModified":"2024-05-09T17:03:37+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado | Cand\u00e1s 365","og:description":"La Consejer\u00eda de Educaci\u00f3n del Principado ofrece a todos los interesados en BOPA la informaci\u00f3n sobre el nuevo decreto regulador de los requisitos de los","og:url":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias.jpg","og:image:width":893,"og:image:height":647,"article:published_time":"2024-05-09T15:03:37+00:00","article:modified_time":"2024-05-09T15:03:37+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado | Cand\u00e1s 365","twitter:description":"La Consejer\u00eda de Educaci\u00f3n del Principado ofrece a todos los interesados en BOPA la informaci\u00f3n sobre el nuevo decreto regulador de los requisitos de los","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/05\/Educacion-Infantil-Asturias.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"180746","title":null,"description":"La Consejer\u00eda de Educaci\u00f3n del Principado ofrece a todos los interesados en BOPA la informaci\u00f3n sobre el nuevo decreto regulador de los requisitos de los","keywords":null,"keyphrases":{"focus":{"keyphrase":"Educaci\u00f3n","score":72,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[{"keyphrase":"Educaci\u00f3n","score":80,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-02 09:24:23","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-05-09 14:59:00","updated":"2025-09-02 09:24:23"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEducaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Educaci\u00f3n Infantil en Asturias: El nuevo decreto del Principado","link":"https:\/\/candas365.es\/noticias\/educacion-infantil-en-asturias-el-nuevo-decreto-del-principado\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/180746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=180746"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/180746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/180747"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=180746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=180746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=180746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}