{"id":173838,"date":"2023-05-22T21:57:49","date_gmt":"2023-05-22T19:57:49","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=173838"},"modified":"2023-05-22T21:57:49","modified_gmt":"2023-05-22T19:57:49","slug":"28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/","title":{"rendered":"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s"},"content":{"rendered":"<p>Hoy lunes en Cand\u00e1s, el Coordinador general de IU y candidato de<strong> Convocatoria por Asturies<\/strong> a la Presidencia del Principado, <strong>Ovidio Zapico<\/strong>, ha llamado a la movilizaci\u00f3n del electorado progresista, desde los desencantados a quienes est\u00e1n convencidos de que es necesaria la organizaci\u00f3n de la izquierda alternativa. El dirigente asegurado que es imprescindible que el pr\u00f3ximo domingo se llenen las urnas para lograr que Asturias y sus concejos cambien de \u00e9poca algo que, advertido, no suceder\u00e1 si no se logra un gobierno fuerte, de coalici\u00f3n, y centrado en los intereses de la mayor\u00eda social.<\/p>\n<figure id=\"attachment_173839\" aria-describedby=\"caption-attachment-173839\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-173839 size-large\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas-650x448.jpg\" alt=\"Convocatoria por Carre\u00f1o en Cand\u00e1s\" width=\"650\" height=\"448\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas-650x448.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas-360x248.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas-768x529.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas-150x103.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas-450x310.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas.jpg 1078w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-173839\" class=\"wp-caption-text\">FOTO PRENSA IU ASTURIAS<\/figcaption><\/figure>\n<p>\u00abQuiero haber un llamamiento A los votantes progresistas desencantados de lo que ha sido esta legislatura, una legislatura en la que se nos dijo que iba a ser de cambio y no lo ha sido; ha sido de m\u00e1s de lo mismo, continuidad y de inercia. Si queremos, y nosotros lo vamos a hacer, impulsar y transformar a Asturias en los pr\u00f3ximos cuatro a\u00f1os, Todos esos votantes progresistas desencantados, saben que tienen aqu\u00ed su casa, saben que tienen aqu\u00ed su papeleta, saben que no les vamos a defraudar\u00bb.<\/p>\n<p>Zapico ha animado a su base social a la a movilizarse y a movilizar a otros y otras \u201cpara lograr acudir de forma masiva a las urnas el d\u00eda 28. No nos podemos confiar, en estos momentos, no sirve la autocomplacencia, hay que movilizarse, hay que votar, hay que votar en Cand\u00e1s, hay que votar en Asturias y hay que llenar las urnas de ese mensaje de cambio y de transformaci\u00f3n que estamos escuchando y que nosotros mismos, tambi\u00e9n, desde el \u00e1mbito auton\u00f3mico, hemos lanzado\u201c.<\/p>\n<h2>\u00c1ngel Garc\u00eda, tercer alcalde de IU en Carre\u00f1o<\/h2>\n<p>En un acto pol\u00edtico, junto al candidato de Convocatoria por Carre\u00f1o, \u00c1ngel Garc\u00eda Vega, <strong>Zapico se ha mostrado convencido de que es posible lograr ese cambio necesario en este concejo.<\/strong><\/p>\n<p>\u00abConvencido de que <strong>\u00c1ngel va a ser el tercer alcalde de IU en la historia de <a href=\"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/\"><span style=\"color: #ff6600;\">Carre\u00f1o<\/span><\/a><\/strong>, que vamos a recuperar esta alcald\u00eda que es hist\u00f3rica Y que Carre\u00f1o ser\u00e1, despu\u00e9s del 28M, <strong>unos de los consejos que Izquierda Unida Convocatoria por Asturies va a gobernar la pr\u00f3xima legislatura<\/strong>\u201d.<\/p>\n<p>Lo prueba, ha explicado, la buena acogida que est\u00e1n teniendo todos los actos que se desarrollan desde que comenz\u00f3 la precampa\u00f1a y que, como la <strong>casa de cultura de Cand\u00e1s<\/strong>, se han llenado de militantes y simpatizantes que desean ver c\u00f3mo la coalici\u00f3n entre Pedro Sanchez y Yolanda D\u00edaz se traslada tambi\u00e9n a los gobiernos locales y al auton\u00f3mico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy lunes en Cand\u00e1s, el Coordinador general de IU y candidato de Convocatoria por Asturies a la Presidencia del Principado, Ovidio Zapico, ha llamado a la movilizaci\u00f3n del electorado progresista, desde los desencantados a quienes est\u00e1n convencidos de que es necesaria la organizaci\u00f3n de la izquierda alternativa. El dirigente asegurado que es imprescindible que el<\/p>\n","protected":false},"author":1,"featured_media":173839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[533,366,365,413],"class_list":{"0":"post-173838","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-carreno","8":"tag-28m","9":"tag-candas","10":"tag-carreno","11":"tag-elecciones"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hoy lunes en Cand\u00e1s, el Coordinador general de IU y candidato de Convocatoria por Asturies a la Presidencia del Principado, Ovidio Zapico, ha llamado\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"noticias carre\u00f1o\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Hoy lunes en Cand\u00e1s, el Coordinador general de IU y candidato de Convocatoria por Asturies a la Presidencia del Principado, Ovidio Zapico, ha llamado\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1078\" \/>\n\t\t<meta property=\"og:image:height\" content=\"743\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-05-22T19:57:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-22T19:57:49+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hoy lunes en Cand\u00e1s, el Coordinador general de IU y candidato de Convocatoria por Asturies a la Presidencia del Principado, Ovidio Zapico, ha llamado\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/noticias-carreno\\\/#listItem\",\"name\":\"Noticias Carre\\u00f1o\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/noticias-carreno\\\/#listItem\",\"position\":2,\"name\":\"Noticias Carre\\u00f1o\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/noticias-carreno\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#listItem\",\"name\":\"28M: Acto central de campa\\u00f1a de Convocatoria por Carre\\u00f1o en Cand\\u00e1s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#listItem\",\"position\":3,\"name\":\"28M: Acto central de campa\\u00f1a de Convocatoria por Carre\\u00f1o en Cand\\u00e1s\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/noticias-carreno\\\/#listItem\",\"name\":\"Noticias Carre\\u00f1o\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#newsarticle\",\"name\":\"28M: Acto central de campa\\u00f1a de Convocatoria por Carre\\u00f1o en Cand\\u00e1s | Cand\\u00e1s 365\",\"headline\":\"28M: Acto central de campa\\u00f1a de Convocatoria por Carre\\u00f1o en Cand\\u00e1s\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Convocatoria-por-Carreno-en-Candas.jpg\",\"width\":1078,\"height\":743,\"caption\":\"FOTO PRENSA IU ASTURIAS\"},\"datePublished\":\"2023-05-22T21:57:49+02:00\",\"dateModified\":\"2023-05-22T21:57:49+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#webpage\"},\"articleSection\":\"Noticias Carre\\u00f1o, 28M, Cand\\u00e1s, Carre\\u00f1o, Elecciones\",\"dateline\":\"Publicado el mayo 22, 2023.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/\",\"name\":\"28M: Acto central de campa\\u00f1a de Convocatoria por Carre\\u00f1o en Cand\\u00e1s | Cand\\u00e1s 365\",\"description\":\"Hoy lunes en Cand\\u00e1s, el Coordinador general de IU y candidato de Convocatoria por Asturies a la Presidencia del Principado, Ovidio Zapico, ha llamado\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Convocatoria-por-Carreno-en-Candas.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#mainImage\",\"width\":1078,\"height\":743,\"caption\":\"FOTO PRENSA IU ASTURIAS\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\\\/#mainImage\"},\"datePublished\":\"2023-05-22T21:57:49+02:00\",\"dateModified\":\"2023-05-22T21:57:49+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s | Cand\u00e1s 365","description":"Hoy lunes en Cand\u00e1s, el Coordinador general de IU y candidato de Convocatoria por Asturies a la Presidencia del Principado, Ovidio Zapico, ha llamado","canonical_url":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/","robots":"max-image-preview:large","keywords":"noticias carre\u00f1o","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/#listItem","name":"Noticias Carre\u00f1o"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/#listItem","position":2,"name":"Noticias Carre\u00f1o","item":"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#listItem","name":"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#listItem","position":3,"name":"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/#listItem","name":"Noticias Carre\u00f1o"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#newsarticle","name":"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s | Cand\u00e1s 365","headline":"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas.jpg","width":1078,"height":743,"caption":"FOTO PRENSA IU ASTURIAS"},"datePublished":"2023-05-22T21:57:49+02:00","dateModified":"2023-05-22T21:57:49+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#webpage"},"articleSection":"Noticias Carre\u00f1o, 28M, Cand\u00e1s, Carre\u00f1o, Elecciones","dateline":"Publicado el mayo 22, 2023."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#webpage","url":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/","name":"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s | Cand\u00e1s 365","description":"Hoy lunes en Cand\u00e1s, el Coordinador general de IU y candidato de Convocatoria por Asturies a la Presidencia del Principado, Ovidio Zapico, ha llamado","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas.jpg","@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#mainImage","width":1078,"height":743,"caption":"FOTO PRENSA IU ASTURIAS"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/#mainImage"},"datePublished":"2023-05-22T21:57:49+02:00","dateModified":"2023-05-22T21:57:49+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s | Cand\u00e1s 365","og:description":"Hoy lunes en Cand\u00e1s, el Coordinador general de IU y candidato de Convocatoria por Asturies a la Presidencia del Principado, Ovidio Zapico, ha llamado","og:url":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas.jpg","og:image:width":1078,"og:image:height":743,"article:published_time":"2023-05-22T19:57:49+00:00","article:modified_time":"2023-05-22T19:57:49+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s | Cand\u00e1s 365","twitter:description":"Hoy lunes en Cand\u00e1s, el Coordinador general de IU y candidato de Convocatoria por Asturies a la Presidencia del Principado, Ovidio Zapico, ha llamado","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Convocatoria-por-Carreno-en-Candas.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"173838","title":null,"description":"Hoy lunes en Cand\u00e1s, el Coordinador general de IU y candidato de Convocatoria por Asturies a la Presidencia del Principado, Ovidio Zapico, ha llamado","keywords":[],"keyphrases":{"focus":{"keyphrase":"Cand\u00e1s","score":90,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Convocatoria","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},{"keyphrase":"Cand\u00e1s","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-01 20:49:11","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-05-22 19:49:08","updated":"2025-09-01 20:49:11"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/\" title=\"Noticias Carre\u00f1o\">Noticias Carre\u00f1o<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Noticias Carre\u00f1o","link":"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/"},{"label":"28M: Acto central de campa\u00f1a de Convocatoria por Carre\u00f1o en Cand\u00e1s","link":"https:\/\/candas365.es\/noticias\/28m-acto-central-de-campana-de-convocatoria-por-carreno-en-candas\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/173838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=173838"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/173838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/173839"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=173838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=173838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=173838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}