{"id":173829,"date":"2023-05-22T15:14:47","date_gmt":"2023-05-22T13:14:47","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=173829"},"modified":"2023-05-22T15:14:47","modified_gmt":"2023-05-22T13:14:47","slug":"sector-del-cine-menos-salas-y-butacas","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/","title":{"rendered":"Sector del cine: Menos salas y butacas"},"content":{"rendered":"<p>(EP) &#8211; El n\u00famero de locales de cine se incrementa un 2,6% en el \u00faltimo a\u00f1o, alcanzado su m\u00e1ximo desde 2012, mientras el n\u00famero de salas y butacas desciende, seg\u00fan se desprende del 25\u00ba Censo de Salas de Cine que elabora la<strong> Asociaci\u00f3n para la Investigaci\u00f3n de Medios de Comunicaci\u00f3n<\/strong> (AIMC).<\/p>\n<figure id=\"attachment_173830\" aria-describedby=\"caption-attachment-173830\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-173830 size-large\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine-650x360.jpg\" alt=\"cine\" width=\"650\" height=\"360\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine-650x360.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine-360x200.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine-768x426.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine-150x83.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine-450x249.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine.jpg 1122w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-173830\" class=\"wp-caption-text\">Foto: GOBIERNO DE CANARIAS \/ Europa Press<\/figcaption><\/figure>\n<p>En concreto, el n\u00famero de espacios de exhibici\u00f3n de <a href=\"https:\/\/candas365.es\/noticias\/tag\/cultura\/\"><span style=\"color: #ff6600;\"><strong>cine en Espa\u00f1a<\/strong><\/span><\/a> ha pasado de 732 a 751 en el \u00faltimo ejercicio, alcanzando cifras que no se ve\u00edan desde hace diez a\u00f1os, mientras el n\u00famero de salas\/pantallas se sit\u00faa en 3.591, lo que supone una ligera disminuci\u00f3n de 35 pantallas (-1%) respecto al anterior censo, con 93 altas y 128 bajas, pero se mantiene en el nivel previo a la pandemia.<\/p>\n<p>En lo que respecta al n\u00famero butacas, la cifra baja hasta 750.751, 8.044 (-1,1%) menos que las contabilizadas en el censo de 2022, si bien el descenso acumulado en los \u00faltimos ocho a\u00f1os es notable, con y 47.501 butacas (-6%) menos que en 2015.<\/p>\n<blockquote><p>El estudio elaborado por la AIMC muestra as\u00ed una tendencia hacia la existencia de cines con menos pantallas y salas que cuentan con menos butacas, que, a cambio, suelen ser m\u00e1s grandes y c\u00f3modas.<\/p><\/blockquote>\n<p>La media de butacas por sala\/pantalla es de 210 unidades (15 menos que en 2014) y cada local tiene de media 4,8 salas (5 menos que en 2014). En consecuencia, el promedio del total de butacas por local de cine, incluyendo todas las salas, tambi\u00e9n ha descendido, pasando de las 1.203 butacas de 2014 a las 1.010 actuales.<\/p>\n<p>En el caso de los cines de verano, el aforo por pantalla suele ser mayor, con 558 butacas de media frente a las 201 de los convencionales, si bien el promedio de salas por local en este tipo de espacios es inferior con 1,1 salas frente a las 5,3 de los convencionales.<\/p>\n<p>Adem\u00e1s, un 52,3% de los locales de cine en general cuenta con m\u00e1s de una sala\/pantalla, apreci\u00e1ndose descensos de 2,8 puntos en comparaci\u00f3n con 2022 y de 7,6 puntos respecto a 2014, y el 48,2% de las salas\/pantallas se encuentran en locales de 10 o m\u00e1s salas.<\/p>\n<h2>MUNICIPIOS CON CINE<\/h2>\n<p>Por otro lado, el censo se\u00f1ala a un aumento de la poblaci\u00f3n que reside en municipios con cine. En concreto, 2 de cada 3 espa\u00f1oles reside en una localidad que cuenta con, al menos, un cine, lo que supone un aumento de 2,6 puntos en relaci\u00f3n con 2016.<\/p>\n<p>Asimismo, el n\u00famero de municipios con cine tambi\u00e9n se ha visto incrementado hasta los 493, 14 m\u00e1s que en 2022 y 56 m\u00e1s que en 2016, lo que supone un 6,1% respecto al total. Esto ha hecho que tanto el n\u00famero de municipios con cine, como la poblaci\u00f3n que reside en ellos, alcancen m\u00e1ximos desde 2006. En promedio, existen aproximadamente 1,5 locales y 7,5 salas por municipio con cine.<\/p>\n<p>En este contexto, el informe de la AIMC especifica que el 68,4% de las salas (2.457) se localizan en poblaciones de m\u00e1s de 50.000 habitantes y que el 94,4% de las personas que viven en estos municipios tienen cine en su localidad, frente a los individuos de poblaciones de menor tama\u00f1o, donde s\u00f3lo el 29,4% dispone de \u00e9l.<\/p>\n<h2>LA MITAD DE LAS SALAS, EN MADRID, CATALU\u00d1A Y ANDALUC\u00cdA<\/h2>\n<p>La mitad de las salas de cine en Espa\u00f1a se reparten entre Andaluc\u00eda (649), Catalu\u00f1a (600) y Madrid (534), seg\u00fan el estudio, que sit\u00faa a Madrid como l\u00edder del ranking por provincias, seguida de Barcelona (411), Valencia (215), Alicante (176), Sevilla (153), M\u00e1laga (135), C\u00e1diz (127) y Murcia (123).<\/p>\n<blockquote><p>El censo tambi\u00e9n precisa que en Espa\u00f1a existen 76 salas de cine por cada mill\u00f3n de habitantes, una cifra similar a la de las \u00faltimas entregas aunque marca una disminuci\u00f3n de 5 cines respecto a hace diez a\u00f1os.<\/p><\/blockquote>\n<p>Las comunidades que tienen 80 o m\u00e1s salas por mill\u00f3n de habitantes son La Rioja (113), Navarra (92), Pa\u00eds Vasco (90), Comunidad Valenciana (84) y Murcia (80). En el lado opuesto, se encuentran las comunidades de Ceuta y Melilla (48), Extremadura (61), Canarias (62), Galicia (62) y Arag\u00f3n (66).<\/p>\n<p>Por provincias, las que cuentan con mayor densidad de salas son, por orden, Soria, La Rioja, Tarragona, Salamanca, C\u00e1diz y Ciudad Real, que igualan o superan las 100 salas por mill\u00f3n de habitantes. <strong>Asimismo, las provincias que cuentan con una menor concentraci\u00f3n de salas por mill\u00f3n de habitantes son Melilla, Zamora, Teruel, Ourense y Ja\u00e9n, donde ninguna supera las 50.<\/strong><\/p>\n<blockquote><p>En t\u00e9rminos de aforo, la densidad media es de aproximadamente 16 butacas por cada 1.000 habitantes, mismo dato que en el censo de 2022.<\/p><\/blockquote>\n<h2>KIN\u00c9POLIS, LOS CINES CON M\u00c1S SALAS<\/h2>\n<p>En cuanto a empresas, los cines con m\u00e1s salas del territorio espa\u00f1ol son Kin\u00e9polis Full Splau (28 salas) en Cornell\u00e1 de Llobregat (Barcelona); Kin\u00e9polis Ciudad de la Imagen (24 salas), en Pozuelo de Alarc\u00f3n (Madrid); Cinesa Las Rozas (24 salas), en Las Rozas (Madrid), y Kin\u00e9polis Valencia (24 salas), en Paterna (Valencia).<\/p>\n<p>En cuanto al aforo, los locales capaces de reunir un mayor n\u00famero de personas en su interior y que superan las 5.000 butacas contabilizando todas sus salas son dos de los Kin\u00e9polis ya mencionados, Kin\u00e9polis Valencia (8.145 butacas) y Kin\u00e9polis Ciudad de la Imagen (8.104 butacas), as\u00ed como Cinesa Nassica (5.003 butacas) en Getafe (Madrid).<\/p>\n<blockquote><p>Por \u00faltimo, el informe de la AIMC destaca que los espectadores est\u00e1n retomando el h\u00e1bito de acudir al cine tras la pandemia, pues las cifras del Estudio General de Medios (EGM) muestran que la l\u00f3gica ca\u00edda de la asistencia al cine generada por el Covid-19 toc\u00f3 fondo a principios de 2021.<\/p><\/blockquote>\n<p><strong>De este modo, en el primer trimestre de 2023 el n\u00famero de espectadores semanales se quede muy cerca de los niveles prepand\u00e9micos ya que supone un 96% de los que hab\u00eda, en promedio, en el periodo 2016-2018.<\/strong> Comparando con el promedio de 2019, en el que se registr\u00f3 un m\u00e1ximo de audiencia en muchos a\u00f1os, la audiencia del primer trimestre de 2023 representa un porcentaje algo menor (81%), por lo que, de cara al futuro, quede margen para que el n\u00famero de espectadores contin\u00fae creciendo, ha concluido el censo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP) &#8211; El n\u00famero de locales de cine se incrementa un 2,6% en el \u00faltimo a\u00f1o, alcanzado su m\u00e1ximo desde 2012, mientras el n\u00famero de salas y butacas desciende, seg\u00fan se desprende del 25\u00ba Censo de Salas de Cine que elabora la Asociaci\u00f3n para la Investigaci\u00f3n de Medios de Comunicaci\u00f3n (AIMC). En concreto, el n\u00famero<\/p>\n","protected":false},"author":1,"featured_media":173830,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[504,430],"class_list":{"0":"post-173829","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-canal-empresas","8":"tag-cine","9":"tag-cultura"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"(EP) - El n\u00famero de locales de cine se incrementa un 2,6% en el \u00faltimo a\u00f1o, alcanzado su m\u00e1ximo desde 2012, mientras el n\u00famero de salas y butacas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"canal empresas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sector del cine: Menos salas y butacas | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(EP) - El n\u00famero de locales de cine se incrementa un 2,6% en el \u00faltimo a\u00f1o, alcanzado su m\u00e1ximo desde 2012, mientras el n\u00famero de salas y butacas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1122\" \/>\n\t\t<meta property=\"og:image:height\" content=\"622\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-05-22T13:14:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-22T13:14:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sector del cine: Menos salas y butacas | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(EP) - El n\u00famero de locales de cine se incrementa un 2,6% en el \u00faltimo a\u00f1o, alcanzado su m\u00e1ximo desde 2012, mientras el n\u00famero de salas y butacas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"position\":2,\"name\":\"Canal Empresas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#listItem\",\"name\":\"Sector del cine: Menos salas y butacas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#listItem\",\"position\":3,\"name\":\"Sector del cine: Menos salas y butacas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/canal-empresas\\\/#listItem\",\"name\":\"Canal Empresas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#newsarticle\",\"name\":\"Sector del cine: Menos salas y butacas | Cand\\u00e1s 365\",\"headline\":\"Sector del cine: Menos salas y butacas\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cine.jpg\",\"width\":1122,\"height\":622,\"caption\":\"Foto: GOBIERNO DE CANARIAS \\\/ Europa Press\"},\"datePublished\":\"2023-05-22T15:14:47+02:00\",\"dateModified\":\"2023-05-22T15:14:47+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#webpage\"},\"articleSection\":\"Canal Empresas, Cine, cultura\",\"dateline\":\"Publicado el mayo 22, 2023.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/\",\"name\":\"Sector del cine: Menos salas y butacas | Cand\\u00e1s 365\",\"description\":\"(EP) - El n\\u00famero de locales de cine se incrementa un 2,6% en el \\u00faltimo a\\u00f1o, alcanzado su m\\u00e1ximo desde 2012, mientras el n\\u00famero de salas y butacas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cine.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#mainImage\",\"width\":1122,\"height\":622,\"caption\":\"Foto: GOBIERNO DE CANARIAS \\\/ Europa Press\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/sector-del-cine-menos-salas-y-butacas\\\/#mainImage\"},\"datePublished\":\"2023-05-22T15:14:47+02:00\",\"dateModified\":\"2023-05-22T15:14:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Sector del cine: Menos salas y butacas | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Sector del cine: Menos salas y butacas | Cand\u00e1s 365","description":"(EP) - El n\u00famero de locales de cine se incrementa un 2,6% en el \u00faltimo a\u00f1o, alcanzado su m\u00e1ximo desde 2012, mientras el n\u00famero de salas y butacas","canonical_url":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/","robots":"max-image-preview:large","keywords":"canal empresas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","position":2,"name":"Canal Empresas","item":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#listItem","name":"Sector del cine: Menos salas y butacas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#listItem","position":3,"name":"Sector del cine: Menos salas y butacas","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/#listItem","name":"Canal Empresas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#newsarticle","name":"Sector del cine: Menos salas y butacas | Cand\u00e1s 365","headline":"Sector del cine: Menos salas y butacas","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine.jpg","width":1122,"height":622,"caption":"Foto: GOBIERNO DE CANARIAS \/ Europa Press"},"datePublished":"2023-05-22T15:14:47+02:00","dateModified":"2023-05-22T15:14:47+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#webpage"},"articleSection":"Canal Empresas, Cine, cultura","dateline":"Publicado el mayo 22, 2023."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#webpage","url":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/","name":"Sector del cine: Menos salas y butacas | Cand\u00e1s 365","description":"(EP) - El n\u00famero de locales de cine se incrementa un 2,6% en el \u00faltimo a\u00f1o, alcanzado su m\u00e1ximo desde 2012, mientras el n\u00famero de salas y butacas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine.jpg","@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#mainImage","width":1122,"height":622,"caption":"Foto: GOBIERNO DE CANARIAS \/ Europa Press"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/#mainImage"},"datePublished":"2023-05-22T15:14:47+02:00","dateModified":"2023-05-22T15:14:47+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Sector del cine: Menos salas y butacas | Cand\u00e1s 365","og:description":"(EP) - El n\u00famero de locales de cine se incrementa un 2,6% en el \u00faltimo a\u00f1o, alcanzado su m\u00e1ximo desde 2012, mientras el n\u00famero de salas y butacas","og:url":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine.jpg","og:image:width":1122,"og:image:height":622,"article:published_time":"2023-05-22T13:14:47+00:00","article:modified_time":"2023-05-22T13:14:47+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Sector del cine: Menos salas y butacas | Cand\u00e1s 365","twitter:description":"(EP) - El n\u00famero de locales de cine se incrementa un 2,6% en el \u00faltimo a\u00f1o, alcanzado su m\u00e1ximo desde 2012, mientras el n\u00famero de salas y butacas","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/cine.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"173829","title":null,"description":"(EP) - El n\u00famero de locales de cine se incrementa un 2,6% en el \u00faltimo a\u00f1o, alcanzado su m\u00e1ximo desde 2012, mientras el n\u00famero de salas y butacas","keywords":[],"keyphrases":{"focus":{"keyphrase":"cine","score":93,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"locales de cine","score":83,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":3},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}},{"keyphrase":"salas y butacas","score":83,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":3},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}},{"keyphrase":"cine","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-01 20:48:25","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-05-22 12:57:08","updated":"2025-09-01 20:48:25"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/\" title=\"Canal Empresas\">Canal Empresas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tSector del cine: Menos salas y butacas\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Canal Empresas","link":"https:\/\/candas365.es\/noticias\/category\/canal-empresas\/"},{"label":"Sector del cine: Menos salas y butacas","link":"https:\/\/candas365.es\/noticias\/sector-del-cine-menos-salas-y-butacas\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/173829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=173829"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/173829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/173830"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=173829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=173829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=173829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}