{"id":173810,"date":"2023-05-20T17:42:11","date_gmt":"2023-05-20T15:42:11","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=173810"},"modified":"2023-05-20T17:42:11","modified_gmt":"2023-05-20T15:42:11","slug":"vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/","title":{"rendered":"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa"},"content":{"rendered":"<p>El viernes se disput\u00f3 la primera etapa de la <a href=\"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-primera-etapa\/\"><span style=\"color: #ff6600;\"><strong>Vuelta a la Monta\u00f1a Central de Asturias<\/strong><\/span><\/a> Junior. Y nuestro compa\u00f1ero David Y\u00e1\u00f1ez, <a href=\"https:\/\/www.facebook.com\/profile.php?id=100082914563602\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>director de la Pr\u00f3rroga<\/strong><\/span><\/a> nos acerca la cr\u00f3nica de la prueba deportiva.<\/p>\n<figure id=\"attachment_173811\" aria-describedby=\"caption-attachment-173811\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-173811 size-large\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias-650x426.jpg\" alt=\"Vuelta a la Monta\u00f1a Central de Asturias \" width=\"650\" height=\"426\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias-650x426.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias-360x236.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias-768x503.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias-150x98.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias-450x295.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias.jpg 929w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-173811\" class=\"wp-caption-text\">Foto: David Y\u00e1\u00f1ez \/ LP<\/figcaption><\/figure>\n<p><strong>La segunda etapa part\u00eda desde la localidad mierense de Figaredo<\/strong> bajo una fina lluvia que serv\u00eda de homenaje del pelot\u00f3n al corredor del Eolo Kometa, Arturo Gr\u00e1vales, que fallec\u00eda esta madrugada v\u00edctima de una larga enfermedad.<\/p>\n<p>Tras unos kil\u00f3metros neutralizados, se bajaba la bandera y se manten\u00eda la calma en los primeros compases de la etapa donde los corredores parec\u00eda que ten\u00edan la mente en esa ascensi\u00f3n al Alto de Carabanzo a falta de 10 km de la meta en las calles de MIeres.<\/p>\n<p>Tras un segundo paso por la Meta Volante de Figaredo se produc\u00eda la fuga del d\u00eda con tres corredores, <strong>Eleazar Jim\u00e9nez (Team Junior Ciudad de Talavera), Mart\u00ed Pratginestos (Europa-Tadesan-Bluepower) y Alberto Galindo (MX Pidal-Asesores Diego Diez) que llegaban al inicio del Alto de Carabanzo con 30 segundos de diferencia, llegaron a tener 2 minutos y 32 segundos<\/strong>, sobre el gran grupo donde el conjunto del Eolo Kometa-Fundaci\u00f3n Contador intentaba neutralizar la fuga para conseguir la victoria en un d\u00eda de tristeza para la escuadra madrile\u00f1a.<\/p>\n<p>En estas primeras rampas se marchaba el corredor del conjunto de Talavera de la Reina que consegu\u00eda en la cima una ventaja de 10 segundos que le permit\u00edan descender en un descenso vertiginoso hacia MIeres donde a falta de 3 km era cogido por el gran grupo donde el conjunto del Bathco Cycling Team impon\u00eda el control de cara a esa llegada donde el conjunto del Besaya consegu\u00eda la victoria en un ajustado sprint por medio del corredor Francisco Cresp\u00ed y que permit\u00eda a su compa\u00f1ero de equipo, <strong>Diego Guti\u00e9rrez enfundar el malliot amarillo de l\u00edder provisional de la General.<\/strong><\/p>\n<p>Hoy s\u00e1bado jornada de dos sectores. Uno por la ma\u00f1ana, contrarreloj por equipos, entre Laviana y Soto de Agues con 13.7 km de recorrido y por la tarde Laviana-Laviana con 73.9 km y el Alto de la Faya de los Lobos de 2\u00aa categor\u00eda a 10 km de meta. <strong>Interesante jornada la de hoy s\u00e1bado donde se empezaran a marcar las primeras diferencias.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes se disput\u00f3 la primera etapa de la Vuelta a la Monta\u00f1a Central de Asturias Junior. Y nuestro compa\u00f1ero David Y\u00e1\u00f1ez, director de la Pr\u00f3rroga nos acerca la cr\u00f3nica de la prueba deportiva. La segunda etapa part\u00eda desde la localidad mierense de Figaredo bajo una fina lluvia que serv\u00eda de homenaje del pelot\u00f3n al<\/p>\n","protected":false},"author":1,"featured_media":173811,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[387],"class_list":{"0":"post-173810","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte","8":"tag-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"El viernes se disput\u00f3 la primera etapa de la Vuelta a la Monta\u00f1a Central de Asturias Junior. Y nuestro compa\u00f1ero David Y\u00e1\u00f1ez, director de la Pr\u00f3rroga nos acerca\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El viernes se disput\u00f3 la primera etapa de la Vuelta a la Monta\u00f1a Central de Asturias Junior. Y nuestro compa\u00f1ero David Y\u00e1\u00f1ez, director de la Pr\u00f3rroga nos acerca\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"929\" \/>\n\t\t<meta property=\"og:image:height\" content=\"609\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-05-20T15:42:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-20T15:42:11+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El viernes se disput\u00f3 la primera etapa de la Vuelta a la Monta\u00f1a Central de Asturias Junior. Y nuestro compa\u00f1ero David Y\u00e1\u00f1ez, director de la Pr\u00f3rroga nos acerca\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#listItem\",\"name\":\"Vuelta a la Monta\\u00f1a Central de Asturias Junior: Resumen segunda etapa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#listItem\",\"position\":3,\"name\":\"Vuelta a la Monta\\u00f1a Central de Asturias Junior: Resumen segunda etapa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#newsarticle\",\"name\":\"Vuelta a la Monta\\u00f1a Central de Asturias Junior: Resumen segunda etapa | Cand\\u00e1s 365\",\"headline\":\"Vuelta a la Monta\\u00f1a Central de Asturias Junior: Resumen segunda etapa\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Vuelta-a-la-Montana-Central-de-Asturias.jpg\",\"width\":929,\"height\":609,\"caption\":\"Foto: David Y\\u00e1\\u00f1ez \\\/ LP\"},\"datePublished\":\"2023-05-20T17:42:11+02:00\",\"dateModified\":\"2023-05-20T17:42:11+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#webpage\"},\"articleSection\":\"Deporte, deporte\",\"dateline\":\"Publicado el mayo 20, 2023.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/\",\"name\":\"Vuelta a la Monta\\u00f1a Central de Asturias Junior: Resumen segunda etapa | Cand\\u00e1s 365\",\"description\":\"El viernes se disput\\u00f3 la primera etapa de la Vuelta a la Monta\\u00f1a Central de Asturias Junior. Y nuestro compa\\u00f1ero David Y\\u00e1\\u00f1ez, director de la Pr\\u00f3rroga nos acerca\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Vuelta-a-la-Montana-Central-de-Asturias.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#mainImage\",\"width\":929,\"height\":609,\"caption\":\"Foto: David Y\\u00e1\\u00f1ez \\\/ LP\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\\\/#mainImage\"},\"datePublished\":\"2023-05-20T17:42:11+02:00\",\"dateModified\":\"2023-05-20T17:42:11+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa | Cand\u00e1s 365","description":"El viernes se disput\u00f3 la primera etapa de la Vuelta a la Monta\u00f1a Central de Asturias Junior. Y nuestro compa\u00f1ero David Y\u00e1\u00f1ez, director de la Pr\u00f3rroga nos acerca","canonical_url":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#listItem","name":"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#listItem","position":3,"name":"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#newsarticle","name":"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa | Cand\u00e1s 365","headline":"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias.jpg","width":929,"height":609,"caption":"Foto: David Y\u00e1\u00f1ez \/ LP"},"datePublished":"2023-05-20T17:42:11+02:00","dateModified":"2023-05-20T17:42:11+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#webpage"},"articleSection":"Deporte, deporte","dateline":"Publicado el mayo 20, 2023."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#webpage","url":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/","name":"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa | Cand\u00e1s 365","description":"El viernes se disput\u00f3 la primera etapa de la Vuelta a la Monta\u00f1a Central de Asturias Junior. Y nuestro compa\u00f1ero David Y\u00e1\u00f1ez, director de la Pr\u00f3rroga nos acerca","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias.jpg","@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#mainImage","width":929,"height":609,"caption":"Foto: David Y\u00e1\u00f1ez \/ LP"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/#mainImage"},"datePublished":"2023-05-20T17:42:11+02:00","dateModified":"2023-05-20T17:42:11+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa | Cand\u00e1s 365","og:description":"El viernes se disput\u00f3 la primera etapa de la Vuelta a la Monta\u00f1a Central de Asturias Junior. Y nuestro compa\u00f1ero David Y\u00e1\u00f1ez, director de la Pr\u00f3rroga nos acerca","og:url":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias.jpg","og:image:width":929,"og:image:height":609,"article:published_time":"2023-05-20T15:42:11+00:00","article:modified_time":"2023-05-20T15:42:11+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa | Cand\u00e1s 365","twitter:description":"El viernes se disput\u00f3 la primera etapa de la Vuelta a la Monta\u00f1a Central de Asturias Junior. Y nuestro compa\u00f1ero David Y\u00e1\u00f1ez, director de la Pr\u00f3rroga nos acerca","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Vuelta-a-la-Montana-Central-de-Asturias.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"173810","title":null,"description":"El viernes se disput\u00f3 la primera etapa de la Vuelta a la Monta\u00f1a Central de Asturias Junior. Y nuestro compa\u00f1ero David Y\u00e1\u00f1ez, director de la Pr\u00f3rroga nos acerca","keywords":[],"keyphrases":{"focus":{"keyphrase":"Vuelta","score":92,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Vuelta a la Monta\u00f1a Central de Asturias","score":92,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":6,"maxScore":9,"error":1,"length":7},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},{"keyphrase":"Monta\u00f1a Central de Asturias","score":100,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":4},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-01 20:47:27","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-05-20 15:34:07","updated":"2025-09-01 20:47:27"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tVuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"Vuelta a la Monta\u00f1a Central de Asturias Junior: Resumen segunda etapa","link":"https:\/\/candas365.es\/noticias\/vuelta-a-la-montana-central-de-asturias-junior-resumen-segunda-etapa\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/173810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=173810"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/173810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/173811"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=173810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=173810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=173810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}