{"id":173697,"date":"2023-05-15T02:42:04","date_gmt":"2023-05-15T00:42:04","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=173697"},"modified":"2023-05-15T02:42:04","modified_gmt":"2023-05-15T00:42:04","slug":"feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/","title":{"rendered":"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas"},"content":{"rendered":"<p>(EP) &#8211; El presidente del PP, Alberto N\u00fa\u00f1ez Feij\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa \u00abgran mayor\u00eda\u00bb de vascos que desean la \u00abreconciliaci\u00f3n\u00bb y que se siente \u00abavergonzados\u00bb por la decisi\u00f3n de EH Bildu de incluir a \u00abverdugos\u00bb en sus listas para las elecciones del d\u00eda 28, algo que considera una humillaci\u00f3n\u00bb a las v\u00edctimas.<\/p>\n<figure id=\"attachment_173698\" aria-describedby=\"caption-attachment-173698\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-173698 size-large\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1-650x418.jpg\" alt=\"Feij\u00f3o\" width=\"650\" height=\"418\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1-650x418.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1-360x232.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1-768x494.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1-150x97.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1-450x290.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1.jpg 1005w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-173698\" class=\"wp-caption-text\">Foto: I\u00f1aki Berasaluce &#8211; Europa Press<\/figcaption><\/figure>\n<p>Feij\u00f3o ha intervenido en un acto del PP junto a la candidata a la Alcald\u00eda de la capital alavesa, Ainhoa Domaica, y el presidente del Partido Popular vasco, Carlos Iturgaiz, quien ha calificado de \u00abignominia\u00bb que el presidente del Gobierno, Pedro S\u00e1nchez, y el PSOE \u00abcolegueen\u00bb &#8211;seg\u00fan ha dicho&#8211; con la coalici\u00f3n soberanista.<\/p>\n<h2>\u00abLO CONTRARIO A LA RECONCILIACI\u00d3N\u00bb<\/h2>\n<p>En su intervenci\u00f3n, Feij\u00f3o se ha mostrado partidario de la \u00abreconciliaci\u00f3n\u00bb. No obstante, ha denunciado que la decisi\u00f3n de EH Bildu de incluir en sus listas para las elecciones municipales y forales a 44 personas condenadas por pertenencia o colaboraci\u00f3n con ETA \u00abes exactamente lo contrario de la reconciliaci\u00f3n\u00bb.<\/p>\n<p>\u00abEs volver al pasado; es tocar lo que no debemos de tocar. Es una declaraci\u00f3n en contra de la reconciliaci\u00f3n\u00bb, ha subrayado Feij\u00f3o, quien ha a\u00f1adido que \u00ablos verdugos no pueden ser representantes pol\u00edticos de las v\u00edctimas\u00bb y que \u00ablos sueldos de los verdugos no los pueden pagar las v\u00edctimas\u00bb. Eso no es reconciliaci\u00f3n, es una humillaci\u00f3n; eso no es buscar unir a nadie, es volver a romper la sociedad\u00bb, ha criticado.<\/p>\n<p>El l\u00edder del PP se ha mostrado \u00abconvencido\u00bb de que \u00abla gran mayor\u00eda del pueblo vasco est\u00e1 avergonzado\u00bb por la decisi\u00f3n adoptada por la coalici\u00f3n soberanista. \u00abPor eso le pido el voto a la gran mayor\u00eda del pueblo vasco, a todos aquellos que quieren la reconciliaci\u00f3n: votar que no; no a Bildu y no a sus socios\u00bb, ha a\u00f1adido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP) &#8211; El presidente del PP, Alberto N\u00fa\u00f1ez Feij\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa \u00abgran mayor\u00eda\u00bb de vascos que desean la \u00abreconciliaci\u00f3n\u00bb y que se siente \u00abavergonzados\u00bb por la decisi\u00f3n de EH Bildu de incluir a \u00abverdugos\u00bb en sus listas para las elecciones del d\u00eda 28,<\/p>\n","protected":false},"author":1,"featured_media":173698,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[533,413,466],"class_list":{"0":"post-173697","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-28m","9":"tag-elecciones","10":"tag-espana"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"(EP) - El presidente del PP, Alberto N\u00fa\u00f1ez Feij\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa &quot;gran mayor\u00eda&quot; de vascos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(EP) - El presidente del PP, Alberto N\u00fa\u00f1ez Feij\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa &quot;gran mayor\u00eda&quot; de vascos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1005\" \/>\n\t\t<meta property=\"og:image:height\" content=\"647\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-05-15T00:42:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-15T00:42:04+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(EP) - El presidente del PP, Alberto N\u00fa\u00f1ez Feij\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa &quot;gran mayor\u00eda&quot; de vascos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#listItem\",\"name\":\"Feij\\u00f3o pide el voto a la \\u00abgran mayor\\u00eda\\u00bb de vascos \\u00abavergonzados\\u00bb por la \\u00abhumillaci\\u00f3n\\u00bb de EH Bildu a las v\\u00edctimas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#listItem\",\"position\":3,\"name\":\"Feij\\u00f3o pide el voto a la \\u00abgran mayor\\u00eda\\u00bb de vascos \\u00abavergonzados\\u00bb por la \\u00abhumillaci\\u00f3n\\u00bb de EH Bildu a las v\\u00edctimas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#newsarticle\",\"name\":\"Feij\\u00f3o pide el voto a la \\u00abgran mayor\\u00eda\\u00bb de vascos \\u00abavergonzados\\u00bb por la \\u00abhumillaci\\u00f3n\\u00bb de EH Bildu a las v\\u00edctimas | Cand\\u00e1s 365\",\"headline\":\"Feij\\u00f3o pide el voto a la \\u00abgran mayor\\u00eda\\u00bb de vascos \\u00abavergonzados\\u00bb por la \\u00abhumillaci\\u00f3n\\u00bb de EH Bildu a las v\\u00edctimas\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Feijoo-1.jpg\",\"width\":1005,\"height\":647,\"caption\":\"Foto: I\\u00f1aki Berasaluce - Europa Press\"},\"datePublished\":\"2023-05-15T02:42:04+02:00\",\"dateModified\":\"2023-05-15T02:42:04+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#webpage\"},\"articleSection\":\"Actualidad, 28M, Elecciones, Espa\\u00f1a\",\"dateline\":\"Publicado el mayo 15, 2023.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/\",\"name\":\"Feij\\u00f3o pide el voto a la \\u00abgran mayor\\u00eda\\u00bb de vascos \\u00abavergonzados\\u00bb por la \\u00abhumillaci\\u00f3n\\u00bb de EH Bildu a las v\\u00edctimas | Cand\\u00e1s 365\",\"description\":\"(EP) - El presidente del PP, Alberto N\\u00fa\\u00f1ez Feij\\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa \\\"gran mayor\\u00eda\\\" de vascos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Feijoo-1.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#mainImage\",\"width\":1005,\"height\":647,\"caption\":\"Foto: I\\u00f1aki Berasaluce - Europa Press\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\\\/#mainImage\"},\"datePublished\":\"2023-05-15T02:42:04+02:00\",\"dateModified\":\"2023-05-15T02:42:04+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas | Cand\u00e1s 365","description":"(EP) - El presidente del PP, Alberto N\u00fa\u00f1ez Feij\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa \"gran mayor\u00eda\" de vascos","canonical_url":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#listItem","name":"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#listItem","position":3,"name":"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#newsarticle","name":"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas | Cand\u00e1s 365","headline":"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1.jpg","width":1005,"height":647,"caption":"Foto: I\u00f1aki Berasaluce - Europa Press"},"datePublished":"2023-05-15T02:42:04+02:00","dateModified":"2023-05-15T02:42:04+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#webpage"},"articleSection":"Actualidad, 28M, Elecciones, Espa\u00f1a","dateline":"Publicado el mayo 15, 2023."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#webpage","url":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/","name":"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas | Cand\u00e1s 365","description":"(EP) - El presidente del PP, Alberto N\u00fa\u00f1ez Feij\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa \"gran mayor\u00eda\" de vascos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1.jpg","@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#mainImage","width":1005,"height":647,"caption":"Foto: I\u00f1aki Berasaluce - Europa Press"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/#mainImage"},"datePublished":"2023-05-15T02:42:04+02:00","dateModified":"2023-05-15T02:42:04+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas | Cand\u00e1s 365","og:description":"(EP) - El presidente del PP, Alberto N\u00fa\u00f1ez Feij\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa &quot;gran mayor\u00eda&quot; de vascos","og:url":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1.jpg","og:image:width":1005,"og:image:height":647,"article:published_time":"2023-05-15T00:42:04+00:00","article:modified_time":"2023-05-15T00:42:04+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas | Cand\u00e1s 365","twitter:description":"(EP) - El presidente del PP, Alberto N\u00fa\u00f1ez Feij\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa &quot;gran mayor\u00eda&quot; de vascos","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2023\/05\/Feijoo-1.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"173697","title":null,"description":"(EP) - El presidente del PP, Alberto N\u00fa\u00f1ez Feij\u00f3o, ha pedido este domingo, en un acto celebrado en Vitoria-Gasteiz, el voto de esa \"gran mayor\u00eda\" de vascos","keywords":[],"keyphrases":{"focus":{"keyphrase":"Feij\u00f3o","score":83,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"PP","score":83,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}},{"keyphrase":"N\u00fa\u00f1ez Feij\u00f3o","score":83,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-01 20:40:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-05-15 00:32:43","updated":"2025-09-01 20:40:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tFeij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Feij\u00f3o pide el voto a la \u00abgran mayor\u00eda\u00bb de vascos \u00abavergonzados\u00bb por la \u00abhumillaci\u00f3n\u00bb de EH Bildu a las v\u00edctimas","link":"https:\/\/candas365.es\/noticias\/feijoo-pide-el-voto-a-la-gran-mayoria-de-vascos-avergonzados-por-la-humillacion-de-eh-bildu-a-las-victimas\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/173697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=173697"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/173697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/173698"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=173697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=173697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=173697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}