{"id":165748,"date":"2022-09-02T19:30:13","date_gmt":"2022-09-02T17:30:13","guid":{"rendered":"https:\/\/candas365.es\/noticias\/?p=165748"},"modified":"2022-09-02T19:30:13","modified_gmt":"2022-09-02T17:30:13","slug":"unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/","title":{"rendered":"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner"},"content":{"rendered":"<p>(EP) &#8211; Unidas Podemos se ha sumado este viernes a la concentraci\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado contra la vicepresidenta del pa\u00eds suramericana, Cristina Fern\u00e1ndez de Kirchner.<\/p>\n<figure id=\"attachment_165749\" aria-describedby=\"caption-attachment-165749\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-165749 size-large\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner-650x417.jpg\" alt=\"Kirchner\" width=\"650\" height=\"417\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner-650x417.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner-360x231.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner-150x96.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner-450x289.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner.jpg 679w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-165749\" class=\"wp-caption-text\">Foto: IU \/ Europa Press<\/figcaption><\/figure>\n<p>La secretaria de Organizaci\u00f3n de los &#8216;morados&#8217;, Lilith Verstrynge, ve este \u00abintento de asesinato\u00bb como \u00abun claro mensaje de violencia pol\u00edtica y de discursos de odio generados por el hostigamiento pol\u00edtico apoyado por sectores medi\u00e1ticos\u00bb.<\/p>\n<p>\u00abFrente a la dictadura y el terrorismo de Estado, hay que defender a la democracia\u00bb, ha a\u00f1adido la tambi\u00e9n secretaria de estado de Agenda 2030.<\/p>\n<p>En la concentraci\u00f3n tambi\u00e9n ha estado su antecesor en el Ministerio, Enrique Santiago, que es secretario general del PCE y portavoz adjunto de IU. En redes sociales ha expresado su solidaridad \u00abfrente al fascismo y en defensa de la democracia\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP) &#8211; Unidas Podemos se ha sumado este viernes a la concentraci\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado contra la vicepresidenta del pa\u00eds suramericana, Cristina Fern\u00e1ndez de Kirchner. La secretaria de Organizaci\u00f3n de los &#8216;morados&#8217;, Lilith Verstrynge, ve este \u00abintento de asesinato\u00bb como \u00abun claro mensaje de violencia pol\u00edtica<\/p>\n","protected":false},"author":1,"featured_media":165749,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[466,470],"class_list":{"0":"post-165748","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-espana","9":"tag-politica"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"(EP) - Unidas Podemos se ha sumado este viernes a la concentraci\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(EP) - Unidas Podemos se ha sumado este viernes a la concentraci\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"679\" \/>\n\t\t<meta property=\"og:image:height\" content=\"436\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-09-02T17:30:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-09-02T17:30:13+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(EP) - Unidas Podemos se ha sumado este viernes a la concentraci\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#listItem\",\"name\":\"Unidas Podemos muestra su apoyo a Cristina Fern\\u00e1ndez de Kirchner\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#listItem\",\"position\":3,\"name\":\"Unidas Podemos muestra su apoyo a Cristina Fern\\u00e1ndez de Kirchner\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#newsarticle\",\"name\":\"Unidas Podemos muestra su apoyo a Cristina Fern\\u00e1ndez de Kirchner | Cand\\u00e1s 365\",\"headline\":\"Unidas Podemos muestra su apoyo a Cristina Fern\\u00e1ndez de Kirchner\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Kirchner.jpg\",\"width\":679,\"height\":436,\"caption\":\"Foto: IU \\\/ Europa Press\"},\"datePublished\":\"2022-09-02T19:30:13+02:00\",\"dateModified\":\"2022-09-02T19:30:13+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#webpage\"},\"articleSection\":\"Actualidad, Espa\\u00f1a, pol\\u00edtica\",\"dateline\":\"Publicado el septiembre 2, 2022.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/\",\"name\":\"Unidas Podemos muestra su apoyo a Cristina Fern\\u00e1ndez de Kirchner | Cand\\u00e1s 365\",\"description\":\"(EP) - Unidas Podemos se ha sumado este viernes a la concentraci\\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Kirchner.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#mainImage\",\"width\":679,\"height\":436,\"caption\":\"Foto: IU \\\/ Europa Press\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\\\/#mainImage\"},\"datePublished\":\"2022-09-02T19:30:13+02:00\",\"dateModified\":\"2022-09-02T19:30:13+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner | Cand\u00e1s 365","description":"(EP) - Unidas Podemos se ha sumado este viernes a la concentraci\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado","canonical_url":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#listItem","name":"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#listItem","position":3,"name":"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#newsarticle","name":"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner | Cand\u00e1s 365","headline":"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner.jpg","width":679,"height":436,"caption":"Foto: IU \/ Europa Press"},"datePublished":"2022-09-02T19:30:13+02:00","dateModified":"2022-09-02T19:30:13+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#webpage"},"articleSection":"Actualidad, Espa\u00f1a, pol\u00edtica","dateline":"Publicado el septiembre 2, 2022."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#webpage","url":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/","name":"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner | Cand\u00e1s 365","description":"(EP) - Unidas Podemos se ha sumado este viernes a la concentraci\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner.jpg","@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#mainImage","width":679,"height":436,"caption":"Foto: IU \/ Europa Press"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/#mainImage"},"datePublished":"2022-09-02T19:30:13+02:00","dateModified":"2022-09-02T19:30:13+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner | Cand\u00e1s 365","og:description":"(EP) - Unidas Podemos se ha sumado este viernes a la concentraci\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado","og:url":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner.jpg","og:image:width":679,"og:image:height":436,"article:published_time":"2022-09-02T17:30:13+00:00","article:modified_time":"2022-09-02T17:30:13+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner | Cand\u00e1s 365","twitter:description":"(EP) - Unidas Podemos se ha sumado este viernes a la concentraci\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/09\/Kirchner.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"165748","title":null,"description":"(EP) - Unidas Podemos se ha sumado este viernes a la concentraci\u00f3n convocada ante la embajada argentina en Madrid en repulsa por el atentado","keywords":[],"keyphrases":{"focus":{"keyphrase":"Unidas Podemos ","score":80,"analysis":{"keyphraseInTitle":{"title":"Focus keyphrase in SEO title","description":"Focus keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"title":"Focus keyphrase in URL","description":"Focus keyphrase not found in the URL.","score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"title":"Focus keyphrase in image alt attributes","description":"Focus keyphrase not found in image alt attribute(s). Add an image with your Focus keyphrase as alt text.","score":3,"maxScore":9,"error":1}}},"additional":[{"keyphrase":"Unidas Podemos ","score":83,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Keyphrase in image alt attributes","description":"Keyphrase not found in image alt attribute(s). Add an image with your Keyphrase as alt text.","score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-09-01 11:34:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2022-09-02 17:17:58","updated":"2025-09-01 11:34:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tUnidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Unidas Podemos muestra su apoyo a Cristina Fern\u00e1ndez de Kirchner","link":"https:\/\/candas365.es\/noticias\/unidas-podemos-muestra-su-apoyo-a-cristina-fernandez-de-kirchner\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/165748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=165748"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/165748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/165749"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=165748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=165748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=165748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}