{"id":160104,"date":"2022-01-05T15:43:57","date_gmt":"2022-01-05T15:43:57","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=160104"},"modified":"2022-01-05T15:43:57","modified_gmt":"2022-01-05T15:43:57","slug":"patos-de-goma-y-su-contribucion-a-la-ciencia","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/","title":{"rendered":"Patos de goma y su contribuci\u00f3n a la ciencia"},"content":{"rendered":"<p>(dpa) &#8211; El <a href=\"https:\/\/es.wikipedia.org\/wiki\/10_de_enero\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>10 de enero<\/strong><\/span><\/a> de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/candas365.es\/noticias\/category\/el-tiempo\/\" target=\"_blank\" rel=\"noopener\"><strong>fuerte tormenta en el Oc\u00e9ano Pac\u00edfico Norte<\/strong><\/a><\/span>.<\/p>\n<figure id=\"attachment_160105\" aria-describedby=\"caption-attachment-160105\" style=\"width: 1012px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-160105\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma.jpg\" alt=\"patos de goma\" width=\"1012\" height=\"665\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma.jpg 1012w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma-360x237.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma-650x427.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma-768x505.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma-150x99.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma-450x296.jpg 450w\" sizes=\"(max-width: 1012px) 100vw, 1012px\" \/><figcaption id=\"caption-attachment-160105\" class=\"wp-caption-text\">Foto: Stefan Sauer\/dpa<\/figcaption><\/figure>\n<p>Debido a los fuertes vientos y a las altas olas, varios contenedores cayeron por la borda. Al menos uno se abri\u00f3 y verti\u00f3 su carga en el mar: patitos, castores, tortugas y ranas. Casi <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/naberco.es\/como-patitos-de-plastico-caidos-al-mar-sirven-a-oceanografos-alemanes\/\" target=\"_blank\" rel=\"noopener\"><strong>30.000 animales de pl\u00e1stico<\/strong><\/a><\/span> para la ba\u00f1era flotaban en el mar.<\/p>\n<p>La historia podr\u00eda haber terminado en ese momento, pero en realidad reci\u00e9n comenzaba. Impulsados por el viento y las corrientes, l<strong>os animales ba\u00f1istas emprendieron un viaje, llegaron a diversas costas<\/strong>, fueron recogidos por los paseantes en las playas y finalmente se convirtieron en objeto de investigaci\u00f3n cient\u00edfica.<\/p>\n<p>Los lugares en los que fueron encontrados permitieron reconstruir sus rutas y tiempos de viaje y, por lo tanto, obtener numerosos datos sobre las corrientes mar\u00edtimas.<\/p>\n<blockquote><p>La informaci\u00f3n fue recogida principalmente por el ocean\u00f3grafo estadounidense Curtis Ebbesmeyer, que ya est\u00e1 retirado.<\/p><\/blockquote>\n<p>Unos a\u00f1os antes,<strong> Ebbesmeyer hab\u00eda recogido informaci\u00f3n cient\u00edfica de un accidente de barco similar, en el que m\u00e1s de 60.000 zapatillas Nike se perdieron por la borda y llegaron a la costa oeste de Estados Unidos y Canad\u00e1<\/strong> en los meses siguientes.<\/p>\n<p>Ebbesmeyer cre\u00f3 una red de buscadores de objetos en playas, que le suministraban datos sobre todo tipo de hallazgos. Tras el accidente en el Oc\u00e9ano Pac\u00edfico, los recolectores le volvieron a informar del encuentro de los animales de goma. A trav\u00e9s de los datos del fabricante grabados en los juguetes fue posible constatar el origen de los mismos.<\/p>\n<p>\u00abEl accidente de los animales de goma aport\u00f3 un verdadero tesoro a la investigaci\u00f3n\u00bb, destaca Johanna Baehr, ocean\u00f3grafa de la Universidad de Hamburgo. \u00abDe pronto hab\u00eda miles de puntos de datos. No hubi\u00e9semos podido contar nunca con tantos instrumentos de medici\u00f3n cient\u00edfica a la vez\u00bb, apunta.<\/p>\n<p>La idea de investigar las corrientes oce\u00e1nicas con la ayuda de dispositivos de medici\u00f3n flotantes no es nueva. <strong>El uso de los llamados \u00abdrifters\u00bb (cosas que flotan sin rumbo de un lugar a otro), es uno de los m\u00e9todos m\u00e1s antiguos de investigaci\u00f3n marina\u00bb, afirma el ocean\u00f3grafo J\u00f6rg-Olaf Wolff, de la Universidad de Oldenburg<\/strong>.<\/p>\n<p>Ya en 1864, el investigador <strong><span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/es.wikipedia.org\/wiki\/Georg_Balthasar_von_Neumayer\" target=\"_blank\" rel=\"noopener\">Georg von Neumayer<\/a><\/span><\/strong>, del entonces Observatorio Naval Alem\u00e1n de Hamburgo, hizo arrojar una botella con un mensaje por la borda de un barco frente al Cabo de Hornos. En el mensaje Neumayer ped\u00eda que se le informara d\u00f3nde y cu\u00e1ndo se hab\u00eda encontrado la botella. Esta se encontr\u00f3 posteriormente en Australia.<\/p>\n<blockquote><p>\u00abEso fue hace m\u00e1s de 150 a\u00f1os y ayud\u00f3 a comprender mejor las corrientes mar\u00edtimas a gran escala\u00bb, se\u00f1ala Wolff.<\/p><\/blockquote>\n<p>Hoy en d\u00eda, los investigadores utilizan dispositivos de medici\u00f3n m\u00e1s precisos equipados con un Sistema de Posicionamiento Global (GPS) y que pueden registrar datos como la temperatura, la salinidad del agua o la presi\u00f3n del aire y enviarlos por radio a los sat\u00e9lites.<\/p>\n<p>\u00abTambi\u00e9n hay dispositivos de flotaci\u00f3n, que se hunden repetidamente desde la superficie hasta profundidades de uno y dos kil\u00f3metros, y van recogiendo datos a medida que avanzan\u00bb, explica Wolff.<\/p>\n<p>En comparaci\u00f3n con estos,<strong> los \u00abdrifter\u00bb, como los animales de goma para la ba\u00f1era, solo proporcionan datos muy imprecisos<\/strong>.<\/p>\n<p>\u00abPero es mejor que nada, sobre todo porque los datos se generaron de forma gratuita\u00bb, se\u00f1ala el ocean\u00f3grafo alem\u00e1n, y acota que los aparatos de medici\u00f3n digitales son caros y no pueden utilizarse en un n\u00famero elevado.<\/p>\n<p><strong>\u00bfPor d\u00f3nde viajaron los animalitos de goma?<\/strong> Tras analizar los datos se descubri\u00f3 que primero se movilizaron en sentido contrario a las agujas del reloj en la corriente del Pac\u00edfico Norte. Circularon desde Sitka, en la costa de Alaska, a lo largo de las islas Aleutianas, pasando por la pen\u00ednsula de Kamchatka y, finalmente, volvieron a cruzar el Pac\u00edfico recorriendo la costa occidental de Estados Unidos hasta Alaska.<\/p>\n<p>En 1994, 1998, 2001 y 2003 recibi\u00f3 Ebbesmeyer datos de hallazgos en Sitka, lo que sugiere que los patitos y dem\u00e1s hab\u00edan dado algunas vueltas en c\u00edrculos. Otros escaparon del v\u00f3rtice y llegaron hasta Haw\u00e1i y Australia.<\/p>\n<p>\u00abQuiz\u00e1 uno de los hallazgos m\u00e1s emocionantes es que los juguetitos se desplazaron desde el Pac\u00edfico hasta el Atl\u00e1ntico Norte\u00bb, se\u00f1ala Baehr. \u00abEsto ya hab\u00eda sido pronosticado anteriormente mediante modelos, pero los animales demostraron que es algo que sucede realmente\u00bb, a\u00f1ade.<\/p>\n<p>As\u00ed, a principios de la d\u00e9cada del 2000 se encontraron ejemplares en la costa oeste de Estados Unidos, as\u00ed como en Escocia e Inglaterra. Los ba\u00f1istas se hab\u00edan desplazado a trav\u00e9s del estrecho de Bering hacia el oc\u00e9ano \u00c1rtico, hasta Groenlandia, en el Atl\u00e1ntico Norte. No se sabe si se congelaron o permanecieron encima de los t\u00e9mpanos.<\/p>\n<blockquote><p>\u00abEsta ruta fue una confirmaci\u00f3n interesante de que all\u00ed hay una corriente superficial que recorre tal distancia\u00bb, apunta Wolff.<\/p><\/blockquote>\n<p>Desde 2016, el investigador de oc\u00e9anos de la Universidad de Oldenburgo utiliz\u00f3, junto con un equipo interdisciplinario, \u00abflotadores\u00bb para investigar c\u00f3mo se distribuye la basura en el Mar del Norte.<\/p>\n<p>Para ello, se lanzaron a la deriva 65.000 boyas peque\u00f1as de madera en el mar del Norte. Se marcaron con un n\u00famero y se adjunt\u00f3 el pedido de que se informara de cualquier hallazgo con detalles del lugar, la fecha y la hora.<\/p>\n<p>Uno de los resultados m\u00e1s sorprendentes del proyecto fue constatar que las condiciones de flujo en el mar del Norte pueden invertirse en determinadas condiciones.<\/p>\n<p>\u00abDe repente recibimos informes de Inglaterra. Esto puso de manifiesto que los flotadores de madera ya no se desplazaban en sentido contrario a las agujas del reloj, como era habitual, sino en el sentido de las agujas del reloj. Esto no se sab\u00eda antes\u00bb, destaca Wolff.<\/p>\n<p>Este tipo de estudios podr\u00edan ayudar a comprender mejor la distribuci\u00f3n de los residuos pl\u00e1sticos y a desarrollar conceptos de prevenci\u00f3n. <strong>Los estudios con instrumentos flotando a la deriva tambi\u00e9n pueden proporcionar importantes datos in situ para el desarrollo de modelos meteorol\u00f3gicos<\/strong>.<\/p>\n<p>\u00abEn \u00faltima instancia, esto puede mejorar las previsiones meteorol\u00f3gicas o, con el tel\u00f3n de fondo del cambio clim\u00e1tico, las predicciones para las pr\u00f3ximas d\u00e9cadas\u00bb, afirma Baehr.<\/p>\n<p>El destino actual de los animalitos de goma no est\u00e1 claro. \u00abNo creo que a\u00fan haya alguno circulando. Treinta a\u00f1os de viento, olas y radiaci\u00f3n solar convierten el pl\u00e1stico en un material fr\u00e1gil, por lo que presumiblemente se hayan desmenuzado en micropl\u00e1sticos\u00bb, detalla el ocean\u00f3grafo Wolff.<\/p>\n<p>Johanna Baehr, por su parte, no descarta la posibilidad de que uno u otro pato aparezca en alg\u00fan lugar, por ejemplo alguno que haya quedado atascado en el hielo. \u00abLos patos de goma tienen una vida \u00fatil espantosamente larga, como todo el pl\u00e1stico que acaba en el mar\u00bb, comenta.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Anja Garms (dpa)<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; El 10 de enero de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una fuerte tormenta en el Oc\u00e9ano Pac\u00edfico Norte. Debido a los fuertes vientos y a las altas olas, varios contenedores cayeron por la borda. Al menos uno se abri\u00f3 y verti\u00f3 su<\/p>\n","protected":false},"author":1,"featured_media":160105,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[143],"tags":[454,408],"class_list":["post-160104","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sociedad","tag-ciencia","tag-sociedad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El 10 de enero de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una fuerte tormenta en el Oc\u00e9ano\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"sociedad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Patos de goma y su contribuci\u00f3n a la ciencia | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El 10 de enero de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una fuerte tormenta en el Oc\u00e9ano\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1012\" \/>\n\t\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-01-05T15:43:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-01-05T15:43:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Patos de goma y su contribuci\u00f3n a la ciencia | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El 10 de enero de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una fuerte tormenta en el Oc\u00e9ano\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"position\":2,\"name\":\"Sociedad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#listItem\",\"name\":\"Patos de goma y su contribuci\\u00f3n a la ciencia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#listItem\",\"position\":3,\"name\":\"Patos de goma y su contribuci\\u00f3n a la ciencia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#newsarticle\",\"name\":\"Patos de goma y su contribuci\\u00f3n a la ciencia | Cand\\u00e1s 365\",\"headline\":\"Patos de goma y su contribuci\\u00f3n a la ciencia\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/patos-de-goma.jpg\",\"width\":1012,\"height\":665,\"caption\":\"Foto: Stefan Sauer\\\/dpa\"},\"datePublished\":\"2022-01-05T15:43:57+01:00\",\"dateModified\":\"2022-01-05T15:43:57+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#webpage\"},\"articleSection\":\"Sociedad, Ciencia, sociedad\",\"dateline\":\"Publicado el enero 5, 2022.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/\",\"name\":\"Patos de goma y su contribuci\\u00f3n a la ciencia | Cand\\u00e1s 365\",\"description\":\"El 10 de enero de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una fuerte tormenta en el Oc\\u00e9ano\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/patos-de-goma.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#mainImage\",\"width\":1012,\"height\":665,\"caption\":\"Foto: Stefan Sauer\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/patos-de-goma-y-su-contribucion-a-la-ciencia\\\/#mainImage\"},\"datePublished\":\"2022-01-05T15:43:57+01:00\",\"dateModified\":\"2022-01-05T15:43:57+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Patos de goma y su contribuci\u00f3n a la ciencia | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Patos de goma y su contribuci\u00f3n a la ciencia | Cand\u00e1s 365","description":"El 10 de enero de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una fuerte tormenta en el Oc\u00e9ano","canonical_url":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/","robots":"max-image-preview:large","keywords":"sociedad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","position":2,"name":"Sociedad","item":"https:\/\/candas365.es\/noticias\/category\/sociedad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#listItem","name":"Patos de goma y su contribuci\u00f3n a la ciencia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#listItem","position":3,"name":"Patos de goma y su contribuci\u00f3n a la ciencia","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#newsarticle","name":"Patos de goma y su contribuci\u00f3n a la ciencia | Cand\u00e1s 365","headline":"Patos de goma y su contribuci\u00f3n a la ciencia","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma.jpg","width":1012,"height":665,"caption":"Foto: Stefan Sauer\/dpa"},"datePublished":"2022-01-05T15:43:57+01:00","dateModified":"2022-01-05T15:43:57+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#webpage"},"articleSection":"Sociedad, Ciencia, sociedad","dateline":"Publicado el enero 5, 2022."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#webpage","url":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/","name":"Patos de goma y su contribuci\u00f3n a la ciencia | Cand\u00e1s 365","description":"El 10 de enero de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una fuerte tormenta en el Oc\u00e9ano","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma.jpg","@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#mainImage","width":1012,"height":665,"caption":"Foto: Stefan Sauer\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/#mainImage"},"datePublished":"2022-01-05T15:43:57+01:00","dateModified":"2022-01-05T15:43:57+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Patos de goma y su contribuci\u00f3n a la ciencia | Cand\u00e1s 365","og:description":"El 10 de enero de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una fuerte tormenta en el Oc\u00e9ano","og:url":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma.jpg","og:image:width":1012,"og:image:height":665,"article:published_time":"2022-01-05T15:43:57+00:00","article:modified_time":"2022-01-05T15:43:57+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Patos de goma y su contribuci\u00f3n a la ciencia | Cand\u00e1s 365","twitter:description":"El 10 de enero de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una fuerte tormenta en el Oc\u00e9ano","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2022\/01\/patos-de-goma.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"6 minutos"},"aioseo_meta_data":{"post_id":"160104","title":null,"description":"El 10 de enero de 1992, un buque portacontenedores procedente de Hong Kong con destino a Estados Unidos fue sorprendido por una fuerte tormenta en el Oc\u00e9ano &nbsp;","keywords":[],"keyphrases":{"focus":{"keyphrase":"portacontenedores ","score":68,"analysis":{"keyphraseInTitle":{"title":"Focus keyphrase in SEO title","description":"Focus keyphrase not found in SEO title.","score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseInURL":{"title":"Focus keyphrase in URL","description":"Focus keyphrase not found in the URL.","score":1,"maxScore":5,"error":1},"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"title":"Focus keyphrase in image alt attributes","description":"Focus keyphrase not found in image alt attribute(s). Add an image with your Focus keyphrase as alt text.","score":3,"maxScore":9,"error":1}}},"additional":[{"keyphrase":"10 de enero ","score":83,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Keyphrase in image alt attributes","description":"Keyphrase not found in image alt attribute(s). Add an image with your Keyphrase as alt text.","score":3,"maxScore":9,"error":1}}},{"keyphrase":"fuerte tormenta ","score":83,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Keyphrase in image alt attributes","description":"Keyphrase not found in image alt attribute(s). Add an image with your Keyphrase as alt text.","score":3,"maxScore":9,"error":1}}},{"keyphrase":"Patos de goma","score":67,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase not found in meta description.","score":3,"maxScore":9,"error":1},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":3},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase does not appear in the first paragraph. Make sure the topic is clear immediately.","score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"title":"Keyphrase in image alt attributes","description":"Keyphrase found in image alt attribute(s).","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-28 08:50:01","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2022-01-05 15:32:52","updated":"2026-05-28 08:50:01"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/sociedad\/\" title=\"Sociedad\">Sociedad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tPatos de goma y su contribuci\u00f3n a la ciencia\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Sociedad","link":"https:\/\/candas365.es\/noticias\/category\/sociedad\/"},{"label":"Patos de goma y su contribuci\u00f3n a la ciencia","link":"https:\/\/candas365.es\/noticias\/patos-de-goma-y-su-contribucion-a-la-ciencia\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/160104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=160104"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/160104\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/160105"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=160104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=160104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=160104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}