{"id":157901,"date":"2021-08-31T13:50:14","date_gmt":"2021-08-31T13:50:14","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=157901"},"modified":"2021-08-31T14:06:10","modified_gmt":"2021-08-31T14:06:10","slug":"reunion-entre-principado-y-la-alcaldesa-de-ibias","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/","title":{"rendered":"Reuni\u00f3n entre Principado y la alcaldesa de Ibias"},"content":{"rendered":"<p>Hoy martes, el consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\u00f3n, Bego\u00f1a L\u00f3pez, se han reunido con la alcaldesa de Ibias, Gemma \u00c1lvarez.<\/p>\n<figure id=\"attachment_157902\" aria-describedby=\"caption-attachment-157902\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-157902 size-large\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias-650x455.jpg\" alt=\"Alcaldesa Ibias\" width=\"650\" height=\"455\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias-650x455.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias-360x252.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias-768x537.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias.jpg 1071w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><figcaption id=\"caption-attachment-157902\" class=\"wp-caption-text\">FOTO: GOBIERNO DE ASTURIAS<\/figcaption><\/figure>\n<p>En la reuni\u00f3n se analizaron varias peticiones de infraestructuras rurales en los montes y en el parque natural.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy martes, el consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\u00f3n, Bego\u00f1a L\u00f3pez, se han reunido con la alcaldesa de Ibias, Gemma \u00c1lvarez. En la reuni\u00f3n se analizaron varias peticiones de infraestructuras rurales en los montes y en el parque natural.<\/p>\n","protected":false},"author":1,"featured_media":157902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[380,368],"class_list":{"0":"post-157901","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-asturias","8":"tag-asturias","9":"tag-principado"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"El consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\u00f3n, Bego\u00f1a L\u00f3pez, se han reunido con la alcaldesa de Ibias\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Reuni\u00f3n entre Principado y la alcaldesa de Ibias | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\u00f3n, Bego\u00f1a L\u00f3pez, se han reunido con la alcaldesa de Ibias\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1071\" \/>\n\t\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-31T13:50:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-08-31T14:06:10+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Reuni\u00f3n entre Principado y la alcaldesa de Ibias | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\u00f3n, Bego\u00f1a L\u00f3pez, se han reunido con la alcaldesa de Ibias\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#listItem\",\"name\":\"Reuni\\u00f3n entre Principado y la alcaldesa de Ibias\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#listItem\",\"position\":3,\"name\":\"Reuni\\u00f3n entre Principado y la alcaldesa de Ibias\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#newsarticle\",\"name\":\"Reuni\\u00f3n entre Principado y la alcaldesa de Ibias | Cand\\u00e1s 365\",\"headline\":\"Reuni\\u00f3n entre Principado y la alcaldesa de Ibias\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Alcaldesa-Ibias.jpg\",\"width\":1071,\"height\":749,\"caption\":\"FOTO: GOBIERNO DE ASTURIAS\"},\"datePublished\":\"2021-08-31T13:50:14+02:00\",\"dateModified\":\"2021-08-31T14:06:10+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#webpage\"},\"articleSection\":\"Asturias, Asturias, Principado\",\"dateline\":\"Publicado el agosto 31, 2021.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/\",\"name\":\"Reuni\\u00f3n entre Principado y la alcaldesa de Ibias | Cand\\u00e1s 365\",\"description\":\"El consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\\u00f3n, Bego\\u00f1a L\\u00f3pez, se han reunido con la alcaldesa de Ibias\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Alcaldesa-Ibias.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#mainImage\",\"width\":1071,\"height\":749,\"caption\":\"FOTO: GOBIERNO DE ASTURIAS\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/reunion-entre-principado-y-la-alcaldesa-de-ibias\\\/#mainImage\"},\"datePublished\":\"2021-08-31T13:50:14+02:00\",\"dateModified\":\"2021-08-31T14:06:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Reuni\u00f3n entre Principado y la alcaldesa de Ibias | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Reuni\u00f3n entre Principado y la alcaldesa de Ibias | Cand\u00e1s 365","description":"El consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\u00f3n, Bego\u00f1a L\u00f3pez, se han reunido con la alcaldesa de Ibias","canonical_url":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#listItem","name":"Reuni\u00f3n entre Principado y la alcaldesa de Ibias"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#listItem","position":3,"name":"Reuni\u00f3n entre Principado y la alcaldesa de Ibias","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#newsarticle","name":"Reuni\u00f3n entre Principado y la alcaldesa de Ibias | Cand\u00e1s 365","headline":"Reuni\u00f3n entre Principado y la alcaldesa de Ibias","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias.jpg","width":1071,"height":749,"caption":"FOTO: GOBIERNO DE ASTURIAS"},"datePublished":"2021-08-31T13:50:14+02:00","dateModified":"2021-08-31T14:06:10+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#webpage"},"articleSection":"Asturias, Asturias, Principado","dateline":"Publicado el agosto 31, 2021."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#webpage","url":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/","name":"Reuni\u00f3n entre Principado y la alcaldesa de Ibias | Cand\u00e1s 365","description":"El consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\u00f3n, Bego\u00f1a L\u00f3pez, se han reunido con la alcaldesa de Ibias","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias.jpg","@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#mainImage","width":1071,"height":749,"caption":"FOTO: GOBIERNO DE ASTURIAS"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/#mainImage"},"datePublished":"2021-08-31T13:50:14+02:00","dateModified":"2021-08-31T14:06:10+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Reuni\u00f3n entre Principado y la alcaldesa de Ibias | Cand\u00e1s 365","og:description":"El consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\u00f3n, Bego\u00f1a L\u00f3pez, se han reunido con la alcaldesa de Ibias","og:url":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias.jpg","og:image:width":1071,"og:image:height":749,"article:published_time":"2021-08-31T13:50:14+00:00","article:modified_time":"2021-08-31T14:06:10+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Reuni\u00f3n entre Principado y la alcaldesa de Ibias | Cand\u00e1s 365","twitter:description":"El consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\u00f3n, Bego\u00f1a L\u00f3pez, se han reunido con la alcaldesa de Ibias","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2021\/08\/Alcaldesa-Ibias.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365"},"aioseo_meta_data":{"post_id":"157901","title":null,"description":"El consejero asturiano, Alejandro Calvo, y la directora general de Desarrollo Rural y Agroalimentaci\u00f3n, Bego\u00f1a L\u00f3pez, se han reunido con la alcaldesa de Ibias","keywords":[],"keyphrases":{"focus":{"keyphrase":"Ibias","score":100,"analysis":{"keyphraseInTitle":{"title":"Frase clave objetivo en el t\u00edtulo SEO","description":"Frase clave objetivo encontrada en el t\u00edtulo SEO.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Frase clave objetivo en la meta descripci\u00f3n","description":"Frase clave objetivo encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInURL":{"title":"Frase clave objetivo en la URL","description":"Frase clave objetivo usada en la URL.","score":5,"maxScore":5,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave objetivo","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Frase clave objetivo en la introducci\u00f3n","description":"Su Frase clave objetivo aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"title":"Frase clave objetivo en los atributos alt de la imagen.","description":"Frase clave objetivo encontrada en los atributos alt de la(s) imagen(es).","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"consejero asturiano","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1}}},{"keyphrase":"alcaldesa de Ibias","score":100,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":3},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave encontrada en los atributos alt de la(s) imagen(es).","score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"seo_analyzer_scan_date":"2025-09-01 01:36:27","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2021-08-31 13:46:09","updated":"2025-09-01 01:36:27"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tReuni\u00f3n entre Principado y la alcaldesa de Ibias\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Reuni\u00f3n entre Principado y la alcaldesa de Ibias","link":"https:\/\/candas365.es\/noticias\/reunion-entre-principado-y-la-alcaldesa-de-ibias\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/157901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=157901"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/157901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/157902"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=157901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=157901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=157901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}