{"id":148826,"date":"2020-11-26T18:50:36","date_gmt":"2020-11-26T18:50:36","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=148826"},"modified":"2020-11-26T18:50:36","modified_gmt":"2020-11-26T18:50:36","slug":"venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/","title":{"rendered":"Venezuela reclama a la ONU que financie el &#8216;Plan de Vuelta a la Patria&#8217;"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-101053\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>(Europa Press) &#8211;\u00a0El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al &#8216;Plan de Vuelta a la Patria&#8217;, el programa con el que el Ejecutivo de Nicol\u00e1s Maduro quiere facilitar el regreso de miles de venezolanos que han emigrado en los \u00faltimos a\u00f1os para escapar de la crisis social, econ\u00f3mica y pol\u00edtica.<\/p>\n<p>Maduro ya denunci\u00f3 el domingo una supuesta falta de colaboraci\u00f3n de la Organizaci\u00f3n Internacional para las Migraciones (OIM) y el Alto Comisionado de la ONU para los Refugiados (ACNUR), que coordinan la asistencia a los m\u00e1s de cuatro millones de venezolanos emigrados. \u00abNo nos han apoyado\u00bb, lament\u00f3.<\/p>\n<p>El ministro de Exteriores, Jorge Arreaza, se ha reunido con el coordinador de la ONU en Venezuela, Peter Grohmann, y los representantes de ACNUR y la OIM, Matthew Crentsil y Jorge Vall\u00e9s, respectivamente, para trasladarles personalmente esta queja y pedirles una revisi\u00f3n del destino de los fondos.<\/p>\n<p>Arreaza ha recriminado a la ONU que no apoye a los migrantes \u00abque quieren regresar a Venezuela\u00bb y que han \u00abcolapsado\u00bb las oficinas diplom\u00e1ticas en el extranjero. En este sentido, ha asegurado que quienes han vuelto se han quejado de que no han recibido apoyo de otros gobiernos o de agencias internacionales \u00abpara mejorar sus condiciones de vida en los pa\u00edses a los cuales migraron y de los cuales se est\u00e1n regresando\u00bb.<\/p>\n<p>Seg\u00fan Arreaza, de la reuni\u00f3n del martes ha salido el acuerdo sobre una especie de revisi\u00f3n\u00bb sobre los recursos que han sido aprobados, \u00abpor no llamarla rendici\u00f3n de cuentas\u00bb, informa la cadena de televisi\u00f3n p\u00fablica VTV.<\/p>\n<p>La ONU estimaba antes de la pandemia de COVID-19 que unos 4,8 millones de venezolanos hab\u00eda emigrado fuera de su pa\u00eds, con m\u00e1s de 3,7 millones ubicados en pa\u00edses de la regi\u00f3n. La crisis sanitaria, que ha complicado la movilidad y la b\u00fasqueda de trabajo en la zona, se habr\u00eda traducido en el retorno de m\u00e1s de 100.00 personas, seg\u00fan datos de la Organizaci\u00f3n de Estados Americanos (OEA).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Europa Press) &#8211;\u00a0El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al &#8216;Plan de Vuelta a la Patria&#8217;, el programa con el que el Ejecutivo de Nicol\u00e1s Maduro quiere facilitar el regreso de miles de venezolanos que han emigrado en los \u00faltimos a\u00f1os para escapar de la crisis social,<\/p>\n","protected":false},"author":1,"featured_media":101053,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-148826","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al &#039;Plan de Vuelta a la Patria&#039;,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"internacional,actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Venezuela reclama a la ONU que financie el &#039;Plan de Vuelta a la Patria&#039; | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al &#039;Plan de Vuelta a la Patria&#039;,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-11-26T18:50:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-11-26T18:50:36+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Venezuela reclama a la ONU que financie el &#039;Plan de Vuelta a la Patria&#039; | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al &#039;Plan de Vuelta a la Patria&#039;,\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#listItem\",\"name\":\"Venezuela reclama a la ONU que financie el &#8216;Plan de Vuelta a la Patria&#8217;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#listItem\",\"position\":3,\"name\":\"Venezuela reclama a la ONU que financie el &#8216;Plan de Vuelta a la Patria&#8217;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#newsarticle\",\"name\":\"Venezuela reclama a la ONU que financie el 'Plan de Vuelta a la Patria' | Cand\\u00e1s 365\",\"headline\":\"Venezuela reclama a la ONU que financie el &#8216;Plan de Vuelta a la Patria&#8217;\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/caracas-264581_960_720.jpg\",\"width\":960,\"height\":720},\"datePublished\":\"2020-11-26T18:50:36+01:00\",\"dateModified\":\"2020-11-26T18:50:36+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el noviembre 26, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/\",\"name\":\"Venezuela reclama a la ONU que financie el 'Plan de Vuelta a la Patria' | Cand\\u00e1s 365\",\"description\":\"El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al 'Plan de Vuelta a la Patria',\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/caracas-264581_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#mainImage\",\"width\":960,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\\\/#mainImage\"},\"datePublished\":\"2020-11-26T18:50:36+01:00\",\"dateModified\":\"2020-11-26T18:50:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Venezuela reclama a la ONU que financie el 'Plan de Vuelta a la Patria' | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Venezuela reclama a la ONU que financie el 'Plan de Vuelta a la Patria' | Cand\u00e1s 365","description":"El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al 'Plan de Vuelta a la Patria',","canonical_url":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/","robots":"max-image-preview:large","keywords":"internacional,actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#listItem","name":"Venezuela reclama a la ONU que financie el &#8216;Plan de Vuelta a la Patria&#8217;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#listItem","position":3,"name":"Venezuela reclama a la ONU que financie el &#8216;Plan de Vuelta a la Patria&#8217;","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#newsarticle","name":"Venezuela reclama a la ONU que financie el 'Plan de Vuelta a la Patria' | Cand\u00e1s 365","headline":"Venezuela reclama a la ONU que financie el &#8216;Plan de Vuelta a la Patria&#8217;","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720.jpg","width":960,"height":720},"datePublished":"2020-11-26T18:50:36+01:00","dateModified":"2020-11-26T18:50:36+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el noviembre 26, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#webpage","url":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/","name":"Venezuela reclama a la ONU que financie el 'Plan de Vuelta a la Patria' | Cand\u00e1s 365","description":"El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al 'Plan de Vuelta a la Patria',","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#mainImage","width":960,"height":720},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/#mainImage"},"datePublished":"2020-11-26T18:50:36+01:00","dateModified":"2020-11-26T18:50:36+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Venezuela reclama a la ONU que financie el 'Plan de Vuelta a la Patria' | Cand\u00e1s 365","og:description":"El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al 'Plan de Vuelta a la Patria',","og:url":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720.jpg","og:image:width":960,"og:image:height":720,"article:published_time":"2020-11-26T18:50:36+00:00","article:modified_time":"2020-11-26T18:50:36+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Venezuela reclama a la ONU que financie el 'Plan de Vuelta a la Patria' | Cand\u00e1s 365","twitter:description":"El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al 'Plan de Vuelta a la Patria',","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/07\/caracas-264581_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"148826","title":"Venezuela reclama a la ONU que financie el 'Plan de Vuelta a la Patria' | #site_title","description":"El Gobierno de Venezuela ha solicitado a Naciones Unidas que dirija parte de sus recursos al 'Plan de Vuelta a la Patria',","keywords":[{"label":"Internacional","value":"Internacional"}],"keyphrases":null,"primary_term":null,"canonical_url":"","og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-27 03:15:13","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:38:09","updated":"2026-05-27 03:15:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tVenezuela reclama a la ONU que financie el \u2018Plan de Vuelta a la Patria\u2019\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Venezuela reclama a la ONU que financie el &#8216;Plan de Vuelta a la Patria&#8217;","link":"https:\/\/candas365.es\/noticias\/venezuela-reclama-a-la-onu-que-financie-el-plan-de-vuelta-a-la-patria\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/148826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=148826"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/148826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/101053"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=148826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=148826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=148826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}