{"id":143874,"date":"2020-06-21T17:26:31","date_gmt":"2020-06-21T17:26:31","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=143874"},"modified":"2020-06-21T17:26:31","modified_gmt":"2020-06-21T17:26:31","slug":"pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/","title":{"rendered":"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-97526\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720-360x238.jpg\" alt=\"\" width=\"360\" height=\"238\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720-360x238.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720-768x508.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720-655x433.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720-696x460.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720-635x420.jpg 635w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Comisi\u00f3n ha publicado su Comunicaci\u00f3n anual sobre el progreso de la gesti\u00f3n de las poblaciones de peces en la UE, que se basa en datos de 2018. La edici\u00f3n de este a\u00f1o,\u00a0<a href=\"https:\/\/ec.europa.eu\/transparency\/regdoc\/rep\/1\/2020\/EN\/COM-2020-248-F1-EN-MAIN-PART-1.PDF\" target=\"_blank\" rel=\"nofollow noopener noreferrer\" data-auth=\"NotApplicable\"><span style=\"color: #ff0000;\"><strong>\u00abHacia una pesca m\u00e1s sostenible en la UE: situaci\u00f3n actual y orientaciones para 2021\u00bb<\/strong><\/span><\/a>, revalida el firme compromiso de la Comisi\u00f3n de promover una pesca que sea sostenible desde el punto de vista medioambiental y econ\u00f3micamente viable, y muestra los progresos que la UE ha realizado para alcanzar ese objetivo. Se invita a los Estados miembros, a los consejos consultivos, a la industria pesquera, a las organizaciones no gubernamentales y a los ciudadanos interesados a participar en una<span style=\"color: #ff0000;\"><strong>\u00a0<a style=\"color: #ff0000;\" href=\"https:\/\/ec.europa.eu\/info\/consultations\/fishing-opportunities-2021-under-common-fisheries-policy_es\" target=\"_blank\" rel=\"nofollow noopener noreferrer\" data-auth=\"NotApplicable\">consulta p\u00fablica<\/a><\/strong><\/span>\u00a0y a expresar sus puntos de vista sobre las posibilidades de pesca para 2021. La Comisi\u00f3n se pondr\u00e1 en contacto con ellos y los escuchar\u00e1 activamente durante las pr\u00f3ximas semanas.<\/p>\n<p>Virginijus\u00a0<strong>Sinkevi\u010dius<\/strong>, comisario responsable de Medio Ambiente, Oc\u00e9anos y Pesca, ha declarado lo siguiente:\u00a0<em>\u00abLos primeros meses de este a\u00f1o fueron extremadamente dif\u00edciles para el sector pesquero, pero lo respaldamos en toda la UE. La pesca sostenible, que se materializa a trav\u00e9s de la pol\u00edtica pesquera com\u00fan, es necesaria para aumentar la resiliencia y cumplir el Pacto Verde Europeo, en particular en dos estrategias recientes: \u00abde la granja a la mesa\u00bb y la Estrategia de la UE sobre Biodiversidad\u00bb. La ordenaci\u00f3n de la pesca en la UE nos ha aportado buenas noticias: en el Atl\u00e1ntico del Nordeste actualmente hay un 50\u00a0% m\u00e1s de peces que en 2003. Las cifras revelan asimismo que los segmentos de gran tama\u00f1o de la flota han pasado a ser muy rentables en los \u00faltimos a\u00f1os y han contribuido al aumento de los salarios. No obstante, sigue habiendo retos; por ejemplo, debemos intensificar nuestros esfuerzos para eliminar los descartes. Cuento con el esfuerzo de todos: los Estados miembros, la industria y las partes interesadas. Debemos cumplir lo que nos hemos propuesto\u00bb.<\/em><\/p>\n<p>La Comunicaci\u00f3n de 2020 pone de manifiesto que la pesca en el Atl\u00e1ntico del Nordeste es cada vez m\u00e1s sostenible, lo cual genera poblaciones de peces m\u00e1s abundantes. Los resultados econ\u00f3micos de la flota de la UE han seguido siendo muy buenos, con un beneficio neto de aproximadamente 1\u00a0400 millones de euros y un margen de beneficio neto medio del 18\u00a0% en 2018. Los salarios de los pescadores tambi\u00e9n han seguido aumentando.<\/p>\n<p>A pesar de las mejoras significativas, sigue habiendo retos. Si bien se espera que se confirmen unos resultados econ\u00f3micos similares para 2019, las previsiones para 2020 siguen siendo muy inciertas debido al impacto de la crisis del coronavirus. Por lo que respecta al mar Mediterr\u00e1neo y al mar Negro, los decididos esfuerzos de conservaci\u00f3n han de proseguir y, en las cuencas mar\u00edtimas atl\u00e1nticas, algunas poblaciones siguen siendo objeto de sobrepesca o permanecen fuera de los l\u00edmites biol\u00f3gicos de seguridad. En el segundo a\u00f1o de su plena aplicaci\u00f3n, las disposiciones de aplicaci\u00f3n de la obligaci\u00f3n de desembarque sigue siendo motivo de preocupaci\u00f3n. Los Estados miembros deben intensificar la aplicaci\u00f3n y el control del cumplimiento de la obligaci\u00f3n de desembarque, en particular utilizando instrumentos de control adecuados, como sistemas de seguimiento electr\u00f3nico remoto. La Comisi\u00f3n seguir\u00e1 trabajando con el Parlamento Europeo y el Consejo para alcanzar un acuerdo sobre el r\u00e9gimen revisado de control de la pesca, que facilitar\u00e1 el uso de dichas herramientas.<\/p>\n<h3><strong>Contexto<\/strong><\/h3>\n<p>Cada a\u00f1o, la Comisi\u00f3n publica una comunicaci\u00f3n en la que se exponen los avances en la situaci\u00f3n de las poblaciones de peces y se abre una amplia consulta p\u00fablica sobre la fijaci\u00f3n de las posibilidades de pesca anuales para el a\u00f1o siguiente. Dicha comunicaci\u00f3n eval\u00faa la situaci\u00f3n de la aplicaci\u00f3n de la pol\u00edtica pesquera com\u00fan y expone la justificaci\u00f3n de la propuesta sobre las posibilidades de pesca para el a\u00f1o siguiente. La Comisi\u00f3n invita a los Estados miembros, a los consejos consultivos \u2014que incluyen a la industria pesquera y a las ONG\u2014y a los ciudadanos y organizaciones interesados, a que aporten su contribuci\u00f3n a trav\u00e9s de una consulta p\u00fablica en l\u00ednea.<\/p>\n<p>En oto\u00f1o, la Comisi\u00f3n presentar\u00e1 sus propuestas de Reglamento en lo que respecta a las posibilidades de pesca para 2021 en el Atl\u00e1ntico, el mar del Norte y el mar B\u00e1ltico, a las poblaciones de aguas profundas, as\u00ed como al mar Mediterr\u00e1neo y el mar Negro. A partir de este a\u00f1o, las poblaciones de peces deben gestionarse en consonancia con el objetivo de rendimiento m\u00e1ximo sostenible, a saber, la cantidad m\u00e1xima de peces que los pescadores pueden extraer del mar sin poner en peligro la regeneraci\u00f3n y la futura productividad de la poblaci\u00f3n. El principal objetivo de las propuestas de la Comisi\u00f3n sobre las posibilidades de pesca en 2021 ser\u00e1 mantener o alcanzar un nivel de pesca que permita maximizar, pero de forma sostenible, la explotaci\u00f3n de las poblaciones. Las propuestas tienen en cuenta los planes plurianuales y se basan en dict\u00e1menes cient\u00edficos independientes del Consejo Internacional para la Exploraci\u00f3n del Mar (CIEM) y de otros organismos independientes, como el an\u00e1lisis econ\u00f3mico realizado por el Comit\u00e9 Cient\u00edfico, T\u00e9cnico y Econ\u00f3mico de Pesca (CCTEP). Las propuestas incluir\u00e1n asimismo ajustes resultantes de la aplicaci\u00f3n de la obligaci\u00f3n de desembarque.<\/p>\n<p>Las posibilidades de pesca negociadas por la Comisi\u00f3n y acordadas en el marco de las organizaciones regionales de ordenaci\u00f3n pesquera (OROP) tambi\u00e9n se han incorporado en los reglamentos sobre posibilidades de pesca tras las reuniones de estas organizaciones. El Consejo de Ministros de Pesca de la Uni\u00f3n Europea debate las propuestas de la Comisi\u00f3n y establece el reparto de las posibilidades de pesca. Los Estados miembros son entonces responsables de repartir sus cuotas nacionales entre los distintos segmentos de la flota.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n ha publicado su Comunicaci\u00f3n anual sobre el progreso de la gesti\u00f3n de las poblaciones de peces en la UE, que se basa en datos de 2018. La edici\u00f3n de este a\u00f1o,\u00a0\u00abHacia una pesca m\u00e1s sostenible en la UE: situaci\u00f3n actual y orientaciones para 2021\u00bb, revalida el firme compromiso de la Comisi\u00f3n de promover<\/p>\n","protected":false},"author":1,"featured_media":97526,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-143874","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Comisi\u00f3n ha publicado su Comunicaci\u00f3n anual sobre el progreso de la gesti\u00f3n de las poblaciones de peces en la UE, que se basa en datos de 2018. La edici\u00f3n de este a\u00f1o, \u00abHacia una pesca m\u00e1s sostenible en la UE: situaci\u00f3n actual y orientaciones para 2021\u00bb, revalida el firme compromiso de la Comisi\u00f3n de promover\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La Comisi\u00f3n ha publicado su Comunicaci\u00f3n anual sobre el progreso de la gesti\u00f3n de las poblaciones de peces en la UE, que se basa en datos de 2018. La edici\u00f3n de este a\u00f1o, \u00abHacia una pesca m\u00e1s sostenible en la UE: situaci\u00f3n actual y orientaciones para 2021\u00bb, revalida el firme compromiso de la Comisi\u00f3n de promover\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-21T17:26:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-21T17:26:31+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Comisi\u00f3n ha publicado su Comunicaci\u00f3n anual sobre el progreso de la gesti\u00f3n de las poblaciones de peces en la UE, que se basa en datos de 2018. La edici\u00f3n de este a\u00f1o, \u00abHacia una pesca m\u00e1s sostenible en la UE: situaci\u00f3n actual y orientaciones para 2021\u00bb, revalida el firme compromiso de la Comisi\u00f3n de promover\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#listItem\",\"name\":\"Pesca sostenible: La Comisi\\u00f3n hace balance de la pol\\u00edtica pesquera\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#listItem\",\"position\":3,\"name\":\"Pesca sostenible: La Comisi\\u00f3n hace balance de la pol\\u00edtica pesquera\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#newsarticle\",\"name\":\"Pesca sostenible: La Comisi\\u00f3n hace balance de la pol\\u00edtica pesquera | Cand\\u00e1s 365\",\"headline\":\"Pesca sostenible: La Comisi\\u00f3n hace balance de la pol\\u00edtica pesquera\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/fishing-nets-2329659_960_720.jpg\",\"width\":960,\"height\":635,\"caption\":\"mar\"},\"datePublished\":\"2020-06-21T17:26:31+02:00\",\"dateModified\":\"2020-06-21T17:26:31+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 21, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/\",\"name\":\"Pesca sostenible: La Comisi\\u00f3n hace balance de la pol\\u00edtica pesquera | Cand\\u00e1s 365\",\"description\":\"La Comisi\\u00f3n ha publicado su Comunicaci\\u00f3n anual sobre el progreso de la gesti\\u00f3n de las poblaciones de peces en la UE, que se basa en datos de 2018. La edici\\u00f3n de este a\\u00f1o, \\u00abHacia una pesca m\\u00e1s sostenible en la UE: situaci\\u00f3n actual y orientaciones para 2021\\u00bb, revalida el firme compromiso de la Comisi\\u00f3n de promover\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/fishing-nets-2329659_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#mainImage\",\"width\":960,\"height\":635,\"caption\":\"mar\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\\\/#mainImage\"},\"datePublished\":\"2020-06-21T17:26:31+02:00\",\"dateModified\":\"2020-06-21T17:26:31+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera | Cand\u00e1s 365","description":"La Comisi\u00f3n ha publicado su Comunicaci\u00f3n anual sobre el progreso de la gesti\u00f3n de las poblaciones de peces en la UE, que se basa en datos de 2018. La edici\u00f3n de este a\u00f1o, \u00abHacia una pesca m\u00e1s sostenible en la UE: situaci\u00f3n actual y orientaciones para 2021\u00bb, revalida el firme compromiso de la Comisi\u00f3n de promover","canonical_url":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#listItem","name":"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#listItem","position":3,"name":"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#newsarticle","name":"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera | Cand\u00e1s 365","headline":"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720.jpg","width":960,"height":635,"caption":"mar"},"datePublished":"2020-06-21T17:26:31+02:00","dateModified":"2020-06-21T17:26:31+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 21, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#webpage","url":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/","name":"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera | Cand\u00e1s 365","description":"La Comisi\u00f3n ha publicado su Comunicaci\u00f3n anual sobre el progreso de la gesti\u00f3n de las poblaciones de peces en la UE, que se basa en datos de 2018. La edici\u00f3n de este a\u00f1o, \u00abHacia una pesca m\u00e1s sostenible en la UE: situaci\u00f3n actual y orientaciones para 2021\u00bb, revalida el firme compromiso de la Comisi\u00f3n de promover","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#mainImage","width":960,"height":635,"caption":"mar"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/#mainImage"},"datePublished":"2020-06-21T17:26:31+02:00","dateModified":"2020-06-21T17:26:31+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera | Cand\u00e1s 365","og:description":"La Comisi\u00f3n ha publicado su Comunicaci\u00f3n anual sobre el progreso de la gesti\u00f3n de las poblaciones de peces en la UE, que se basa en datos de 2018. La edici\u00f3n de este a\u00f1o, \u00abHacia una pesca m\u00e1s sostenible en la UE: situaci\u00f3n actual y orientaciones para 2021\u00bb, revalida el firme compromiso de la Comisi\u00f3n de promover","og:url":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720.jpg","og:image:width":960,"og:image:height":635,"article:published_time":"2020-06-21T17:26:31+00:00","article:modified_time":"2020-06-21T17:26:31+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera | Cand\u00e1s 365","twitter:description":"La Comisi\u00f3n ha publicado su Comunicaci\u00f3n anual sobre el progreso de la gesti\u00f3n de las poblaciones de peces en la UE, que se basa en datos de 2018. La edici\u00f3n de este a\u00f1o, \u00abHacia una pesca m\u00e1s sostenible en la UE: situaci\u00f3n actual y orientaciones para 2021\u00bb, revalida el firme compromiso de la Comisi\u00f3n de promover","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/fishing-nets-2329659_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"143874","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 13:21:23","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:41:23","updated":"2026-05-26 13:21:23"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tPesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Pesca sostenible: La Comisi\u00f3n hace balance de la pol\u00edtica pesquera","link":"https:\/\/candas365.es\/noticias\/pesca-sostenible-la-comision-hace-balance-de-la-politica-pesquera\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=143874"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/97526"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=143874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=143874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=143874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}