{"id":143642,"date":"2020-06-15T16:01:22","date_gmt":"2020-06-15T16:01:22","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=143642"},"modified":"2020-06-15T16:01:22","modified_gmt":"2020-06-15T16:01:22","slug":"paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/","title":{"rendered":"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje"},"content":{"rendered":"<figure id=\"attachment_143643\" aria-describedby=\"caption-attachment-143643\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-143643\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan-360x244.jpg\" alt=\"\" width=\"360\" height=\"244\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan-360x244.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan-655x443.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan-768x520.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan-696x471.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan-621x420.jpg 621w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan.jpg 983w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-143643\" class=\"wp-caption-text\">Foto: Kristina Kormilicyna\/Kommersant\/ EP<\/figcaption><\/figure>\n<p>(Europa Press) &#8211;\u00a0Un tribunal ruso ha condenado a 16 a\u00f1os de c\u00e1rcel al exmarine estadounidense Paul Whelan, acusado de espionaje por la supuesta obtenci\u00f3n de material clasificado, en un nuevo cap\u00edtulo de un caso que ha supuesto un nuevo pulso pol\u00edtico entre Mosc\u00fa y Washington.<\/p>\n<p>La Fiscal\u00eda ped\u00eda para Whelan 18 a\u00f1os de prisi\u00f3n, pero finalmente el juez ha dictado dos a\u00f1os menos, es decir 16, que deber\u00e1 pasar en una prisi\u00f3n de m\u00e1xima seguridad. El acusado, que en todo momento ha defendido que es inocente, ha anunciado que recurrir\u00e1 la sentencia, seg\u00fan la agencia Sputnik.<\/p>\n<p>Whelan, que tiene pasaporte estadounidense, canadiense y brit\u00e1nico, fue detenido en diciembre de 2018 en un hotel de Mosc\u00fa por agentes del Servicio Federal de Seguridad. Seg\u00fan la Inteligencia rusa, se le encontr\u00f3 un dispositivo de memoria externa que conten\u00eda informaci\u00f3n clasificada.<\/p>\n<p>El exmarine estadounidense, de 50 a\u00f1os, sostiene que le tendieron una trampa. De acuerdo con su versi\u00f3n, el &#8216;pendrive&#8217; se lo dio un conocido ruso y cre\u00eda que conten\u00eda fotos de vacaciones.<\/p>\n<p>Hace dos semanas, fue intervenido de una hernia abdominal, seg\u00fan la Embajada de Estados Unidos, en una \u00aboperaci\u00f3n de urgencia\u00bb. \u00abLas autoridades esperaron hasta que su condici\u00f3n fuese extrema para proporcionarle atenci\u00f3n m\u00e9dica\u00bb, lament\u00f3 la legaci\u00f3n, cuya portavoz, Rebecca Ross, record\u00f3 que el exmarine estar\u00eda detenido \u00absin pruebas de haber cometido ning\u00fan delito\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Europa Press) &#8211;\u00a0Un tribunal ruso ha condenado a 16 a\u00f1os de c\u00e1rcel al exmarine estadounidense Paul Whelan, acusado de espionaje por la supuesta obtenci\u00f3n de material clasificado, en un nuevo cap\u00edtulo de un caso que ha supuesto un nuevo pulso pol\u00edtico entre Mosc\u00fa y Washington. La Fiscal\u00eda ped\u00eda para Whelan 18 a\u00f1os de prisi\u00f3n, pero<\/p>\n","protected":false},"author":1,"featured_media":143643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-143642","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"(Europa Press) - Un tribunal ruso ha condenado a 16 a\u00f1os de c\u00e1rcel al exmarine estadounidense Paul Whelan, acusado de espionaje por la supuesta obtenci\u00f3n de material clasificado, en un nuevo cap\u00edtulo de un caso que ha supuesto un nuevo pulso pol\u00edtico entre Mosc\u00fa y Washington. La Fiscal\u00eda ped\u00eda para Whelan 18 a\u00f1os de prisi\u00f3n, pero\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(Europa Press) - Un tribunal ruso ha condenado a 16 a\u00f1os de c\u00e1rcel al exmarine estadounidense Paul Whelan, acusado de espionaje por la supuesta obtenci\u00f3n de material clasificado, en un nuevo cap\u00edtulo de un caso que ha supuesto un nuevo pulso pol\u00edtico entre Mosc\u00fa y Washington. La Fiscal\u00eda ped\u00eda para Whelan 18 a\u00f1os de prisi\u00f3n, pero\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"983\" \/>\n\t\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-15T16:01:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-15T16:01:22+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(Europa Press) - Un tribunal ruso ha condenado a 16 a\u00f1os de c\u00e1rcel al exmarine estadounidense Paul Whelan, acusado de espionaje por la supuesta obtenci\u00f3n de material clasificado, en un nuevo cap\u00edtulo de un caso que ha supuesto un nuevo pulso pol\u00edtico entre Mosc\u00fa y Washington. La Fiscal\u00eda ped\u00eda para Whelan 18 a\u00f1os de prisi\u00f3n, pero\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#listItem\",\"name\":\"Paul Whelan es condenado a 16 a\\u00f1os de c\\u00e1rcel por espionaje\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#listItem\",\"position\":3,\"name\":\"Paul Whelan es condenado a 16 a\\u00f1os de c\\u00e1rcel por espionaje\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#newsarticle\",\"name\":\"Paul Whelan es condenado a 16 a\\u00f1os de c\\u00e1rcel por espionaje | Cand\\u00e1s 365\",\"headline\":\"Paul Whelan es condenado a 16 a\\u00f1os de c\\u00e1rcel por espionaje\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Paul-Whelan.jpg\",\"width\":983,\"height\":665,\"caption\":\"Foto: Kristina Kormilicyna\\\/Kommersant\\\/ EP\"},\"datePublished\":\"2020-06-15T16:01:22+02:00\",\"dateModified\":\"2020-06-15T16:01:22+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 15, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/\",\"name\":\"Paul Whelan es condenado a 16 a\\u00f1os de c\\u00e1rcel por espionaje | Cand\\u00e1s 365\",\"description\":\"(Europa Press) - Un tribunal ruso ha condenado a 16 a\\u00f1os de c\\u00e1rcel al exmarine estadounidense Paul Whelan, acusado de espionaje por la supuesta obtenci\\u00f3n de material clasificado, en un nuevo cap\\u00edtulo de un caso que ha supuesto un nuevo pulso pol\\u00edtico entre Mosc\\u00fa y Washington. La Fiscal\\u00eda ped\\u00eda para Whelan 18 a\\u00f1os de prisi\\u00f3n, pero\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Paul-Whelan.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#mainImage\",\"width\":983,\"height\":665,\"caption\":\"Foto: Kristina Kormilicyna\\\/Kommersant\\\/ EP\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\\\/#mainImage\"},\"datePublished\":\"2020-06-15T16:01:22+02:00\",\"dateModified\":\"2020-06-15T16:01:22+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje | Cand\u00e1s 365","description":"(Europa Press) - Un tribunal ruso ha condenado a 16 a\u00f1os de c\u00e1rcel al exmarine estadounidense Paul Whelan, acusado de espionaje por la supuesta obtenci\u00f3n de material clasificado, en un nuevo cap\u00edtulo de un caso que ha supuesto un nuevo pulso pol\u00edtico entre Mosc\u00fa y Washington. La Fiscal\u00eda ped\u00eda para Whelan 18 a\u00f1os de prisi\u00f3n, pero","canonical_url":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#listItem","name":"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#listItem","position":3,"name":"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#newsarticle","name":"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje | Cand\u00e1s 365","headline":"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan.jpg","width":983,"height":665,"caption":"Foto: Kristina Kormilicyna\/Kommersant\/ EP"},"datePublished":"2020-06-15T16:01:22+02:00","dateModified":"2020-06-15T16:01:22+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 15, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#webpage","url":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/","name":"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje | Cand\u00e1s 365","description":"(Europa Press) - Un tribunal ruso ha condenado a 16 a\u00f1os de c\u00e1rcel al exmarine estadounidense Paul Whelan, acusado de espionaje por la supuesta obtenci\u00f3n de material clasificado, en un nuevo cap\u00edtulo de un caso que ha supuesto un nuevo pulso pol\u00edtico entre Mosc\u00fa y Washington. La Fiscal\u00eda ped\u00eda para Whelan 18 a\u00f1os de prisi\u00f3n, pero","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan.jpg","@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#mainImage","width":983,"height":665,"caption":"Foto: Kristina Kormilicyna\/Kommersant\/ EP"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/#mainImage"},"datePublished":"2020-06-15T16:01:22+02:00","dateModified":"2020-06-15T16:01:22+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje | Cand\u00e1s 365","og:description":"(Europa Press) - Un tribunal ruso ha condenado a 16 a\u00f1os de c\u00e1rcel al exmarine estadounidense Paul Whelan, acusado de espionaje por la supuesta obtenci\u00f3n de material clasificado, en un nuevo cap\u00edtulo de un caso que ha supuesto un nuevo pulso pol\u00edtico entre Mosc\u00fa y Washington. La Fiscal\u00eda ped\u00eda para Whelan 18 a\u00f1os de prisi\u00f3n, pero","og:url":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan.jpg","og:image:width":983,"og:image:height":665,"article:published_time":"2020-06-15T16:01:22+00:00","article:modified_time":"2020-06-15T16:01:22+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje | Cand\u00e1s 365","twitter:description":"(Europa Press) - Un tribunal ruso ha condenado a 16 a\u00f1os de c\u00e1rcel al exmarine estadounidense Paul Whelan, acusado de espionaje por la supuesta obtenci\u00f3n de material clasificado, en un nuevo cap\u00edtulo de un caso que ha supuesto un nuevo pulso pol\u00edtico entre Mosc\u00fa y Washington. La Fiscal\u00eda ped\u00eda para Whelan 18 a\u00f1os de prisi\u00f3n, pero","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Paul-Whelan.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"143642","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 12:41:23","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:41:29","updated":"2026-05-26 12:41:23"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tPaul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Paul Whelan es condenado a 16 a\u00f1os de c\u00e1rcel por espionaje","link":"https:\/\/candas365.es\/noticias\/paul-whelan-es-condenado-a-16-anos-de-carcel-por-espionaje\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=143642"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/143643"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=143642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=143642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=143642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}