{"id":143638,"date":"2020-06-15T15:53:51","date_gmt":"2020-06-15T15:53:51","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=143638"},"modified":"2020-06-15T15:53:51","modified_gmt":"2020-06-15T15:53:51","slug":"coronavirus-mas-de-433-000-muertos","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/","title":{"rendered":"Coronavirus: M\u00e1s de 433.000 muertos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-143623\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640-360x245.jpg\" alt=\"\" width=\"360\" height=\"245\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640-360x245.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640-617x420.jpg 617w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640.jpg 640w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>(Europa Press) &#8211;\u00a0La pandemia del nuevo coronavirus originada en la ciudad china de Wuhan ha registrado en las \u00faltimas 24 horas 132.000 casos, lo que supone el tercer m\u00e1ximo de la serie hist\u00f3rica y eleva el total a m\u00e1s de 7,9 millones de positivos y m\u00e1s de 433.000 v\u00edctimas mortales, seg\u00fan el \u00faltimo balance de la Universidad Johns Hopkins.<\/p>\n<p>De acuerdo con los datos actualizados a las 9.00 horas de este lunes, el balance global del coronavirus asciende a 7,9 millones de casos y 433.472 v\u00edctimas mortales en 188 pa\u00edses y territorios. El total de personas recuperadas supera los 3,77 millones, con Estados Unidos al frente de la lista, con 561.816 personas curadas.<\/p>\n<p>Estados Unidos sigue como el pa\u00eds m\u00e1s afectado por la pandemia con 2,09 millones de personas contagiadas y 115.732 v\u00edctimas mortales, tras registrar 19.500 casos en las \u00faltimas 24 horas.<\/p>\n<p>Brasil sigue en segunda posici\u00f3n y registra en las \u00faltimas 24 horas 17.100 positivos, lo que eleva el balance a m\u00e1s 867.624 personas contagiadas y 43.332 fallecidos. Rusia se queda en la tercera posici\u00f3n, con 528.267 positivos y 6.938 muertos, tras sumar 8.800 casos desde el balance anterior.<\/p>\n<h3><strong>INDIA SUPERA LOS 330.000 CASOS<\/strong><\/h3>\n<p>En cuarta posici\u00f3n, India acumula 332.424 casos y 9.520 fallecidos, tras sumar m\u00e1s de 11.900 casos en las \u00faltimas 24 horas. A continuaci\u00f3n, Reino Unido registra 297.347 personas contagiadas y 41.783 muertos, por delante de Espa\u00f1a, que tiene a 243.928 personas con coronavirus y 27.136 v\u00edctimas mortales.<\/p>\n<p>Italia, por su parte, registra 236.989 casos y 34.345 fallecidos, por delante de Per\u00fa, que contabiliza a 229.736 contagiados y 6.688 fallecidos. En la siguiente posici\u00f3n, Francia contabiliza 194.153 contagios y 29.410 v\u00edctimas mortales, por delante de Alemania, que contabiliza 187.427 casos y 8.801 fallecidos, y de Ir\u00e1n, que registra 187.427 contagios y 8.837 decesos.<\/p>\n<p>En la duod\u00e9cima posici\u00f3n, Turqu\u00eda tiene a 178.239 personas con coronavirus y 4.807 muertos, seguida por Chile, con 174.293 contagiados y 3.323 decesos, y M\u00e9xico, con 146.837 casos y 17.141 v\u00edctimas mortales.<\/p>\n<h3><strong>ARABIA SAUD\u00cd REBASA LOS 125.000 CONTAGIOS<\/strong><\/h3>\n<p>Cerrando el grupo de m\u00e1s de 100.000 contagios se encuentran Pakist\u00e1n, con 144.478 contagiados y 2.729 muertos, Arabia Saud\u00ed, con m\u00e1s de 127.541 contagios y 972 decesos y Canad\u00e1, con 100.404 casos y 8.218 v\u00edctimas mortales.<\/p>\n<p>Por debajo de los 100.000 positivos, Bangladesh acumula 87.520 personas contagiadas y 1.171 muertos, por delante de China, el pa\u00eds en el que se origin\u00f3 la pandemia y que acumula 84.335 casos con 4.638 fallecidos.<\/p>\n<p>Por su parte, Qatar contabiliza 79.602 contagiados y 73 decesos. Sud\u00e1frica registra 70.038 personas con coronavirus y 1.480 fallecidos, por delante de B\u00e9lgica, con 60.029 casos y 9.655 fallecidos, y de Bielorrusia, que acumula 53.972 contagios y 308 v\u00edctimas mortales. Suecia cierra la lista de pa\u00edses con m\u00e1s de 50.000 casos, con 51.614 contagiados y 4.874 decesos.<\/p>\n<p>Superando los 40.000 positivos est\u00e1n Pa\u00edses Bajos, Colombia, Ecuador, Egipto, Emiratos \u00c1rabes Unidos y Singapur, mientras que Indonesia Portugal, Kuwait, Ucrania, Argentina y Suiza acumulan m\u00e1s de 30.000 casos.<\/p>\n<p>Por su parte, Polonia, Filipinas, Irlanda, Afganist\u00e1n, Om\u00e1n, Rep\u00fablica Dominicana, Ruman\u00eda, Panam\u00e1 e Irak rebasan los 20.000 positivos por coronavirus, por delante de Israel, Bolivia, Bahr\u00e9in, Jap\u00f3n, Austria, Armenia, Nigeria, Kazajist\u00e1n, Dinamarca, Serbia, Corea del Sur, Ghana, Moldavia, Argelia y Rep\u00fablica Checa, que tienen m\u00e1s de 10.000 contagios.<\/p>\n<p>Azerbaiy\u00e1n, Camer\u00fan y Guatemala superan los 9.000 casos y Honduras, Marruecos, Noruega y Malasia tienen m\u00e1s de 8.000 positivos. A continuaci\u00f3n, Australia, Sud\u00e1n y Finlandia superan los 7.000 casos y Nepal, Uzbekist\u00e1n, Senegal, Costa de Marfil y Tayikist\u00e1n sobrepasan los 5.000.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Europa Press) &#8211;\u00a0La pandemia del nuevo coronavirus originada en la ciudad china de Wuhan ha registrado en las \u00faltimas 24 horas 132.000 casos, lo que supone el tercer m\u00e1ximo de la serie hist\u00f3rica y eleva el total a m\u00e1s de 7,9 millones de positivos y m\u00e1s de 433.000 v\u00edctimas mortales, seg\u00fan el \u00faltimo balance de<\/p>\n","protected":false},"author":1,"featured_media":143623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-143638","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"(Europa Press) - La pandemia del nuevo coronavirus originada en la ciudad china de Wuhan ha registrado en las \u00faltimas 24 horas 132.000 casos, lo que supone el tercer m\u00e1ximo de la serie hist\u00f3rica y eleva el total a m\u00e1s de 7,9 millones de positivos y m\u00e1s de 433.000 v\u00edctimas mortales, seg\u00fan el \u00faltimo balance de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coronavirus: M\u00e1s de 433.000 muertos | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(Europa Press) - La pandemia del nuevo coronavirus originada en la ciudad china de Wuhan ha registrado en las \u00faltimas 24 horas 132.000 casos, lo que supone el tercer m\u00e1ximo de la serie hist\u00f3rica y eleva el total a m\u00e1s de 7,9 millones de positivos y m\u00e1s de 433.000 v\u00edctimas mortales, seg\u00fan el \u00faltimo balance de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t\t<meta property=\"og:image:height\" content=\"436\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-15T15:53:51+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-15T15:53:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coronavirus: M\u00e1s de 433.000 muertos | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(Europa Press) - La pandemia del nuevo coronavirus originada en la ciudad china de Wuhan ha registrado en las \u00faltimas 24 horas 132.000 casos, lo que supone el tercer m\u00e1ximo de la serie hist\u00f3rica y eleva el total a m\u00e1s de 7,9 millones de positivos y m\u00e1s de 433.000 v\u00edctimas mortales, seg\u00fan el \u00faltimo balance de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#listItem\",\"name\":\"Coronavirus: M\\u00e1s de 433.000 muertos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#listItem\",\"position\":3,\"name\":\"Coronavirus: M\\u00e1s de 433.000 muertos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#newsarticle\",\"name\":\"Coronavirus: M\\u00e1s de 433.000 muertos | Cand\\u00e1s 365\",\"headline\":\"Coronavirus: M\\u00e1s de 433.000 muertos\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/connection-4884862_640.jpg\",\"width\":640,\"height\":436,\"caption\":\"covid-19\"},\"datePublished\":\"2020-06-15T15:53:51+02:00\",\"dateModified\":\"2020-06-15T15:53:51+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 15, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/\",\"name\":\"Coronavirus: M\\u00e1s de 433.000 muertos | Cand\\u00e1s 365\",\"description\":\"(Europa Press) - La pandemia del nuevo coronavirus originada en la ciudad china de Wuhan ha registrado en las \\u00faltimas 24 horas 132.000 casos, lo que supone el tercer m\\u00e1ximo de la serie hist\\u00f3rica y eleva el total a m\\u00e1s de 7,9 millones de positivos y m\\u00e1s de 433.000 v\\u00edctimas mortales, seg\\u00fan el \\u00faltimo balance de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/connection-4884862_640.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#mainImage\",\"width\":640,\"height\":436,\"caption\":\"covid-19\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/coronavirus-mas-de-433-000-muertos\\\/#mainImage\"},\"datePublished\":\"2020-06-15T15:53:51+02:00\",\"dateModified\":\"2020-06-15T15:53:51+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Coronavirus: M\u00e1s de 433.000 muertos | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Coronavirus: M\u00e1s de 433.000 muertos | Cand\u00e1s 365","description":"(Europa Press) - La pandemia del nuevo coronavirus originada en la ciudad china de Wuhan ha registrado en las \u00faltimas 24 horas 132.000 casos, lo que supone el tercer m\u00e1ximo de la serie hist\u00f3rica y eleva el total a m\u00e1s de 7,9 millones de positivos y m\u00e1s de 433.000 v\u00edctimas mortales, seg\u00fan el \u00faltimo balance de","canonical_url":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#listItem","name":"Coronavirus: M\u00e1s de 433.000 muertos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#listItem","position":3,"name":"Coronavirus: M\u00e1s de 433.000 muertos","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#newsarticle","name":"Coronavirus: M\u00e1s de 433.000 muertos | Cand\u00e1s 365","headline":"Coronavirus: M\u00e1s de 433.000 muertos","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640.jpg","width":640,"height":436,"caption":"covid-19"},"datePublished":"2020-06-15T15:53:51+02:00","dateModified":"2020-06-15T15:53:51+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 15, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#webpage","url":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/","name":"Coronavirus: M\u00e1s de 433.000 muertos | Cand\u00e1s 365","description":"(Europa Press) - La pandemia del nuevo coronavirus originada en la ciudad china de Wuhan ha registrado en las \u00faltimas 24 horas 132.000 casos, lo que supone el tercer m\u00e1ximo de la serie hist\u00f3rica y eleva el total a m\u00e1s de 7,9 millones de positivos y m\u00e1s de 433.000 v\u00edctimas mortales, seg\u00fan el \u00faltimo balance de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640.jpg","@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#mainImage","width":640,"height":436,"caption":"covid-19"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/#mainImage"},"datePublished":"2020-06-15T15:53:51+02:00","dateModified":"2020-06-15T15:53:51+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Coronavirus: M\u00e1s de 433.000 muertos | Cand\u00e1s 365","og:description":"(Europa Press) - La pandemia del nuevo coronavirus originada en la ciudad china de Wuhan ha registrado en las \u00faltimas 24 horas 132.000 casos, lo que supone el tercer m\u00e1ximo de la serie hist\u00f3rica y eleva el total a m\u00e1s de 7,9 millones de positivos y m\u00e1s de 433.000 v\u00edctimas mortales, seg\u00fan el \u00faltimo balance de","og:url":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640.jpg","og:image:width":640,"og:image:height":436,"article:published_time":"2020-06-15T15:53:51+00:00","article:modified_time":"2020-06-15T15:53:51+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Coronavirus: M\u00e1s de 433.000 muertos | Cand\u00e1s 365","twitter:description":"(Europa Press) - La pandemia del nuevo coronavirus originada en la ciudad china de Wuhan ha registrado en las \u00faltimas 24 horas 132.000 casos, lo que supone el tercer m\u00e1ximo de la serie hist\u00f3rica y eleva el total a m\u00e1s de 7,9 millones de positivos y m\u00e1s de 433.000 v\u00edctimas mortales, seg\u00fan el \u00faltimo balance de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/connection-4884862_640.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"143638","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 12:41:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:41:29","updated":"2026-05-26 12:41:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tCoronavirus: M\u00e1s de 433.000 muertos\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Coronavirus: M\u00e1s de 433.000 muertos","link":"https:\/\/candas365.es\/noticias\/coronavirus-mas-de-433-000-muertos\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=143638"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/143623"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=143638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=143638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=143638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}