{"id":143410,"date":"2020-06-09T16:21:17","date_gmt":"2020-06-09T16:21:17","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=143410"},"modified":"2020-06-09T16:21:17","modified_gmt":"2020-06-09T16:21:17","slug":"polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/","title":{"rendered":"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-97927\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720-360x230.jpg\" alt=\"\" width=\"360\" height=\"230\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720-360x230.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720-768x490.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720-655x418.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720-696x444.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720-658x420.jpg 658w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 9 jun (dpa) &#8211; La contaminaci\u00f3n del aire urbano con di\u00f3xido de nitr\u00f3geno, nocivo para la salud, disminuy\u00f3 considerablemente en Alemania durante el a\u00f1o pasado, informaron hoy la Oficina Federal de Medio Ambiente (UBA) y el Ministerio alem\u00e1n de Medio Ambiente.<\/p>\n<p>Seg\u00fan las autoridades medioambientales, solo 25 ciudades alemanas superaron el l\u00edmite fijado por la Uni\u00f3n Europea como media anual para 2019.<\/p>\n<p>Esto significa que la cifra se ha reducido en m\u00e1s de un 50 por ciento, ya que en 2018 hab\u00eda 57 ciudades que exced\u00edan este l\u00edmite. Si bien esta tendencia ya era evidente, ahora se dispone de la evaluaci\u00f3n final de los datos de los estados federados.<\/p>\n<p>El di\u00f3xido de nitr\u00f3geno (NO2) es el motivo de que en algunas ciudades se proh\u00edba conducir veh\u00edculos di\u00e9sel.<\/p>\n<p>Seg\u00fan la Oficina Federal de Medio Ambiente, la media anual de NO2 en las ciudades m\u00e1s concurridas est\u00e1 causada principalmente por las emisiones de los motores di\u00e9sel y no debe superar los 40 microgramos por metro c\u00fabico de aire. Este valor se aplica desde 2010.<\/p>\n<p>La ministra alemana de Medio Ambiente, Svenja Schulze, acogi\u00f3 con agrado los resultados. \u00abEsto demuestra que la pol\u00edtica ambiental funciona\u00bb, declar\u00f3.<\/p>\n<p>No obstante, Schulze cree que las medidas adoptadas hasta ahora no fueron suficientes para cumplir realmente con el valor l\u00edmite en todas partes. \u00abLa soluci\u00f3n est\u00e1 en veh\u00edculos m\u00e1s ecol\u00f3gicos y un cambio fundamental en la movilidad\u00bb, se\u00f1al\u00f3.<\/p>\n<p>El valor l\u00edmite solo se super\u00f3 en carreteras con mucho tr\u00e1fico en las aglomeraciones urbanas y las ciudades. A finales de mayo, M\u00fanich, Darmstadt, Stuttgart, Limburgo y Fr\u00e1ncfort eran los puntos donde se registr\u00f3 una mayor poluci\u00f3n. Aunque los valores tambi\u00e9n fueron m\u00e1s bajos.<\/p>\n<p>En opini\u00f3n de los expertos de la UBA, esta mejora se debe a los l\u00edmites de velocidad, las prohibiciones de conducir veh\u00edculos di\u00e9sel en determinadas zonas o los autobuses m\u00e1s ecol\u00f3gicos, pero tambi\u00e9n a las actualizaciones de software para el control de las emisiones de los veh\u00edculos di\u00e9sel, la renovaci\u00f3n de la flota de veh\u00edculos, as\u00ed como el clima, ya que este tambi\u00e9n influye en la propagaci\u00f3n de los contaminantes atmosf\u00e9ricos.<\/p>\n<p>La crisis originada por el coronavirus se refleja en los valores para 2020. En algunos lugares, la contaminaci\u00f3n por NO2 ha disminuido a\u00fan m\u00e1s hasta un 40 por ciento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 9 jun (dpa) &#8211; La contaminaci\u00f3n del aire urbano con di\u00f3xido de nitr\u00f3geno, nocivo para la salud, disminuy\u00f3 considerablemente en Alemania durante el a\u00f1o pasado, informaron hoy la Oficina Federal de Medio Ambiente (UBA) y el Ministerio alem\u00e1n de Medio Ambiente. Seg\u00fan las autoridades medioambientales, solo 25 ciudades alemanas superaron el l\u00edmite fijado por<\/p>\n","protected":false},"author":1,"featured_media":97927,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-143410","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 9 jun (dpa) - La contaminaci\u00f3n del aire urbano con di\u00f3xido de nitr\u00f3geno, nocivo para la salud, disminuy\u00f3 considerablemente en Alemania durante el a\u00f1o pasado, informaron hoy la Oficina Federal de Medio Ambiente (UBA) y el Ministerio alem\u00e1n de Medio Ambiente. Seg\u00fan las autoridades medioambientales, solo 25 ciudades alemanas superaron el l\u00edmite fijado por\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 9 jun (dpa) - La contaminaci\u00f3n del aire urbano con di\u00f3xido de nitr\u00f3geno, nocivo para la salud, disminuy\u00f3 considerablemente en Alemania durante el a\u00f1o pasado, informaron hoy la Oficina Federal de Medio Ambiente (UBA) y el Ministerio alem\u00e1n de Medio Ambiente. Seg\u00fan las autoridades medioambientales, solo 25 ciudades alemanas superaron el l\u00edmite fijado por\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-09T16:21:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-09T16:21:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 9 jun (dpa) - La contaminaci\u00f3n del aire urbano con di\u00f3xido de nitr\u00f3geno, nocivo para la salud, disminuy\u00f3 considerablemente en Alemania durante el a\u00f1o pasado, informaron hoy la Oficina Federal de Medio Ambiente (UBA) y el Ministerio alem\u00e1n de Medio Ambiente. Seg\u00fan las autoridades medioambientales, solo 25 ciudades alemanas superaron el l\u00edmite fijado por\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#listItem\",\"name\":\"Poluci\\u00f3n del aire por di\\u00f3xido de nitr\\u00f3geno disminuye en Alemania\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#listItem\",\"position\":3,\"name\":\"Poluci\\u00f3n del aire por di\\u00f3xido de nitr\\u00f3geno disminuye en Alemania\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#newsarticle\",\"name\":\"Poluci\\u00f3n del aire por di\\u00f3xido de nitr\\u00f3geno disminuye en Alemania | Cand\\u00e1s 365\",\"headline\":\"Poluci\\u00f3n del aire por di\\u00f3xido de nitr\\u00f3geno disminuye en Alemania\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/berlin-1467502_960_720.jpg\",\"width\":960,\"height\":613},\"datePublished\":\"2020-06-09T16:21:17+02:00\",\"dateModified\":\"2020-06-09T16:21:17+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 9, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/\",\"name\":\"Poluci\\u00f3n del aire por di\\u00f3xido de nitr\\u00f3geno disminuye en Alemania | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 9 jun (dpa) - La contaminaci\\u00f3n del aire urbano con di\\u00f3xido de nitr\\u00f3geno, nocivo para la salud, disminuy\\u00f3 considerablemente en Alemania durante el a\\u00f1o pasado, informaron hoy la Oficina Federal de Medio Ambiente (UBA) y el Ministerio alem\\u00e1n de Medio Ambiente. Seg\\u00fan las autoridades medioambientales, solo 25 ciudades alemanas superaron el l\\u00edmite fijado por\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/berlin-1467502_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#mainImage\",\"width\":960,\"height\":613},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\\\/#mainImage\"},\"datePublished\":\"2020-06-09T16:21:17+02:00\",\"dateModified\":\"2020-06-09T16:21:17+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania | Cand\u00e1s 365","description":"Berl\u00edn, 9 jun (dpa) - La contaminaci\u00f3n del aire urbano con di\u00f3xido de nitr\u00f3geno, nocivo para la salud, disminuy\u00f3 considerablemente en Alemania durante el a\u00f1o pasado, informaron hoy la Oficina Federal de Medio Ambiente (UBA) y el Ministerio alem\u00e1n de Medio Ambiente. Seg\u00fan las autoridades medioambientales, solo 25 ciudades alemanas superaron el l\u00edmite fijado por","canonical_url":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#listItem","name":"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#listItem","position":3,"name":"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#newsarticle","name":"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania | Cand\u00e1s 365","headline":"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720.jpg","width":960,"height":613},"datePublished":"2020-06-09T16:21:17+02:00","dateModified":"2020-06-09T16:21:17+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 9, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#webpage","url":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/","name":"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania | Cand\u00e1s 365","description":"Berl\u00edn, 9 jun (dpa) - La contaminaci\u00f3n del aire urbano con di\u00f3xido de nitr\u00f3geno, nocivo para la salud, disminuy\u00f3 considerablemente en Alemania durante el a\u00f1o pasado, informaron hoy la Oficina Federal de Medio Ambiente (UBA) y el Ministerio alem\u00e1n de Medio Ambiente. Seg\u00fan las autoridades medioambientales, solo 25 ciudades alemanas superaron el l\u00edmite fijado por","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#mainImage","width":960,"height":613},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/#mainImage"},"datePublished":"2020-06-09T16:21:17+02:00","dateModified":"2020-06-09T16:21:17+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania | Cand\u00e1s 365","og:description":"Berl\u00edn, 9 jun (dpa) - La contaminaci\u00f3n del aire urbano con di\u00f3xido de nitr\u00f3geno, nocivo para la salud, disminuy\u00f3 considerablemente en Alemania durante el a\u00f1o pasado, informaron hoy la Oficina Federal de Medio Ambiente (UBA) y el Ministerio alem\u00e1n de Medio Ambiente. Seg\u00fan las autoridades medioambientales, solo 25 ciudades alemanas superaron el l\u00edmite fijado por","og:url":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720.jpg","og:image:width":960,"og:image:height":613,"article:published_time":"2020-06-09T16:21:17+00:00","article:modified_time":"2020-06-09T16:21:17+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 9 jun (dpa) - La contaminaci\u00f3n del aire urbano con di\u00f3xido de nitr\u00f3geno, nocivo para la salud, disminuy\u00f3 considerablemente en Alemania durante el a\u00f1o pasado, informaron hoy la Oficina Federal de Medio Ambiente (UBA) y el Ministerio alem\u00e1n de Medio Ambiente. Seg\u00fan las autoridades medioambientales, solo 25 ciudades alemanas superaron el l\u00edmite fijado por","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-1467502_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"143410","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 12:04:16","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:41:38","updated":"2026-05-26 12:04:16"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tPoluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Poluci\u00f3n del aire por di\u00f3xido de nitr\u00f3geno disminuye en Alemania","link":"https:\/\/candas365.es\/noticias\/polucion-del-aire-por-dioxido-de-nitrogeno-disminuye-en-alemania\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=143410"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/97927"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=143410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=143410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=143410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}