{"id":143356,"date":"2020-06-08T16:05:13","date_gmt":"2020-06-08T16:05:13","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=143356"},"modified":"2020-06-08T16:05:13","modified_gmt":"2020-06-08T16:05:13","slug":"deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/","title":{"rendered":"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-111683\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 8 jun (dpa) &#8211; La mayor empresa ferroviaria alemana Deutsche Bahn reducir\u00e1 las tarifas de los trenes de larga distancia en un 1,9 por ciento a partir del 1 de julio, inform\u00f3 hoy a dpa Berthold Huber, directivo del departamento de transporte de pasajeros.<\/p>\n<p>Esto se aplica a las diferentes ofertas de billetes, as\u00ed como a las tarjetas de descuento y a los abonos de temporada para viajes de larga distancia.<\/p>\n<p>El Gobierno alem\u00e1n decidi\u00f3 reducir el impuesto sobre el valor a\u00f1adido desde el 1 de julio hasta finales de a\u00f1o. La tarifa reducida, que desde principios de a\u00f1o se aplica tambi\u00e9n a los billetes de tren para viajes de larga distancia, bajar\u00e1 del siete al cinco por ciento.<\/p>\n<p>Seg\u00fan Huber, con la decisi\u00f3n de disminuir los precios, trasladan a los clientes la reducci\u00f3n del impuesto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 8 jun (dpa) &#8211; La mayor empresa ferroviaria alemana Deutsche Bahn reducir\u00e1 las tarifas de los trenes de larga distancia en un 1,9 por ciento a partir del 1 de julio, inform\u00f3 hoy a dpa Berthold Huber, directivo del departamento de transporte de pasajeros. Esto se aplica a las diferentes ofertas de billetes, as\u00ed<\/p>\n","protected":false},"author":1,"featured_media":111683,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-143356","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 8 jun (dpa) - La mayor empresa ferroviaria alemana Deutsche Bahn reducir\u00e1 las tarifas de los trenes de larga distancia en un 1,9 por ciento a partir del 1 de julio, inform\u00f3 hoy a dpa Berthold Huber, directivo del departamento de transporte de pasajeros. Esto se aplica a las diferentes ofertas de billetes, as\u00ed\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 8 jun (dpa) - La mayor empresa ferroviaria alemana Deutsche Bahn reducir\u00e1 las tarifas de los trenes de larga distancia en un 1,9 por ciento a partir del 1 de julio, inform\u00f3 hoy a dpa Berthold Huber, directivo del departamento de transporte de pasajeros. Esto se aplica a las diferentes ofertas de billetes, as\u00ed\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-08T16:05:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-08T16:05:13+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 8 jun (dpa) - La mayor empresa ferroviaria alemana Deutsche Bahn reducir\u00e1 las tarifas de los trenes de larga distancia en un 1,9 por ciento a partir del 1 de julio, inform\u00f3 hoy a dpa Berthold Huber, directivo del departamento de transporte de pasajeros. Esto se aplica a las diferentes ofertas de billetes, as\u00ed\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#listItem\",\"name\":\"Deutsche Bahn reducir\\u00e1 las tarifas de larga distancia desde julio\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#listItem\",\"position\":3,\"name\":\"Deutsche Bahn reducir\\u00e1 las tarifas de larga distancia desde julio\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#newsarticle\",\"name\":\"Deutsche Bahn reducir\\u00e1 las tarifas de larga distancia desde julio | Cand\\u00e1s 365\",\"headline\":\"Deutsche Bahn reducir\\u00e1 las tarifas de larga distancia desde julio\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/berlin-3333520_960_720.jpg\",\"width\":960,\"height\":640},\"datePublished\":\"2020-06-08T16:05:13+02:00\",\"dateModified\":\"2020-06-08T16:05:13+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 8, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/\",\"name\":\"Deutsche Bahn reducir\\u00e1 las tarifas de larga distancia desde julio | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 8 jun (dpa) - La mayor empresa ferroviaria alemana Deutsche Bahn reducir\\u00e1 las tarifas de los trenes de larga distancia en un 1,9 por ciento a partir del 1 de julio, inform\\u00f3 hoy a dpa Berthold Huber, directivo del departamento de transporte de pasajeros. Esto se aplica a las diferentes ofertas de billetes, as\\u00ed\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/berlin-3333520_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\\\/#mainImage\"},\"datePublished\":\"2020-06-08T16:05:13+02:00\",\"dateModified\":\"2020-06-08T16:05:13+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio | Cand\u00e1s 365","description":"Berl\u00edn, 8 jun (dpa) - La mayor empresa ferroviaria alemana Deutsche Bahn reducir\u00e1 las tarifas de los trenes de larga distancia en un 1,9 por ciento a partir del 1 de julio, inform\u00f3 hoy a dpa Berthold Huber, directivo del departamento de transporte de pasajeros. Esto se aplica a las diferentes ofertas de billetes, as\u00ed","canonical_url":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#listItem","name":"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#listItem","position":3,"name":"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#newsarticle","name":"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio | Cand\u00e1s 365","headline":"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720.jpg","width":960,"height":640},"datePublished":"2020-06-08T16:05:13+02:00","dateModified":"2020-06-08T16:05:13+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 8, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#webpage","url":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/","name":"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio | Cand\u00e1s 365","description":"Berl\u00edn, 8 jun (dpa) - La mayor empresa ferroviaria alemana Deutsche Bahn reducir\u00e1 las tarifas de los trenes de larga distancia en un 1,9 por ciento a partir del 1 de julio, inform\u00f3 hoy a dpa Berthold Huber, directivo del departamento de transporte de pasajeros. Esto se aplica a las diferentes ofertas de billetes, as\u00ed","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/#mainImage"},"datePublished":"2020-06-08T16:05:13+02:00","dateModified":"2020-06-08T16:05:13+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio | Cand\u00e1s 365","og:description":"Berl\u00edn, 8 jun (dpa) - La mayor empresa ferroviaria alemana Deutsche Bahn reducir\u00e1 las tarifas de los trenes de larga distancia en un 1,9 por ciento a partir del 1 de julio, inform\u00f3 hoy a dpa Berthold Huber, directivo del departamento de transporte de pasajeros. Esto se aplica a las diferentes ofertas de billetes, as\u00ed","og:url":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2020-06-08T16:05:13+00:00","article:modified_time":"2020-06-08T16:05:13+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 8 jun (dpa) - La mayor empresa ferroviaria alemana Deutsche Bahn reducir\u00e1 las tarifas de los trenes de larga distancia en un 1,9 por ciento a partir del 1 de julio, inform\u00f3 hoy a dpa Berthold Huber, directivo del departamento de transporte de pasajeros. Esto se aplica a las diferentes ofertas de billetes, as\u00ed","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/12\/berlin-3333520_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"143356","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 11:54:28","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:41:43","updated":"2026-05-26 11:54:28"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDeutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Deutsche Bahn reducir\u00e1 las tarifas de larga distancia desde julio","link":"https:\/\/candas365.es\/noticias\/deutsche-bahn-reducira-las-tarifas-de-larga-distancia-desde-julio\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=143356"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/111683"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=143356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=143356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=143356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}