{"id":143241,"date":"2020-06-05T18:13:43","date_gmt":"2020-06-05T18:13:43","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=143241"},"modified":"2020-06-05T18:13:43","modified_gmt":"2020-06-05T18:13:43","slug":"ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/","title":{"rendered":"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados"},"content":{"rendered":"<figure id=\"attachment_143242\" aria-describedby=\"caption-attachment-143242\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-143242\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder-360x234.jpg\" alt=\"\" width=\"360\" height=\"234\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder-360x234.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder-655x426.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder-768x500.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder-696x453.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder-645x420.jpg 645w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder.jpg 1017w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-143242\" class=\"wp-caption-text\">Foto: Carsten Koall\/dpa<\/figcaption><\/figure>\n<p>Berl\u00edn, 5 jun (dpa) &#8211; El ministro alem\u00e1n del Interior, Horst Seehofer, pidi\u00f3 hoy que se avance en la reforma del derecho europeo de asilo e hizo un llamado a la solidaridad con los estados del sur de Europa.<\/p>\n<p>\u00abDebemos poner todos nuestros esfuerzos en encontrar una soluci\u00f3n, porque las cosas no pueden seguir as\u00ed\u00bb, dijo Seehofer en Berl\u00edn tras una videoconferencia con sus pares de la Uni\u00f3n Europea (UE). \u00abLucharemos muy, muy duro por esto\u00bb, subray\u00f3.<\/p>\n<p>Alemania asumir\u00e1 la presidencia rotativa de la Uni\u00f3n Europea en la segunda mitad de este a\u00f1o. Antes de fin de junio se espera una nueva propuesta de la Comisi\u00f3n de la UE para una reforma de la ley de asilo, que ha estado estancada durante a\u00f1os.<\/p>\n<p>Seehofer enfatiz\u00f3 que Grecia, Italia, Espa\u00f1a y Portugal, donde llegan muchos migrantes, no deben ser dejados solos. Agreg\u00f3 que junto con Francia, Italia y Espa\u00f1a, Alemania estaba tratando de \u00abmantener el tren en marcha\u00bb.<\/p>\n<p>Al mismo tiempo, reafirm\u00f3 su postura de que la primera evaluaci\u00f3n de una solicitud de asilo debe hacerse en las fronteras exteriores de Europa. Desde all\u00ed, las personas deben ser devueltas a sus pa\u00edses de origen si es necesario.<\/p>\n<p>El ministro a\u00f1adi\u00f3 que el objetivo del Gobierno alem\u00e1n es que todos los estados de la UE participen en la admisi\u00f3n de migrantes. Sin embargo dijo que si no se puede convencer a todos los pa\u00edses, deber\u00eda haber otras posibilidades de solidaridad, como el apoyo financiero o el empleo de polic\u00edas para integrar la fuerza de protecci\u00f3n de fronteras de la UE, Frontex.<\/p>\n<p>\u00abEs importante mostrar que el coraz\u00f3n de Europa late y es capaz de manejar situaciones dif\u00edciles\u00bb, destac\u00f3 el ministro germano.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 5 jun (dpa) &#8211; El ministro alem\u00e1n del Interior, Horst Seehofer, pidi\u00f3 hoy que se avance en la reforma del derecho europeo de asilo e hizo un llamado a la solidaridad con los estados del sur de Europa. \u00abDebemos poner todos nuestros esfuerzos en encontrar una soluci\u00f3n, porque las cosas no pueden seguir as\u00ed\u00bb,<\/p>\n","protected":false},"author":1,"featured_media":143242,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-143241","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 5 jun (dpa) - El ministro alem\u00e1n del Interior, Horst Seehofer, pidi\u00f3 hoy que se avance en la reforma del derecho europeo de asilo e hizo un llamado a la solidaridad con los estados del sur de Europa. &quot;Debemos poner todos nuestros esfuerzos en encontrar una soluci\u00f3n, porque las cosas no pueden seguir as\u00ed&quot;,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 5 jun (dpa) - El ministro alem\u00e1n del Interior, Horst Seehofer, pidi\u00f3 hoy que se avance en la reforma del derecho europeo de asilo e hizo un llamado a la solidaridad con los estados del sur de Europa. &quot;Debemos poner todos nuestros esfuerzos en encontrar una soluci\u00f3n, porque las cosas no pueden seguir as\u00ed&quot;,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1017\" \/>\n\t\t<meta property=\"og:image:height\" content=\"662\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-05T18:13:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-05T18:13:43+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 5 jun (dpa) - El ministro alem\u00e1n del Interior, Horst Seehofer, pidi\u00f3 hoy que se avance en la reforma del derecho europeo de asilo e hizo un llamado a la solidaridad con los estados del sur de Europa. &quot;Debemos poner todos nuestros esfuerzos en encontrar una soluci\u00f3n, porque las cosas no pueden seguir as\u00ed&quot;,\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#listItem\",\"name\":\"Ministro alem\\u00e1n pide solidaridad con el sur de Europa por refugiados\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#listItem\",\"position\":3,\"name\":\"Ministro alem\\u00e1n pide solidaridad con el sur de Europa por refugiados\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#newsarticle\",\"name\":\"Ministro alem\\u00e1n pide solidaridad con el sur de Europa por refugiados | Cand\\u00e1s 365\",\"headline\":\"Ministro alem\\u00e1n pide solidaridad con el sur de Europa por refugiados\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Horst-Seehoder.jpg\",\"width\":1017,\"height\":662,\"caption\":\"Foto: Carsten Koall\\\/dpa\"},\"datePublished\":\"2020-06-05T18:13:43+02:00\",\"dateModified\":\"2020-06-05T18:13:43+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el junio 5, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/\",\"name\":\"Ministro alem\\u00e1n pide solidaridad con el sur de Europa por refugiados | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 5 jun (dpa) - El ministro alem\\u00e1n del Interior, Horst Seehofer, pidi\\u00f3 hoy que se avance en la reforma del derecho europeo de asilo e hizo un llamado a la solidaridad con los estados del sur de Europa. \\\"Debemos poner todos nuestros esfuerzos en encontrar una soluci\\u00f3n, porque las cosas no pueden seguir as\\u00ed\\\",\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Horst-Seehoder.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#mainImage\",\"width\":1017,\"height\":662,\"caption\":\"Foto: Carsten Koall\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\\\/#mainImage\"},\"datePublished\":\"2020-06-05T18:13:43+02:00\",\"dateModified\":\"2020-06-05T18:13:43+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados | Cand\u00e1s 365","description":"Berl\u00edn, 5 jun (dpa) - El ministro alem\u00e1n del Interior, Horst Seehofer, pidi\u00f3 hoy que se avance en la reforma del derecho europeo de asilo e hizo un llamado a la solidaridad con los estados del sur de Europa. \"Debemos poner todos nuestros esfuerzos en encontrar una soluci\u00f3n, porque las cosas no pueden seguir as\u00ed\",","canonical_url":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#listItem","name":"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#listItem","position":3,"name":"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#newsarticle","name":"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados | Cand\u00e1s 365","headline":"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder.jpg","width":1017,"height":662,"caption":"Foto: Carsten Koall\/dpa"},"datePublished":"2020-06-05T18:13:43+02:00","dateModified":"2020-06-05T18:13:43+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el junio 5, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#webpage","url":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/","name":"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados | Cand\u00e1s 365","description":"Berl\u00edn, 5 jun (dpa) - El ministro alem\u00e1n del Interior, Horst Seehofer, pidi\u00f3 hoy que se avance en la reforma del derecho europeo de asilo e hizo un llamado a la solidaridad con los estados del sur de Europa. \"Debemos poner todos nuestros esfuerzos en encontrar una soluci\u00f3n, porque las cosas no pueden seguir as\u00ed\",","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder.jpg","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#mainImage","width":1017,"height":662,"caption":"Foto: Carsten Koall\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/#mainImage"},"datePublished":"2020-06-05T18:13:43+02:00","dateModified":"2020-06-05T18:13:43+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados | Cand\u00e1s 365","og:description":"Berl\u00edn, 5 jun (dpa) - El ministro alem\u00e1n del Interior, Horst Seehofer, pidi\u00f3 hoy que se avance en la reforma del derecho europeo de asilo e hizo un llamado a la solidaridad con los estados del sur de Europa. &quot;Debemos poner todos nuestros esfuerzos en encontrar una soluci\u00f3n, porque las cosas no pueden seguir as\u00ed&quot;,","og:url":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder.jpg","og:image:width":1017,"og:image:height":662,"article:published_time":"2020-06-05T18:13:43+00:00","article:modified_time":"2020-06-05T18:13:43+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 5 jun (dpa) - El ministro alem\u00e1n del Interior, Horst Seehofer, pidi\u00f3 hoy que se avance en la reforma del derecho europeo de asilo e hizo un llamado a la solidaridad con los estados del sur de Europa. &quot;Debemos poner todos nuestros esfuerzos en encontrar una soluci\u00f3n, porque las cosas no pueden seguir as\u00ed&quot;,","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/06\/Horst-Seehoder.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"143241","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 11:34:17","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:41:43","updated":"2026-05-26 11:34:17"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMinistro alem\u00e1n pide solidaridad con el sur de Europa por refugiados\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Ministro alem\u00e1n pide solidaridad con el sur de Europa por refugiados","link":"https:\/\/candas365.es\/noticias\/ministro-aleman-pide-solidaridad-con-el-sur-de-europa-por-refugiados\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=143241"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/143241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/143242"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=143241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=143241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=143241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}