{"id":142927,"date":"2020-05-30T17:56:35","date_gmt":"2020-05-30T17:56:35","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=142927"},"modified":"2020-05-30T17:56:35","modified_gmt":"2020-05-30T17:56:35","slug":"aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/","title":{"rendered":"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-110714\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>D\u00fcsseldorf (Alemania), 30 may (dpa) &#8211; La fuerte reticencia de los alemanes a comprar coches durante la crisis desatada por el coronavirus est\u00e1 disminuyendo, seg\u00fan una reciente encuesta de la consultora McKinsey, que revel\u00f3 que de 100 personas que quer\u00edan comprar un auto nuevo antes de la pandemia, 79 sostienen actualmente ese plan.<\/p>\n<p>M\u00e1s de 1.000 ciudadanos fueron entrevistados entre el 9 y el 17 de mayo. A principios de abril, solo el 58 por ciento de los interesados en comprar un coche nuevo indic\u00f3 seguir con esa intenci\u00f3n, a mediados de abril la cifra hab\u00eda aumentado al 68 por ciento.<\/p>\n<p>El 44 por ciento de los encuestados dijo que no ve\u00edan a\u00fan descuentos mayores a los ofrecidos con anterior a la crisis. Seg\u00fan el sondeo, los hogares con ingresos m\u00e1s bajos han tendido m\u00e1s a posponer su decisi\u00f3n de compra que aquellos que tienen ingresos m\u00e1s altos.<\/p>\n<p>El an\u00e1lisis de McKinsey reflej\u00f3 asimismo que el leasing de coches como opci\u00f3n de financiaci\u00f3n es ahora m\u00e1s considerado que antes de la pandemia: el 26 por ciento de los interesados se\u00f1alaron que est\u00e1n estudiando esa posibilidad, lo que significa un aumento de 9 puntos porcentuales.<\/p>\n<p>La industria automotriz alemana sufri\u00f3 en marzo y especialmente en abril una fuerte retracci\u00f3n en las ventas de coches debido al cierre de los concesionarios de autom\u00f3viles a causa de la propagaci\u00f3n del coronavirus.<\/p>\n<p>Esto tambi\u00e9n condujo a paros de producci\u00f3n en todas las grandes f\u00e1bricas de autom\u00f3viles de Volkswagen, Daimler, BMW, Audi, Opel y Porsche, as\u00ed como en las plantas de los proveedores.<\/p>\n<p>El sector insiste actualmente en que el Gobierno alem\u00e1n proporcione subsidios estatales en forma de primas de compra para impulsar nuevamente las ventas.<\/p>\n<p>Tambi\u00e9n en otros pa\u00edses aument\u00f3 la disposici\u00f3n a comprar coche nuevo. En Italia, el 75 por ciento de los previamente interesados creen que la compra de un coche es probable, en comparaci\u00f3n con solo el 48 por ciento a mediados de abril. En Francia la cifra es ahora del 89 por ciento, un aumento de 35 puntos en comparaci\u00f3n con el mes anterior.<\/p>\n<p>Ambos pa\u00edses est\u00e1n especialmente afectados por la pandemia, Francia anunci\u00f3 recientemente una relajaci\u00f3n de gran alcance de las restricciones implementadas a causa del coronavirus.<\/p>\n<p>En Reino Unido, seg\u00fan las estad\u00edsticas oficiales, el pa\u00eds con el mayor n\u00famero de muertes relacionadas con el virus en Europa, la disposici\u00f3n a comprar disminuy\u00f3 recientemente a\u00fan m\u00e1s, de 64 a 60 por ciento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00fcsseldorf (Alemania), 30 may (dpa) &#8211; La fuerte reticencia de los alemanes a comprar coches durante la crisis desatada por el coronavirus est\u00e1 disminuyendo, seg\u00fan una reciente encuesta de la consultora McKinsey, que revel\u00f3 que de 100 personas que quer\u00edan comprar un auto nuevo antes de la pandemia, 79 sostienen actualmente ese plan. M\u00e1s de<\/p>\n","protected":false},"author":1,"featured_media":110714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-142927","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"D\u00fcsseldorf (Alemania), 30 may (dpa) - La fuerte reticencia de los alemanes a comprar coches durante la crisis desatada por el coronavirus est\u00e1 disminuyendo, seg\u00fan una reciente encuesta de la consultora McKinsey, que revel\u00f3 que de 100 personas que quer\u00edan comprar un auto nuevo antes de la pandemia, 79 sostienen actualmente ese plan. M\u00e1s de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"D\u00fcsseldorf (Alemania), 30 may (dpa) - La fuerte reticencia de los alemanes a comprar coches durante la crisis desatada por el coronavirus est\u00e1 disminuyendo, seg\u00fan una reciente encuesta de la consultora McKinsey, que revel\u00f3 que de 100 personas que quer\u00edan comprar un auto nuevo antes de la pandemia, 79 sostienen actualmente ese plan. M\u00e1s de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-05-30T17:56:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-05-30T17:56:35+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"D\u00fcsseldorf (Alemania), 30 may (dpa) - La fuerte reticencia de los alemanes a comprar coches durante la crisis desatada por el coronavirus est\u00e1 disminuyendo, seg\u00fan una reciente encuesta de la consultora McKinsey, que revel\u00f3 que de 100 personas que quer\u00edan comprar un auto nuevo antes de la pandemia, 79 sostienen actualmente ese plan. M\u00e1s de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#listItem\",\"name\":\"Aumenta en Alemania la disposici\\u00f3n a comprar un coche nuevo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#listItem\",\"position\":3,\"name\":\"Aumenta en Alemania la disposici\\u00f3n a comprar un coche nuevo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#newsarticle\",\"name\":\"Aumenta en Alemania la disposici\\u00f3n a comprar un coche nuevo | Cand\\u00e1s 365\",\"headline\":\"Aumenta en Alemania la disposici\\u00f3n a comprar un coche nuevo\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/traffic-332857_960_720.jpg\",\"width\":960,\"height\":640},\"datePublished\":\"2020-05-30T17:56:35+02:00\",\"dateModified\":\"2020-05-30T17:56:35+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el mayo 30, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/\",\"name\":\"Aumenta en Alemania la disposici\\u00f3n a comprar un coche nuevo | Cand\\u00e1s 365\",\"description\":\"D\\u00fcsseldorf (Alemania), 30 may (dpa) - La fuerte reticencia de los alemanes a comprar coches durante la crisis desatada por el coronavirus est\\u00e1 disminuyendo, seg\\u00fan una reciente encuesta de la consultora McKinsey, que revel\\u00f3 que de 100 personas que quer\\u00edan comprar un auto nuevo antes de la pandemia, 79 sostienen actualmente ese plan. M\\u00e1s de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/traffic-332857_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\\\/#mainImage\"},\"datePublished\":\"2020-05-30T17:56:35+02:00\",\"dateModified\":\"2020-05-30T17:56:35+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo | Cand\u00e1s 365","description":"D\u00fcsseldorf (Alemania), 30 may (dpa) - La fuerte reticencia de los alemanes a comprar coches durante la crisis desatada por el coronavirus est\u00e1 disminuyendo, seg\u00fan una reciente encuesta de la consultora McKinsey, que revel\u00f3 que de 100 personas que quer\u00edan comprar un auto nuevo antes de la pandemia, 79 sostienen actualmente ese plan. M\u00e1s de","canonical_url":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#listItem","name":"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#listItem","position":3,"name":"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#newsarticle","name":"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo | Cand\u00e1s 365","headline":"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720.jpg","width":960,"height":640},"datePublished":"2020-05-30T17:56:35+02:00","dateModified":"2020-05-30T17:56:35+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el mayo 30, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#webpage","url":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/","name":"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo | Cand\u00e1s 365","description":"D\u00fcsseldorf (Alemania), 30 may (dpa) - La fuerte reticencia de los alemanes a comprar coches durante la crisis desatada por el coronavirus est\u00e1 disminuyendo, seg\u00fan una reciente encuesta de la consultora McKinsey, que revel\u00f3 que de 100 personas que quer\u00edan comprar un auto nuevo antes de la pandemia, 79 sostienen actualmente ese plan. M\u00e1s de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/#mainImage"},"datePublished":"2020-05-30T17:56:35+02:00","dateModified":"2020-05-30T17:56:35+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo | Cand\u00e1s 365","og:description":"D\u00fcsseldorf (Alemania), 30 may (dpa) - La fuerte reticencia de los alemanes a comprar coches durante la crisis desatada por el coronavirus est\u00e1 disminuyendo, seg\u00fan una reciente encuesta de la consultora McKinsey, que revel\u00f3 que de 100 personas que quer\u00edan comprar un auto nuevo antes de la pandemia, 79 sostienen actualmente ese plan. M\u00e1s de","og:url":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2020-05-30T17:56:35+00:00","article:modified_time":"2020-05-30T17:56:35+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo | Cand\u00e1s 365","twitter:description":"D\u00fcsseldorf (Alemania), 30 may (dpa) - La fuerte reticencia de los alemanes a comprar coches durante la crisis desatada por el coronavirus est\u00e1 disminuyendo, seg\u00fan una reciente encuesta de la consultora McKinsey, que revel\u00f3 que de 100 personas que quer\u00edan comprar un auto nuevo antes de la pandemia, 79 sostienen actualmente ese plan. M\u00e1s de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/11\/traffic-332857_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"142927","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 10:42:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:41:59","updated":"2026-05-26 10:42:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAumenta en Alemania la disposici\u00f3n a comprar un coche nuevo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Aumenta en Alemania la disposici\u00f3n a comprar un coche nuevo","link":"https:\/\/candas365.es\/noticias\/aumenta-en-alemania-la-disposicion-a-comprar-un-coche-nuevo\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/142927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=142927"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/142927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/110714"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=142927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=142927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=142927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}