{"id":141796,"date":"2020-05-05T14:18:46","date_gmt":"2020-05-05T14:18:46","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=141796"},"modified":"2021-08-06T15:13:30","modified_gmt":"2021-08-06T15:13:30","slug":"aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/","title":{"rendered":"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-141797\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas-315x300.jpg\" alt=\"\" width=\"315\" height=\"300\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas-315x300.jpg 315w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas-505x480.jpg 505w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas-442x420.jpg 442w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas.jpg 551w\" sizes=\"(max-width: 315px) 100vw, 315px\" \/>El pasado noviembre, el Tribunal Supremo anul\u00f3 una condena de 3 a\u00f1os y 8 meses a un hombre acusado de estafa agravada por medio mill\u00f3n de euros. La sentencia caus\u00f3 revuelo, y se coment\u00f3 de forma masiva en los medios porque parec\u00eda implicar que \u00abrobar a la suegra no es delito\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero para <\/span><span style=\"color: #000000;\"><strong>Luis Chabaneix<\/strong><\/span><span style=\"font-weight: 400;\"> y su equipo de abogados, no es m\u00e1s que un d\u00eda normal en el trabajo. Los miembros del bufete Chabaneix Abogados Penalistas est\u00e1n acostumbrados a cosechar \u00e9xitos en procedimientos penales por delitos econ\u00f3micos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este caso, Luis Chabaneix recurri\u00f3 a la primera sentencia condenatoria de la Audiencia Provincial de Madrid para solicitar que se aplicara la llamada \u00abexcusa absolutoria del art\u00edculo 268 del C\u00f3digo Penal\u00bb, que exime de responsabilidad penal en circunstancias como esta por haber un parentesco por afinidad en primer grado. Dado que los implicados viv\u00edan juntos, el v\u00ednculo parental entre suegra y yerno no se hab\u00eda extinguido pese a la muerte de la mujer del acusado. De esta forma, el Supremo estim\u00f3 el argumento de Chabaneix Abogados, y gracias a esto, su defendido no entrar\u00e1 en prisi\u00f3n.<\/span><\/p>\n<h2><b>\u00bf8 a\u00f1os? Que sean 8 meses. Y sin prisi\u00f3n<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La defensa de delitos econ\u00f3micos y financieros se ha convertido en una de las especialidades del despacho dirigido por Luis Chabaneix. El bufete ha hecho de las defraudaciones y delitos de estafa una de sus especialidades, \u00a1pero no se trata de cualquier estafa menor!, sino de estafas y defraudaciones masivas y piramidales.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el caso \u00abarte y naturaleza\u00bb, una estafa piramidal y masiva derivada del caso Afinsa, con m\u00e1s de 15.000 afectados, Chabaneix Abogados Penalistas consigui\u00f3 una condena de un a\u00f1o de c\u00e1rcel sin entrada en prisi\u00f3n y sin responsabilidad civil para uno de los imputados de la trama, contra el cual algunas acusaciones particulares solicitaban m\u00e1s de 16 a\u00f1os de c\u00e1rcel. La primera condena ante la Audiencia Nacional fue de 4 a\u00f1os de prisi\u00f3n, pero tras el recurso de casaci\u00f3n ante el Supremo, se redujo a 1 a\u00f1o y, posteriormente, se suspendi\u00f3. As\u00ed, Chabaneix Abogados evit\u00f3 la prisi\u00f3n a su defendido.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El a\u00f1o pasado, en el juicio ante la Audiencia Nacional de la Operaci\u00f3n ALPINE por estafa masiva en el sector de la multipropiedad, la defendida se enfrentaba a una pena de 8 a\u00f1os de prisi\u00f3n. Luis Chabaneix obtuvo una pena de 8 meses, y la acusada tampoco entrar\u00e1 en prisi\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Han seguido otros \u00e9xitos en casos de estafas masivas relacionadas con la multipropiedad, como el juicio que se celebr\u00f3 recientemente, y durante m\u00e1s de un mes, en enero de este a\u00f1o ante la Secci\u00f3n 15 de la Audiencia Provincial de Madrid, o el de febrero en la Audiencia Provincial de Ja\u00e9n. En ambos juicios, las penas solicitadas eran de 8 a\u00f1os y medio, pero su obtuvieron penas de 2 a\u00f1os y un a\u00f1o y medio, que evitan el ingreso a prisi\u00f3n de los acusados. \u00a0<\/span><\/p>\n<h2><b>No es una estafa cualquiera<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Desde que Luis Chabaneix obtuvo el archivo y el sobreseimiento para uno de los directivos de Vitaldent, Chabaneix Abogados ha ostentado la defensa y tambi\u00e9n la acusaci\u00f3n en procedimientos por estafas masivas y piramidales ante la Audiencia Nacional. Algunos casos han sido tan relevantes como el caso Idental o el caso Publiolimpia (del Madoff catal\u00e1n).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero las defraudaciones no son la \u00fanica especialidad del despacho: defienden casos de blanqueo de capitales y corrupci\u00f3n en transacciones internacionales, como los Casos Morodo o la Operaci\u00f3n Helio, el Caso Emperador (caso de Gao Ping), la Operaci\u00f3n Troika, la Operaci\u00f3n F\u00e9nix (caso Mario Conde) o la Operaci\u00f3n Card\u00f3n sobre blanqueo y tr\u00e1fico internacional de armas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Chabaneix Abogados Penalistas ha sido un despacho muy presente en la Audiencia Nacional. Durante los \u00faltimos a\u00f1os, Luis Chabaneix y su equipo se han afianzado como referentes en la defensa de casos de estafas y defraudaciones graves.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado noviembre, el Tribunal Supremo anul\u00f3 una condena de 3 a\u00f1os y 8 meses a un hombre acusado de estafa agravada por medio mill\u00f3n de euros. La sentencia caus\u00f3 revuelo, y se coment\u00f3 de forma masiva en los medios porque parec\u00eda implicar que \u00abrobar a la suegra no es delito\u00bb. Pero para Luis Chabaneix<\/p>\n","protected":false},"author":1,"featured_media":141797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-141796","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El pasado noviembre, el Tribunal Supremo anul\u00f3 una condena de 3 a\u00f1os y 8 meses a un hombre acusado de estafa agravada por medio mill\u00f3n de euros. La sentencia caus\u00f3 revuelo, y se coment\u00f3 de forma masiva en los medios porque parec\u00eda implicar que \u00abrobar a la suegra no es delito\u00bb. Pero para Luis Chabaneix\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El pasado noviembre, el Tribunal Supremo anul\u00f3 una condena de 3 a\u00f1os y 8 meses a un hombre acusado de estafa agravada por medio mill\u00f3n de euros. La sentencia caus\u00f3 revuelo, y se coment\u00f3 de forma masiva en los medios porque parec\u00eda implicar que \u00abrobar a la suegra no es delito\u00bb. Pero para Luis Chabaneix\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"551\" \/>\n\t\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-05-05T14:18:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-08-06T15:13:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El pasado noviembre, el Tribunal Supremo anul\u00f3 una condena de 3 a\u00f1os y 8 meses a un hombre acusado de estafa agravada por medio mill\u00f3n de euros. La sentencia caus\u00f3 revuelo, y se coment\u00f3 de forma masiva en los medios porque parec\u00eda implicar que \u00abrobar a la suegra no es delito\u00bb. Pero para Luis Chabaneix\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#listItem\",\"name\":\"Aumenta la larga lista de \\u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#listItem\",\"position\":3,\"name\":\"Aumenta la larga lista de \\u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#newsarticle\",\"name\":\"Aumenta la larga lista de \\u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa | Cand\\u00e1s 365\",\"headline\":\"Aumenta la larga lista de \\u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/penalistas.jpg\",\"width\":551,\"height\":524},\"datePublished\":\"2020-05-05T14:18:46+02:00\",\"dateModified\":\"2021-08-06T15:13:30+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el mayo 5, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/\",\"name\":\"Aumenta la larga lista de \\u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa | Cand\\u00e1s 365\",\"description\":\"El pasado noviembre, el Tribunal Supremo anul\\u00f3 una condena de 3 a\\u00f1os y 8 meses a un hombre acusado de estafa agravada por medio mill\\u00f3n de euros. La sentencia caus\\u00f3 revuelo, y se coment\\u00f3 de forma masiva en los medios porque parec\\u00eda implicar que \\u00abrobar a la suegra no es delito\\u00bb. Pero para Luis Chabaneix\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/penalistas.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#mainImage\",\"width\":551,\"height\":524},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\\\/#mainImage\"},\"datePublished\":\"2020-05-05T14:18:46+02:00\",\"dateModified\":\"2021-08-06T15:13:30+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa | Cand\u00e1s 365","description":"El pasado noviembre, el Tribunal Supremo anul\u00f3 una condena de 3 a\u00f1os y 8 meses a un hombre acusado de estafa agravada por medio mill\u00f3n de euros. La sentencia caus\u00f3 revuelo, y se coment\u00f3 de forma masiva en los medios porque parec\u00eda implicar que \u00abrobar a la suegra no es delito\u00bb. Pero para Luis Chabaneix","canonical_url":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#listItem","name":"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#listItem","position":3,"name":"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#newsarticle","name":"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa | Cand\u00e1s 365","headline":"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas.jpg","width":551,"height":524},"datePublished":"2020-05-05T14:18:46+02:00","dateModified":"2021-08-06T15:13:30+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el mayo 5, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#webpage","url":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/","name":"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa | Cand\u00e1s 365","description":"El pasado noviembre, el Tribunal Supremo anul\u00f3 una condena de 3 a\u00f1os y 8 meses a un hombre acusado de estafa agravada por medio mill\u00f3n de euros. La sentencia caus\u00f3 revuelo, y se coment\u00f3 de forma masiva en los medios porque parec\u00eda implicar que \u00abrobar a la suegra no es delito\u00bb. Pero para Luis Chabaneix","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas.jpg","@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#mainImage","width":551,"height":524},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/#mainImage"},"datePublished":"2020-05-05T14:18:46+02:00","dateModified":"2021-08-06T15:13:30+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa | Cand\u00e1s 365","og:description":"El pasado noviembre, el Tribunal Supremo anul\u00f3 una condena de 3 a\u00f1os y 8 meses a un hombre acusado de estafa agravada por medio mill\u00f3n de euros. La sentencia caus\u00f3 revuelo, y se coment\u00f3 de forma masiva en los medios porque parec\u00eda implicar que \u00abrobar a la suegra no es delito\u00bb. Pero para Luis Chabaneix","og:url":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas.jpg","og:image:width":551,"og:image:height":524,"article:published_time":"2020-05-05T14:18:46+00:00","article:modified_time":"2021-08-06T15:13:30+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa | Cand\u00e1s 365","twitter:description":"El pasado noviembre, el Tribunal Supremo anul\u00f3 una condena de 3 a\u00f1os y 8 meses a un hombre acusado de estafa agravada por medio mill\u00f3n de euros. La sentencia caus\u00f3 revuelo, y se coment\u00f3 de forma masiva en los medios porque parec\u00eda implicar que \u00abrobar a la suegra no es delito\u00bb. Pero para Luis Chabaneix","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/05\/penalistas.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"141796","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"seo_analyzer_scan_date":"2026-05-26 07:34:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:42:41","updated":"2026-05-26 07:34:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Aumenta la larga lista de \u00e9xitos cosechados por el abogado penalista Luis Chabaneix como defensa en delitos de estafa","link":"https:\/\/candas365.es\/noticias\/aumenta-la-larga-lista-de-exitos-cosechados-por-el-abogado-penalista-luis-chabaneix-como-defensa-en-delitos-de-estafa\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/141796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=141796"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/141796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/141797"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=141796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=141796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=141796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}