{"id":140951,"date":"2020-04-14T06:55:28","date_gmt":"2020-04-14T06:55:28","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=140951"},"modified":"2020-04-14T06:55:28","modified_gmt":"2020-04-14T06:55:28","slug":"la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/","title":{"rendered":"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb"},"content":{"rendered":"<figure id=\"attachment_140952\" aria-describedby=\"caption-attachment-140952\" style=\"width: 212px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-140952\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN-212x300.jpg 212w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN-339x480.jpg 339w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN-296x420.jpg 296w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN.jpg 443w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><figcaption id=\"caption-attachment-140952\" class=\"wp-caption-text\">FOTO: CARLOS VILLALON \/ Europa Press<\/figcaption><\/figure>\n<p>(Europa Press) &#8211;\u00a0La guerrilla del Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) ha expresado su rechazo al nombramiento de Francisco Gal\u00e1n y Felipe Torres como \u00abpromotores de paz\u00bb al considerar que ahora son \u00abfuncionarios\u00bb del Gobierno del presidente Iv\u00e1n Duque.<\/p>\n<p>\u00abFrancisco Gal\u00e1n y Felipe Torres son funcionarios nombrados por el Gobierno colombiano y funcionales a sus planes. Por tanto est\u00e1n inhabilitados para realizar labores de acercamientos con el ELN\u00bb, ha se\u00f1alado la guerrilla en un comunicado remitido a la Comisi\u00f3n Facilitadora Civil.<\/p>\n<p>El ELN destaca que tom\u00f3 la decisi\u00f3n de un alto el fuego unilateral, pero \u00abni el Gobierno de Duque ni las Fuerzas Armadas tuvieron la grandeza de valorar nuestro gesto para responder de manera similar\u00bb. \u00abPor el contrario, lo desconocieron e intensificaron sus operaciones militares y realizaron pronunciamientos desobligantes\u00bb, subraya la guerrilla.<\/p>\n<p>\u00abEs claro su af\u00e1n guerrerista y la poca valoraci\u00f3n por la paz de Colombia\u00bb, remacha el ELN, que en cambio valora como \u00abmuy positiva\u00bb la iniciativa de la Comisi\u00f3n Facilitadora Civil de \u00abreactivar los esfuerzos por la b\u00fasqueda de una Salida Pol\u00edtica al Conflicto Social y Armado que vive Colombia\u00bb.<\/p>\n<p>Adem\u00e1s, advierten de que el alto el fuego es \u00abactivo\u00bb porque \u00abnos reservamos el derecho a defendernos ante los ataques de las fuerzas estatales, integradas por tropas regulares, paramilitares y bandas narcotraficantes en varias regiones del pa\u00eds\u00bb.<\/p>\n<p>El ELN declar\u00f3 una tregua unilateral que estar\u00e1 vigente entre el 1 y el 30 de abril como un \u00abgesto humanitario\u00bb, respondiendo as\u00ed a la petici\u00f3n del secretario general de Naciones Unidas, Antonio Guterres, de cesar los combates en todo el mundo para centrar los esfuerzos en la lucha contra el coronavirus.<\/p>\n<p>Sin embargo, el Gobierno ha advertido de que esta tregua no es suficiente para volver a la mesa de negociaciones. El \u00faltimo di\u00e1logo de paz con el ELN, que comenz\u00f3 en febrero de 2017 con el Gobierno de Juan Manuel Santos, se rompi\u00f3 dos a\u00f1os despu\u00e9s, ya con Iv\u00e1n Duque en la Presidencia, tras el atentado perpetrado por la guerrilla contra una escuela de cadetes de Bogot\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Europa Press) &#8211;\u00a0La guerrilla del Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) ha expresado su rechazo al nombramiento de Francisco Gal\u00e1n y Felipe Torres como \u00abpromotores de paz\u00bb al considerar que ahora son \u00abfuncionarios\u00bb del Gobierno del presidente Iv\u00e1n Duque. \u00abFrancisco Gal\u00e1n y Felipe Torres son funcionarios nombrados por el Gobierno colombiano y funcionales a sus planes.<\/p>\n","protected":false},"author":1,"featured_media":140952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-140951","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"(Europa Press) - La guerrilla del Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) ha expresado su rechazo al nombramiento de Francisco Gal\u00e1n y Felipe Torres como &quot;promotores de paz&quot; al considerar que ahora son &quot;funcionarios&quot; del Gobierno del presidente Iv\u00e1n Duque. &quot;Francisco Gal\u00e1n y Felipe Torres son funcionarios nombrados por el Gobierno colombiano y funcionales a sus planes.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(Europa Press) - La guerrilla del Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) ha expresado su rechazo al nombramiento de Francisco Gal\u00e1n y Felipe Torres como &quot;promotores de paz&quot; al considerar que ahora son &quot;funcionarios&quot; del Gobierno del presidente Iv\u00e1n Duque. &quot;Francisco Gal\u00e1n y Felipe Torres son funcionarios nombrados por el Gobierno colombiano y funcionales a sus planes.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"443\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-04-14T06:55:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-04-14T06:55:28+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(Europa Press) - La guerrilla del Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) ha expresado su rechazo al nombramiento de Francisco Gal\u00e1n y Felipe Torres como &quot;promotores de paz&quot; al considerar que ahora son &quot;funcionarios&quot; del Gobierno del presidente Iv\u00e1n Duque. &quot;Francisco Gal\u00e1n y Felipe Torres son funcionarios nombrados por el Gobierno colombiano y funcionales a sus planes.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#listItem\",\"name\":\"La guerrilla del ELN rechaza a los \\u00abpromotores de paz\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#listItem\",\"position\":3,\"name\":\"La guerrilla del ELN rechaza a los \\u00abpromotores de paz\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#newsarticle\",\"name\":\"La guerrilla del ELN rechaza a los \\u00abpromotores de paz\\u00bb | Cand\\u00e1s 365\",\"headline\":\"La guerrilla del ELN rechaza a los \\u00abpromotores de paz\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ELN.jpg\",\"width\":443,\"height\":628,\"caption\":\"FOTO: CARLOS VILLALON \\\/ Europa Press\"},\"datePublished\":\"2020-04-14T06:55:28+02:00\",\"dateModified\":\"2020-04-14T06:55:28+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el abril 14, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/\",\"name\":\"La guerrilla del ELN rechaza a los \\u00abpromotores de paz\\u00bb | Cand\\u00e1s 365\",\"description\":\"(Europa Press) - La guerrilla del Ej\\u00e9rcito de Liberaci\\u00f3n Nacional (ELN) ha expresado su rechazo al nombramiento de Francisco Gal\\u00e1n y Felipe Torres como \\\"promotores de paz\\\" al considerar que ahora son \\\"funcionarios\\\" del Gobierno del presidente Iv\\u00e1n Duque. \\\"Francisco Gal\\u00e1n y Felipe Torres son funcionarios nombrados por el Gobierno colombiano y funcionales a sus planes.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/ELN.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#mainImage\",\"width\":443,\"height\":628,\"caption\":\"FOTO: CARLOS VILLALON \\\/ Europa Press\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\\\/#mainImage\"},\"datePublished\":\"2020-04-14T06:55:28+02:00\",\"dateModified\":\"2020-04-14T06:55:28+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb | Cand\u00e1s 365","description":"(Europa Press) - La guerrilla del Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) ha expresado su rechazo al nombramiento de Francisco Gal\u00e1n y Felipe Torres como \"promotores de paz\" al considerar que ahora son \"funcionarios\" del Gobierno del presidente Iv\u00e1n Duque. \"Francisco Gal\u00e1n y Felipe Torres son funcionarios nombrados por el Gobierno colombiano y funcionales a sus planes.","canonical_url":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#listItem","name":"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#listItem","position":3,"name":"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#newsarticle","name":"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb | Cand\u00e1s 365","headline":"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN.jpg","width":443,"height":628,"caption":"FOTO: CARLOS VILLALON \/ Europa Press"},"datePublished":"2020-04-14T06:55:28+02:00","dateModified":"2020-04-14T06:55:28+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el abril 14, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/","name":"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb | Cand\u00e1s 365","description":"(Europa Press) - La guerrilla del Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) ha expresado su rechazo al nombramiento de Francisco Gal\u00e1n y Felipe Torres como \"promotores de paz\" al considerar que ahora son \"funcionarios\" del Gobierno del presidente Iv\u00e1n Duque. \"Francisco Gal\u00e1n y Felipe Torres son funcionarios nombrados por el Gobierno colombiano y funcionales a sus planes.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN.jpg","@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#mainImage","width":443,"height":628,"caption":"FOTO: CARLOS VILLALON \/ Europa Press"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/#mainImage"},"datePublished":"2020-04-14T06:55:28+02:00","dateModified":"2020-04-14T06:55:28+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb | Cand\u00e1s 365","og:description":"(Europa Press) - La guerrilla del Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) ha expresado su rechazo al nombramiento de Francisco Gal\u00e1n y Felipe Torres como &quot;promotores de paz&quot; al considerar que ahora son &quot;funcionarios&quot; del Gobierno del presidente Iv\u00e1n Duque. &quot;Francisco Gal\u00e1n y Felipe Torres son funcionarios nombrados por el Gobierno colombiano y funcionales a sus planes.","og:url":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN.jpg","og:image:width":443,"og:image:height":628,"article:published_time":"2020-04-14T06:55:28+00:00","article:modified_time":"2020-04-14T06:55:28+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb | Cand\u00e1s 365","twitter:description":"(Europa Press) - La guerrilla del Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) ha expresado su rechazo al nombramiento de Francisco Gal\u00e1n y Felipe Torres como &quot;promotores de paz&quot; al considerar que ahora son &quot;funcionarios&quot; del Gobierno del presidente Iv\u00e1n Duque. &quot;Francisco Gal\u00e1n y Felipe Torres son funcionarios nombrados por el Gobierno colombiano y funcionales a sus planes.","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/04\/ELN.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"140951","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 05:00:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:43:40","updated":"2026-05-26 05:00:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"La guerrilla del ELN rechaza a los \u00abpromotores de paz\u00bb","link":"https:\/\/candas365.es\/noticias\/la-guerrilla-del-eln-rechaza-a-los-promotores-de-paz\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/140951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=140951"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/140951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/140952"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=140951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=140951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=140951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}