{"id":140184,"date":"2020-03-25T14:36:07","date_gmt":"2020-03-25T14:36:07","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=140184"},"modified":"2020-03-25T14:36:07","modified_gmt":"2020-03-25T14:36:07","slug":"gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/","title":{"rendered":"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-140185\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez.jpg 512w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>En la reuni\u00f3n informal del Consejo de Asuntos Exteriores de la Uni\u00f3n Europea, la ministra de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, Arancha Gonz\u00e1lez Laya, ha defendido una mejora de la coordinaci\u00f3n consular que facilite el regreso de aquellos turistas que en estos momentos quieren regresar a sus pa\u00edses de residencia.<\/p>\n<p>Gonz\u00e1lez Laya, que ha asistido al encuentro telem\u00e1tico celebrado por videoconferencia con el Alto Representante Josep Borrell y el resto de hom\u00f3logos europeos, ha insistido en que <strong>\u00abdebemos reforzar la coordinaci\u00f3n consular europea para facilitar el regreso de nuestros turistas a sus hogares.\u00bb<\/strong> Para ello, la prioridad es ahora a trav\u00e9s de los vuelos comerciales que permitan dar soluci\u00f3n a los problemas que se encuentran los turistas que quieren abandonar los pa\u00edses en los que se encuentran.<\/p>\n<p>A pesar de las crecientes dificultades debido al cierre de espacios a\u00e9reos y las restricciones de las cuarentenas,<strong> Espa\u00f1a ha resaltado la prioridad de anteponer el regreso de turistas y de aquellos en mayor situaci\u00f3n de vulnerabilidad<\/strong>. Asimismo, ha expresado su preocupaci\u00f3n por la expansi\u00f3n del virus en regiones estructuralmente fr\u00e1giles y, por ello, respaldado que se estudie la toma de medidas en favor de los pa\u00edses necesitados.<\/p>\n<p>Por otra parte, en la lucha contra la desinformaci\u00f3n, la ministra ha se\u00f1alado que debemos trabajar mejor y aprender las lecciones de lo que se est\u00e1 haciendo. A su juicio, es un aspecto cr\u00edtico que debe contribuir a elaborar una narrativa en defensa de la Uni\u00f3n Europea.<\/p>\n<p>El Alto Representante ha ofrecido las delegaciones de la Uni\u00f3n Europea en todos los pa\u00edses del mundo para que coordinen con las Embajadas de los Estados Miembros los medios de viaje disponibles y su distribuci\u00f3n entre los turistas europeos con dificultades para regresar a sus pa\u00edses. En este encuentro, los ministros de Asuntos Exteriores han compartido su an\u00e1lisis sobre las consecuencias geoestrat\u00e9gicas de la crisis del coronavirus.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la reuni\u00f3n informal del Consejo de Asuntos Exteriores de la Uni\u00f3n Europea, la ministra de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, Arancha Gonz\u00e1lez Laya, ha defendido una mejora de la coordinaci\u00f3n consular que facilite el regreso de aquellos turistas que en estos momentos quieren regresar a sus pa\u00edses de residencia. Gonz\u00e1lez Laya, que ha<\/p>\n","protected":false},"author":1,"featured_media":140185,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-140184","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En la reuni\u00f3n informal del Consejo de Asuntos Exteriores de la Uni\u00f3n Europea, la ministra de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, Arancha Gonz\u00e1lez Laya, ha defendido una mejora de la coordinaci\u00f3n consular que facilite el regreso de aquellos turistas que en estos momentos quieren regresar a sus pa\u00edses de residencia. Gonz\u00e1lez Laya, que ha\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"En la reuni\u00f3n informal del Consejo de Asuntos Exteriores de la Uni\u00f3n Europea, la ministra de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, Arancha Gonz\u00e1lez Laya, ha defendido una mejora de la coordinaci\u00f3n consular que facilite el regreso de aquellos turistas que en estos momentos quieren regresar a sus pa\u00edses de residencia. Gonz\u00e1lez Laya, que ha\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-03-25T14:36:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-03-25T14:36:07+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En la reuni\u00f3n informal del Consejo de Asuntos Exteriores de la Uni\u00f3n Europea, la ministra de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, Arancha Gonz\u00e1lez Laya, ha defendido una mejora de la coordinaci\u00f3n consular que facilite el regreso de aquellos turistas que en estos momentos quieren regresar a sus pa\u00edses de residencia. Gonz\u00e1lez Laya, que ha\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#listItem\",\"name\":\"Gonz\\u00e1lez Laya aboga por mejorar la coordinaci\\u00f3n europea para facilitar el regreso de los turistas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#listItem\",\"position\":3,\"name\":\"Gonz\\u00e1lez Laya aboga por mejorar la coordinaci\\u00f3n europea para facilitar el regreso de los turistas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#newsarticle\",\"name\":\"Gonz\\u00e1lez Laya aboga por mejorar la coordinaci\\u00f3n europea para facilitar el regreso de los turistas | Cand\\u00e1s 365\",\"headline\":\"Gonz\\u00e1lez Laya aboga por mejorar la coordinaci\\u00f3n europea para facilitar el regreso de los turistas\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Ar\\u00e1nzazu-Gonz\\u00e1lez.jpg\",\"width\":512,\"height\":340},\"datePublished\":\"2020-03-25T14:36:07+01:00\",\"dateModified\":\"2020-03-25T14:36:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el marzo 25, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/\",\"name\":\"Gonz\\u00e1lez Laya aboga por mejorar la coordinaci\\u00f3n europea para facilitar el regreso de los turistas | Cand\\u00e1s 365\",\"description\":\"En la reuni\\u00f3n informal del Consejo de Asuntos Exteriores de la Uni\\u00f3n Europea, la ministra de Asuntos Exteriores, Uni\\u00f3n Europea y Cooperaci\\u00f3n, Arancha Gonz\\u00e1lez Laya, ha defendido una mejora de la coordinaci\\u00f3n consular que facilite el regreso de aquellos turistas que en estos momentos quieren regresar a sus pa\\u00edses de residencia. Gonz\\u00e1lez Laya, que ha\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Ar\\u00e1nzazu-Gonz\\u00e1lez.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#mainImage\",\"width\":512,\"height\":340},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\\\/#mainImage\"},\"datePublished\":\"2020-03-25T14:36:07+01:00\",\"dateModified\":\"2020-03-25T14:36:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas | Cand\u00e1s 365","description":"En la reuni\u00f3n informal del Consejo de Asuntos Exteriores de la Uni\u00f3n Europea, la ministra de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, Arancha Gonz\u00e1lez Laya, ha defendido una mejora de la coordinaci\u00f3n consular que facilite el regreso de aquellos turistas que en estos momentos quieren regresar a sus pa\u00edses de residencia. Gonz\u00e1lez Laya, que ha","canonical_url":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#listItem","name":"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#listItem","position":3,"name":"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#newsarticle","name":"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas | Cand\u00e1s 365","headline":"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez.jpg","width":512,"height":340},"datePublished":"2020-03-25T14:36:07+01:00","dateModified":"2020-03-25T14:36:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el marzo 25, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#webpage","url":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/","name":"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas | Cand\u00e1s 365","description":"En la reuni\u00f3n informal del Consejo de Asuntos Exteriores de la Uni\u00f3n Europea, la ministra de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, Arancha Gonz\u00e1lez Laya, ha defendido una mejora de la coordinaci\u00f3n consular que facilite el regreso de aquellos turistas que en estos momentos quieren regresar a sus pa\u00edses de residencia. Gonz\u00e1lez Laya, que ha","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez.jpg","@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#mainImage","width":512,"height":340},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/#mainImage"},"datePublished":"2020-03-25T14:36:07+01:00","dateModified":"2020-03-25T14:36:07+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas | Cand\u00e1s 365","og:description":"En la reuni\u00f3n informal del Consejo de Asuntos Exteriores de la Uni\u00f3n Europea, la ministra de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, Arancha Gonz\u00e1lez Laya, ha defendido una mejora de la coordinaci\u00f3n consular que facilite el regreso de aquellos turistas que en estos momentos quieren regresar a sus pa\u00edses de residencia. Gonz\u00e1lez Laya, que ha","og:url":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez.jpg","og:image:width":512,"og:image:height":340,"article:published_time":"2020-03-25T14:36:07+00:00","article:modified_time":"2020-03-25T14:36:07+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas | Cand\u00e1s 365","twitter:description":"En la reuni\u00f3n informal del Consejo de Asuntos Exteriores de la Uni\u00f3n Europea, la ministra de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, Arancha Gonz\u00e1lez Laya, ha defendido una mejora de la coordinaci\u00f3n consular que facilite el regreso de aquellos turistas que en estos momentos quieren regresar a sus pa\u00edses de residencia. Gonz\u00e1lez Laya, que ha","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/Ar\u00e1nzazu-Gonz\u00e1lez.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"140184","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 02:57:22","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:44:05","updated":"2026-05-26 02:57:22"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tGonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Gonz\u00e1lez Laya aboga por mejorar la coordinaci\u00f3n europea para facilitar el regreso de los turistas","link":"https:\/\/candas365.es\/noticias\/gonzalez-laya-aboga-por-mejorar-la-coordinacion-europea-para-facilitar-el-regreso-de-los-turistas\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/140184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=140184"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/140184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/140185"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=140184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=140184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=140184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}