{"id":139619,"date":"2020-03-17T12:40:29","date_gmt":"2020-03-17T12:40:29","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=139619"},"modified":"2020-03-17T12:40:29","modified_gmt":"2020-03-17T12:40:29","slug":"que-es-el-capex","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/","title":{"rendered":"Qu\u00e9 es el Capex"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\">Los t\u00e9rminos relacionados con la econom\u00eda no siempre son f\u00e1ciles de conocer y asumir. Si quieres conocer la <\/span><\/i><span style=\"color: #ff6600;\"><strong><a style=\"color: #ff6600;\" href=\"https:\/\/economipedia.com\/definiciones\/capex.html\" target=\"_blank\" rel=\"noopener noreferrer\"><i>explicaci\u00f3n del CAPEX<\/i><\/a><\/strong><\/span><i><span style=\"font-weight: 400;\">: qu\u00e9 es, y para qu\u00e9 sirve, te lo contamos.<\/span><\/i><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-139620 size-large\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO-655x454.jpg\" alt=\"\" width=\"655\" height=\"454\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO-655x454.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO-360x250.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO-768x532.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO-218x150.jpg 218w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO-696x482.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO-1068x740.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO-606x420.jpg 606w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO-100x70.jpg 100w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO.jpg 1098w\" sizes=\"(max-width: 655px) 100vw, 655px\" \/><\/p>\n<h2><b>A qu\u00e9 llamamos Capex<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">El Capex hace referencia al \u00a0gasto en capital que se realiza, es decir, se trata de la inversi\u00f3n en capital o en inmovilizado fijo que se hace ya sea para adquirir, mantener o mejorar la parte del activo no corriente que tiene.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es decir se puede concluir que se trata de la inversi\u00f3n requerida para poder mantener y hacer crecer los bienes que se dan dentro de la actividad de la propia empresa \u00a0as\u00ed como su propia devoluci\u00f3n futura.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este sentido tanto el futuro de una empresa as\u00ed como su crecimiento, y los flujos en la caja que puede llegar a generar depender\u00e1n de las inversiones que se realicen y es aqu\u00ed donde el Capex se ve como un elemento de gran importancia dentro de un negocio. Adem\u00e1s, aporta informaci\u00f3n valiosa sobre si la empresa est\u00e1 invirtiendo para crecer o si lo que busca simplemente es mantenerse.<\/span><\/p>\n<h3><b>Tipos de Capex<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">De este modo si nos fijamos en la inversi\u00f3n sobre el inmovilizado por parte de la empresa vemos que hay de dos tipos, en funci\u00f3n del objetivo que tenga esa inversi\u00f3n:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por un lado encontramos el llamado capex de mantenimiento. Es la inversi\u00f3n de reposici\u00f3n, es decir, la inversi\u00f3n que se necesita para poder cubrir el deterioro y el gasto derivado de las amortizaciones del inmovilizado. Dicho de otro modo, es \u00a0la inversi\u00f3n necesaria que debe hacer la empresa para poder mantener el mismo nivel de ventas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Capex de expansi\u00f3n. En cuanto a este tipo de capex hace referencia a la inversi\u00f3n necesaria en inmovilizado que sirve para incrementar el nivel actual de ventas, es decir, la cantidad que invierte la firma para as\u00ed lograr nuevos activos fijos y mejorar el nivel de ventas que se tenga en la actualidad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De este modo si nos centramos en la inversi\u00f3n total en Capex que realiza una empresa decir que esta ser\u00e1 el total que sumen las dos anteriores. As\u00ed pues, una compa\u00f1\u00eda llevar\u00e1 una estrategia de expansi\u00f3n cuando se d\u00e9 que el nivel total de Capex sea mayor que el gasto derivado de las amortizaciones. Si esto es as\u00ed significar\u00e1 que la empresa est\u00e1 invirtiendo \u00a0para reponer activos, pero tambi\u00e9n para mejorar los mismos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De este modo, la ecuaci\u00f3n del capex ser\u00eda la siguiente:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Capex = Inmovilizado Material Neto (a\u00f1o t) \u2013 Inmovilizado Material Neto(a\u00f1o t-1) + Amortizaciones(a\u00f1o t)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As\u00ed pues para realizar el c\u00e1lculo del Capex hay que seguir estas indicaciones:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En primer lugar hay que coger el balance de la compa\u00f1\u00eda que se da en el a\u00f1o actual y mirar el dato derivado del Inmovilizado Neto, sobre \u00e9l hay que restar el Inmovilizado neto actual al Inmovilizado neto del balance que se dio en el a\u00f1o anterior y al resultado de esta operaci\u00f3n hay que sumar el gasto que se deriva en amortizaciones del a\u00f1o vigente y que vemos en la cuenta de resultados.<\/span><\/p>\n<h2><b>Diferencias entre Capex y Opex<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Hay quien no acaba de diferenciar qu\u00e9 es el capex y qu\u00e9 es el opex. Aqu\u00ed te dejamos las diferencias entre ambos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al hablar de OPEX lo hacemos del gasto operativo y est\u00e1 relacionado con el corte derivado de las operaciones y servicios. Por ejemplo,si compramos un material para la empresa ser\u00eda un CAPEX, pero si tenemos un gasto \u00fanico por servicios derivados del transporte se podr\u00eda clasificar como OPEX.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As\u00ed pues, en t\u00e9rminos generales la gran parte de los costes anuales que tiene una empresa se consideran gastos operativosy, por ello, lograr reducir el OPEX es uno de los principales objetivos que toda empresa ha de tener, eso s\u00ed, siempre que la calidad de los productos que vende o los servicios que ofrece no se vea deteriorada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El c\u00e1lculo del OPEX es m\u00e1s sencillo que el del CAPEX. Para ello, se deben coger los costes operativos de las ense\u00f1as en un per\u00edodo determinado de tiempo que, generalmente, suele ser un a\u00f1o. A partir de los resultados es f\u00e1cil ver qu\u00e9 modelo es el m\u00e1s adecuado para aplicar en tu firma. Para acertar hay que ver los precios a lo largo del tiempo as\u00ed como que las ense\u00f1as tengan suficiente efectivo para poder mantenerse en el tiempo.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los t\u00e9rminos relacionados con la econom\u00eda no siempre son f\u00e1ciles de conocer y asumir. Si quieres conocer la explicaci\u00f3n del CAPEX: qu\u00e9 es, y para qu\u00e9 sirve, te lo contamos. A qu\u00e9 llamamos Capex El Capex hace referencia al \u00a0gasto en capital que se realiza, es decir, se trata de la inversi\u00f3n en capital o<\/p>\n","protected":false},"author":1,"featured_media":139620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-139619","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los t\u00e9rminos relacionados con la econom\u00eda no siempre son f\u00e1ciles de conocer y asumir. Si quieres conocer la explicaci\u00f3n del CAPEX: qu\u00e9 es, y para qu\u00e9 sirve, te lo contamos. A qu\u00e9 llamamos Capex El Capex hace referencia al gasto en capital que se realiza, es decir, se trata de la inversi\u00f3n en capital o\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/que-es-el-capex\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Qu\u00e9 es el Capex | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Los t\u00e9rminos relacionados con la econom\u00eda no siempre son f\u00e1ciles de conocer y asumir. Si quieres conocer la explicaci\u00f3n del CAPEX: qu\u00e9 es, y para qu\u00e9 sirve, te lo contamos. A qu\u00e9 llamamos Capex El Capex hace referencia al gasto en capital que se realiza, es decir, se trata de la inversi\u00f3n en capital o\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/que-es-el-capex\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1098\" \/>\n\t\t<meta property=\"og:image:height\" content=\"761\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-03-17T12:40:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-03-17T12:40:29+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Qu\u00e9 es el Capex | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los t\u00e9rminos relacionados con la econom\u00eda no siempre son f\u00e1ciles de conocer y asumir. Si quieres conocer la explicaci\u00f3n del CAPEX: qu\u00e9 es, y para qu\u00e9 sirve, te lo contamos. A qu\u00e9 llamamos Capex El Capex hace referencia al gasto en capital que se realiza, es decir, se trata de la inversi\u00f3n en capital o\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#listItem\",\"name\":\"Qu\\u00e9 es el Capex\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#listItem\",\"position\":3,\"name\":\"Qu\\u00e9 es el Capex\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#newsarticle\",\"name\":\"Qu\\u00e9 es el Capex | Cand\\u00e1s 365\",\"headline\":\"Qu\\u00e9 es el Capex\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/FINANCIERO.jpg\",\"width\":1098,\"height\":761},\"datePublished\":\"2020-03-17T12:40:29+01:00\",\"dateModified\":\"2020-03-17T12:40:29+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el marzo 17, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/\",\"name\":\"Qu\\u00e9 es el Capex | Cand\\u00e1s 365\",\"description\":\"Los t\\u00e9rminos relacionados con la econom\\u00eda no siempre son f\\u00e1ciles de conocer y asumir. Si quieres conocer la explicaci\\u00f3n del CAPEX: qu\\u00e9 es, y para qu\\u00e9 sirve, te lo contamos. A qu\\u00e9 llamamos Capex El Capex hace referencia al gasto en capital que se realiza, es decir, se trata de la inversi\\u00f3n en capital o\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/FINANCIERO.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#mainImage\",\"width\":1098,\"height\":761},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/que-es-el-capex\\\/#mainImage\"},\"datePublished\":\"2020-03-17T12:40:29+01:00\",\"dateModified\":\"2020-03-17T12:40:29+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Qu\u00e9 es el Capex | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Qu\u00e9 es el Capex | Cand\u00e1s 365","description":"Los t\u00e9rminos relacionados con la econom\u00eda no siempre son f\u00e1ciles de conocer y asumir. Si quieres conocer la explicaci\u00f3n del CAPEX: qu\u00e9 es, y para qu\u00e9 sirve, te lo contamos. A qu\u00e9 llamamos Capex El Capex hace referencia al gasto en capital que se realiza, es decir, se trata de la inversi\u00f3n en capital o","canonical_url":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#listItem","name":"Qu\u00e9 es el Capex"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#listItem","position":3,"name":"Qu\u00e9 es el Capex","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#newsarticle","name":"Qu\u00e9 es el Capex | Cand\u00e1s 365","headline":"Qu\u00e9 es el Capex","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO.jpg","width":1098,"height":761},"datePublished":"2020-03-17T12:40:29+01:00","dateModified":"2020-03-17T12:40:29+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el marzo 17, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#webpage","url":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/","name":"Qu\u00e9 es el Capex | Cand\u00e1s 365","description":"Los t\u00e9rminos relacionados con la econom\u00eda no siempre son f\u00e1ciles de conocer y asumir. Si quieres conocer la explicaci\u00f3n del CAPEX: qu\u00e9 es, y para qu\u00e9 sirve, te lo contamos. A qu\u00e9 llamamos Capex El Capex hace referencia al gasto en capital que se realiza, es decir, se trata de la inversi\u00f3n en capital o","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO.jpg","@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#mainImage","width":1098,"height":761},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/#mainImage"},"datePublished":"2020-03-17T12:40:29+01:00","dateModified":"2020-03-17T12:40:29+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Qu\u00e9 es el Capex | Cand\u00e1s 365","og:description":"Los t\u00e9rminos relacionados con la econom\u00eda no siempre son f\u00e1ciles de conocer y asumir. Si quieres conocer la explicaci\u00f3n del CAPEX: qu\u00e9 es, y para qu\u00e9 sirve, te lo contamos. A qu\u00e9 llamamos Capex El Capex hace referencia al gasto en capital que se realiza, es decir, se trata de la inversi\u00f3n en capital o","og:url":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO.jpg","og:image:width":1098,"og:image:height":761,"article:published_time":"2020-03-17T12:40:29+00:00","article:modified_time":"2020-03-17T12:40:29+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Qu\u00e9 es el Capex | Cand\u00e1s 365","twitter:description":"Los t\u00e9rminos relacionados con la econom\u00eda no siempre son f\u00e1ciles de conocer y asumir. Si quieres conocer la explicaci\u00f3n del CAPEX: qu\u00e9 es, y para qu\u00e9 sirve, te lo contamos. A qu\u00e9 llamamos Capex El Capex hace referencia al gasto en capital que se realiza, es decir, se trata de la inversi\u00f3n en capital o","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/FINANCIERO.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"139619","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 01:37:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:44:26","updated":"2026-05-26 01:37:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tQu\u00e9 es el Capex\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Qu\u00e9 es el Capex","link":"https:\/\/candas365.es\/noticias\/que-es-el-capex\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/139619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=139619"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/139619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/139620"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=139619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=139619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=139619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}