{"id":139593,"date":"2020-03-17T11:41:13","date_gmt":"2020-03-17T11:41:13","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=139593"},"modified":"2020-03-17T11:41:13","modified_gmt":"2020-03-17T11:41:13","slug":"el-sepe-cierra-su-servicio-presencial","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/","title":{"rendered":"El SEPE cierra su servicio presencial"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-139594\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo.jpg 496w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Servicio P\u00fablico de Empleo Estatal (SEPE) del Ministerio de Trabajo y Econom\u00eda Social ha ordenado cerrar el servicio de atenci\u00f3n al p\u00fablico presencial en sus oficinas de prestaciones a partir del lunes 16 de marzo, debido a la pandemia de COVID-19.<\/p>\n<p>Con esta medida, de car\u00e1cter extraordinario, se pretende atender a las recomendaciones de las autoridades sanitarias por motivos de salud p\u00fablica, evitando los desplazamientos de los ciudadanos y el contacto presencial.<\/p>\n<p>El cierre de las Oficinas al p\u00fablico forma parte del conjunto de medidas adoptadas por el SEPE, en coordinaci\u00f3n con las comunidades aut\u00f3nomas, en el seno del Sistema Nacional de Empleo. Los centros de trabajo se mantendr\u00e1n en funcionamiento a puerta cerrada, garantizando la tramitaci\u00f3n de las prestaciones por desempleo.<\/p>\n<p>De la misma manera, se est\u00e1 trabajando en reforzar la atenci\u00f3n telef\u00f3nica y por medios electr\u00f3nicos. El SEPE dispone de una Sede Electr\u00f3nica para realizar tr\u00e1mites por v\u00eda telem\u00e1tica, e igualmente se cuenta con atenci\u00f3n telef\u00f3nica a los usuarios (listado de tel\u00e9fonos por provincias). Puede hacerse uso de estos tel\u00e9fonos a partir de ma\u00f1ana d\u00eda 16 de marzo.<\/p>\n<p>Es importante resaltar, adem\u00e1s, que se ha decretado la suspensi\u00f3n de t\u00e9rminos y la interrupci\u00f3n de plazos de los procedimientos administrativos, para no perjudicar a la ciudadan\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Servicio P\u00fablico de Empleo Estatal (SEPE) del Ministerio de Trabajo y Econom\u00eda Social ha ordenado cerrar el servicio de atenci\u00f3n al p\u00fablico presencial en sus oficinas de prestaciones a partir del lunes 16 de marzo, debido a la pandemia de COVID-19. Con esta medida, de car\u00e1cter extraordinario, se pretende atender a las recomendaciones de<\/p>\n","protected":false},"author":1,"featured_media":139594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-139593","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Servicio P\u00fablico de Empleo Estatal (SEPE) del Ministerio de Trabajo y Econom\u00eda Social ha ordenado cerrar el servicio de atenci\u00f3n al p\u00fablico presencial en sus oficinas de prestaciones a partir del lunes 16 de marzo, debido a la pandemia de COVID-19. Con esta medida, de car\u00e1cter extraordinario, se pretende atender a las recomendaciones de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El SEPE cierra su servicio presencial | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Servicio P\u00fablico de Empleo Estatal (SEPE) del Ministerio de Trabajo y Econom\u00eda Social ha ordenado cerrar el servicio de atenci\u00f3n al p\u00fablico presencial en sus oficinas de prestaciones a partir del lunes 16 de marzo, debido a la pandemia de COVID-19. Con esta medida, de car\u00e1cter extraordinario, se pretende atender a las recomendaciones de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"496\" \/>\n\t\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-03-17T11:41:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-03-17T11:41:13+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El SEPE cierra su servicio presencial | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Servicio P\u00fablico de Empleo Estatal (SEPE) del Ministerio de Trabajo y Econom\u00eda Social ha ordenado cerrar el servicio de atenci\u00f3n al p\u00fablico presencial en sus oficinas de prestaciones a partir del lunes 16 de marzo, debido a la pandemia de COVID-19. Con esta medida, de car\u00e1cter extraordinario, se pretende atender a las recomendaciones de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#listItem\",\"name\":\"El SEPE cierra su servicio presencial\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#listItem\",\"position\":3,\"name\":\"El SEPE cierra su servicio presencial\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#newsarticle\",\"name\":\"El SEPE cierra su servicio presencial | Cand\\u00e1s 365\",\"headline\":\"El SEPE cierra su servicio presencial\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/020813_OficinaEmpleo.jpg\",\"width\":496,\"height\":330},\"datePublished\":\"2020-03-17T11:41:13+01:00\",\"dateModified\":\"2020-03-17T11:41:13+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el marzo 17, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/\",\"name\":\"El SEPE cierra su servicio presencial | Cand\\u00e1s 365\",\"description\":\"El Servicio P\\u00fablico de Empleo Estatal (SEPE) del Ministerio de Trabajo y Econom\\u00eda Social ha ordenado cerrar el servicio de atenci\\u00f3n al p\\u00fablico presencial en sus oficinas de prestaciones a partir del lunes 16 de marzo, debido a la pandemia de COVID-19. Con esta medida, de car\\u00e1cter extraordinario, se pretende atender a las recomendaciones de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/020813_OficinaEmpleo.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#mainImage\",\"width\":496,\"height\":330},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-sepe-cierra-su-servicio-presencial\\\/#mainImage\"},\"datePublished\":\"2020-03-17T11:41:13+01:00\",\"dateModified\":\"2020-03-17T11:41:13+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El SEPE cierra su servicio presencial | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El SEPE cierra su servicio presencial | Cand\u00e1s 365","description":"El Servicio P\u00fablico de Empleo Estatal (SEPE) del Ministerio de Trabajo y Econom\u00eda Social ha ordenado cerrar el servicio de atenci\u00f3n al p\u00fablico presencial en sus oficinas de prestaciones a partir del lunes 16 de marzo, debido a la pandemia de COVID-19. Con esta medida, de car\u00e1cter extraordinario, se pretende atender a las recomendaciones de","canonical_url":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#listItem","name":"El SEPE cierra su servicio presencial"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#listItem","position":3,"name":"El SEPE cierra su servicio presencial","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#newsarticle","name":"El SEPE cierra su servicio presencial | Cand\u00e1s 365","headline":"El SEPE cierra su servicio presencial","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo.jpg","width":496,"height":330},"datePublished":"2020-03-17T11:41:13+01:00","dateModified":"2020-03-17T11:41:13+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el marzo 17, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/","name":"El SEPE cierra su servicio presencial | Cand\u00e1s 365","description":"El Servicio P\u00fablico de Empleo Estatal (SEPE) del Ministerio de Trabajo y Econom\u00eda Social ha ordenado cerrar el servicio de atenci\u00f3n al p\u00fablico presencial en sus oficinas de prestaciones a partir del lunes 16 de marzo, debido a la pandemia de COVID-19. Con esta medida, de car\u00e1cter extraordinario, se pretende atender a las recomendaciones de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo.jpg","@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#mainImage","width":496,"height":330},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/#mainImage"},"datePublished":"2020-03-17T11:41:13+01:00","dateModified":"2020-03-17T11:41:13+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El SEPE cierra su servicio presencial | Cand\u00e1s 365","og:description":"El Servicio P\u00fablico de Empleo Estatal (SEPE) del Ministerio de Trabajo y Econom\u00eda Social ha ordenado cerrar el servicio de atenci\u00f3n al p\u00fablico presencial en sus oficinas de prestaciones a partir del lunes 16 de marzo, debido a la pandemia de COVID-19. Con esta medida, de car\u00e1cter extraordinario, se pretende atender a las recomendaciones de","og:url":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo.jpg","og:image:width":496,"og:image:height":330,"article:published_time":"2020-03-17T11:41:13+00:00","article:modified_time":"2020-03-17T11:41:13+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El SEPE cierra su servicio presencial | Cand\u00e1s 365","twitter:description":"El Servicio P\u00fablico de Empleo Estatal (SEPE) del Ministerio de Trabajo y Econom\u00eda Social ha ordenado cerrar el servicio de atenci\u00f3n al p\u00fablico presencial en sus oficinas de prestaciones a partir del lunes 16 de marzo, debido a la pandemia de COVID-19. Con esta medida, de car\u00e1cter extraordinario, se pretende atender a las recomendaciones de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/03\/020813_OficinaEmpleo.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"139593","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 01:34:19","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:44:26","updated":"2026-05-26 01:34:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl SEPE cierra su servicio presencial\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"El SEPE cierra su servicio presencial","link":"https:\/\/candas365.es\/noticias\/el-sepe-cierra-su-servicio-presencial\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/139593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=139593"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/139593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/139594"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=139593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=139593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=139593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}