{"id":139278,"date":"2020-03-08T17:26:44","date_gmt":"2020-03-08T17:26:44","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=139278"},"modified":"2020-03-08T17:26:44","modified_gmt":"2020-03-08T17:26:44","slug":"ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/","title":{"rendered":"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-117745\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720-360x238.jpg\" alt=\"\" width=\"360\" height=\"238\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720-360x238.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720-768x508.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720-655x433.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720-696x460.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720-635x420.jpg 635w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 8 mar (dpa) &#8211; El ministro alem\u00e1n de Salud, Jens Spahn, recomend\u00f3 hoy cancelar por el momento los eventos a los que asistan m\u00e1s de mil personas como modo de prevenir contagios con el coronavirus, seg\u00fan se\u00f1al\u00f3 a la agencia dpa.<\/p>\n<p>Spahn opin\u00f3 que a\u00fan se est\u00e1 dudando demasiado en cuanto a aplicar tal medida. \u00abEn vista de la din\u00e1mica que presenta el desarrollo de los \u00faltimos d\u00edas, esto deber\u00eda cambiar\u00bb, coment\u00f3 el titular de Salud en Berl\u00edn.<\/p>\n<p>Tales cancelaciones podr\u00edan afectar, por ejemplo, a los partidos de la Liga alemana de f\u00fatbol, ferias y conciertos multitudinarios.<\/p>\n<p>El ministro a\u00f1adi\u00f3 que la prioridad absoluta es frenar la expansi\u00f3n del nuevo agente pat\u00f3geno. \u00abCuanto m\u00e1s lento se propague el virus, mejor podr\u00e1 actuar nuestro sistema de salud\u00bb, adujo.<\/p>\n<p>\u00abTras haber mantenido numerosas conversaciones con los responsables, insto expresamente a cancelar hasta nuevo aviso los eventos con m\u00e1s de mil participantes\u00bb, acot\u00f3 Spahn.<\/p>\n<p>El ministro explic\u00f3 que el Instituto Robert Koch (RKI) de Berl\u00edn, especializado en detectar y prevenir enfermedades, ha elaborado criterios para gestionar eventos con menor afluencia de p\u00fablico.<\/p>\n<p>\u00abSoy consciente de las consecuencias que esto tiene para las ciudadanas y ciudadanos o para los organizadores de eventos. En los pr\u00f3ximos d\u00edas vamos a analizar c\u00f3mo hacer frente a las consecuencias econ\u00f3micas\u00bb, continu\u00f3 Spahn, recordando que la salud es primordial.<\/p>\n<p>Apuntando hacia la poblaci\u00f3n en general, se\u00f1al\u00f3: \u00abAnimo a cada uno a sopesar lo que le es importante en la rutina propia, si no le resultar\u00eda posible prescindir de eso en los pr\u00f3ximos dos o tres meses, ya sea de asistir al club, a una fiesta de cumplea\u00f1os en el c\u00edrculo familiar o a la reuni\u00f3n de una asociaci\u00f3n\u00bb.<\/p>\n<p>\u00abConf\u00edo en que, en estos tiempos, las ciudadanas y ciudadanos tomen decisiones sabias para s\u00ed y para sus seres queridos, porque con esta precauci\u00f3n estamos protegiendo en especial a nuestros conciudadanos mayores y enfermos cr\u00f3nicos\u00bb, indic\u00f3 el ministro.<\/p>\n<p>Anteriormente, el ministro hab\u00eda reclamado, en vista del aumento del n\u00famero de infecciones, la creaci\u00f3n de una entidad europea similar al Instituto Robert Koch (RKI) de Berl\u00edn.<\/p>\n<p>\u00abEl Centro Europeo para la Prevenci\u00f3n y Control de Enfermedades (ECDC) es demasiado peque\u00f1o como para poder manejar con eficiencia epidemias como \u00e9sta\u00bb, se\u00f1al\u00f3 Spahn al dominical \u00abBild am Sonntag\u00bb, acotando que el ECDC necesita un presupuesto mayor y m\u00e1s competencias.<\/p>\n<p>\u00abNecesitamos una especie de Instituto Robert Koch en el plano europeo\u00bb, adujo Spahn, y pidi\u00f3 que esta propuesta sea contemplada en el pr\u00f3ximo presupuesto de la Uni\u00f3n Europea.<\/p>\n<p>Adem\u00e1s, el ministro germano indic\u00f3 que quiere introducir la obligaci\u00f3n de registrar y comunicar todas las pruebas de coronavirus que se realicen en Alemania.<\/p>\n<p>\u00abHasta ahora solo se deben registrar y comunicar las pruebas en las que se confirma el coronavirus\u00bb, explic\u00f3 Spahn. \u00abEn el futuro tambi\u00e9n se registrar\u00e1n y comunicar\u00e1n los tests en los que no se detecte ninguna infecci\u00f3n\u00bb, precis\u00f3, a\u00f1adiendo que esto ayudar\u00e1 a evaluar mejor la situaci\u00f3n.<\/p>\n<p>Asimismo, en sus declaraciones al \u00abBild am Sonntag\u00bb, Spahn se mostr\u00f3 en contra del cierre de las escuelas para frenar la epidemia.<\/p>\n<p>\u00abSeg\u00fan determina la ley de prevenci\u00f3n de infecciones, solo las autoridades locales pueden ordenar el cierre de las escuelas\u00bb, coment\u00f3 el ministro. \u00abY me parecer\u00eda equivocado dictaminar un cierre en el plano nacional\u00bb.<\/p>\n<p>Por su parte, el RKI actualiz\u00f3 el n\u00famero de infecciones en Alemania a 847 personas infectadas con el virus, cifra que supone unos 50 casos m\u00e1s que el d\u00eda anterior y m\u00e1s de diez veces m\u00e1s que hace una semana.<\/p>\n<p>El estado federado de Renania del Norte-Westfalia sigue registrando el mayor n\u00famero de casos en todo el pa\u00eds, con 392, por delante de Baden-Wurtemberg (182) y Baviera (148). Con excepci\u00f3n de Sajonia-Anhalt, todos los estados federados alemanes est\u00e1n afectados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 8 mar (dpa) &#8211; El ministro alem\u00e1n de Salud, Jens Spahn, recomend\u00f3 hoy cancelar por el momento los eventos a los que asistan m\u00e1s de mil personas como modo de prevenir contagios con el coronavirus, seg\u00fan se\u00f1al\u00f3 a la agencia dpa. Spahn opin\u00f3 que a\u00fan se est\u00e1 dudando demasiado en cuanto a aplicar tal<\/p>\n","protected":false},"author":1,"featured_media":117745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-139278","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 8 mar (dpa) - El ministro alem\u00e1n de Salud, Jens Spahn, recomend\u00f3 hoy cancelar por el momento los eventos a los que asistan m\u00e1s de mil personas como modo de prevenir contagios con el coronavirus, seg\u00fan se\u00f1al\u00f3 a la agencia dpa. Spahn opin\u00f3 que a\u00fan se est\u00e1 dudando demasiado en cuanto a aplicar tal\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 8 mar (dpa) - El ministro alem\u00e1n de Salud, Jens Spahn, recomend\u00f3 hoy cancelar por el momento los eventos a los que asistan m\u00e1s de mil personas como modo de prevenir contagios con el coronavirus, seg\u00fan se\u00f1al\u00f3 a la agencia dpa. Spahn opin\u00f3 que a\u00fan se est\u00e1 dudando demasiado en cuanto a aplicar tal\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-03-08T17:26:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-03-08T17:26:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 8 mar (dpa) - El ministro alem\u00e1n de Salud, Jens Spahn, recomend\u00f3 hoy cancelar por el momento los eventos a los que asistan m\u00e1s de mil personas como modo de prevenir contagios con el coronavirus, seg\u00fan se\u00f1al\u00f3 a la agencia dpa. Spahn opin\u00f3 que a\u00fan se est\u00e1 dudando demasiado en cuanto a aplicar tal\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#listItem\",\"name\":\"Ministro alem\\u00e1n recomienda cancelar eventos con m\\u00e1s de mil personas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#listItem\",\"position\":3,\"name\":\"Ministro alem\\u00e1n recomienda cancelar eventos con m\\u00e1s de mil personas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#newsarticle\",\"name\":\"Ministro alem\\u00e1n recomienda cancelar eventos con m\\u00e1s de mil personas | Cand\\u00e1s 365\",\"headline\":\"Ministro alem\\u00e1n recomienda cancelar eventos con m\\u00e1s de mil personas\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/pedestrians-400811_960_720.jpg\",\"width\":960,\"height\":635},\"datePublished\":\"2020-03-08T17:26:44+01:00\",\"dateModified\":\"2020-03-08T17:26:44+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el marzo 8, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/\",\"name\":\"Ministro alem\\u00e1n recomienda cancelar eventos con m\\u00e1s de mil personas | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 8 mar (dpa) - El ministro alem\\u00e1n de Salud, Jens Spahn, recomend\\u00f3 hoy cancelar por el momento los eventos a los que asistan m\\u00e1s de mil personas como modo de prevenir contagios con el coronavirus, seg\\u00fan se\\u00f1al\\u00f3 a la agencia dpa. Spahn opin\\u00f3 que a\\u00fan se est\\u00e1 dudando demasiado en cuanto a aplicar tal\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/pedestrians-400811_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#mainImage\",\"width\":960,\"height\":635},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\\\/#mainImage\"},\"datePublished\":\"2020-03-08T17:26:44+01:00\",\"dateModified\":\"2020-03-08T17:26:44+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas | Cand\u00e1s 365","description":"Berl\u00edn, 8 mar (dpa) - El ministro alem\u00e1n de Salud, Jens Spahn, recomend\u00f3 hoy cancelar por el momento los eventos a los que asistan m\u00e1s de mil personas como modo de prevenir contagios con el coronavirus, seg\u00fan se\u00f1al\u00f3 a la agencia dpa. Spahn opin\u00f3 que a\u00fan se est\u00e1 dudando demasiado en cuanto a aplicar tal","canonical_url":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#listItem","name":"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#listItem","position":3,"name":"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#newsarticle","name":"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas | Cand\u00e1s 365","headline":"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720.jpg","width":960,"height":635},"datePublished":"2020-03-08T17:26:44+01:00","dateModified":"2020-03-08T17:26:44+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el marzo 8, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#webpage","url":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/","name":"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas | Cand\u00e1s 365","description":"Berl\u00edn, 8 mar (dpa) - El ministro alem\u00e1n de Salud, Jens Spahn, recomend\u00f3 hoy cancelar por el momento los eventos a los que asistan m\u00e1s de mil personas como modo de prevenir contagios con el coronavirus, seg\u00fan se\u00f1al\u00f3 a la agencia dpa. Spahn opin\u00f3 que a\u00fan se est\u00e1 dudando demasiado en cuanto a aplicar tal","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#mainImage","width":960,"height":635},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/#mainImage"},"datePublished":"2020-03-08T17:26:44+01:00","dateModified":"2020-03-08T17:26:44+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas | Cand\u00e1s 365","og:description":"Berl\u00edn, 8 mar (dpa) - El ministro alem\u00e1n de Salud, Jens Spahn, recomend\u00f3 hoy cancelar por el momento los eventos a los que asistan m\u00e1s de mil personas como modo de prevenir contagios con el coronavirus, seg\u00fan se\u00f1al\u00f3 a la agencia dpa. Spahn opin\u00f3 que a\u00fan se est\u00e1 dudando demasiado en cuanto a aplicar tal","og:url":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720.jpg","og:image:width":960,"og:image:height":635,"article:published_time":"2020-03-08T17:26:44+00:00","article:modified_time":"2020-03-08T17:26:44+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 8 mar (dpa) - El ministro alem\u00e1n de Salud, Jens Spahn, recomend\u00f3 hoy cancelar por el momento los eventos a los que asistan m\u00e1s de mil personas como modo de prevenir contagios con el coronavirus, seg\u00fan se\u00f1al\u00f3 a la agencia dpa. Spahn opin\u00f3 que a\u00fan se est\u00e1 dudando demasiado en cuanto a aplicar tal","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/pedestrians-400811_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"139278","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-26 00:38:26","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:44:42","updated":"2026-05-26 00:38:26"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMinistro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Ministro alem\u00e1n recomienda cancelar eventos con m\u00e1s de mil personas","link":"https:\/\/candas365.es\/noticias\/ministro-aleman-recomienda-cancelar-eventos-con-mas-de-mil-personas\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/139278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=139278"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/139278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/117745"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=139278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=139278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=139278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}