{"id":138503,"date":"2020-02-21T19:10:58","date_gmt":"2020-02-21T19:10:58","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=138503"},"modified":"2020-02-21T19:10:58","modified_gmt":"2020-02-21T19:10:58","slug":"alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/","title":{"rendered":"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia"},"content":{"rendered":"<p>Berl\u00edn, 21 feb (dpa) &#8211; La Fundaci\u00f3n del Patrimonio Cultural Prusiano concluy\u00f3 la investigaci\u00f3n acerca del origen de casi 1.200 cr\u00e1neos humanos de la antigua colonia \u00c1frica Oriental Alemana, inform\u00f3 la instituci\u00f3n en Berl\u00edn.<\/p>\n<p>\u00abDesde el punto de vista moral, estos cr\u00e1neos nunca debieron ser tra\u00eddos aqu\u00ed\u00bb, se\u00f1al\u00f3 a dpa Hermann Parzinger, presidente de la Fundaci\u00f3n.<\/p>\n<p>Los cr\u00e1neos forman parte de las colecciones antropol\u00f3gicas del hospital universitario Charit\u00e9 de Berl\u00edn, de las que la Fundaci\u00f3n se hizo cargo en 2011. Con la finalizaci\u00f3n del trabajo de investigaci\u00f3n se clarific\u00f3 el origen de los cr\u00e1neos.<\/p>\n<p>\u00abDe los casi 1.200 cr\u00e1neos examinados, unos 900 son de Ruanda, unos 250 de Tanzania y unos 30 de Kenia, algunos pocos no los pudimos clasificar\u00bb, precis\u00f3 Parzinger.<\/p>\n<p>\u00abDe manera que alrededor del 98 por ciento proviene de la antigua colonia de \u00c1frica Oriental Alemana\u00bb, afirm\u00f3. Seg\u00fan Parzinger, es la primera vez que investigan una cantidad tan grande de restos humanos, y se har\u00e1 una amplia documentaci\u00f3n al respecto.<\/p>\n<p>Ahora se tratar\u00e1n las modalidades de restituci\u00f3n. \u00abEstamos en contacto con las embajadas de los tres pa\u00edses en cuesti\u00f3n. De manera conjunta debemos considerar ahora c\u00f3mo proceder, cu\u00e1les ser\u00e1n los siguientes pasos\u00bb, explic\u00f3 Parzinger, a la vez que acot\u00f3: \u00abNo nos corresponde a nosotros juzgar lo que sucede con los restos despu\u00e9s de la repatriaci\u00f3n\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 21 feb (dpa) &#8211; La Fundaci\u00f3n del Patrimonio Cultural Prusiano concluy\u00f3 la investigaci\u00f3n acerca del origen de casi 1.200 cr\u00e1neos humanos de la antigua colonia \u00c1frica Oriental Alemana, inform\u00f3 la instituci\u00f3n en Berl\u00edn. \u00abDesde el punto de vista moral, estos cr\u00e1neos nunca debieron ser tra\u00eddos aqu\u00ed\u00bb, se\u00f1al\u00f3 a dpa Hermann Parzinger, presidente de la<\/p>\n","protected":false},"author":1,"featured_media":91170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-138503","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 21 feb (dpa) - La Fundaci\u00f3n del Patrimonio Cultural Prusiano concluy\u00f3 la investigaci\u00f3n acerca del origen de casi 1.200 cr\u00e1neos humanos de la antigua colonia \u00c1frica Oriental Alemana, inform\u00f3 la instituci\u00f3n en Berl\u00edn. &quot;Desde el punto de vista moral, estos cr\u00e1neos nunca debieron ser tra\u00eddos aqu\u00ed&quot;, se\u00f1al\u00f3 a dpa Hermann Parzinger, presidente de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 21 feb (dpa) - La Fundaci\u00f3n del Patrimonio Cultural Prusiano concluy\u00f3 la investigaci\u00f3n acerca del origen de casi 1.200 cr\u00e1neos humanos de la antigua colonia \u00c1frica Oriental Alemana, inform\u00f3 la instituci\u00f3n en Berl\u00edn. &quot;Desde el punto de vista moral, estos cr\u00e1neos nunca debieron ser tra\u00eddos aqu\u00ed&quot;, se\u00f1al\u00f3 a dpa Hermann Parzinger, presidente de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/technology-785742_1280.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/technology-785742_1280.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-21T19:10:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-02-21T19:10:58+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 21 feb (dpa) - La Fundaci\u00f3n del Patrimonio Cultural Prusiano concluy\u00f3 la investigaci\u00f3n acerca del origen de casi 1.200 cr\u00e1neos humanos de la antigua colonia \u00c1frica Oriental Alemana, inform\u00f3 la instituci\u00f3n en Berl\u00edn. &quot;Desde el punto de vista moral, estos cr\u00e1neos nunca debieron ser tra\u00eddos aqu\u00ed&quot;, se\u00f1al\u00f3 a dpa Hermann Parzinger, presidente de la\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/technology-785742_1280.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#listItem\",\"name\":\"Alemania retorna cr\\u00e1neos de \\u00e9poca colonial a Ruanda, Tanzania y Kenia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#listItem\",\"position\":3,\"name\":\"Alemania retorna cr\\u00e1neos de \\u00e9poca colonial a Ruanda, Tanzania y Kenia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#newsarticle\",\"name\":\"Alemania retorna cr\\u00e1neos de \\u00e9poca colonial a Ruanda, Tanzania y Kenia | Cand\\u00e1s 365\",\"headline\":\"Alemania retorna cr\\u00e1neos de \\u00e9poca colonial a Ruanda, Tanzania y Kenia\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/technology-785742_1280.jpg\",\"width\":1280,\"height\":853},\"datePublished\":\"2020-02-21T19:10:58+01:00\",\"dateModified\":\"2020-02-21T19:10:58+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el febrero 21, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/\",\"name\":\"Alemania retorna cr\\u00e1neos de \\u00e9poca colonial a Ruanda, Tanzania y Kenia | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 21 feb (dpa) - La Fundaci\\u00f3n del Patrimonio Cultural Prusiano concluy\\u00f3 la investigaci\\u00f3n acerca del origen de casi 1.200 cr\\u00e1neos humanos de la antigua colonia \\u00c1frica Oriental Alemana, inform\\u00f3 la instituci\\u00f3n en Berl\\u00edn. \\\"Desde el punto de vista moral, estos cr\\u00e1neos nunca debieron ser tra\\u00eddos aqu\\u00ed\\\", se\\u00f1al\\u00f3 a dpa Hermann Parzinger, presidente de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/technology-785742_1280.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#mainImage\",\"width\":1280,\"height\":853},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\\\/#mainImage\"},\"datePublished\":\"2020-02-21T19:10:58+01:00\",\"dateModified\":\"2020-02-21T19:10:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia | Cand\u00e1s 365","description":"Berl\u00edn, 21 feb (dpa) - La Fundaci\u00f3n del Patrimonio Cultural Prusiano concluy\u00f3 la investigaci\u00f3n acerca del origen de casi 1.200 cr\u00e1neos humanos de la antigua colonia \u00c1frica Oriental Alemana, inform\u00f3 la instituci\u00f3n en Berl\u00edn. \"Desde el punto de vista moral, estos cr\u00e1neos nunca debieron ser tra\u00eddos aqu\u00ed\", se\u00f1al\u00f3 a dpa Hermann Parzinger, presidente de la","canonical_url":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#listItem","name":"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#listItem","position":3,"name":"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#newsarticle","name":"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia | Cand\u00e1s 365","headline":"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/technology-785742_1280.jpg","width":1280,"height":853},"datePublished":"2020-02-21T19:10:58+01:00","dateModified":"2020-02-21T19:10:58+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el febrero 21, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#webpage","url":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/","name":"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia | Cand\u00e1s 365","description":"Berl\u00edn, 21 feb (dpa) - La Fundaci\u00f3n del Patrimonio Cultural Prusiano concluy\u00f3 la investigaci\u00f3n acerca del origen de casi 1.200 cr\u00e1neos humanos de la antigua colonia \u00c1frica Oriental Alemana, inform\u00f3 la instituci\u00f3n en Berl\u00edn. \"Desde el punto de vista moral, estos cr\u00e1neos nunca debieron ser tra\u00eddos aqu\u00ed\", se\u00f1al\u00f3 a dpa Hermann Parzinger, presidente de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/technology-785742_1280.jpg","@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#mainImage","width":1280,"height":853},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/#mainImage"},"datePublished":"2020-02-21T19:10:58+01:00","dateModified":"2020-02-21T19:10:58+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia | Cand\u00e1s 365","og:description":"Berl\u00edn, 21 feb (dpa) - La Fundaci\u00f3n del Patrimonio Cultural Prusiano concluy\u00f3 la investigaci\u00f3n acerca del origen de casi 1.200 cr\u00e1neos humanos de la antigua colonia \u00c1frica Oriental Alemana, inform\u00f3 la instituci\u00f3n en Berl\u00edn. &quot;Desde el punto de vista moral, estos cr\u00e1neos nunca debieron ser tra\u00eddos aqu\u00ed&quot;, se\u00f1al\u00f3 a dpa Hermann Parzinger, presidente de la","og:url":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/technology-785742_1280.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/technology-785742_1280.jpg","og:image:width":1280,"og:image:height":853,"article:published_time":"2020-02-21T19:10:58+00:00","article:modified_time":"2020-02-21T19:10:58+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 21 feb (dpa) - La Fundaci\u00f3n del Patrimonio Cultural Prusiano concluy\u00f3 la investigaci\u00f3n acerca del origen de casi 1.200 cr\u00e1neos humanos de la antigua colonia \u00c1frica Oriental Alemana, inform\u00f3 la instituci\u00f3n en Berl\u00edn. &quot;Desde el punto de vista moral, estos cr\u00e1neos nunca debieron ser tra\u00eddos aqu\u00ed&quot;, se\u00f1al\u00f3 a dpa Hermann Parzinger, presidente de la","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/03\/technology-785742_1280.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"138503","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 22:27:47","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:45:13","updated":"2026-05-25 22:27:47"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAlemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Alemania retorna cr\u00e1neos de \u00e9poca colonial a Ruanda, Tanzania y Kenia","link":"https:\/\/candas365.es\/noticias\/alemania-retorna-craneos-de-epoca-colonial-a-ruanda-tanzania-y-kenia\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/138503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=138503"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/138503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/91170"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=138503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=138503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=138503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}