{"id":137759,"date":"2020-02-06T05:42:45","date_gmt":"2020-02-06T05:42:45","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=137759"},"modified":"2020-02-06T05:42:45","modified_gmt":"2020-02-06T05:42:45","slug":"pruebas-de-certificacion-b2-de-lengua-asturiana","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/","title":{"rendered":"Pruebas de certificaci\u00f3n B2 de lengua asturiana"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-119676\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2-675x450.jpg 675w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Consejer\u00eda de Educaci\u00f3n, en colaboraci\u00f3n con la de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Turismo, ha convocado las primeras <strong>pruebas de certificaci\u00f3n de lengua asturiana del nivel de competencia Intermedio B2<\/strong>. La convocatoria se ha hecho de acuerdo con el decreto 47\/2019, de 21 de junio, por el que se establecen los niveles de competencia en el uso de la lengua asturiana y se regula la prueba de certificaci\u00f3n correspondiente al Marco Com\u00fan Europeo de Referencia de las Lenguas.<\/p>\n<p><strong>Este a\u00f1o se celebrar\u00e1 una \u00fanica convocatoria, a la que podr\u00e1n concurrir un m\u00e1ximo de 500 aspirantes<\/strong>. Las personas interesadas deber\u00e1n presentar sus solicitudes de admisi\u00f3n entre este jueves, d\u00eda 6, y el pr\u00f3ximo viernes 14 de febrero en los siguientes centros: IES Aramo, en Oviedo; IES Calder\u00f3n de la Barca, en Gij\u00f3n; IES Carre\u00f1o Miranda, en Avil\u00e9s, e IES Bernaldo de Quir\u00f3s, en Mieres. Adem\u00e1s, podr\u00e1n entregarlas las a trav\u00e9s de los \u00f3rganos se\u00f1alados en el art\u00edculo 16.4 de la Ley 39\/2015, de 1 de octubre, del Procedimiento Administrativo Com\u00fan de las Administraciones P\u00fablicas. El listado de inscripci\u00f3n definitivo se publicar\u00e1 el 20 de abril.<\/p>\n<p>Los ejercicios de las cinco partes que componen la prueba de certificaci\u00f3n se realizar\u00e1n en dos bloques. En el bloque 1, que tendr\u00e1 lugar el viernes 29 de mayo, se desarrollar\u00e1n los ejercicios correspondientes a las partes de comprensi\u00f3n de textos escritos y orales y de producci\u00f3n y coproducci\u00f3n de textos escritos. En el bloque 2, que se realizar\u00e1 en jornadas distintas a partir del jueves 21 de mayo, se ejecutar\u00e1n los correspondientes a la parte de producci\u00f3n y coproducci\u00f3n de textos orales y a la parte de mediaci\u00f3n.<\/p>\n<p>Las sedes escogidas para la realizaci\u00f3n de estas primeras pruebas de acreditaci\u00f3n son la Facultad de Formaci\u00f3n del Profesorado y Educaci\u00f3n, donde se desarrollar\u00e1 \u00edntegramente el bloque 1, y el IES Aramo, donde los aspirantes llevar\u00e1n a cabo las pruebas correspondientes al bloque 2.<\/p>\n<p>Tras este primer examen, el Gobierno de Asturias convocar\u00e1 al menos una vez al a\u00f1o pruebas de certificaci\u00f3n de lengua asturiana para un m\u00ednimo de uno de los niveles (A1, A2, B1, B2, C1)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Consejer\u00eda de Educaci\u00f3n, en colaboraci\u00f3n con la de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Turismo, ha convocado las primeras pruebas de certificaci\u00f3n de lengua asturiana del nivel de competencia Intermedio B2. La convocatoria se ha hecho de acuerdo con el decreto 47\/2019, de 21 de junio, por el que se establecen los niveles de competencia en<\/p>\n","protected":false},"author":1,"featured_media":119676,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-137759","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-asturias"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Consejer\u00eda de Educaci\u00f3n, en colaboraci\u00f3n con la de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Turismo, ha convocado las primeras pruebas de certificaci\u00f3n de lengua asturiana del nivel de competencia Intermedio B2. La convocatoria se ha hecho de acuerdo con el decreto 47\/2019, de 21 de junio, por el que se establecen los niveles de competencia en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pruebas de certificaci\u00f3n B2 de lengua asturiana | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La Consejer\u00eda de Educaci\u00f3n, en colaboraci\u00f3n con la de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Turismo, ha convocado las primeras pruebas de certificaci\u00f3n de lengua asturiana del nivel de competencia Intermedio B2. La convocatoria se ha hecho de acuerdo con el decreto 47\/2019, de 21 de junio, por el que se establecen los niveles de competencia en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-06T05:42:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-02-06T05:42:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pruebas de certificaci\u00f3n B2 de lengua asturiana | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Consejer\u00eda de Educaci\u00f3n, en colaboraci\u00f3n con la de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Turismo, ha convocado las primeras pruebas de certificaci\u00f3n de lengua asturiana del nivel de competencia Intermedio B2. La convocatoria se ha hecho de acuerdo con el decreto 47\/2019, de 21 de junio, por el que se establecen los niveles de competencia en\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"position\":2,\"name\":\"Asturias\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#listItem\",\"name\":\"Pruebas de certificaci\\u00f3n B2 de lengua asturiana\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#listItem\",\"position\":3,\"name\":\"Pruebas de certificaci\\u00f3n B2 de lengua asturiana\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/asturias\\\/#listItem\",\"name\":\"Asturias\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#newsarticle\",\"name\":\"Pruebas de certificaci\\u00f3n B2 de lengua asturiana | Cand\\u00e1s 365\",\"headline\":\"Pruebas de certificaci\\u00f3n B2 de lengua asturiana\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/window-770535_960_720-2.jpg\",\"width\":960,\"height\":640},\"datePublished\":\"2020-02-06T05:42:45+01:00\",\"dateModified\":\"2020-02-06T05:42:45+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#webpage\"},\"articleSection\":\"Asturias\",\"dateline\":\"Publicado el febrero 6, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/\",\"name\":\"Pruebas de certificaci\\u00f3n B2 de lengua asturiana | Cand\\u00e1s 365\",\"description\":\"La Consejer\\u00eda de Educaci\\u00f3n, en colaboraci\\u00f3n con la de Cultura, Pol\\u00edtica Lling\\u00fc\\u00edstica y Turismo, ha convocado las primeras pruebas de certificaci\\u00f3n de lengua asturiana del nivel de competencia Intermedio B2. La convocatoria se ha hecho de acuerdo con el decreto 47\\\/2019, de 21 de junio, por el que se establecen los niveles de competencia en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/window-770535_960_720-2.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pruebas-de-certificacion-b2-de-lengua-asturiana\\\/#mainImage\"},\"datePublished\":\"2020-02-06T05:42:45+01:00\",\"dateModified\":\"2020-02-06T05:42:45+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Pruebas de certificaci\u00f3n B2 de lengua asturiana | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Pruebas de certificaci\u00f3n B2 de lengua asturiana | Cand\u00e1s 365","description":"La Consejer\u00eda de Educaci\u00f3n, en colaboraci\u00f3n con la de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Turismo, ha convocado las primeras pruebas de certificaci\u00f3n de lengua asturiana del nivel de competencia Intermedio B2. La convocatoria se ha hecho de acuerdo con el decreto 47\/2019, de 21 de junio, por el que se establecen los niveles de competencia en","canonical_url":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/","robots":"max-image-preview:large","keywords":"asturias","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","position":2,"name":"Asturias","item":"https:\/\/candas365.es\/noticias\/category\/asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#listItem","name":"Pruebas de certificaci\u00f3n B2 de lengua asturiana"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#listItem","position":3,"name":"Pruebas de certificaci\u00f3n B2 de lengua asturiana","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/asturias\/#listItem","name":"Asturias"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#newsarticle","name":"Pruebas de certificaci\u00f3n B2 de lengua asturiana | Cand\u00e1s 365","headline":"Pruebas de certificaci\u00f3n B2 de lengua asturiana","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2.jpg","width":960,"height":640},"datePublished":"2020-02-06T05:42:45+01:00","dateModified":"2020-02-06T05:42:45+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#webpage"},"articleSection":"Asturias","dateline":"Publicado el febrero 6, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#webpage","url":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/","name":"Pruebas de certificaci\u00f3n B2 de lengua asturiana | Cand\u00e1s 365","description":"La Consejer\u00eda de Educaci\u00f3n, en colaboraci\u00f3n con la de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Turismo, ha convocado las primeras pruebas de certificaci\u00f3n de lengua asturiana del nivel de competencia Intermedio B2. La convocatoria se ha hecho de acuerdo con el decreto 47\/2019, de 21 de junio, por el que se establecen los niveles de competencia en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2.jpg","@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/#mainImage"},"datePublished":"2020-02-06T05:42:45+01:00","dateModified":"2020-02-06T05:42:45+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Pruebas de certificaci\u00f3n B2 de lengua asturiana | Cand\u00e1s 365","og:description":"La Consejer\u00eda de Educaci\u00f3n, en colaboraci\u00f3n con la de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Turismo, ha convocado las primeras pruebas de certificaci\u00f3n de lengua asturiana del nivel de competencia Intermedio B2. La convocatoria se ha hecho de acuerdo con el decreto 47\/2019, de 21 de junio, por el que se establecen los niveles de competencia en","og:url":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2020-02-06T05:42:45+00:00","article:modified_time":"2020-02-06T05:42:45+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Pruebas de certificaci\u00f3n B2 de lengua asturiana | Cand\u00e1s 365","twitter:description":"La Consejer\u00eda de Educaci\u00f3n, en colaboraci\u00f3n con la de Cultura, Pol\u00edtica Lling\u00fc\u00edstica y Turismo, ha convocado las primeras pruebas de certificaci\u00f3n de lengua asturiana del nivel de competencia Intermedio B2. La convocatoria se ha hecho de acuerdo con el decreto 47\/2019, de 21 de junio, por el que se establecen los niveles de competencia en","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/03\/window-770535_960_720-2.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"137759","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-30 23:22:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:45:39","updated":"2025-08-30 23:22:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/asturias\/\" title=\"Asturias\">Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tPruebas de certificaci\u00f3n B2 de lengua asturiana\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Asturias","link":"https:\/\/candas365.es\/noticias\/category\/asturias\/"},{"label":"Pruebas de certificaci\u00f3n B2 de lengua asturiana","link":"https:\/\/candas365.es\/noticias\/pruebas-de-certificacion-b2-de-lengua-asturiana\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=137759"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/119676"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=137759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=137759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=137759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}