{"id":137741,"date":"2020-02-05T22:37:18","date_gmt":"2020-02-05T22:37:18","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=137741"},"modified":"2020-02-05T22:37:18","modified_gmt":"2020-02-05T22:37:18","slug":"operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/","title":{"rendered":"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio"},"content":{"rendered":"<figure id=\"attachment_137742\" aria-describedby=\"caption-attachment-137742\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-137742\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula-655x434.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula-768x509.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula-696x461.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula-634x420.jpg 634w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula.jpg 987w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-137742\" class=\"wp-caption-text\">Foto: Paulo Lopes\/ZUMA Wire\/dpa<\/figcaption><\/figure>\n<p>(Europa Press) &#8211;\u00a0El expresidente de Brasil Lula da Silva ha comunicado este martes a la Justicia Federal de Brasilia que viajar\u00e1 la pr\u00f3xima semana a El Vaticano para reunirse con el Papa Francisco y ha pedido que, por lo tanto, se suspenda de momento su interrogatorio en el marco de la &#8216;Operaci\u00f3n Zelotes&#8217;, en la cual se le acusa de \u00abcorrupci\u00f3n pasiva\u00bb.<\/p>\n<p>Los abogados del l\u00edder del Partido de los Trabajadores han puntualizado que, tal y como ha venido sucediendo, Lula \u00abno dejar\u00e1 de comparecer ante ning\u00fan acto judicial para el cual su presencia sea obligatoria\u00bb.<\/p>\n<p>El interrogatorio est\u00e1 fijado para el 11 de febrero, dos d\u00edas antes de que el Papa Francisco reciba a Lula, quien deber\u00e1 tomar un avi\u00f3n el 12 y regresar tres d\u00edas despu\u00e9s.<\/p>\n<p>En esta ocasi\u00f3n, Lula deber\u00e1 responder ante la Justicia por haber cometido supuestamente un crimen de corrupci\u00f3n pasiva, cuando en 2009 promulg\u00f3 la pr\u00f3rroga de los incentivos fiscales de los fabricantes de coches y cadenas de montaje del norte, noroeste y centro del pa\u00eds, que aprob\u00f3 previamente el Senado.<\/p>\n<p>La audiencia otorgada por el Papa se produce despu\u00e9s del viaje a El Vaticano del presidente de Argentina, Alberto Fern\u00e1ndez, quien le traslad\u00f3 al Sumo Pont\u00edfice el inter\u00e9s del antiguo presidente de Brasil por reunirse con \u00e9l.<\/p>\n<p>Se trata de la segunda vez, tal y como ha recordado el diario &#8216;Estadao&#8217;, que Fern\u00e1ndez media entre Lula y el Papa. La primera fue en 2018, cuando el expresidente, en aquel entonces en prisi\u00f3n, recibi\u00f3 una carta de Francisco pidi\u00e9ndole que no se desanimase, puesto que el \u00abbien vencer\u00e1 al mal y la verdad vencer\u00e1 a la mentira\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Europa Press) &#8211;\u00a0El expresidente de Brasil Lula da Silva ha comunicado este martes a la Justicia Federal de Brasilia que viajar\u00e1 la pr\u00f3xima semana a El Vaticano para reunirse con el Papa Francisco y ha pedido que, por lo tanto, se suspenda de momento su interrogatorio en el marco de la &#8216;Operaci\u00f3n Zelotes&#8217;, en la<\/p>\n","protected":false},"author":1,"featured_media":137742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-137741","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(Europa Press) - El expresidente de Brasil Lula da Silva ha comunicado este martes a la Justicia Federal de Brasilia que viajar\u00e1 la pr\u00f3xima semana a El Vaticano para reunirse con el Papa Francisco y ha pedido que, por lo tanto, se suspenda de momento su interrogatorio en el marco de la &#039;Operaci\u00f3n Zelotes&#039;, en la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(Europa Press) - El expresidente de Brasil Lula da Silva ha comunicado este martes a la Justicia Federal de Brasilia que viajar\u00e1 la pr\u00f3xima semana a El Vaticano para reunirse con el Papa Francisco y ha pedido que, por lo tanto, se suspenda de momento su interrogatorio en el marco de la &#039;Operaci\u00f3n Zelotes&#039;, en la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"987\" \/>\n\t\t<meta property=\"og:image:height\" content=\"654\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-05T22:37:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-02-05T22:37:18+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(Europa Press) - El expresidente de Brasil Lula da Silva ha comunicado este martes a la Justicia Federal de Brasilia que viajar\u00e1 la pr\u00f3xima semana a El Vaticano para reunirse con el Papa Francisco y ha pedido que, por lo tanto, se suspenda de momento su interrogatorio en el marco de la &#039;Operaci\u00f3n Zelotes&#039;, en la\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#listItem\",\"name\":\"Operaci\\u00f3n Zelotes: Lula pide la \\u201csuspensi\\u00f3n\\u201d de su interrogatorio\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#listItem\",\"position\":3,\"name\":\"Operaci\\u00f3n Zelotes: Lula pide la \\u201csuspensi\\u00f3n\\u201d de su interrogatorio\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#newsarticle\",\"name\":\"Operaci\\u00f3n Zelotes: Lula pide la \\u201csuspensi\\u00f3n\\u201d de su interrogatorio | Cand\\u00e1s 365\",\"headline\":\"Operaci\\u00f3n Zelotes: Lula pide la \\u201csuspensi\\u00f3n\\u201d de su interrogatorio\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Lula.jpg\",\"width\":987,\"height\":654,\"caption\":\"Foto: Paulo Lopes\\\/ZUMA Wire\\\/dpa\"},\"datePublished\":\"2020-02-05T22:37:18+01:00\",\"dateModified\":\"2020-02-05T22:37:18+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el febrero 5, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/\",\"name\":\"Operaci\\u00f3n Zelotes: Lula pide la \\u201csuspensi\\u00f3n\\u201d de su interrogatorio | Cand\\u00e1s 365\",\"description\":\"(Europa Press) - El expresidente de Brasil Lula da Silva ha comunicado este martes a la Justicia Federal de Brasilia que viajar\\u00e1 la pr\\u00f3xima semana a El Vaticano para reunirse con el Papa Francisco y ha pedido que, por lo tanto, se suspenda de momento su interrogatorio en el marco de la 'Operaci\\u00f3n Zelotes', en la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Lula.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#mainImage\",\"width\":987,\"height\":654,\"caption\":\"Foto: Paulo Lopes\\\/ZUMA Wire\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\\\/#mainImage\"},\"datePublished\":\"2020-02-05T22:37:18+01:00\",\"dateModified\":\"2020-02-05T22:37:18+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio | Cand\u00e1s 365","description":"(Europa Press) - El expresidente de Brasil Lula da Silva ha comunicado este martes a la Justicia Federal de Brasilia que viajar\u00e1 la pr\u00f3xima semana a El Vaticano para reunirse con el Papa Francisco y ha pedido que, por lo tanto, se suspenda de momento su interrogatorio en el marco de la 'Operaci\u00f3n Zelotes', en la","canonical_url":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#listItem","name":"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#listItem","position":3,"name":"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#newsarticle","name":"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio | Cand\u00e1s 365","headline":"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula.jpg","width":987,"height":654,"caption":"Foto: Paulo Lopes\/ZUMA Wire\/dpa"},"datePublished":"2020-02-05T22:37:18+01:00","dateModified":"2020-02-05T22:37:18+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el febrero 5, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#webpage","url":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/","name":"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio | Cand\u00e1s 365","description":"(Europa Press) - El expresidente de Brasil Lula da Silva ha comunicado este martes a la Justicia Federal de Brasilia que viajar\u00e1 la pr\u00f3xima semana a El Vaticano para reunirse con el Papa Francisco y ha pedido que, por lo tanto, se suspenda de momento su interrogatorio en el marco de la 'Operaci\u00f3n Zelotes', en la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula.jpg","@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#mainImage","width":987,"height":654,"caption":"Foto: Paulo Lopes\/ZUMA Wire\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/#mainImage"},"datePublished":"2020-02-05T22:37:18+01:00","dateModified":"2020-02-05T22:37:18+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio | Cand\u00e1s 365","og:description":"(Europa Press) - El expresidente de Brasil Lula da Silva ha comunicado este martes a la Justicia Federal de Brasilia que viajar\u00e1 la pr\u00f3xima semana a El Vaticano para reunirse con el Papa Francisco y ha pedido que, por lo tanto, se suspenda de momento su interrogatorio en el marco de la 'Operaci\u00f3n Zelotes', en la","og:url":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula.jpg","og:image:width":987,"og:image:height":654,"article:published_time":"2020-02-05T22:37:18+00:00","article:modified_time":"2020-02-05T22:37:18+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio | Cand\u00e1s 365","twitter:description":"(Europa Press) - El expresidente de Brasil Lula da Silva ha comunicado este martes a la Justicia Federal de Brasilia que viajar\u00e1 la pr\u00f3xima semana a El Vaticano para reunirse con el Papa Francisco y ha pedido que, por lo tanto, se suspenda de momento su interrogatorio en el marco de la 'Operaci\u00f3n Zelotes', en la","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Lula.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"137741","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-30 23:21:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:45:39","updated":"2025-08-30 23:21:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tOperaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Operaci\u00f3n Zelotes: Lula pide la \u201csuspensi\u00f3n\u201d de su interrogatorio","link":"https:\/\/candas365.es\/noticias\/operacion-zelotes-lula-pide-la-suspension-de-su-interrogatorio\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=137741"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/137742"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=137741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=137741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=137741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}