{"id":137733,"date":"2020-02-05T22:23:57","date_gmt":"2020-02-05T22:23:57","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=137733"},"modified":"2020-02-05T22:23:57","modified_gmt":"2020-02-05T22:23:57","slug":"merz-abandona-cargo-en-empresa-para-volver-a-la-politica","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/","title":{"rendered":"Merz abandona cargo en empresa para volver a la pol\u00edtica"},"content":{"rendered":"<p>Berl\u00edn, 5 feb (dpa) &#8211; Friedrich Merz, antiguo diputado y l\u00edder del grupo parlamentario Uni\u00f3n Cristianodem\u00f3crata (CDU), anunci\u00f3 a dpa que dejar\u00e1 su cargo como presidente del consejo de supervisi\u00f3n de la empresa de gesti\u00f3n de inversiones estadounidense Blackrock a finales de marzo.<\/p>\n<p>\u00abHe decidido poner fin a mi cargo de presidente del consejo de supervisi\u00f3n de Blackrock en Alemania al final del primer trimestre. Fue un placer y un gran honor para m\u00ed acompa\u00f1ar a la compa\u00f1\u00eda en Alemania durante los \u00faltimos cuatro a\u00f1os\u00bb, declar\u00f3 Merz.<\/p>\n<p>El empresario coment\u00f3 que le gustar\u00eda \u00abutilizar su tiempo ahora para apoyar a la Uni\u00f3n Cristianodem\u00f3crata (CDU) con mayor fuerza en su renovaci\u00f3n y seguir desempe\u00f1ando un papel pol\u00edtico\u00bb.<\/p>\n<p>En su opini\u00f3n, Alemania y Europa se enfrentan a grandes retos a principios de la nueva d\u00e9cada. \u00abMe gustar\u00eda contribuir a asegurar que nuestro pa\u00eds siga teniendo \u00e9xito y est\u00e9 preparado para el futuro\u00bb, dijo Merz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 5 feb (dpa) &#8211; Friedrich Merz, antiguo diputado y l\u00edder del grupo parlamentario Uni\u00f3n Cristianodem\u00f3crata (CDU), anunci\u00f3 a dpa que dejar\u00e1 su cargo como presidente del consejo de supervisi\u00f3n de la empresa de gesti\u00f3n de inversiones estadounidense Blackrock a finales de marzo. \u00abHe decidido poner fin a mi cargo de presidente del consejo de<\/p>\n","protected":false},"author":1,"featured_media":85069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":{"0":"post-137733","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 5 feb (dpa) - Friedrich Merz, antiguo diputado y l\u00edder del grupo parlamentario Uni\u00f3n Cristianodem\u00f3crata (CDU), anunci\u00f3 a dpa que dejar\u00e1 su cargo como presidente del consejo de supervisi\u00f3n de la empresa de gesti\u00f3n de inversiones estadounidense Blackrock a finales de marzo. &quot;He decidido poner fin a mi cargo de presidente del consejo de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Merz abandona cargo en empresa para volver a la pol\u00edtica | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 5 feb (dpa) - Friedrich Merz, antiguo diputado y l\u00edder del grupo parlamentario Uni\u00f3n Cristianodem\u00f3crata (CDU), anunci\u00f3 a dpa que dejar\u00e1 su cargo como presidente del consejo de supervisi\u00f3n de la empresa de gesti\u00f3n de inversiones estadounidense Blackrock a finales de marzo. &quot;He decidido poner fin a mi cargo de presidente del consejo de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-05T22:23:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-02-05T22:23:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Merz abandona cargo en empresa para volver a la pol\u00edtica | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 5 feb (dpa) - Friedrich Merz, antiguo diputado y l\u00edder del grupo parlamentario Uni\u00f3n Cristianodem\u00f3crata (CDU), anunci\u00f3 a dpa que dejar\u00e1 su cargo como presidente del consejo de supervisi\u00f3n de la empresa de gesti\u00f3n de inversiones estadounidense Blackrock a finales de marzo. &quot;He decidido poner fin a mi cargo de presidente del consejo de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#listItem\",\"name\":\"Merz abandona cargo en empresa para volver a la pol\\u00edtica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#listItem\",\"position\":3,\"name\":\"Merz abandona cargo en empresa para volver a la pol\\u00edtica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#newsarticle\",\"name\":\"Merz abandona cargo en empresa para volver a la pol\\u00edtica | Cand\\u00e1s 365\",\"headline\":\"Merz abandona cargo en empresa para volver a la pol\\u00edtica\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"datePublished\":\"2020-02-05T22:23:57+01:00\",\"dateModified\":\"2020-02-05T22:23:57+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el febrero 5, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/\",\"name\":\"Merz abandona cargo en empresa para volver a la pol\\u00edtica | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 5 feb (dpa) - Friedrich Merz, antiguo diputado y l\\u00edder del grupo parlamentario Uni\\u00f3n Cristianodem\\u00f3crata (CDU), anunci\\u00f3 a dpa que dejar\\u00e1 su cargo como presidente del consejo de supervisi\\u00f3n de la empresa de gesti\\u00f3n de inversiones estadounidense Blackrock a finales de marzo. \\\"He decidido poner fin a mi cargo de presidente del consejo de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#mainImage\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\\\/#mainImage\"},\"datePublished\":\"2020-02-05T22:23:57+01:00\",\"dateModified\":\"2020-02-05T22:23:57+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Merz abandona cargo en empresa para volver a la pol\u00edtica | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Merz abandona cargo en empresa para volver a la pol\u00edtica | Cand\u00e1s 365","description":"Berl\u00edn, 5 feb (dpa) - Friedrich Merz, antiguo diputado y l\u00edder del grupo parlamentario Uni\u00f3n Cristianodem\u00f3crata (CDU), anunci\u00f3 a dpa que dejar\u00e1 su cargo como presidente del consejo de supervisi\u00f3n de la empresa de gesti\u00f3n de inversiones estadounidense Blackrock a finales de marzo. \"He decidido poner fin a mi cargo de presidente del consejo de","canonical_url":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#listItem","name":"Merz abandona cargo en empresa para volver a la pol\u00edtica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#listItem","position":3,"name":"Merz abandona cargo en empresa para volver a la pol\u00edtica","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#newsarticle","name":"Merz abandona cargo en empresa para volver a la pol\u00edtica | Cand\u00e1s 365","headline":"Merz abandona cargo en empresa para volver a la pol\u00edtica","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","width":960,"height":640,"caption":"bundestag"},"datePublished":"2020-02-05T22:23:57+01:00","dateModified":"2020-02-05T22:23:57+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el febrero 5, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#webpage","url":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/","name":"Merz abandona cargo en empresa para volver a la pol\u00edtica | Cand\u00e1s 365","description":"Berl\u00edn, 5 feb (dpa) - Friedrich Merz, antiguo diputado y l\u00edder del grupo parlamentario Uni\u00f3n Cristianodem\u00f3crata (CDU), anunci\u00f3 a dpa que dejar\u00e1 su cargo como presidente del consejo de supervisi\u00f3n de la empresa de gesti\u00f3n de inversiones estadounidense Blackrock a finales de marzo. \"He decidido poner fin a mi cargo de presidente del consejo de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#mainImage","width":960,"height":640,"caption":"bundestag"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/#mainImage"},"datePublished":"2020-02-05T22:23:57+01:00","dateModified":"2020-02-05T22:23:57+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Merz abandona cargo en empresa para volver a la pol\u00edtica | Cand\u00e1s 365","og:description":"Berl\u00edn, 5 feb (dpa) - Friedrich Merz, antiguo diputado y l\u00edder del grupo parlamentario Uni\u00f3n Cristianodem\u00f3crata (CDU), anunci\u00f3 a dpa que dejar\u00e1 su cargo como presidente del consejo de supervisi\u00f3n de la empresa de gesti\u00f3n de inversiones estadounidense Blackrock a finales de marzo. &quot;He decidido poner fin a mi cargo de presidente del consejo de","og:url":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2020-02-05T22:23:57+00:00","article:modified_time":"2020-02-05T22:23:57+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Merz abandona cargo en empresa para volver a la pol\u00edtica | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 5 feb (dpa) - Friedrich Merz, antiguo diputado y l\u00edder del grupo parlamentario Uni\u00f3n Cristianodem\u00f3crata (CDU), anunci\u00f3 a dpa que dejar\u00e1 su cargo como presidente del consejo de supervisi\u00f3n de la empresa de gesti\u00f3n de inversiones estadounidense Blackrock a finales de marzo. &quot;He decidido poner fin a mi cargo de presidente del consejo de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"137733","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-30 23:21:11","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:45:39","updated":"2025-08-30 23:21:11"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMerz abandona cargo en empresa para volver a la pol\u00edtica\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Merz abandona cargo en empresa para volver a la pol\u00edtica","link":"https:\/\/candas365.es\/noticias\/merz-abandona-cargo-en-empresa-para-volver-a-la-politica\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=137733"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/85069"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=137733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=137733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=137733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}