{"id":137689,"date":"2020-02-05T19:10:32","date_gmt":"2020-02-05T19:10:32","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=137689"},"modified":"2020-02-05T19:10:32","modified_gmt":"2020-02-05T19:10:32","slug":"el-dortmund-es-feliz-con-erling-haaland","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/","title":{"rendered":"El Dortmund es \u201cfeliz\u201d con Erling Haaland"},"content":{"rendered":"<p>Dortmund, 5 feb (dpa) &#8211; El fichaje del delantero noruego Erling Haaland fue uno de los \u00abm\u00e1s dif\u00edciles\u00bb de la carrera del director deportivo del Borussia Dortmund, Michael Zorc, seg\u00fan explic\u00f3 en un entrevista publicada hoy por \u00abSport Bild\u00bb.<\/p>\n<p>\u00abAlcanzamos un nivel muy alto con Erling y no es ning\u00fan secreto que otros clubes de renombre hicieron grandes esfuerzos para ficharlo\u00bb, dijo el directivo del Dortmund.<\/p>\n<figure id=\"attachment_137690\" aria-describedby=\"caption-attachment-137690\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-137690\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa-360x220.jpg\" alt=\"\" width=\"360\" height=\"220\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa-360x220.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa-655x401.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa-768x470.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa-696x426.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa-686x420.jpg 686w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa.jpg 1028w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-137690\" class=\"wp-caption-text\">Foto: David Hecker\/dpa<\/figcaption><\/figure>\n<p>Zorc dijo que el d\u00eda de Nochebuena estuvo negociando por tel\u00e9fono con el asesor de Haaland, Mino Raiola, hasta las cuatro de la tarde. \u00abCuando conseguimos el s\u00ed de un jugador de su categor\u00eda, me puse tan contento como un ni\u00f1o peque\u00f1o\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>El Dortmund fich\u00f3 a Haaland por 20 millones de euros (22 milones de d\u00f3lares) procedente del Salzburgo austriaco en el mercado de invierno. El equipo alem\u00e1n super\u00f3 las ofertas del Leipzig, la Juventus de Tur\u00edn y el Manchester United debido a que su oferta al noruego de 19 a\u00f1os era m\u00e1s favorable para su carrera posterior.<\/p>\n<p>A Haaland tambi\u00e9n le convenci\u00f3 un v\u00eddeo con im\u00e1genes emotivas de la tribuna Sur del estadio del Dortmund. \u00abEs cierto que se lo enviamos. Creo que le gust\u00f3 mucho\u00bb, prosigui\u00f3 Zorc.<\/p>\n<p>Seg\u00fan el director deportivo del Dortmund, el ambiente en el Signal Iduna Park le inspira: \u00abExplota literalmente en el c\u00e9sped. Su lenguaje corporal es impresionante para un chico de 19 a\u00f1os\u00bb.<\/p>\n<p>Hasta ahora, el rendimiento de Haaland es impresionate, tras marcar ocho goles en cuatro partidos.<\/p>\n<p>\u00abLa combinaci\u00f3n de robustez, calidad resolutiva, buena t\u00e9cnica y velocidad hace a Erling especial. Erling y el Dortmund encajan al cien por cien\u00bb, reconoci\u00f3 Zorc, para quien Haaland es el tipo exacto de jugador que le faltaba al equipo.<\/p>\n<p>Sin embargo, Zorc afirm\u00f3 que quiere asegurarse de que \u00ablas expectativas no se descontrolen, y que Erling explote solo en el campo, no en las revistas ni ante las c\u00e1maras de televisi\u00f3n\u00bb.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dortmund, 5 feb (dpa) &#8211; El fichaje del delantero noruego Erling Haaland fue uno de los \u00abm\u00e1s dif\u00edciles\u00bb de la carrera del director deportivo del Borussia Dortmund, Michael Zorc, seg\u00fan explic\u00f3 en un entrevista publicada hoy por \u00abSport Bild\u00bb. \u00abAlcanzamos un nivel muy alto con Erling y no es ning\u00fan secreto que otros clubes de<\/p>\n","protected":false},"author":1,"featured_media":137690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":{"0":"post-137689","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Dortmund, 5 feb (dpa) - El fichaje del delantero noruego Erling Haaland fue uno de los &quot;m\u00e1s dif\u00edciles&quot; de la carrera del director deportivo del Borussia Dortmund, Michael Zorc, seg\u00fan explic\u00f3 en un entrevista publicada hoy por &quot;Sport Bild&quot;. &quot;Alcanzamos un nivel muy alto con Erling y no es ning\u00fan secreto que otros clubes de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Dortmund es \u201cfeliz\u201d con Erling Haaland | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Dortmund, 5 feb (dpa) - El fichaje del delantero noruego Erling Haaland fue uno de los &quot;m\u00e1s dif\u00edciles&quot; de la carrera del director deportivo del Borussia Dortmund, Michael Zorc, seg\u00fan explic\u00f3 en un entrevista publicada hoy por &quot;Sport Bild&quot;. &quot;Alcanzamos un nivel muy alto con Erling y no es ning\u00fan secreto que otros clubes de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1028\" \/>\n\t\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-05T19:10:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-02-05T19:10:32+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Dortmund es \u201cfeliz\u201d con Erling Haaland | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Dortmund, 5 feb (dpa) - El fichaje del delantero noruego Erling Haaland fue uno de los &quot;m\u00e1s dif\u00edciles&quot; de la carrera del director deportivo del Borussia Dortmund, Michael Zorc, seg\u00fan explic\u00f3 en un entrevista publicada hoy por &quot;Sport Bild&quot;. &quot;Alcanzamos un nivel muy alto con Erling y no es ning\u00fan secreto que otros clubes de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"position\":2,\"name\":\"Deporte\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#listItem\",\"name\":\"El Dortmund es \\u201cfeliz\\u201d con Erling Haaland\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#listItem\",\"position\":3,\"name\":\"El Dortmund es \\u201cfeliz\\u201d con Erling Haaland\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/deporte\\\/#listItem\",\"name\":\"Deporte\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#newsarticle\",\"name\":\"El Dortmund es \\u201cfeliz\\u201d con Erling Haaland | Cand\\u00e1s 365\",\"headline\":\"El Dortmund es \\u201cfeliz\\u201d con Erling Haaland\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Erling-Haaland-dpa.jpg\",\"width\":1028,\"height\":629,\"caption\":\"Foto: David Hecker\\\/dpa\"},\"datePublished\":\"2020-02-05T19:10:32+01:00\",\"dateModified\":\"2020-02-05T19:10:32+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#webpage\"},\"articleSection\":\"Deporte\",\"dateline\":\"Publicado el febrero 5, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/\",\"name\":\"El Dortmund es \\u201cfeliz\\u201d con Erling Haaland | Cand\\u00e1s 365\",\"description\":\"Dortmund, 5 feb (dpa) - El fichaje del delantero noruego Erling Haaland fue uno de los \\\"m\\u00e1s dif\\u00edciles\\\" de la carrera del director deportivo del Borussia Dortmund, Michael Zorc, seg\\u00fan explic\\u00f3 en un entrevista publicada hoy por \\\"Sport Bild\\\". \\\"Alcanzamos un nivel muy alto con Erling y no es ning\\u00fan secreto que otros clubes de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Erling-Haaland-dpa.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#mainImage\",\"width\":1028,\"height\":629,\"caption\":\"Foto: David Hecker\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-dortmund-es-feliz-con-erling-haaland\\\/#mainImage\"},\"datePublished\":\"2020-02-05T19:10:32+01:00\",\"dateModified\":\"2020-02-05T19:10:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Dortmund es \u201cfeliz\u201d con Erling Haaland | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El Dortmund es \u201cfeliz\u201d con Erling Haaland | Cand\u00e1s 365","description":"Dortmund, 5 feb (dpa) - El fichaje del delantero noruego Erling Haaland fue uno de los \"m\u00e1s dif\u00edciles\" de la carrera del director deportivo del Borussia Dortmund, Michael Zorc, seg\u00fan explic\u00f3 en un entrevista publicada hoy por \"Sport Bild\". \"Alcanzamos un nivel muy alto con Erling y no es ning\u00fan secreto que otros clubes de","canonical_url":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/","robots":"max-image-preview:large","keywords":"deporte","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","position":2,"name":"Deporte","item":"https:\/\/candas365.es\/noticias\/category\/deporte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#listItem","name":"El Dortmund es \u201cfeliz\u201d con Erling Haaland"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#listItem","position":3,"name":"El Dortmund es \u201cfeliz\u201d con Erling Haaland","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/deporte\/#listItem","name":"Deporte"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#newsarticle","name":"El Dortmund es \u201cfeliz\u201d con Erling Haaland | Cand\u00e1s 365","headline":"El Dortmund es \u201cfeliz\u201d con Erling Haaland","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa.jpg","width":1028,"height":629,"caption":"Foto: David Hecker\/dpa"},"datePublished":"2020-02-05T19:10:32+01:00","dateModified":"2020-02-05T19:10:32+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#webpage"},"articleSection":"Deporte","dateline":"Publicado el febrero 5, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/","name":"El Dortmund es \u201cfeliz\u201d con Erling Haaland | Cand\u00e1s 365","description":"Dortmund, 5 feb (dpa) - El fichaje del delantero noruego Erling Haaland fue uno de los \"m\u00e1s dif\u00edciles\" de la carrera del director deportivo del Borussia Dortmund, Michael Zorc, seg\u00fan explic\u00f3 en un entrevista publicada hoy por \"Sport Bild\". \"Alcanzamos un nivel muy alto con Erling y no es ning\u00fan secreto que otros clubes de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa.jpg","@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#mainImage","width":1028,"height":629,"caption":"Foto: David Hecker\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/#mainImage"},"datePublished":"2020-02-05T19:10:32+01:00","dateModified":"2020-02-05T19:10:32+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El Dortmund es \u201cfeliz\u201d con Erling Haaland | Cand\u00e1s 365","og:description":"Dortmund, 5 feb (dpa) - El fichaje del delantero noruego Erling Haaland fue uno de los &quot;m\u00e1s dif\u00edciles&quot; de la carrera del director deportivo del Borussia Dortmund, Michael Zorc, seg\u00fan explic\u00f3 en un entrevista publicada hoy por &quot;Sport Bild&quot;. &quot;Alcanzamos un nivel muy alto con Erling y no es ning\u00fan secreto que otros clubes de","og:url":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa.jpg","og:image:width":1028,"og:image:height":629,"article:published_time":"2020-02-05T19:10:32+00:00","article:modified_time":"2020-02-05T19:10:32+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El Dortmund es \u201cfeliz\u201d con Erling Haaland | Cand\u00e1s 365","twitter:description":"Dortmund, 5 feb (dpa) - El fichaje del delantero noruego Erling Haaland fue uno de los &quot;m\u00e1s dif\u00edciles&quot; de la carrera del director deportivo del Borussia Dortmund, Michael Zorc, seg\u00fan explic\u00f3 en un entrevista publicada hoy por &quot;Sport Bild&quot;. &quot;Alcanzamos un nivel muy alto con Erling y no es ning\u00fan secreto que otros clubes de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Erling-Haaland-dpa.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"137689","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-30 23:17:09","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:45:50","updated":"2025-08-30 23:17:09"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/deporte\/\" title=\"Deporte\">Deporte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl Dortmund es \u201cfeliz\u201d con Erling Haaland\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Deporte","link":"https:\/\/candas365.es\/noticias\/category\/deporte\/"},{"label":"El Dortmund es \u201cfeliz\u201d con Erling Haaland","link":"https:\/\/candas365.es\/noticias\/el-dortmund-es-feliz-con-erling-haaland\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=137689"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/137690"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=137689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=137689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=137689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}