{"id":137679,"date":"2020-02-05T16:30:30","date_gmt":"2020-02-05T16:30:30","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=137679"},"modified":"2020-02-05T16:30:30","modified_gmt":"2020-02-05T16:30:30","slug":"cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/","title":{"rendered":"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-137680\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa-655x436.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa.jpg 995w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>(dpa) &#8211; El llamado \u00abcibergrooming\u00bb es una pesadilla para muchos padres: se trata de personas adultas desconocidos que a trav\u00e9s de Internet intentan ganarse la confianza de los menores, a menudo con la intenci\u00f3n de abusar sexualmente de ellos.<\/p>\n<p><strong>\u00abEl tema no debe ser silenciado, al contrario. Siempre aconsejamos a los padres que hablen abiertamente de este tema con sus hijos\u00bb<\/strong>, se\u00f1ala Kristin Langer, de la iniciativa alemana \u00abSchau hin! (\u00a1Mira!).<\/p>\n<p>Langer y sus colegas orientan a padres con hijos de entre tres y 13 a\u00f1os en el manejo de los medios de comunicaci\u00f3n modernos.<\/p>\n<p><strong>El cibergrooming puede afectar a ni\u00f1as y ni\u00f1os por igual<\/strong>, asegura la especialista.<\/p>\n<p>En teor\u00eda, los menores est\u00e1n en riesgo desde el momento en que est\u00e1n en la red de forma independiente y privada, por ejemplo, cuando usan su primer smartphone.<\/p>\n<p>La puerta de entrada para un \u00abgroomer\u00bb (el adulto que se hace pasar por un menor con un objetivo sexual) suele ser el chat, ya sea en aplicaciones, en foros o en cualquier otro lugar, por ejemplo en los videojuegos.<\/p>\n<p>Langer hace hincapi\u00e9 en que hay que informar claramente a los hijos sobre el peligro de un acoso a trav\u00e9s de la red. El ni\u00f1o debe saber que en Internet hay gente que no quiere nada bueno para \u00e9l o para la familia, agrega.<\/p>\n<p><strong>Es bueno que los menores tambi\u00e9n sepan c\u00f3mo funciona exactamente el cibergrooming<\/strong>. Por ejemplo, que los abusadores a menudo se hacen pasar ni\u00f1os y adolescentes de la misma edad, muchas veces como agentes de casting o de modelos.<\/p>\n<p><strong>Por lo general los groomers se expresan de manera muy optimista<\/strong>, con muchas promesas y elogios exagerados.<\/p>\n<p>La asesora aconseja que los padres deben advertir a su hijos no dar informaci\u00f3n sobre s\u00ed mismos y evitar mencionar el lugar donde viven, su edad y n\u00famero de tel\u00e9fono m\u00f3vil.<\/p>\n<p><strong>\u00abPara los ni\u00f1os muchas veces es una sensaci\u00f3n estupenda tener su propio celular y poder dar su n\u00famero\u00bb<\/strong>, se\u00f1ala Langer y recalca que los padres deben esclarecer a los hijos en ese sentido.<\/p>\n<p>Para ello, seg\u00fan la especialista, los ni\u00f1os necesitan un confidente al que puedan acudir en caso de tener alguna pregunta o inquietud. Especialmente cuando la relaci\u00f3n con los padres es algo tensa durante la pubertad.<\/p>\n<p>\u00abEn ese caso tal vez pueda ayudar un padrino o madrina, o un amigo de la misma edad\u00bb, apunta.<\/p>\n<p>Los amigos deben estar siempre presentes al momento de tomar contacto online con un desconocido. <strong>Tambi\u00e9n los adultos deben estar informados<\/strong>. No importa si se trata de un encuentro en persona o trav\u00e9s de la webcam, que a menudo parece una forma de comunicaci\u00f3n inofensiva.<\/p>\n<p>\u00abLos ni\u00f1os a\u00fan no son capaces de evaluar las consecuencias e implicancias del uso de tales tecnolog\u00edas. Son ni\u00f1os y no tienen por qu\u00e9 saberlas. Pero ah\u00ed es donde tienen que estar presentes los padres\u00bb, enfatiza Langer.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; El llamado \u00abcibergrooming\u00bb es una pesadilla para muchos padres: se trata de personas adultas desconocidos que a trav\u00e9s de Internet intentan ganarse la confianza de los menores, a menudo con la intenci\u00f3n de abusar sexualmente de ellos. \u00abEl tema no debe ser silenciado, al contrario. Siempre aconsejamos a los padres que hablen abiertamente<\/p>\n","protected":false},"author":1,"featured_media":137680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[143],"tags":[],"class_list":{"0":"post-137679","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sociedad"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - El llamado &quot;cibergrooming&quot; es una pesadilla para muchos padres: se trata de personas adultas desconocidos que a trav\u00e9s de Internet intentan ganarse la confianza de los menores, a menudo con la intenci\u00f3n de abusar sexualmente de ellos. &quot;El tema no debe ser silenciado, al contrario. Siempre aconsejamos a los padres que hablen abiertamente\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"sociedad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - El llamado &quot;cibergrooming&quot; es una pesadilla para muchos padres: se trata de personas adultas desconocidos que a trav\u00e9s de Internet intentan ganarse la confianza de los menores, a menudo con la intenci\u00f3n de abusar sexualmente de ellos. &quot;El tema no debe ser silenciado, al contrario. Siempre aconsejamos a los padres que hablen abiertamente\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"995\" \/>\n\t\t<meta property=\"og:image:height\" content=\"663\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-05T16:30:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-02-05T16:30:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - El llamado &quot;cibergrooming&quot; es una pesadilla para muchos padres: se trata de personas adultas desconocidos que a trav\u00e9s de Internet intentan ganarse la confianza de los menores, a menudo con la intenci\u00f3n de abusar sexualmente de ellos. &quot;El tema no debe ser silenciado, al contrario. Siempre aconsejamos a los padres que hablen abiertamente\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"position\":2,\"name\":\"Sociedad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#listItem\",\"name\":\"Cibergrooming: Hay que alertar a los ni\\u00f1os por abusos en Internet\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#listItem\",\"position\":3,\"name\":\"Cibergrooming: Hay que alertar a los ni\\u00f1os por abusos en Internet\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#newsarticle\",\"name\":\"Cibergrooming: Hay que alertar a los ni\\u00f1os por abusos en Internet | Cand\\u00e1s 365\",\"headline\":\"Cibergrooming: Hay que alertar a los ni\\u00f1os por abusos en Internet\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Cibergrooming-dpa.jpg\",\"width\":995,\"height\":663},\"datePublished\":\"2020-02-05T16:30:30+01:00\",\"dateModified\":\"2020-02-05T16:30:30+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#webpage\"},\"articleSection\":\"Sociedad\",\"dateline\":\"Publicado el febrero 5, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/\",\"name\":\"Cibergrooming: Hay que alertar a los ni\\u00f1os por abusos en Internet | Cand\\u00e1s 365\",\"description\":\"(dpa) - El llamado \\\"cibergrooming\\\" es una pesadilla para muchos padres: se trata de personas adultas desconocidos que a trav\\u00e9s de Internet intentan ganarse la confianza de los menores, a menudo con la intenci\\u00f3n de abusar sexualmente de ellos. \\\"El tema no debe ser silenciado, al contrario. Siempre aconsejamos a los padres que hablen abiertamente\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Cibergrooming-dpa.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#mainImage\",\"width\":995,\"height\":663},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\\\/#mainImage\"},\"datePublished\":\"2020-02-05T16:30:30+01:00\",\"dateModified\":\"2020-02-05T16:30:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet | Cand\u00e1s 365","description":"(dpa) - El llamado \"cibergrooming\" es una pesadilla para muchos padres: se trata de personas adultas desconocidos que a trav\u00e9s de Internet intentan ganarse la confianza de los menores, a menudo con la intenci\u00f3n de abusar sexualmente de ellos. \"El tema no debe ser silenciado, al contrario. Siempre aconsejamos a los padres que hablen abiertamente","canonical_url":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/","robots":"max-image-preview:large","keywords":"sociedad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","position":2,"name":"Sociedad","item":"https:\/\/candas365.es\/noticias\/category\/sociedad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#listItem","name":"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#listItem","position":3,"name":"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#newsarticle","name":"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet | Cand\u00e1s 365","headline":"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa.jpg","width":995,"height":663},"datePublished":"2020-02-05T16:30:30+01:00","dateModified":"2020-02-05T16:30:30+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#webpage"},"articleSection":"Sociedad","dateline":"Publicado el febrero 5, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#webpage","url":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/","name":"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet | Cand\u00e1s 365","description":"(dpa) - El llamado \"cibergrooming\" es una pesadilla para muchos padres: se trata de personas adultas desconocidos que a trav\u00e9s de Internet intentan ganarse la confianza de los menores, a menudo con la intenci\u00f3n de abusar sexualmente de ellos. \"El tema no debe ser silenciado, al contrario. Siempre aconsejamos a los padres que hablen abiertamente","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa.jpg","@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#mainImage","width":995,"height":663},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/#mainImage"},"datePublished":"2020-02-05T16:30:30+01:00","dateModified":"2020-02-05T16:30:30+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet | Cand\u00e1s 365","og:description":"(dpa) - El llamado &quot;cibergrooming&quot; es una pesadilla para muchos padres: se trata de personas adultas desconocidos que a trav\u00e9s de Internet intentan ganarse la confianza de los menores, a menudo con la intenci\u00f3n de abusar sexualmente de ellos. &quot;El tema no debe ser silenciado, al contrario. Siempre aconsejamos a los padres que hablen abiertamente","og:url":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa.jpg","og:image:width":995,"og:image:height":663,"article:published_time":"2020-02-05T16:30:30+00:00","article:modified_time":"2020-02-05T16:30:30+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet | Cand\u00e1s 365","twitter:description":"(dpa) - El llamado &quot;cibergrooming&quot; es una pesadilla para muchos padres: se trata de personas adultas desconocidos que a trav\u00e9s de Internet intentan ganarse la confianza de los menores, a menudo con la intenci\u00f3n de abusar sexualmente de ellos. &quot;El tema no debe ser silenciado, al contrario. Siempre aconsejamos a los padres que hablen abiertamente","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/02\/Cibergrooming-dpa.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"137679","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-30 23:15:22","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:45:50","updated":"2025-08-30 23:15:22"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/sociedad\/\" title=\"Sociedad\">Sociedad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tCibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Sociedad","link":"https:\/\/candas365.es\/noticias\/category\/sociedad\/"},{"label":"Cibergrooming: Hay que alertar a los ni\u00f1os por abusos en Internet","link":"https:\/\/candas365.es\/noticias\/cibergrooming-hay-que-alertar-a-los-ninos-por-abusos-en-internet\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=137679"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/137680"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=137679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=137679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=137679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}