{"id":137527,"date":"2020-02-02T16:30:11","date_gmt":"2020-02-02T16:30:11","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=137527"},"modified":"2020-02-02T16:30:11","modified_gmt":"2020-02-02T16:30:11","slug":"cdu-y-spd-crecen-en-intencion-de-voto-en-alemania","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/","title":{"rendered":"CDU y SPD crecen en intenci\u00f3n de voto en Alemania"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-85069\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720-84x55.jpg 84w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 2 feb (dpa) &#8211; La coalici\u00f3n de Gobierno integrada por los democristianos de la canciller alemana Angela Merkel (CDU) y sus aliados b\u00e1varos, la Uni\u00f3n Social Cristiana (CSU), y el Partido Socialdem\u00f3crata (SPD) crecen en intenci\u00f3n de voto en un punto, seg\u00fan un sondeo publicado hoy por el peri\u00f3dico dominical \u00abBild am Sonntag\u00bb.<\/p>\n<p>La CDU\/CSU sigue siendo el partido m\u00e1s fuerte, con un 27 por ciento, indica la encuesta realizada por el instituto demosc\u00f3pico Kantar (antes Emnid). El SPD alcanza un 15 por ciento, mientras que los Verdes se mantienen en el 21 por ciento.<\/p>\n<p>Seg\u00fan la consulta, el partido ultraderechista Alternativa para Alemania (AfD) se sit\u00faa en el 14 por ciento, mientras que el partido La Izquierda y el partido Liberal (FDP), alcanzan el 9 y 8 por ciento, respectivamente. Cada uno de estos partidos perdi\u00f3 un punto porcentual.<\/p>\n<p>El mandato de la actual gran coalici\u00f3n de conservadores y socialdem\u00f3cratas al mando de Merkel expira en 2021. La canciller, que encabeza su cuarto gobierno consecutivo, comunic\u00f3 que abandonar\u00e1 la pol\u00edtica al t\u00e9rmino de la Legislatura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 2 feb (dpa) &#8211; La coalici\u00f3n de Gobierno integrada por los democristianos de la canciller alemana Angela Merkel (CDU) y sus aliados b\u00e1varos, la Uni\u00f3n Social Cristiana (CSU), y el Partido Socialdem\u00f3crata (SPD) crecen en intenci\u00f3n de voto en un punto, seg\u00fan un sondeo publicado hoy por el peri\u00f3dico dominical \u00abBild am Sonntag\u00bb. La<\/p>\n","protected":false},"author":1,"featured_media":85069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-137527","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 2 feb (dpa) - La coalici\u00f3n de Gobierno integrada por los democristianos de la canciller alemana Angela Merkel (CDU) y sus aliados b\u00e1varos, la Uni\u00f3n Social Cristiana (CSU), y el Partido Socialdem\u00f3crata (SPD) crecen en intenci\u00f3n de voto en un punto, seg\u00fan un sondeo publicado hoy por el peri\u00f3dico dominical &quot;Bild am Sonntag&quot;. La\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CDU y SPD crecen en intenci\u00f3n de voto en Alemania | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 2 feb (dpa) - La coalici\u00f3n de Gobierno integrada por los democristianos de la canciller alemana Angela Merkel (CDU) y sus aliados b\u00e1varos, la Uni\u00f3n Social Cristiana (CSU), y el Partido Socialdem\u00f3crata (SPD) crecen en intenci\u00f3n de voto en un punto, seg\u00fan un sondeo publicado hoy por el peri\u00f3dico dominical &quot;Bild am Sonntag&quot;. La\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-02T16:30:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-02-02T16:30:11+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CDU y SPD crecen en intenci\u00f3n de voto en Alemania | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 2 feb (dpa) - La coalici\u00f3n de Gobierno integrada por los democristianos de la canciller alemana Angela Merkel (CDU) y sus aliados b\u00e1varos, la Uni\u00f3n Social Cristiana (CSU), y el Partido Socialdem\u00f3crata (SPD) crecen en intenci\u00f3n de voto en un punto, seg\u00fan un sondeo publicado hoy por el peri\u00f3dico dominical &quot;Bild am Sonntag&quot;. La\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#listItem\",\"name\":\"CDU y SPD crecen en intenci\\u00f3n de voto en Alemania\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#listItem\",\"position\":3,\"name\":\"CDU y SPD crecen en intenci\\u00f3n de voto en Alemania\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#newsarticle\",\"name\":\"CDU y SPD crecen en intenci\\u00f3n de voto en Alemania | Cand\\u00e1s 365\",\"headline\":\"CDU y SPD crecen en intenci\\u00f3n de voto en Alemania\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"datePublished\":\"2020-02-02T16:30:11+01:00\",\"dateModified\":\"2020-02-02T16:30:11+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el febrero 2, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/\",\"name\":\"CDU y SPD crecen en intenci\\u00f3n de voto en Alemania | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 2 feb (dpa) - La coalici\\u00f3n de Gobierno integrada por los democristianos de la canciller alemana Angela Merkel (CDU) y sus aliados b\\u00e1varos, la Uni\\u00f3n Social Cristiana (CSU), y el Partido Socialdem\\u00f3crata (SPD) crecen en intenci\\u00f3n de voto en un punto, seg\\u00fan un sondeo publicado hoy por el peri\\u00f3dico dominical \\\"Bild am Sonntag\\\". La\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/bundestag-2463231_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#mainImage\",\"width\":960,\"height\":640,\"caption\":\"bundestag\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\\\/#mainImage\"},\"datePublished\":\"2020-02-02T16:30:11+01:00\",\"dateModified\":\"2020-02-02T16:30:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>CDU y SPD crecen en intenci\u00f3n de voto en Alemania | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"CDU y SPD crecen en intenci\u00f3n de voto en Alemania | Cand\u00e1s 365","description":"Berl\u00edn, 2 feb (dpa) - La coalici\u00f3n de Gobierno integrada por los democristianos de la canciller alemana Angela Merkel (CDU) y sus aliados b\u00e1varos, la Uni\u00f3n Social Cristiana (CSU), y el Partido Socialdem\u00f3crata (SPD) crecen en intenci\u00f3n de voto en un punto, seg\u00fan un sondeo publicado hoy por el peri\u00f3dico dominical \"Bild am Sonntag\". La","canonical_url":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#listItem","name":"CDU y SPD crecen en intenci\u00f3n de voto en Alemania"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#listItem","position":3,"name":"CDU y SPD crecen en intenci\u00f3n de voto en Alemania","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#newsarticle","name":"CDU y SPD crecen en intenci\u00f3n de voto en Alemania | Cand\u00e1s 365","headline":"CDU y SPD crecen en intenci\u00f3n de voto en Alemania","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","width":960,"height":640,"caption":"bundestag"},"datePublished":"2020-02-02T16:30:11+01:00","dateModified":"2020-02-02T16:30:11+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el febrero 2, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#webpage","url":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/","name":"CDU y SPD crecen en intenci\u00f3n de voto en Alemania | Cand\u00e1s 365","description":"Berl\u00edn, 2 feb (dpa) - La coalici\u00f3n de Gobierno integrada por los democristianos de la canciller alemana Angela Merkel (CDU) y sus aliados b\u00e1varos, la Uni\u00f3n Social Cristiana (CSU), y el Partido Socialdem\u00f3crata (SPD) crecen en intenci\u00f3n de voto en un punto, seg\u00fan un sondeo publicado hoy por el peri\u00f3dico dominical \"Bild am Sonntag\". La","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#mainImage","width":960,"height":640,"caption":"bundestag"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/#mainImage"},"datePublished":"2020-02-02T16:30:11+01:00","dateModified":"2020-02-02T16:30:11+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"CDU y SPD crecen en intenci\u00f3n de voto en Alemania | Cand\u00e1s 365","og:description":"Berl\u00edn, 2 feb (dpa) - La coalici\u00f3n de Gobierno integrada por los democristianos de la canciller alemana Angela Merkel (CDU) y sus aliados b\u00e1varos, la Uni\u00f3n Social Cristiana (CSU), y el Partido Socialdem\u00f3crata (SPD) crecen en intenci\u00f3n de voto en un punto, seg\u00fan un sondeo publicado hoy por el peri\u00f3dico dominical &quot;Bild am Sonntag&quot;. La","og:url":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2020-02-02T16:30:11+00:00","article:modified_time":"2020-02-02T16:30:11+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"CDU y SPD crecen en intenci\u00f3n de voto en Alemania | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 2 feb (dpa) - La coalici\u00f3n de Gobierno integrada por los democristianos de la canciller alemana Angela Merkel (CDU) y sus aliados b\u00e1varos, la Uni\u00f3n Social Cristiana (CSU), y el Partido Socialdem\u00f3crata (SPD) crecen en intenci\u00f3n de voto en un punto, seg\u00fan un sondeo publicado hoy por el peri\u00f3dico dominical &quot;Bild am Sonntag&quot;. La","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2017\/11\/bundestag-2463231_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"137527","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 19:40:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:45:51","updated":"2026-05-25 19:40:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tCDU y SPD crecen en intenci\u00f3n de voto en Alemania\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"CDU y SPD crecen en intenci\u00f3n de voto en Alemania","link":"https:\/\/candas365.es\/noticias\/cdu-y-spd-crecen-en-intencion-de-voto-en-alemania\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=137527"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/137527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/85069"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=137527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=137527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=137527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}