{"id":136967,"date":"2020-01-24T20:17:10","date_gmt":"2020-01-24T20:17:10","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=136967"},"modified":"2020-01-24T20:17:10","modified_gmt":"2020-01-24T20:17:10","slug":"encuentro-de-ministros-iberoamericanos-en-el-palacio-real","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/","title":{"rendered":"Encuentro de ministros iberoamericanos en el Palacio Real"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-136968\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto.jpg 512w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La ministra de Industria, Comercio y Turismo, <strong>Reyes Maroto<\/strong>, ha se\u00f1alado que <strong>\u00abla colaboraci\u00f3n en materia tur\u00edstica y el incremento de los flujos es esencial para reforzar los lazos culturales, idiom\u00e1ticos y de amistad\u00bb<\/strong> que unen a Espa\u00f1a e Iberoam\u00e9rica.<\/p>\n<p>Reyes Maroto ha presidido un encuentro con ministros de Turismo iberoamericanos en el Palacio Real de Madrid, al que han asistido tambi\u00e9n la secretaria de Estado de Turismo del Ministerio de Industria, Comercio y Turismo, Isabel Oliver; el secretario de Estado de Cooperaci\u00f3n Internacional y para Iberoam\u00e9rica y el Caribe del Ministerio de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, Juan Pablo de Laiglesia; la directora de la Agencia Espa\u00f1ola de Cooperaci\u00f3n Internacional para el Desarrollo (AECID) , Aina Calvo; el secretario general de la Organizaci\u00f3n Mundial del Turismo (OMT), Zurab Pololikasvili, y el presidente de Patrimonio Nacional, Alfredo P\u00e9rez de Armi\u00f1\u00e1n.<\/p>\n<p>Reyes Maroto ha se\u00f1alado que el turismo es un sector que \u00abcrea riqueza, favorece la igualdad, ayuda a combatir la despoblaci\u00f3n, que nos permite estar m\u00e1s y mejor conectados internacionalmente, y que ha demostrado ser un medio eficaz para poder compartir y dar a conocer nuestra cultura y valores en el mundo\u00bb.<\/p>\n<p>Asimismo, ha se\u00f1alado que la Conferencia Iberoamericana de Ministros de Econom\u00eda y Turismo de Guatemala en 2018 fue muy importante para articular pol\u00edticas p\u00fablicas para el desarrollo y la gesti\u00f3n del turismo sostenible: <strong>\u00abIberoam\u00e9rica siempre ha sido una prioridad para Espa\u00f1a: tenemos que caminar juntos en nuestra estrategia tur\u00edstica para promover un modelo de turismo sostenible econ\u00f3mica, social y medioambientalmente\u00bb<\/strong>.<\/p>\n<p>En el encuentro, los responsables de turismo iberoamericanos intercambiaron opiniones sobre el trabajo conjunto que se desarrollar\u00e1 este a\u00f1o en la XXVII Cumbre Iberoamericana de Andorra, bajo el lema &#8216;Innovaci\u00f3n para el desarrollo sostenible-Objetivo 2030&#8217;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ministra de Industria, Comercio y Turismo, Reyes Maroto, ha se\u00f1alado que \u00abla colaboraci\u00f3n en materia tur\u00edstica y el incremento de los flujos es esencial para reforzar los lazos culturales, idiom\u00e1ticos y de amistad\u00bb que unen a Espa\u00f1a e Iberoam\u00e9rica. Reyes Maroto ha presidido un encuentro con ministros de Turismo iberoamericanos en el Palacio Real<\/p>\n","protected":false},"author":1,"featured_media":136968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-136967","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La ministra de Industria, Comercio y Turismo, Reyes Maroto, ha se\u00f1alado que &quot;la colaboraci\u00f3n en materia tur\u00edstica y el incremento de los flujos es esencial para reforzar los lazos culturales, idiom\u00e1ticos y de amistad&quot; que unen a Espa\u00f1a e Iberoam\u00e9rica. Reyes Maroto ha presidido un encuentro con ministros de Turismo iberoamericanos en el Palacio Real\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Encuentro de ministros iberoamericanos en el Palacio Real | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La ministra de Industria, Comercio y Turismo, Reyes Maroto, ha se\u00f1alado que &quot;la colaboraci\u00f3n en materia tur\u00edstica y el incremento de los flujos es esencial para reforzar los lazos culturales, idiom\u00e1ticos y de amistad&quot; que unen a Espa\u00f1a e Iberoam\u00e9rica. Reyes Maroto ha presidido un encuentro con ministros de Turismo iberoamericanos en el Palacio Real\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-24T20:17:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-01-24T20:17:10+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Encuentro de ministros iberoamericanos en el Palacio Real | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La ministra de Industria, Comercio y Turismo, Reyes Maroto, ha se\u00f1alado que &quot;la colaboraci\u00f3n en materia tur\u00edstica y el incremento de los flujos es esencial para reforzar los lazos culturales, idiom\u00e1ticos y de amistad&quot; que unen a Espa\u00f1a e Iberoam\u00e9rica. Reyes Maroto ha presidido un encuentro con ministros de Turismo iberoamericanos en el Palacio Real\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#listItem\",\"name\":\"Encuentro de ministros iberoamericanos en el Palacio Real\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#listItem\",\"position\":3,\"name\":\"Encuentro de ministros iberoamericanos en el Palacio Real\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#newsarticle\",\"name\":\"Encuentro de ministros iberoamericanos en el Palacio Real | Cand\\u00e1s 365\",\"headline\":\"Encuentro de ministros iberoamericanos en el Palacio Real\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/200120-maroto.jpg\",\"width\":512,\"height\":340},\"datePublished\":\"2020-01-24T20:17:10+01:00\",\"dateModified\":\"2020-01-24T20:17:10+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el enero 24, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/\",\"name\":\"Encuentro de ministros iberoamericanos en el Palacio Real | Cand\\u00e1s 365\",\"description\":\"La ministra de Industria, Comercio y Turismo, Reyes Maroto, ha se\\u00f1alado que \\\"la colaboraci\\u00f3n en materia tur\\u00edstica y el incremento de los flujos es esencial para reforzar los lazos culturales, idiom\\u00e1ticos y de amistad\\\" que unen a Espa\\u00f1a e Iberoam\\u00e9rica. Reyes Maroto ha presidido un encuentro con ministros de Turismo iberoamericanos en el Palacio Real\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/200120-maroto.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#mainImage\",\"width\":512,\"height\":340},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\\\/#mainImage\"},\"datePublished\":\"2020-01-24T20:17:10+01:00\",\"dateModified\":\"2020-01-24T20:17:10+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Encuentro de ministros iberoamericanos en el Palacio Real | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Encuentro de ministros iberoamericanos en el Palacio Real | Cand\u00e1s 365","description":"La ministra de Industria, Comercio y Turismo, Reyes Maroto, ha se\u00f1alado que \"la colaboraci\u00f3n en materia tur\u00edstica y el incremento de los flujos es esencial para reforzar los lazos culturales, idiom\u00e1ticos y de amistad\" que unen a Espa\u00f1a e Iberoam\u00e9rica. Reyes Maroto ha presidido un encuentro con ministros de Turismo iberoamericanos en el Palacio Real","canonical_url":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#listItem","name":"Encuentro de ministros iberoamericanos en el Palacio Real"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#listItem","position":3,"name":"Encuentro de ministros iberoamericanos en el Palacio Real","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#newsarticle","name":"Encuentro de ministros iberoamericanos en el Palacio Real | Cand\u00e1s 365","headline":"Encuentro de ministros iberoamericanos en el Palacio Real","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto.jpg","width":512,"height":340},"datePublished":"2020-01-24T20:17:10+01:00","dateModified":"2020-01-24T20:17:10+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el enero 24, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#webpage","url":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/","name":"Encuentro de ministros iberoamericanos en el Palacio Real | Cand\u00e1s 365","description":"La ministra de Industria, Comercio y Turismo, Reyes Maroto, ha se\u00f1alado que \"la colaboraci\u00f3n en materia tur\u00edstica y el incremento de los flujos es esencial para reforzar los lazos culturales, idiom\u00e1ticos y de amistad\" que unen a Espa\u00f1a e Iberoam\u00e9rica. Reyes Maroto ha presidido un encuentro con ministros de Turismo iberoamericanos en el Palacio Real","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto.jpg","@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#mainImage","width":512,"height":340},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/#mainImage"},"datePublished":"2020-01-24T20:17:10+01:00","dateModified":"2020-01-24T20:17:10+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Encuentro de ministros iberoamericanos en el Palacio Real | Cand\u00e1s 365","og:description":"La ministra de Industria, Comercio y Turismo, Reyes Maroto, ha se\u00f1alado que &quot;la colaboraci\u00f3n en materia tur\u00edstica y el incremento de los flujos es esencial para reforzar los lazos culturales, idiom\u00e1ticos y de amistad&quot; que unen a Espa\u00f1a e Iberoam\u00e9rica. Reyes Maroto ha presidido un encuentro con ministros de Turismo iberoamericanos en el Palacio Real","og:url":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto.jpg","og:image:width":512,"og:image:height":340,"article:published_time":"2020-01-24T20:17:10+00:00","article:modified_time":"2020-01-24T20:17:10+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Encuentro de ministros iberoamericanos en el Palacio Real | Cand\u00e1s 365","twitter:description":"La ministra de Industria, Comercio y Turismo, Reyes Maroto, ha se\u00f1alado que &quot;la colaboraci\u00f3n en materia tur\u00edstica y el incremento de los flujos es esencial para reforzar los lazos culturales, idiom\u00e1ticos y de amistad&quot; que unen a Espa\u00f1a e Iberoam\u00e9rica. Reyes Maroto ha presidido un encuentro con ministros de Turismo iberoamericanos en el Palacio Real","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/200120-maroto.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"136967","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 18:08:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:47:42","updated":"2026-05-25 18:08:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEncuentro de ministros iberoamericanos en el Palacio Real\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Encuentro de ministros iberoamericanos en el Palacio Real","link":"https:\/\/candas365.es\/noticias\/encuentro-de-ministros-iberoamericanos-en-el-palacio-real\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=136967"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/136968"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=136967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=136967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=136967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}