{"id":136607,"date":"2020-01-17T20:40:23","date_gmt":"2020-01-17T20:40:23","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=136607"},"modified":"2020-01-17T20:40:23","modified_gmt":"2020-01-17T20:40:23","slug":"merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/","title":{"rendered":"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-96924\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720-360x228.jpg\" alt=\"\" width=\"360\" height=\"228\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720-360x228.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720-768x486.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720-655x414.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720-696x440.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720-664x420.jpg 664w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 17 ene (dpa) &#8211; La canciller alemana, Angela Merkel, viajar\u00e1 a Estambul el 24 de enero para reunirse con el presidente turco, Recep Tayyip Erdogan, comunic\u00f3 hoy su oficina.<\/p>\n<p>Se espera que el conflicto en Libia ocupe una parte importante de la agenda tras la conferencia internacional de paz que tendr\u00e1 lugar en Berl\u00edn este domingo.<\/p>\n<p>Tambi\u00e9n se estima que Merkel y Erdogan hablar\u00e1n sobre el conflicto en Siria, as\u00ed como de la situaci\u00f3n en Irak y de las relaciones con Ir\u00e1n.<\/p>\n<p>Por otra parte, es probable que se traten temas vinculados a la migraci\u00f3n as\u00ed como la propuesta de Turqu\u00eda de abrir escuelas turcas en Alemania.<\/p>\n<p>Durante la visita de Merkel est\u00e1 previsto que la canciller inaugure el nuevo campus de la Universidad Turco-Germana en Estambul junto con Erdogan.<\/p>\n<p>La gobernante alemana tambi\u00e9n se reunir\u00e1 con representantes de la industria por invitaci\u00f3n de la C\u00e1mara de Comercio Germano-Turca as\u00ed como con miembros de la sociedad civil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 17 ene (dpa) &#8211; La canciller alemana, Angela Merkel, viajar\u00e1 a Estambul el 24 de enero para reunirse con el presidente turco, Recep Tayyip Erdogan, comunic\u00f3 hoy su oficina. Se espera que el conflicto en Libia ocupe una parte importante de la agenda tras la conferencia internacional de paz que tendr\u00e1 lugar en Berl\u00edn<\/p>\n","protected":false},"author":1,"featured_media":96924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-136607","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 17 ene (dpa) - La canciller alemana, Angela Merkel, viajar\u00e1 a Estambul el 24 de enero para reunirse con el presidente turco, Recep Tayyip Erdogan, comunic\u00f3 hoy su oficina. Se espera que el conflicto en Libia ocupe una parte importante de la agenda tras la conferencia internacional de paz que tendr\u00e1 lugar en Berl\u00edn\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 17 ene (dpa) - La canciller alemana, Angela Merkel, viajar\u00e1 a Estambul el 24 de enero para reunirse con el presidente turco, Recep Tayyip Erdogan, comunic\u00f3 hoy su oficina. Se espera que el conflicto en Libia ocupe una parte importante de la agenda tras la conferencia internacional de paz que tendr\u00e1 lugar en Berl\u00edn\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-17T20:40:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-01-17T20:40:23+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 17 ene (dpa) - La canciller alemana, Angela Merkel, viajar\u00e1 a Estambul el 24 de enero para reunirse con el presidente turco, Recep Tayyip Erdogan, comunic\u00f3 hoy su oficina. Se espera que el conflicto en Libia ocupe una parte importante de la agenda tras la conferencia internacional de paz que tendr\u00e1 lugar en Berl\u00edn\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#listItem\",\"name\":\"Merkel se reunir\\u00e1 la semana pr\\u00f3xima con Erdogan en Estambul\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#listItem\",\"position\":3,\"name\":\"Merkel se reunir\\u00e1 la semana pr\\u00f3xima con Erdogan en Estambul\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#newsarticle\",\"name\":\"Merkel se reunir\\u00e1 la semana pr\\u00f3xima con Erdogan en Estambul | Cand\\u00e1s 365\",\"headline\":\"Merkel se reunir\\u00e1 la semana pr\\u00f3xima con Erdogan en Estambul\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/berlin-1545303_960_720.jpg\",\"width\":960,\"height\":607},\"datePublished\":\"2020-01-17T20:40:23+01:00\",\"dateModified\":\"2020-01-17T20:40:23+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el enero 17, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/\",\"name\":\"Merkel se reunir\\u00e1 la semana pr\\u00f3xima con Erdogan en Estambul | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 17 ene (dpa) - La canciller alemana, Angela Merkel, viajar\\u00e1 a Estambul el 24 de enero para reunirse con el presidente turco, Recep Tayyip Erdogan, comunic\\u00f3 hoy su oficina. Se espera que el conflicto en Libia ocupe una parte importante de la agenda tras la conferencia internacional de paz que tendr\\u00e1 lugar en Berl\\u00edn\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/berlin-1545303_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#mainImage\",\"width\":960,\"height\":607},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\\\/#mainImage\"},\"datePublished\":\"2020-01-17T20:40:23+01:00\",\"dateModified\":\"2020-01-17T20:40:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul | Cand\u00e1s 365","description":"Berl\u00edn, 17 ene (dpa) - La canciller alemana, Angela Merkel, viajar\u00e1 a Estambul el 24 de enero para reunirse con el presidente turco, Recep Tayyip Erdogan, comunic\u00f3 hoy su oficina. Se espera que el conflicto en Libia ocupe una parte importante de la agenda tras la conferencia internacional de paz que tendr\u00e1 lugar en Berl\u00edn","canonical_url":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#listItem","name":"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#listItem","position":3,"name":"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#newsarticle","name":"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul | Cand\u00e1s 365","headline":"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720.jpg","width":960,"height":607},"datePublished":"2020-01-17T20:40:23+01:00","dateModified":"2020-01-17T20:40:23+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el enero 17, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#webpage","url":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/","name":"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul | Cand\u00e1s 365","description":"Berl\u00edn, 17 ene (dpa) - La canciller alemana, Angela Merkel, viajar\u00e1 a Estambul el 24 de enero para reunirse con el presidente turco, Recep Tayyip Erdogan, comunic\u00f3 hoy su oficina. Se espera que el conflicto en Libia ocupe una parte importante de la agenda tras la conferencia internacional de paz que tendr\u00e1 lugar en Berl\u00edn","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#mainImage","width":960,"height":607},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/#mainImage"},"datePublished":"2020-01-17T20:40:23+01:00","dateModified":"2020-01-17T20:40:23+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul | Cand\u00e1s 365","og:description":"Berl\u00edn, 17 ene (dpa) - La canciller alemana, Angela Merkel, viajar\u00e1 a Estambul el 24 de enero para reunirse con el presidente turco, Recep Tayyip Erdogan, comunic\u00f3 hoy su oficina. Se espera que el conflicto en Libia ocupe una parte importante de la agenda tras la conferencia internacional de paz que tendr\u00e1 lugar en Berl\u00edn","og:url":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720.jpg","og:image:width":960,"og:image:height":607,"article:published_time":"2020-01-17T20:40:23+00:00","article:modified_time":"2020-01-17T20:40:23+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 17 ene (dpa) - La canciller alemana, Angela Merkel, viajar\u00e1 a Estambul el 24 de enero para reunirse con el presidente turco, Recep Tayyip Erdogan, comunic\u00f3 hoy su oficina. Se espera que el conflicto en Libia ocupe una parte importante de la agenda tras la conferencia internacional de paz que tendr\u00e1 lugar en Berl\u00edn","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/berlin-1545303_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"136607","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 17:10:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:47:53","updated":"2026-05-25 17:10:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMerkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Merkel se reunir\u00e1 la semana pr\u00f3xima con Erdogan en Estambul","link":"https:\/\/candas365.es\/noticias\/merkel-se-reunira-la-semana-proxima-con-erdogan-en-estambul\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=136607"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/96924"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=136607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=136607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=136607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}