{"id":136342,"date":"2020-01-14T07:15:53","date_gmt":"2020-01-14T07:15:53","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=136342"},"modified":"2020-01-14T07:15:53","modified_gmt":"2020-01-14T07:15:53","slug":"identificadas-50-victimas-del-avion-derribado-por-iran","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/","title":{"rendered":"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n"},"content":{"rendered":"<figure id=\"attachment_136343\" aria-describedby=\"caption-attachment-136343\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-136343\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa-360x249.jpg\" alt=\"\" width=\"360\" height=\"249\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa-360x249.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa-655x454.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa-768x532.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa-218x150.jpg 218w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa-696x482.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa-606x420.jpg 606w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa-100x70.jpg 100w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa.jpg 983w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-136343\" class=\"wp-caption-text\">Foto: Ukrinform\/dpa<\/figcaption><\/figure>\n<p>(Europa Press) &#8211;\u00a0El jefe de la Organizaci\u00f3n de Medicina Forense de Ir\u00e1n, Ab\u00e1s Masjedi, ha anunciado este lunes que han sido identificadas 50 de las v\u00edctimas del avi\u00f3n ucraniano accidentado tras ser alcanzado por misiles de las Fuerzas Armadas de Ir\u00e1n, suceso que dej\u00f3 176 muertos.<\/p>\n<p>Adem\u00e1s, ha especificado que \u00abhasta el momento, se han recolectado 800 muestras de estos cuerpos y hemos utilizado los m\u00e9todos de muestreo m\u00e1s avanzados\u00bb, seg\u00fan ha recogido la agencia de noticias oficial iraqu\u00ed, NINA.<\/p>\n<p>Masjedi ha insistido en que \u00aba pesar del injusto embargo de Estados Unidos, la identificaci\u00f3n (de los cuerpos) se realiza de manera adecuada\u00bb.<\/p>\n<p>En este contexto, ha precisado que en el trabajo de identificaci\u00f3n de los restos biol\u00f3gicos de los ocupantes de la aeronave trabajan 15 equipos de expertos forenses, adem\u00e1s de contar con el apoyo de la Polic\u00eda Internacional (Interpol).<\/p>\n<p>Por otra parte, ha detallado que la identificaci\u00f3n de todas las v\u00edctimas se completar\u00e1 \u00aben los pr\u00f3ximos cinco d\u00edas\u00bb y se podr\u00e1n entregar los restos a las familias.<\/p>\n<p>Este s\u00e1bado las autoridades de Ir\u00e1n reconocieron su responsabilidad en el accidente del avi\u00f3n de Ukraine International Airlines que cost\u00f3 la vida a todos sus pasajeros.<\/p>\n<p>El mismo presidente iran\u00ed, Has\u00e1n Rohani, fue quien anunci\u00f3 que la aeronave fue derribada \u00abinvoluntariamente\u00bb por el Ej\u00e9rcito debido a un \u00aberror humano\u00bb, al tiempo que matiz\u00f3 que el suceso tuvo lugar \u00aben una atm\u00f3sfera de intimidaci\u00f3n de Estados Unidos contra Ir\u00e1n y en defensa por los posibles ataques militares estadounidenses\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Europa Press) &#8211;\u00a0El jefe de la Organizaci\u00f3n de Medicina Forense de Ir\u00e1n, Ab\u00e1s Masjedi, ha anunciado este lunes que han sido identificadas 50 de las v\u00edctimas del avi\u00f3n ucraniano accidentado tras ser alcanzado por misiles de las Fuerzas Armadas de Ir\u00e1n, suceso que dej\u00f3 176 muertos. Adem\u00e1s, ha especificado que \u00abhasta el momento, se han<\/p>\n","protected":false},"author":1,"featured_media":136343,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-136342","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"(Europa Press) - El jefe de la Organizaci\u00f3n de Medicina Forense de Ir\u00e1n, Ab\u00e1s Masjedi, ha anunciado este lunes que han sido identificadas 50 de las v\u00edctimas del avi\u00f3n ucraniano accidentado tras ser alcanzado por misiles de las Fuerzas Armadas de Ir\u00e1n, suceso que dej\u00f3 176 muertos. Adem\u00e1s, ha especificado que &quot;hasta el momento, se han\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"(Europa Press) - El jefe de la Organizaci\u00f3n de Medicina Forense de Ir\u00e1n, Ab\u00e1s Masjedi, ha anunciado este lunes que han sido identificadas 50 de las v\u00edctimas del avi\u00f3n ucraniano accidentado tras ser alcanzado por misiles de las Fuerzas Armadas de Ir\u00e1n, suceso que dej\u00f3 176 muertos. Adem\u00e1s, ha especificado que &quot;hasta el momento, se han\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"983\" \/>\n\t\t<meta property=\"og:image:height\" content=\"681\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-14T07:15:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-01-14T07:15:53+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(Europa Press) - El jefe de la Organizaci\u00f3n de Medicina Forense de Ir\u00e1n, Ab\u00e1s Masjedi, ha anunciado este lunes que han sido identificadas 50 de las v\u00edctimas del avi\u00f3n ucraniano accidentado tras ser alcanzado por misiles de las Fuerzas Armadas de Ir\u00e1n, suceso que dej\u00f3 176 muertos. Adem\u00e1s, ha especificado que &quot;hasta el momento, se han\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#listItem\",\"name\":\"Identificadas 50 v\\u00edctimas del avi\\u00f3n derribado por Ir\\u00e1n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#listItem\",\"position\":3,\"name\":\"Identificadas 50 v\\u00edctimas del avi\\u00f3n derribado por Ir\\u00e1n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#newsarticle\",\"name\":\"Identificadas 50 v\\u00edctimas del avi\\u00f3n derribado por Ir\\u00e1n | Cand\\u00e1s 365\",\"headline\":\"Identificadas 50 v\\u00edctimas del avi\\u00f3n derribado por Ir\\u00e1n\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/avion-Iran-dpa.jpg\",\"width\":983,\"height\":681,\"caption\":\"Foto: Ukrinform\\\/dpa\"},\"datePublished\":\"2020-01-14T07:15:53+01:00\",\"dateModified\":\"2020-01-14T07:15:53+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el enero 14, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/\",\"name\":\"Identificadas 50 v\\u00edctimas del avi\\u00f3n derribado por Ir\\u00e1n | Cand\\u00e1s 365\",\"description\":\"(Europa Press) - El jefe de la Organizaci\\u00f3n de Medicina Forense de Ir\\u00e1n, Ab\\u00e1s Masjedi, ha anunciado este lunes que han sido identificadas 50 de las v\\u00edctimas del avi\\u00f3n ucraniano accidentado tras ser alcanzado por misiles de las Fuerzas Armadas de Ir\\u00e1n, suceso que dej\\u00f3 176 muertos. Adem\\u00e1s, ha especificado que \\\"hasta el momento, se han\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/avion-Iran-dpa.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#mainImage\",\"width\":983,\"height\":681,\"caption\":\"Foto: Ukrinform\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/identificadas-50-victimas-del-avion-derribado-por-iran\\\/#mainImage\"},\"datePublished\":\"2020-01-14T07:15:53+01:00\",\"dateModified\":\"2020-01-14T07:15:53+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n | Cand\u00e1s 365","description":"(Europa Press) - El jefe de la Organizaci\u00f3n de Medicina Forense de Ir\u00e1n, Ab\u00e1s Masjedi, ha anunciado este lunes que han sido identificadas 50 de las v\u00edctimas del avi\u00f3n ucraniano accidentado tras ser alcanzado por misiles de las Fuerzas Armadas de Ir\u00e1n, suceso que dej\u00f3 176 muertos. Adem\u00e1s, ha especificado que \"hasta el momento, se han","canonical_url":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#listItem","name":"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#listItem","position":3,"name":"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#newsarticle","name":"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n | Cand\u00e1s 365","headline":"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa.jpg","width":983,"height":681,"caption":"Foto: Ukrinform\/dpa"},"datePublished":"2020-01-14T07:15:53+01:00","dateModified":"2020-01-14T07:15:53+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el enero 14, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#webpage","url":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/","name":"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n | Cand\u00e1s 365","description":"(Europa Press) - El jefe de la Organizaci\u00f3n de Medicina Forense de Ir\u00e1n, Ab\u00e1s Masjedi, ha anunciado este lunes que han sido identificadas 50 de las v\u00edctimas del avi\u00f3n ucraniano accidentado tras ser alcanzado por misiles de las Fuerzas Armadas de Ir\u00e1n, suceso que dej\u00f3 176 muertos. Adem\u00e1s, ha especificado que \"hasta el momento, se han","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa.jpg","@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#mainImage","width":983,"height":681,"caption":"Foto: Ukrinform\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/#mainImage"},"datePublished":"2020-01-14T07:15:53+01:00","dateModified":"2020-01-14T07:15:53+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n | Cand\u00e1s 365","og:description":"(Europa Press) - El jefe de la Organizaci\u00f3n de Medicina Forense de Ir\u00e1n, Ab\u00e1s Masjedi, ha anunciado este lunes que han sido identificadas 50 de las v\u00edctimas del avi\u00f3n ucraniano accidentado tras ser alcanzado por misiles de las Fuerzas Armadas de Ir\u00e1n, suceso que dej\u00f3 176 muertos. Adem\u00e1s, ha especificado que &quot;hasta el momento, se han","og:url":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa.jpg","og:image:width":983,"og:image:height":681,"article:published_time":"2020-01-14T07:15:53+00:00","article:modified_time":"2020-01-14T07:15:53+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n | Cand\u00e1s 365","twitter:description":"(Europa Press) - El jefe de la Organizaci\u00f3n de Medicina Forense de Ir\u00e1n, Ab\u00e1s Masjedi, ha anunciado este lunes que han sido identificadas 50 de las v\u00edctimas del avi\u00f3n ucraniano accidentado tras ser alcanzado por misiles de las Fuerzas Armadas de Ir\u00e1n, suceso que dej\u00f3 176 muertos. Adem\u00e1s, ha especificado que &quot;hasta el momento, se han","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/avion-Iran-dpa.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"136342","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 16:26:14","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:48:11","updated":"2026-05-25 16:26:14"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tIdentificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Identificadas 50 v\u00edctimas del avi\u00f3n derribado por Ir\u00e1n","link":"https:\/\/candas365.es\/noticias\/identificadas-50-victimas-del-avion-derribado-por-iran\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=136342"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/136343"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=136342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=136342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=136342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}