{"id":136299,"date":"2020-01-13T15:19:38","date_gmt":"2020-01-13T15:19:38","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=136299"},"modified":"2020-01-13T15:19:38","modified_gmt":"2020-01-13T15:19:38","slug":"pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/","title":{"rendered":"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-136300\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO-360x282.jpg\" alt=\"\" width=\"360\" height=\"282\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO-360x282.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO-612x480.jpg 612w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO-696x546.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO-536x420.jpg 536w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO.jpg 700w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El presidente de Unidas Podemos, Pablo Iglesias, agradeci\u00f3 este lunes la confianza de todos los ciudadanos para formar un Gobierno progresista en el que \u00e9l figurar\u00e1 como vicepresidente de Derechos Sociales.<\/p>\n<p>\u201cEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales y Agenda 2030.<\/p>\n<p>Much\u00edsimas gracias a quienes no bajasteis los brazos y a quienes hab\u00e9is empujado siempre. Ahora m\u00e1s que nunca necesitaremos de vuestra fuerza y vuestra cr\u00edtica para seguir haciendo posible lo imposible. \u00a1S\u00ed se puede!\u201d, puntualiz\u00f3 Iglesias mediante su cuenta de Instagram.<\/p>\n<p><strong>Por Soraya Andreina P\u00e9rez Mohammed <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Unidas Podemos, Pablo Iglesias, agradeci\u00f3 este lunes la confianza de todos los ciudadanos para formar un Gobierno progresista en el que \u00e9l figurar\u00e1 como vicepresidente de Derechos Sociales. \u201cEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales y Agenda 2030. Much\u00edsimas gracias a quienes no bajasteis los brazos<\/p>\n","protected":false},"author":1,"featured_media":136300,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-136299","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El presidente de Unidas Podemos, Pablo Iglesias, agradeci\u00f3 este lunes la confianza de todos los ciudadanos para formar un Gobierno progresista en el que \u00e9l figurar\u00e1 como vicepresidente de Derechos Sociales. \u201cEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales y Agenda 2030. Much\u00edsimas gracias a quienes no bajasteis los brazos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El presidente de Unidas Podemos, Pablo Iglesias, agradeci\u00f3 este lunes la confianza de todos los ciudadanos para formar un Gobierno progresista en el que \u00e9l figurar\u00e1 como vicepresidente de Derechos Sociales. \u201cEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales y Agenda 2030. Much\u00edsimas gracias a quienes no bajasteis los brazos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-13T15:19:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-01-13T15:19:38+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El presidente de Unidas Podemos, Pablo Iglesias, agradeci\u00f3 este lunes la confianza de todos los ciudadanos para formar un Gobierno progresista en el que \u00e9l figurar\u00e1 como vicepresidente de Derechos Sociales. \u201cEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales y Agenda 2030. Much\u00edsimas gracias a quienes no bajasteis los brazos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#listItem\",\"name\":\"Pablo Iglesias: \\u00abEs un honor poder servir a mi pa\\u00eds como vicepresidente de Derechos Sociales\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#listItem\",\"position\":3,\"name\":\"Pablo Iglesias: \\u00abEs un honor poder servir a mi pa\\u00eds como vicepresidente de Derechos Sociales\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#newsarticle\",\"name\":\"Pablo Iglesias: \\u00abEs un honor poder servir a mi pa\\u00eds como vicepresidente de Derechos Sociales\\u00bb | Cand\\u00e1s 365\",\"headline\":\"Pablo Iglesias: \\u00abEs un honor poder servir a mi pa\\u00eds como vicepresidente de Derechos Sociales\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/PABLO-IGLESIAS-FOTO.jpg\",\"width\":700,\"height\":549},\"datePublished\":\"2020-01-13T15:19:38+01:00\",\"dateModified\":\"2020-01-13T15:19:38+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el enero 13, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/\",\"name\":\"Pablo Iglesias: \\u00abEs un honor poder servir a mi pa\\u00eds como vicepresidente de Derechos Sociales\\u00bb | Cand\\u00e1s 365\",\"description\":\"El presidente de Unidas Podemos, Pablo Iglesias, agradeci\\u00f3 este lunes la confianza de todos los ciudadanos para formar un Gobierno progresista en el que \\u00e9l figurar\\u00e1 como vicepresidente de Derechos Sociales. \\u201cEs un honor poder servir a mi pa\\u00eds como vicepresidente de Derechos Sociales y Agenda 2030. Much\\u00edsimas gracias a quienes no bajasteis los brazos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/PABLO-IGLESIAS-FOTO.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#mainImage\",\"width\":700,\"height\":549},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\\\/#mainImage\"},\"datePublished\":\"2020-01-13T15:19:38+01:00\",\"dateModified\":\"2020-01-13T15:19:38+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb | Cand\u00e1s 365","description":"El presidente de Unidas Podemos, Pablo Iglesias, agradeci\u00f3 este lunes la confianza de todos los ciudadanos para formar un Gobierno progresista en el que \u00e9l figurar\u00e1 como vicepresidente de Derechos Sociales. \u201cEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales y Agenda 2030. Much\u00edsimas gracias a quienes no bajasteis los brazos","canonical_url":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#listItem","name":"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#listItem","position":3,"name":"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#newsarticle","name":"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb | Cand\u00e1s 365","headline":"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO.jpg","width":700,"height":549},"datePublished":"2020-01-13T15:19:38+01:00","dateModified":"2020-01-13T15:19:38+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el enero 13, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#webpage","url":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/","name":"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb | Cand\u00e1s 365","description":"El presidente de Unidas Podemos, Pablo Iglesias, agradeci\u00f3 este lunes la confianza de todos los ciudadanos para formar un Gobierno progresista en el que \u00e9l figurar\u00e1 como vicepresidente de Derechos Sociales. \u201cEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales y Agenda 2030. Much\u00edsimas gracias a quienes no bajasteis los brazos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO.jpg","@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#mainImage","width":700,"height":549},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/#mainImage"},"datePublished":"2020-01-13T15:19:38+01:00","dateModified":"2020-01-13T15:19:38+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb | Cand\u00e1s 365","og:description":"El presidente de Unidas Podemos, Pablo Iglesias, agradeci\u00f3 este lunes la confianza de todos los ciudadanos para formar un Gobierno progresista en el que \u00e9l figurar\u00e1 como vicepresidente de Derechos Sociales. \u201cEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales y Agenda 2030. Much\u00edsimas gracias a quienes no bajasteis los brazos","og:url":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO.jpg","og:image:width":700,"og:image:height":549,"article:published_time":"2020-01-13T15:19:38+00:00","article:modified_time":"2020-01-13T15:19:38+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb | Cand\u00e1s 365","twitter:description":"El presidente de Unidas Podemos, Pablo Iglesias, agradeci\u00f3 este lunes la confianza de todos los ciudadanos para formar un Gobierno progresista en el que \u00e9l figurar\u00e1 como vicepresidente de Derechos Sociales. \u201cEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales y Agenda 2030. Much\u00edsimas gracias a quienes no bajasteis los brazos","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/PABLO-IGLESIAS-FOTO.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365"},"aioseo_meta_data":{"post_id":"136299","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 16:18:27","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:48:11","updated":"2026-05-25 16:18:27"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tPablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Pablo Iglesias: \u00abEs un honor poder servir a mi pa\u00eds como vicepresidente de Derechos Sociales\u00bb","link":"https:\/\/candas365.es\/noticias\/pablo-iglesias-es-un-honor-poder-servir-a-mi-pais-como-vicepresidente-de-derechos-sociales\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=136299"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/136300"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=136299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=136299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=136299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}