{"id":136070,"date":"2020-01-09T20:07:21","date_gmt":"2020-01-09T20:07:21","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=136070"},"modified":"2020-01-09T20:07:21","modified_gmt":"2020-01-09T20:07:21","slug":"una-desata-las-alarmas-en-la-catedral-de-colonia","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/","title":{"rendered":"Una desata las alarmas en la Catedral de Colonia"},"content":{"rendered":"<p>Colonia, 9 ene (dpa) &#8211; Un transe\u00fante confundi\u00f3 una nube con humo y desat\u00f3 un gran despliegue de bomberos en la Catedral de Colonia, en en el oeste de Alemania.<\/p>\n<figure id=\"attachment_136071\" aria-describedby=\"caption-attachment-136071\" style=\"width: 655px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-136071 size-large\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa-655x368.jpg\" alt=\"\" width=\"655\" height=\"368\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa-655x368.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa-360x202.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa-768x432.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa-696x391.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa-1068x600.jpg 1068w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa-747x420.jpg 747w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa.jpg 1096w\" sizes=\"(max-width: 655px) 100vw, 655px\" \/><figcaption id=\"caption-attachment-136071\" class=\"wp-caption-text\">Foto: NonstopNews\/dpa<\/figcaption><\/figure>\n<p>Cerca de un centenar de bomberos llegaron el jueves por la noche hasta la famosa iglesia g\u00f3tica en decenas de carros tras recibir la alarma y controlaron las torres sin encontrar ning\u00fan fuego.<\/p>\n<p>\u00abLa nube hab\u00eda quedado como colgada en la torre norte de manera que desde abajo parec\u00eda humo\u00bb, dijo el portavoz de los bomberos. El operativo finaliz\u00f3 despu\u00e9s de alrededor de una hora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Colonia, 9 ene (dpa) &#8211; Un transe\u00fante confundi\u00f3 una nube con humo y desat\u00f3 un gran despliegue de bomberos en la Catedral de Colonia, en en el oeste de Alemania. Cerca de un centenar de bomberos llegaron el jueves por la noche hasta la famosa iglesia g\u00f3tica en decenas de carros tras recibir la alarma<\/p>\n","protected":false},"author":1,"featured_media":136071,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-136070","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Colonia, 9 ene (dpa) - Un transe\u00fante confundi\u00f3 una nube con humo y desat\u00f3 un gran despliegue de bomberos en la Catedral de Colonia, en en el oeste de Alemania. Cerca de un centenar de bomberos llegaron el jueves por la noche hasta la famosa iglesia g\u00f3tica en decenas de carros tras recibir la alarma\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Una desata las alarmas en la Catedral de Colonia | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Colonia, 9 ene (dpa) - Un transe\u00fante confundi\u00f3 una nube con humo y desat\u00f3 un gran despliegue de bomberos en la Catedral de Colonia, en en el oeste de Alemania. Cerca de un centenar de bomberos llegaron el jueves por la noche hasta la famosa iglesia g\u00f3tica en decenas de carros tras recibir la alarma\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1096\" \/>\n\t\t<meta property=\"og:image:height\" content=\"616\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-09T20:07:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-01-09T20:07:21+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Una desata las alarmas en la Catedral de Colonia | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Colonia, 9 ene (dpa) - Un transe\u00fante confundi\u00f3 una nube con humo y desat\u00f3 un gran despliegue de bomberos en la Catedral de Colonia, en en el oeste de Alemania. Cerca de un centenar de bomberos llegaron el jueves por la noche hasta la famosa iglesia g\u00f3tica en decenas de carros tras recibir la alarma\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#listItem\",\"name\":\"Una desata las alarmas en la Catedral de Colonia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#listItem\",\"position\":3,\"name\":\"Una desata las alarmas en la Catedral de Colonia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#newsarticle\",\"name\":\"Una desata las alarmas en la Catedral de Colonia | Cand\\u00e1s 365\",\"headline\":\"Una desata las alarmas en la Catedral de Colonia\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Catedral-Colonia-dpa.jpg\",\"width\":1096,\"height\":616,\"caption\":\"Foto:  NonstopNews\\\/dpa\"},\"datePublished\":\"2020-01-09T20:07:21+01:00\",\"dateModified\":\"2020-01-09T20:07:21+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el enero 9, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/\",\"name\":\"Una desata las alarmas en la Catedral de Colonia | Cand\\u00e1s 365\",\"description\":\"Colonia, 9 ene (dpa) - Un transe\\u00fante confundi\\u00f3 una nube con humo y desat\\u00f3 un gran despliegue de bomberos en la Catedral de Colonia, en en el oeste de Alemania. Cerca de un centenar de bomberos llegaron el jueves por la noche hasta la famosa iglesia g\\u00f3tica en decenas de carros tras recibir la alarma\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Catedral-Colonia-dpa.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#mainImage\",\"width\":1096,\"height\":616,\"caption\":\"Foto:  NonstopNews\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/una-desata-las-alarmas-en-la-catedral-de-colonia\\\/#mainImage\"},\"datePublished\":\"2020-01-09T20:07:21+01:00\",\"dateModified\":\"2020-01-09T20:07:21+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Una desata las alarmas en la Catedral de Colonia | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Una desata las alarmas en la Catedral de Colonia | Cand\u00e1s 365","description":"Colonia, 9 ene (dpa) - Un transe\u00fante confundi\u00f3 una nube con humo y desat\u00f3 un gran despliegue de bomberos en la Catedral de Colonia, en en el oeste de Alemania. Cerca de un centenar de bomberos llegaron el jueves por la noche hasta la famosa iglesia g\u00f3tica en decenas de carros tras recibir la alarma","canonical_url":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#listItem","name":"Una desata las alarmas en la Catedral de Colonia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#listItem","position":3,"name":"Una desata las alarmas en la Catedral de Colonia","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#newsarticle","name":"Una desata las alarmas en la Catedral de Colonia | Cand\u00e1s 365","headline":"Una desata las alarmas en la Catedral de Colonia","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa.jpg","width":1096,"height":616,"caption":"Foto:  NonstopNews\/dpa"},"datePublished":"2020-01-09T20:07:21+01:00","dateModified":"2020-01-09T20:07:21+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el enero 9, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#webpage","url":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/","name":"Una desata las alarmas en la Catedral de Colonia | Cand\u00e1s 365","description":"Colonia, 9 ene (dpa) - Un transe\u00fante confundi\u00f3 una nube con humo y desat\u00f3 un gran despliegue de bomberos en la Catedral de Colonia, en en el oeste de Alemania. Cerca de un centenar de bomberos llegaron el jueves por la noche hasta la famosa iglesia g\u00f3tica en decenas de carros tras recibir la alarma","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa.jpg","@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#mainImage","width":1096,"height":616,"caption":"Foto:  NonstopNews\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/#mainImage"},"datePublished":"2020-01-09T20:07:21+01:00","dateModified":"2020-01-09T20:07:21+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Una desata las alarmas en la Catedral de Colonia | Cand\u00e1s 365","og:description":"Colonia, 9 ene (dpa) - Un transe\u00fante confundi\u00f3 una nube con humo y desat\u00f3 un gran despliegue de bomberos en la Catedral de Colonia, en en el oeste de Alemania. Cerca de un centenar de bomberos llegaron el jueves por la noche hasta la famosa iglesia g\u00f3tica en decenas de carros tras recibir la alarma","og:url":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa.jpg","og:image:width":1096,"og:image:height":616,"article:published_time":"2020-01-09T20:07:21+00:00","article:modified_time":"2020-01-09T20:07:21+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Una desata las alarmas en la Catedral de Colonia | Cand\u00e1s 365","twitter:description":"Colonia, 9 ene (dpa) - Un transe\u00fante confundi\u00f3 una nube con humo y desat\u00f3 un gran despliegue de bomberos en la Catedral de Colonia, en en el oeste de Alemania. Cerca de un centenar de bomberos llegaron el jueves por la noche hasta la famosa iglesia g\u00f3tica en decenas de carros tras recibir la alarma","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/Catedral-Colonia-dpa.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"136070","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 15:40:24","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:48:18","updated":"2026-05-25 15:40:24"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tUna desata las alarmas en la Catedral de Colonia\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Una desata las alarmas en la Catedral de Colonia","link":"https:\/\/candas365.es\/noticias\/una-desata-las-alarmas-en-la-catedral-de-colonia\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=136070"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/136071"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=136070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=136070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=136070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}