{"id":136041,"date":"2020-01-09T12:36:36","date_gmt":"2020-01-09T12:36:36","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=136041"},"modified":"2020-01-09T12:36:36","modified_gmt":"2020-01-09T12:36:36","slug":"la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/","title":{"rendered":"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-136042\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia.jpg 600w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>La Uni\u00f3n Sindical Obrera (USO) inform\u00f3 recientemente que la Audiencia Nacional ha dictado sentencia contra la empresa tecnol\u00f3gica T-Systems por vulnerar la libertad sindical y anula la cl\u00e1usula contractual que impone a los trabajadores la obligatoriedad de realizar guardias, contraviniendo el vigente convenio colectivo.<\/p>\n<p>Seg\u00fan la demanda presentada por USO el pasado 2 de octubre de 2019, se solicitaba la \u00abnulidad de la pr\u00e1ctica empresarial de incluir en los contratos de trabajo cl\u00e1usulas que establezcan la obligatoriedad del sistema de guardias\u00bb<\/p>\n<p>Adem\u00e1s, queda probado que hay una \u201cvulneraci\u00f3n del derecho a la libertad sindical (\u2026) y en consecuencia se condena a la empresa al abono a cada una de las organizaciones sindicales actoras de una indemnizaci\u00f3n de 3.126 euros por el da\u00f1o moral producido\u201d.<\/p>\n<p>\u201cM\u00e1s all\u00e1 de la indemnizaci\u00f3n y de revocar esta cl\u00e1usula abusiva, lo m\u00e1s importante de esta sentencia es la condena a renegociar condiciones de trabajo en cada contrato por debajo del paraguas com\u00fan y m\u00e1s garantista del convenio colectivo. Estamos muy satisfechos de que a todos esos trabajadores se les reconozcan las condiciones comunes y m\u00e1s favorables de las que goza el conjunto de la plantilla\u201d, valora Sergio Fern\u00e1ndez, secretario general de la secci\u00f3n sindical de USO en T-Systems.<\/p>\n<p>Esta sentencia afecta a todos los trabajadores de los centros de trabajo que T-Systems tiene en Espa\u00f1a que han visto adendada esa cl\u00e1usula en un anexo en el contrato y que eran, a fecha de la demanda, 310. T-Systems cuenta con 2.300 empleados en toda Espa\u00f1a, repartidos en centros de trabajo en Catalu\u00f1a (Barcelona, Reus y Martorell), Andaluc\u00eda (Granada y Sevilla), Madrid, Galicia, Asturias, Islas Baleares, Comunidad Valenciana y Euskadi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Uni\u00f3n Sindical Obrera (USO) inform\u00f3 recientemente que la Audiencia Nacional ha dictado sentencia contra la empresa tecnol\u00f3gica T-Systems por vulnerar la libertad sindical y anula la cl\u00e1usula contractual que impone a los trabajadores la obligatoriedad de realizar guardias, contraviniendo el vigente convenio colectivo. Seg\u00fan la demanda presentada por USO el pasado 2 de octubre<\/p>\n","protected":false},"author":1,"featured_media":136042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-136041","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Uni\u00f3n Sindical Obrera (USO) inform\u00f3 recientemente que la Audiencia Nacional ha dictado sentencia contra la empresa tecnol\u00f3gica T-Systems por vulnerar la libertad sindical y anula la cl\u00e1usula contractual que impone a los trabajadores la obligatoriedad de realizar guardias, contraviniendo el vigente convenio colectivo. Seg\u00fan la demanda presentada por USO el pasado 2 de octubre\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"La Uni\u00f3n Sindical Obrera (USO) inform\u00f3 recientemente que la Audiencia Nacional ha dictado sentencia contra la empresa tecnol\u00f3gica T-Systems por vulnerar la libertad sindical y anula la cl\u00e1usula contractual que impone a los trabajadores la obligatoriedad de realizar guardias, contraviniendo el vigente convenio colectivo. Seg\u00fan la demanda presentada por USO el pasado 2 de octubre\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-01-09T12:36:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-01-09T12:36:36+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Uni\u00f3n Sindical Obrera (USO) inform\u00f3 recientemente que la Audiencia Nacional ha dictado sentencia contra la empresa tecnol\u00f3gica T-Systems por vulnerar la libertad sindical y anula la cl\u00e1usula contractual que impone a los trabajadores la obligatoriedad de realizar guardias, contraviniendo el vigente convenio colectivo. Seg\u00fan la demanda presentada por USO el pasado 2 de octubre\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#listItem\",\"name\":\"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#listItem\",\"position\":3,\"name\":\"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#newsarticle\",\"name\":\"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical | Cand\\u00e1s 365\",\"headline\":\"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/tecnologia.jpg\",\"width\":600,\"height\":450},\"datePublished\":\"2020-01-09T12:36:36+01:00\",\"dateModified\":\"2020-01-09T12:36:36+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el enero 9, 2020.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/\",\"name\":\"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical | Cand\\u00e1s 365\",\"description\":\"La Uni\\u00f3n Sindical Obrera (USO) inform\\u00f3 recientemente que la Audiencia Nacional ha dictado sentencia contra la empresa tecnol\\u00f3gica T-Systems por vulnerar la libertad sindical y anula la cl\\u00e1usula contractual que impone a los trabajadores la obligatoriedad de realizar guardias, contraviniendo el vigente convenio colectivo. Seg\\u00fan la demanda presentada por USO el pasado 2 de octubre\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/tecnologia.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#mainImage\",\"width\":600,\"height\":450},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\\\/#mainImage\"},\"datePublished\":\"2020-01-09T12:36:36+01:00\",\"dateModified\":\"2020-01-09T12:36:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical | Cand\u00e1s 365","description":"La Uni\u00f3n Sindical Obrera (USO) inform\u00f3 recientemente que la Audiencia Nacional ha dictado sentencia contra la empresa tecnol\u00f3gica T-Systems por vulnerar la libertad sindical y anula la cl\u00e1usula contractual que impone a los trabajadores la obligatoriedad de realizar guardias, contraviniendo el vigente convenio colectivo. Seg\u00fan la demanda presentada por USO el pasado 2 de octubre","canonical_url":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#listItem","name":"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#listItem","position":3,"name":"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#newsarticle","name":"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical | Cand\u00e1s 365","headline":"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia.jpg","width":600,"height":450},"datePublished":"2020-01-09T12:36:36+01:00","dateModified":"2020-01-09T12:36:36+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el enero 9, 2020."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/","name":"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical | Cand\u00e1s 365","description":"La Uni\u00f3n Sindical Obrera (USO) inform\u00f3 recientemente que la Audiencia Nacional ha dictado sentencia contra la empresa tecnol\u00f3gica T-Systems por vulnerar la libertad sindical y anula la cl\u00e1usula contractual que impone a los trabajadores la obligatoriedad de realizar guardias, contraviniendo el vigente convenio colectivo. Seg\u00fan la demanda presentada por USO el pasado 2 de octubre","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia.jpg","@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#mainImage","width":600,"height":450},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/#mainImage"},"datePublished":"2020-01-09T12:36:36+01:00","dateModified":"2020-01-09T12:36:36+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical | Cand\u00e1s 365","og:description":"La Uni\u00f3n Sindical Obrera (USO) inform\u00f3 recientemente que la Audiencia Nacional ha dictado sentencia contra la empresa tecnol\u00f3gica T-Systems por vulnerar la libertad sindical y anula la cl\u00e1usula contractual que impone a los trabajadores la obligatoriedad de realizar guardias, contraviniendo el vigente convenio colectivo. Seg\u00fan la demanda presentada por USO el pasado 2 de octubre","og:url":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia.jpg","og:image:width":600,"og:image:height":450,"article:published_time":"2020-01-09T12:36:36+00:00","article:modified_time":"2020-01-09T12:36:36+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical | Cand\u00e1s 365","twitter:description":"La Uni\u00f3n Sindical Obrera (USO) inform\u00f3 recientemente que la Audiencia Nacional ha dictado sentencia contra la empresa tecnol\u00f3gica T-Systems por vulnerar la libertad sindical y anula la cl\u00e1usula contractual que impone a los trabajadores la obligatoriedad de realizar guardias, contraviniendo el vigente convenio colectivo. Seg\u00fan la demanda presentada por USO el pasado 2 de octubre","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2020\/01\/tecnologia.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"136041","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 15:36:44","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:48:18","updated":"2026-05-25 15:36:44"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"La Audiencia Nacional sanciona a la empresa T-Systems por vulnerar la libertad sindical","link":"https:\/\/candas365.es\/noticias\/la-audiencia-nacional-sanciona-a-la-empresa-t-systems-por-vulnerar-la-libertad-sindical\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=136041"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/136041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/136042"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=136041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=136041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=136041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}