{"id":135574,"date":"2019-12-29T20:32:53","date_gmt":"2019-12-29T20:32:53","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=135574"},"modified":"2019-12-29T20:32:53","modified_gmt":"2019-12-29T20:32:53","slug":"alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/","title":{"rendered":"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-98518\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 29 dic (dpa) &#8211; El ministro alem\u00e1n de Relaciones Exteriores, Heiko Maas, quiere aprovechar el segundo a\u00f1o de Alemania en el Consejo de Seguridad de la Organizaci\u00f3n de Naciones Unidas (ONU) para continuar desarrollando el organismo como una instituci\u00f3n de prevenci\u00f3n de crisis.<\/p>\n<p>\u00abNuestro segundo a\u00f1o (como miembro) del Consejo de Seguridad estar\u00e1 dedicado a la protecci\u00f3n y al desarrollo del orden internacional reglado\u00bb, anunci\u00f3 el ministro en declaraciones a dpa, y agreg\u00f3 que esta instituci\u00f3n \u00ab(&#8230;) debe ser mucho m\u00e1s un \u00f3rgano de prevenci\u00f3n de crisis que de reacci\u00f3n a las crisis\u00bb.<\/p>\n<p>Durante el mes de julio de 2020, Alemania ocupar\u00e1, a la vez, la presidencia del Consejo de Seguridad en la ONU y la presidencia del Consejo de la Uni\u00f3n Europea (UE).<\/p>\n<p>\u00abEsto significa una responsabilidad especialmente destacada sobre el sistema multilateral, que cumpliremos en ambos lugares, tanto en Bruselas como en Nueva York. Continuaremos la estrecha cooperaci\u00f3n franco-alemana\u00bb, se\u00f1al\u00f3 el alto diplom\u00e1tico germano.<\/p>\n<p>Maas asegur\u00f3 que la pol\u00edtica exterior alemana es una pol\u00edtica exterior multilateral y a\u00f1adi\u00f3 que \u00absolo juntos podemos superar los desaf\u00edos actuales: la globalizaci\u00f3n, la digitalizaci\u00f3n, el cambio clim\u00e1tico, la migraci\u00f3n -todos temas que literalmente no tienen fronteras\u00bb.<\/p>\n<p>En su balance sobre el primer a\u00f1o en el Consejo de Seguridad, el ministro alem\u00e1n observ\u00f3 que se han logrado avances en cuestiones importantes: \u00abEn el \u00e1mbito de la mujer, la paz y la seguridad, (&#8230;) hemos creado una base para combatir la violencia sexual en conflictos y hacer que los responsables rindan cuentas\u00bb, dijo.<\/p>\n<p>\u00abJunto con Francia, hemos aprovechado los meses de la presidencia para incluir tambi\u00e9n en el programa del Consejo de Seguridad los temas clima y seguridad, control de armamentos y derecho humanitario internacional\u00bb, indic\u00f3 Maas.<\/p>\n<p>El pol\u00edtico socialdem\u00f3crata asegur\u00f3 que Alemania seguir\u00e1 centr\u00e1ndose en su enfoque preventivo de estas cuestiones durante el pr\u00f3ximo a\u00f1o. Tambi\u00e9n \u00abLibia, la zona del Sahel, Sud\u00e1n, Afganist\u00e1n, Corea del Norte, Siria, Ir\u00e1n y Yemen nos mantendr\u00e1n ocupados\u00bb, enumer\u00f3.<\/p>\n<p>Maas afirm\u00f3 que Alemania trabajar\u00e1 para lograr soluciones pol\u00edticas en el Consejo de Seguridad y en otros formatos. \u00abAl mismo tiempo, debemos reconocer de manera realista que no todos los bloqueos en el seno del Consejo de Seguridad pueden resolverse. Esto limita nuestra capacidad de lograr una soluci\u00f3n pac\u00edfica en Siria\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>El Consejo de Seguridad se ocupa sobre todo de la gesti\u00f3n de crisis y el mantenimiento de la paz.<\/p>\n<p>Alemania hab\u00eda presidido el Consejo de Seguridad de la ONU por \u00faltima vez en septiembre de 2012. En el verano (boreal) de 2019 le sigui\u00f3 otro per\u00edodo de un mes a la cabeza del organismo, que se repetir\u00e1 durante el mismo mes de julio en 2020.<\/p>\n<p>Francia y Alemania acordaron que sus periodos de liderazgo sucesivos deben entenderse como una \u00abdoble presidencia\u00bb conjunta durante dos meses.<\/p>\n<p>Alemania forma parte del organismo m\u00e1s importante de la ONU desde principios de 2019 y es uno de sus diez miembros no permanentes.<\/p>\n<p>Francia, en cambio, es junto a Estados Unidos, Rusia, China y el Reino Unido uno de los cinco miembros permanentes con derecho de veto.<\/p>\n<p>Alemania se postula cada ocho a\u00f1os para una membres\u00eda de dos a\u00f1os en el Consejo de Seguridad, hasta ahora siempre con \u00e9xito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 29 dic (dpa) &#8211; El ministro alem\u00e1n de Relaciones Exteriores, Heiko Maas, quiere aprovechar el segundo a\u00f1o de Alemania en el Consejo de Seguridad de la Organizaci\u00f3n de Naciones Unidas (ONU) para continuar desarrollando el organismo como una instituci\u00f3n de prevenci\u00f3n de crisis. \u00abNuestro segundo a\u00f1o (como miembro) del Consejo de Seguridad estar\u00e1 dedicado<\/p>\n","protected":false},"author":1,"featured_media":98518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-135574","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 29 dic (dpa) - El ministro alem\u00e1n de Relaciones Exteriores, Heiko Maas, quiere aprovechar el segundo a\u00f1o de Alemania en el Consejo de Seguridad de la Organizaci\u00f3n de Naciones Unidas (ONU) para continuar desarrollando el organismo como una instituci\u00f3n de prevenci\u00f3n de crisis. &quot;Nuestro segundo a\u00f1o (como miembro) del Consejo de Seguridad estar\u00e1 dedicado\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 29 dic (dpa) - El ministro alem\u00e1n de Relaciones Exteriores, Heiko Maas, quiere aprovechar el segundo a\u00f1o de Alemania en el Consejo de Seguridad de la Organizaci\u00f3n de Naciones Unidas (ONU) para continuar desarrollando el organismo como una instituci\u00f3n de prevenci\u00f3n de crisis. &quot;Nuestro segundo a\u00f1o (como miembro) del Consejo de Seguridad estar\u00e1 dedicado\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-12-29T20:32:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-12-29T20:32:53+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 29 dic (dpa) - El ministro alem\u00e1n de Relaciones Exteriores, Heiko Maas, quiere aprovechar el segundo a\u00f1o de Alemania en el Consejo de Seguridad de la Organizaci\u00f3n de Naciones Unidas (ONU) para continuar desarrollando el organismo como una instituci\u00f3n de prevenci\u00f3n de crisis. &quot;Nuestro segundo a\u00f1o (como miembro) del Consejo de Seguridad estar\u00e1 dedicado\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#listItem\",\"name\":\"Alemania inicia su segundo a\\u00f1o en el Consejo de Seguridad de la ONU\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#listItem\",\"position\":3,\"name\":\"Alemania inicia su segundo a\\u00f1o en el Consejo de Seguridad de la ONU\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#newsarticle\",\"name\":\"Alemania inicia su segundo a\\u00f1o en el Consejo de Seguridad de la ONU | Cand\\u00e1s 365\",\"headline\":\"Alemania inicia su segundo a\\u00f1o en el Consejo de Seguridad de la ONU\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/berlin-76509_960_720.jpg\",\"width\":960,\"height\":720},\"datePublished\":\"2019-12-29T20:32:53+01:00\",\"dateModified\":\"2019-12-29T20:32:53+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el diciembre 29, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/\",\"name\":\"Alemania inicia su segundo a\\u00f1o en el Consejo de Seguridad de la ONU | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 29 dic (dpa) - El ministro alem\\u00e1n de Relaciones Exteriores, Heiko Maas, quiere aprovechar el segundo a\\u00f1o de Alemania en el Consejo de Seguridad de la Organizaci\\u00f3n de Naciones Unidas (ONU) para continuar desarrollando el organismo como una instituci\\u00f3n de prevenci\\u00f3n de crisis. \\\"Nuestro segundo a\\u00f1o (como miembro) del Consejo de Seguridad estar\\u00e1 dedicado\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/berlin-76509_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#mainImage\",\"width\":960,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\\\/#mainImage\"},\"datePublished\":\"2019-12-29T20:32:53+01:00\",\"dateModified\":\"2019-12-29T20:32:53+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU | Cand\u00e1s 365","description":"Berl\u00edn, 29 dic (dpa) - El ministro alem\u00e1n de Relaciones Exteriores, Heiko Maas, quiere aprovechar el segundo a\u00f1o de Alemania en el Consejo de Seguridad de la Organizaci\u00f3n de Naciones Unidas (ONU) para continuar desarrollando el organismo como una instituci\u00f3n de prevenci\u00f3n de crisis. \"Nuestro segundo a\u00f1o (como miembro) del Consejo de Seguridad estar\u00e1 dedicado","canonical_url":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#listItem","name":"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#listItem","position":3,"name":"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#newsarticle","name":"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU | Cand\u00e1s 365","headline":"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","width":960,"height":720},"datePublished":"2019-12-29T20:32:53+01:00","dateModified":"2019-12-29T20:32:53+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el diciembre 29, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#webpage","url":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/","name":"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU | Cand\u00e1s 365","description":"Berl\u00edn, 29 dic (dpa) - El ministro alem\u00e1n de Relaciones Exteriores, Heiko Maas, quiere aprovechar el segundo a\u00f1o de Alemania en el Consejo de Seguridad de la Organizaci\u00f3n de Naciones Unidas (ONU) para continuar desarrollando el organismo como una instituci\u00f3n de prevenci\u00f3n de crisis. \"Nuestro segundo a\u00f1o (como miembro) del Consejo de Seguridad estar\u00e1 dedicado","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#mainImage","width":960,"height":720},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/#mainImage"},"datePublished":"2019-12-29T20:32:53+01:00","dateModified":"2019-12-29T20:32:53+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU | Cand\u00e1s 365","og:description":"Berl\u00edn, 29 dic (dpa) - El ministro alem\u00e1n de Relaciones Exteriores, Heiko Maas, quiere aprovechar el segundo a\u00f1o de Alemania en el Consejo de Seguridad de la Organizaci\u00f3n de Naciones Unidas (ONU) para continuar desarrollando el organismo como una instituci\u00f3n de prevenci\u00f3n de crisis. &quot;Nuestro segundo a\u00f1o (como miembro) del Consejo de Seguridad estar\u00e1 dedicado","og:url":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","og:image:width":960,"og:image:height":720,"article:published_time":"2019-12-29T20:32:53+00:00","article:modified_time":"2019-12-29T20:32:53+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 29 dic (dpa) - El ministro alem\u00e1n de Relaciones Exteriores, Heiko Maas, quiere aprovechar el segundo a\u00f1o de Alemania en el Consejo de Seguridad de la Organizaci\u00f3n de Naciones Unidas (ONU) para continuar desarrollando el organismo como una instituci\u00f3n de prevenci\u00f3n de crisis. &quot;Nuestro segundo a\u00f1o (como miembro) del Consejo de Seguridad estar\u00e1 dedicado","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"135574","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 14:13:28","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:48:44","updated":"2026-05-25 14:13:28"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAlemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Alemania inicia su segundo a\u00f1o en el Consejo de Seguridad de la ONU","link":"https:\/\/candas365.es\/noticias\/alemania-inicia-su-segundo-ano-en-el-consejo-de-seguridad-de-la-onu\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/135574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=135574"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/135574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/98518"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=135574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=135574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=135574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}