{"id":135401,"date":"2019-12-27T12:42:43","date_gmt":"2019-12-27T12:42:43","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=135401"},"modified":"2019-12-27T12:42:43","modified_gmt":"2019-12-27T12:42:43","slug":"el-alan-kurdi-rescata-32-personas-en-el-mediterraneo","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/","title":{"rendered":"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-98553\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720-360x240.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720-768x512.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720-655x437.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720-696x464.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720-630x420.jpg 630w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Roma, 27 dic (dpa) &#8211; El barco alem\u00e1n de rescate \u00abAlan Kurdi\u00bb subi\u00f3 a bordo a 32 migrantes, entre ellos diez ni\u00f1os y una mujer embarazada, que se encontraban frente a la costa de Libia en un bote de material sint\u00e9tico sobrecargado de personas, inform\u00f3 hoy la organizaci\u00f3n de ayuda humanitaria Sea-Eye.<\/p>\n<p>La instituci\u00f3n alemana agreg\u00f3 que la tripulaci\u00f3n del \u00abAlan Kurdi\u00bb recibi\u00f3 una llamada de auxilio el jueves por la noche y que el barco lleg\u00f3 dos horas m\u00e1s tarde a las coordinadas transmitidas y rescat\u00f3 al grupo, a\u00f1adiendo que hasta el momento ning\u00fan centro de rescate se ha declarado responsable por los refugiados.<\/p>\n<p>La organizaci\u00f3n acot\u00f3 que el \u00abAlan Kurdi\u00bb se dirige ahora a la isla italiana de Lampedusa, ya que se aproxima una tormenta.<\/p>\n<p>Los rescatados dijeron ser todos ciudadanos libios. \u00ab\u00bfQu\u00e9 tan segura puede ser Libia si los propios libios y sus familias ponen sus vidas en peligro en el mar para poder abandonar el pa\u00eds r\u00e1pidamente?\u00bb, cuestion\u00f3 Gorden Isler, presidente de Sea-Eye.<\/p>\n<p>Libia es una de las rutas que usan los migrantes para llegar a Europa a trav\u00e9s del Mediterr\u00e1neo.<\/p>\n<p>La \u00faltima vez que el \u00abAlan Kurdi\u00bb llev\u00f3 refugiados a Italia fue a principios de diciembre.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 27 dic (dpa) &#8211; El barco alem\u00e1n de rescate \u00abAlan Kurdi\u00bb subi\u00f3 a bordo a 32 migrantes, entre ellos diez ni\u00f1os y una mujer embarazada, que se encontraban frente a la costa de Libia en un bote de material sint\u00e9tico sobrecargado de personas, inform\u00f3 hoy la organizaci\u00f3n de ayuda humanitaria Sea-Eye. La instituci\u00f3n alemana<\/p>\n","protected":false},"author":1,"featured_media":98553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-135401","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Roma, 27 dic (dpa) - El barco alem\u00e1n de rescate &quot;Alan Kurdi&quot; subi\u00f3 a bordo a 32 migrantes, entre ellos diez ni\u00f1os y una mujer embarazada, que se encontraban frente a la costa de Libia en un bote de material sint\u00e9tico sobrecargado de personas, inform\u00f3 hoy la organizaci\u00f3n de ayuda humanitaria Sea-Eye. La instituci\u00f3n alemana\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Roma, 27 dic (dpa) - El barco alem\u00e1n de rescate &quot;Alan Kurdi&quot; subi\u00f3 a bordo a 32 migrantes, entre ellos diez ni\u00f1os y una mujer embarazada, que se encontraban frente a la costa de Libia en un bote de material sint\u00e9tico sobrecargado de personas, inform\u00f3 hoy la organizaci\u00f3n de ayuda humanitaria Sea-Eye. La instituci\u00f3n alemana\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-12-27T12:42:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-12-27T12:42:43+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Roma, 27 dic (dpa) - El barco alem\u00e1n de rescate &quot;Alan Kurdi&quot; subi\u00f3 a bordo a 32 migrantes, entre ellos diez ni\u00f1os y una mujer embarazada, que se encontraban frente a la costa de Libia en un bote de material sint\u00e9tico sobrecargado de personas, inform\u00f3 hoy la organizaci\u00f3n de ayuda humanitaria Sea-Eye. La instituci\u00f3n alemana\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#listItem\",\"name\":\"El \\u00abAlan Kurdi\\u00bb rescata 32 personas en el Mediterr\\u00e1neo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#listItem\",\"position\":3,\"name\":\"El \\u00abAlan Kurdi\\u00bb rescata 32 personas en el Mediterr\\u00e1neo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#newsarticle\",\"name\":\"El \\u00abAlan Kurdi\\u00bb rescata 32 personas en el Mediterr\\u00e1neo | Cand\\u00e1s 365\",\"headline\":\"El \\u00abAlan Kurdi\\u00bb rescata 32 personas en el Mediterr\\u00e1neo\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/blue-1977898_960_720.jpg\",\"width\":960,\"height\":640},\"datePublished\":\"2019-12-27T12:42:43+01:00\",\"dateModified\":\"2019-12-27T12:42:43+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el diciembre 27, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/\",\"name\":\"El \\u00abAlan Kurdi\\u00bb rescata 32 personas en el Mediterr\\u00e1neo | Cand\\u00e1s 365\",\"description\":\"Roma, 27 dic (dpa) - El barco alem\\u00e1n de rescate \\\"Alan Kurdi\\\" subi\\u00f3 a bordo a 32 migrantes, entre ellos diez ni\\u00f1os y una mujer embarazada, que se encontraban frente a la costa de Libia en un bote de material sint\\u00e9tico sobrecargado de personas, inform\\u00f3 hoy la organizaci\\u00f3n de ayuda humanitaria Sea-Eye. La instituci\\u00f3n alemana\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/blue-1977898_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\\\/#mainImage\"},\"datePublished\":\"2019-12-27T12:42:43+01:00\",\"dateModified\":\"2019-12-27T12:42:43+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo | Cand\u00e1s 365","description":"Roma, 27 dic (dpa) - El barco alem\u00e1n de rescate \"Alan Kurdi\" subi\u00f3 a bordo a 32 migrantes, entre ellos diez ni\u00f1os y una mujer embarazada, que se encontraban frente a la costa de Libia en un bote de material sint\u00e9tico sobrecargado de personas, inform\u00f3 hoy la organizaci\u00f3n de ayuda humanitaria Sea-Eye. La instituci\u00f3n alemana","canonical_url":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#listItem","name":"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#listItem","position":3,"name":"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#newsarticle","name":"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo | Cand\u00e1s 365","headline":"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720.jpg","width":960,"height":640},"datePublished":"2019-12-27T12:42:43+01:00","dateModified":"2019-12-27T12:42:43+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el diciembre 27, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#webpage","url":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/","name":"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo | Cand\u00e1s 365","description":"Roma, 27 dic (dpa) - El barco alem\u00e1n de rescate \"Alan Kurdi\" subi\u00f3 a bordo a 32 migrantes, entre ellos diez ni\u00f1os y una mujer embarazada, que se encontraban frente a la costa de Libia en un bote de material sint\u00e9tico sobrecargado de personas, inform\u00f3 hoy la organizaci\u00f3n de ayuda humanitaria Sea-Eye. La instituci\u00f3n alemana","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/#mainImage"},"datePublished":"2019-12-27T12:42:43+01:00","dateModified":"2019-12-27T12:42:43+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo | Cand\u00e1s 365","og:description":"Roma, 27 dic (dpa) - El barco alem\u00e1n de rescate &quot;Alan Kurdi&quot; subi\u00f3 a bordo a 32 migrantes, entre ellos diez ni\u00f1os y una mujer embarazada, que se encontraban frente a la costa de Libia en un bote de material sint\u00e9tico sobrecargado de personas, inform\u00f3 hoy la organizaci\u00f3n de ayuda humanitaria Sea-Eye. La instituci\u00f3n alemana","og:url":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2019-12-27T12:42:43+00:00","article:modified_time":"2019-12-27T12:42:43+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo | Cand\u00e1s 365","twitter:description":"Roma, 27 dic (dpa) - El barco alem\u00e1n de rescate &quot;Alan Kurdi&quot; subi\u00f3 a bordo a 32 migrantes, entre ellos diez ni\u00f1os y una mujer embarazada, que se encontraban frente a la costa de Libia en un bote de material sint\u00e9tico sobrecargado de personas, inform\u00f3 hoy la organizaci\u00f3n de ayuda humanitaria Sea-Eye. La instituci\u00f3n alemana","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/blue-1977898_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"135401","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 13:53:18","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:48:45","updated":"2026-05-25 13:53:18"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEl \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"El \u00abAlan Kurdi\u00bb rescata 32 personas en el Mediterr\u00e1neo","link":"https:\/\/candas365.es\/noticias\/el-alan-kurdi-rescata-32-personas-en-el-mediterraneo\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/135401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=135401"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/135401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/98553"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=135401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=135401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=135401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}