{"id":135180,"date":"2019-12-22T20:53:24","date_gmt":"2019-12-22T20:53:24","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=135180"},"modified":"2019-12-22T20:53:24","modified_gmt":"2019-12-22T20:53:24","slug":"mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/","title":{"rendered":"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-135181\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia-360x239.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia.jpg 512w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Durante una semana, 165.284 conductores han sido requeridos por los agentes de la Agrupaci\u00f3n de Tr\u00e1fico de la Guardia Civil para realizar la prueba de control de alcohol y\/o drogas, con motivo de la campa\u00f1a de concienciaci\u00f3n y vigilancia del consumo de estas sustancias al volante que la Direcci\u00f3n General de Tr\u00e1fico realiz\u00f3 entre el 9 y el 15 de diciembre<\/p>\n<p>Respecto a las pruebas de detecci\u00f3n del alcohol, durante los siete d\u00edas se han realizado 163.801 pruebas y 1.606 conductores dieron positivo. De ellos, 1.359 fueron detectados en controles preventivos, 104 tras haber cometido una infracci\u00f3n, otros 136 por estar implicado en un accidente y 7 m\u00e1s por presentar s\u00edntomas evidentes de ingesta de esta sustancia.<\/p>\n<p>De los 1.606 conductores que dieron positivo, a 242 se les han instruido diligencias para su posterior traslado a la autoridad judicial por superar la tasa de 0,60 mg\/l en aire espirado. Adem\u00e1s, contra otros 6 conductores se han abierto diligencias y han sido puestos a disposici\u00f3n judicial por negarse a realizar las pruebas de alcoholemia.<\/p>\n<p>En lo referente a las drogas, de las 4.466 pruebas de detecci\u00f3n de drogas que se realizaron a conductores, 1.348 resultaron positivas en los test indiciarios, de ellos, 1.149 detectados en controles preventivos, 129 tras haber cometido una infracci\u00f3n y 70 por estar implicado en un accidente.<\/p>\n<p>De los 1.348 conductores que dieron positivo a drogas, a 8 de ellos se les instruy\u00f3 diligencias para su posterior traslado a la autoridad judicial, 7 por conducir bajo las influencia de drogas t\u00f3xicas, estupefacientes o sustancias psicotr\u00f3picas y a 1 por negarse a realizar dichas pruebas.<\/p>\n<p>Como viene siendo habitual, entre las drogas m\u00e1s consumidas est\u00e1n el cannabis (978 casos), la coca\u00edna (407 casos) y las anfetaminas (222 casos).<\/p>\n<p>Las pruebas salivares para la detecci\u00f3n de la presencia de drogas en los conductores se est\u00e1n incrementando progresivamente con la idea de llegar a generalizarse como las que se hacen para la detecci\u00f3n del alcohol.<\/p>\n<p>Seg\u00fan recoge la Fiscal\u00eda de Seguridad Vial en su memoria anual, en 2018 se dictaron 56.173 sentencias por conducir con exceso de alcohol (tasa superior a 0,60mg\/l en aire o 1,2 gr\/l en sangre) o bajo la influencia de drogas.<\/p>\n<p><strong>Colaboraci\u00f3n de Polic\u00edas auton\u00f3micas y locales<\/strong><\/p>\n<p>Como viene siendo habitual en las campa\u00f1as que lleva a cabo la Direcci\u00f3n General de Tr\u00e1fico, la colaboraci\u00f3n de las polic\u00edas locales y auton\u00f3micas ha sido muy importante, ya que los controles de alcohol y drogas se han realizado tanto en v\u00edas interurbanas como en urbanas. Los datos de estas polic\u00edas todav\u00eda se est\u00e1n procesando y habr\u00e1 que sumarlas a las presentadas en esta nota.<\/p>\n<p>Pese a que la campa\u00f1a ha finalizado, los agentes de Tr\u00e1fico de la Guardia Civil continuar\u00e1n realizando controles de alcohol y drogas a los conductores a cualquier hora del d\u00eda y en cualquier carretera con el objetivo de disuadirlos de conducir.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante una semana, 165.284 conductores han sido requeridos por los agentes de la Agrupaci\u00f3n de Tr\u00e1fico de la Guardia Civil para realizar la prueba de control de alcohol y\/o drogas, con motivo de la campa\u00f1a de concienciaci\u00f3n y vigilancia del consumo de estas sustancias al volante que la Direcci\u00f3n General de Tr\u00e1fico realiz\u00f3 entre el<\/p>\n","protected":false},"author":1,"featured_media":135181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-135180","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Durante una semana, 165.284 conductores han sido requeridos por los agentes de la Agrupaci\u00f3n de Tr\u00e1fico de la Guardia Civil para realizar la prueba de control de alcohol y\/o drogas, con motivo de la campa\u00f1a de concienciaci\u00f3n y vigilancia del consumo de estas sustancias al volante que la Direcci\u00f3n General de Tr\u00e1fico realiz\u00f3 entre el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Durante una semana, 165.284 conductores han sido requeridos por los agentes de la Agrupaci\u00f3n de Tr\u00e1fico de la Guardia Civil para realizar la prueba de control de alcohol y\/o drogas, con motivo de la campa\u00f1a de concienciaci\u00f3n y vigilancia del consumo de estas sustancias al volante que la Direcci\u00f3n General de Tr\u00e1fico realiz\u00f3 entre el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-12-22T20:53:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-12-22T20:53:24+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Durante una semana, 165.284 conductores han sido requeridos por los agentes de la Agrupaci\u00f3n de Tr\u00e1fico de la Guardia Civil para realizar la prueba de control de alcohol y\/o drogas, con motivo de la campa\u00f1a de concienciaci\u00f3n y vigilancia del consumo de estas sustancias al volante que la Direcci\u00f3n General de Tr\u00e1fico realiz\u00f3 entre el\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#listItem\",\"name\":\"M\\u00e1s de 400 conductores son detectados cada d\\u00eda al volante habiendo consumido alcohol o drogas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#listItem\",\"position\":3,\"name\":\"M\\u00e1s de 400 conductores son detectados cada d\\u00eda al volante habiendo consumido alcohol o drogas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#newsarticle\",\"name\":\"M\\u00e1s de 400 conductores son detectados cada d\\u00eda al volante habiendo consumido alcohol o drogas | Cand\\u00e1s 365\",\"headline\":\"M\\u00e1s de 400 conductores son detectados cada d\\u00eda al volante habiendo consumido alcohol o drogas\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/191219-alcoholemia.jpg\",\"width\":512,\"height\":340},\"datePublished\":\"2019-12-22T20:53:24+01:00\",\"dateModified\":\"2019-12-22T20:53:24+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el diciembre 22, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/\",\"name\":\"M\\u00e1s de 400 conductores son detectados cada d\\u00eda al volante habiendo consumido alcohol o drogas | Cand\\u00e1s 365\",\"description\":\"Durante una semana, 165.284 conductores han sido requeridos por los agentes de la Agrupaci\\u00f3n de Tr\\u00e1fico de la Guardia Civil para realizar la prueba de control de alcohol y\\\/o drogas, con motivo de la campa\\u00f1a de concienciaci\\u00f3n y vigilancia del consumo de estas sustancias al volante que la Direcci\\u00f3n General de Tr\\u00e1fico realiz\\u00f3 entre el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/191219-alcoholemia.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#mainImage\",\"width\":512,\"height\":340},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\\\/#mainImage\"},\"datePublished\":\"2019-12-22T20:53:24+01:00\",\"dateModified\":\"2019-12-22T20:53:24+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas | Cand\u00e1s 365","description":"Durante una semana, 165.284 conductores han sido requeridos por los agentes de la Agrupaci\u00f3n de Tr\u00e1fico de la Guardia Civil para realizar la prueba de control de alcohol y\/o drogas, con motivo de la campa\u00f1a de concienciaci\u00f3n y vigilancia del consumo de estas sustancias al volante que la Direcci\u00f3n General de Tr\u00e1fico realiz\u00f3 entre el","canonical_url":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#listItem","name":"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#listItem","position":3,"name":"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#newsarticle","name":"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas | Cand\u00e1s 365","headline":"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia.jpg","width":512,"height":340},"datePublished":"2019-12-22T20:53:24+01:00","dateModified":"2019-12-22T20:53:24+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el diciembre 22, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#webpage","url":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/","name":"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas | Cand\u00e1s 365","description":"Durante una semana, 165.284 conductores han sido requeridos por los agentes de la Agrupaci\u00f3n de Tr\u00e1fico de la Guardia Civil para realizar la prueba de control de alcohol y\/o drogas, con motivo de la campa\u00f1a de concienciaci\u00f3n y vigilancia del consumo de estas sustancias al volante que la Direcci\u00f3n General de Tr\u00e1fico realiz\u00f3 entre el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia.jpg","@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#mainImage","width":512,"height":340},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/#mainImage"},"datePublished":"2019-12-22T20:53:24+01:00","dateModified":"2019-12-22T20:53:24+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas | Cand\u00e1s 365","og:description":"Durante una semana, 165.284 conductores han sido requeridos por los agentes de la Agrupaci\u00f3n de Tr\u00e1fico de la Guardia Civil para realizar la prueba de control de alcohol y\/o drogas, con motivo de la campa\u00f1a de concienciaci\u00f3n y vigilancia del consumo de estas sustancias al volante que la Direcci\u00f3n General de Tr\u00e1fico realiz\u00f3 entre el","og:url":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia.jpg","og:image:width":512,"og:image:height":340,"article:published_time":"2019-12-22T20:53:24+00:00","article:modified_time":"2019-12-22T20:53:24+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas | Cand\u00e1s 365","twitter:description":"Durante una semana, 165.284 conductores han sido requeridos por los agentes de la Agrupaci\u00f3n de Tr\u00e1fico de la Guardia Civil para realizar la prueba de control de alcohol y\/o drogas, con motivo de la campa\u00f1a de concienciaci\u00f3n y vigilancia del consumo de estas sustancias al volante que la Direcci\u00f3n General de Tr\u00e1fico realiz\u00f3 entre el","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/12\/191219-alcoholemia.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"135180","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 13:15:20","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:49:01","updated":"2026-05-25 13:15:20"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tM\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"M\u00e1s de 400 conductores son detectados cada d\u00eda al volante habiendo consumido alcohol o drogas","link":"https:\/\/candas365.es\/noticias\/mas-de-400-conductores-son-detectados-cada-dia-al-volante-habiendo-consumido-alcohol-o-drogas\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/135180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=135180"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/135180\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/135181"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=135180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=135180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=135180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}