{"id":134330,"date":"2019-12-08T23:17:24","date_gmt":"2019-12-08T23:17:24","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=134330"},"modified":"2019-12-08T23:17:24","modified_gmt":"2019-12-08T23:17:24","slug":"lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/","title":{"rendered":"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-98518\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 8 dic (dpa) &#8211; La l\u00edder de la Uni\u00f3n Cristiana Democr\u00e1tica (CDU), Annegret Kramp-Karrenbauer, sugiri\u00f3 tomar nuevas medidas contra Rusia, tras el presunto asesinato por encargo de un georgiano en Berl\u00edn, inform\u00f3 hoy el dominical \u00abBild am Sonntag\u00bb.<\/p>\n<p>\u00abNosotros, en el Gobierno alem\u00e1n, tendremos que discutir y tomar decisiones sobre otras medidas\u00bb, dijo la ministra alemana de Defensa al peri\u00f3dico alem\u00e1n.<\/p>\n<p>\u00abLa parte rusa tiene ahora que por fin contribuir a esclarecer este crimen\u00bb, se\u00f1al\u00f3. Kramp-Karrenbauer a\u00f1adi\u00f3 que el asesinato es una pesada carga para las relaciones entre Alemania y Rusia.<\/p>\n<p>\u00abLas evidencias pesan mucho\u00bb, constat\u00f3 la pol\u00edtica conservadora. \u00abJunto a los asesinatos en Gran Breta\u00f1a y otras actividades rusas, esto confiere una imagen bastante inquietante\u00bb, reconoci\u00f3.<\/p>\n<p>Kramp-Karrenbauer destac\u00f3 que advierte una percepci\u00f3n completamente diferente en los Estados b\u00e1lticos o en Polonia. \u00abAll\u00ed, Rusia viola una y otra vez el espacio a\u00e9reo y lleva a cabo campa\u00f1as de desinformaci\u00f3n\u00bb, explic\u00f3. \u00abNo deber\u00edamos simplemente borrar las experiencias de estos pa\u00edses\u00bb, opin\u00f3.<\/p>\n<p>La Fiscal\u00eda General de Alemania sospecha que el asesinato del ciudadano georgiano, sucedido el pasado 23 de agosto en Berl\u00edn, pudo ser encargado desde instancias estatales en Rusia o en la Rep\u00fablica de Chechenia.<\/p>\n<p>El Ministerio alem\u00e1n de Relaciones Exteriores declar\u00f3 a dos diplom\u00e1ticos rusos personas non grata y los expuls\u00f3 del pa\u00eds debido a la falta de apoyo en la pesquisa por parte de Rusia. La canciller alemana, Angela Merkel, aconsej\u00f3 entonces esperar a los resultados de la investigaci\u00f3n del asesinato.<\/p>\n<p>El Gobierno alem\u00e1n reaccion\u00f3 as\u00ed a la posible vinculaci\u00f3n del servicio secreto ruso en el caso, pocos d\u00edas antes de la cumbre sobre Ucrania que comenzar\u00e1 ma\u00f1ana lunes en Par\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 8 dic (dpa) &#8211; La l\u00edder de la Uni\u00f3n Cristiana Democr\u00e1tica (CDU), Annegret Kramp-Karrenbauer, sugiri\u00f3 tomar nuevas medidas contra Rusia, tras el presunto asesinato por encargo de un georgiano en Berl\u00edn, inform\u00f3 hoy el dominical \u00abBild am Sonntag\u00bb. \u00abNosotros, en el Gobierno alem\u00e1n, tendremos que discutir y tomar decisiones sobre otras medidas\u00bb, dijo la<\/p>\n","protected":false},"author":1,"featured_media":98518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-134330","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 8 dic (dpa) - La l\u00edder de la Uni\u00f3n Cristiana Democr\u00e1tica (CDU), Annegret Kramp-Karrenbauer, sugiri\u00f3 tomar nuevas medidas contra Rusia, tras el presunto asesinato por encargo de un georgiano en Berl\u00edn, inform\u00f3 hoy el dominical &quot;Bild am Sonntag&quot;. &quot;Nosotros, en el Gobierno alem\u00e1n, tendremos que discutir y tomar decisiones sobre otras medidas&quot;, dijo la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 8 dic (dpa) - La l\u00edder de la Uni\u00f3n Cristiana Democr\u00e1tica (CDU), Annegret Kramp-Karrenbauer, sugiri\u00f3 tomar nuevas medidas contra Rusia, tras el presunto asesinato por encargo de un georgiano en Berl\u00edn, inform\u00f3 hoy el dominical &quot;Bild am Sonntag&quot;. &quot;Nosotros, en el Gobierno alem\u00e1n, tendremos que discutir y tomar decisiones sobre otras medidas&quot;, dijo la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-12-08T23:17:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-12-08T23:17:24+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 8 dic (dpa) - La l\u00edder de la Uni\u00f3n Cristiana Democr\u00e1tica (CDU), Annegret Kramp-Karrenbauer, sugiri\u00f3 tomar nuevas medidas contra Rusia, tras el presunto asesinato por encargo de un georgiano en Berl\u00edn, inform\u00f3 hoy el dominical &quot;Bild am Sonntag&quot;. &quot;Nosotros, en el Gobierno alem\u00e1n, tendremos que discutir y tomar decisiones sobre otras medidas&quot;, dijo la\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#listItem\",\"name\":\"L\\u00edder de CDU sugiere m\\u00e1s medidas contra Rusia por asesinato en Berl\\u00edn\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#listItem\",\"position\":3,\"name\":\"L\\u00edder de CDU sugiere m\\u00e1s medidas contra Rusia por asesinato en Berl\\u00edn\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#newsarticle\",\"name\":\"L\\u00edder de CDU sugiere m\\u00e1s medidas contra Rusia por asesinato en Berl\\u00edn | Cand\\u00e1s 365\",\"headline\":\"L\\u00edder de CDU sugiere m\\u00e1s medidas contra Rusia por asesinato en Berl\\u00edn\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/berlin-76509_960_720.jpg\",\"width\":960,\"height\":720},\"datePublished\":\"2019-12-08T23:17:24+01:00\",\"dateModified\":\"2019-12-08T23:17:24+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el diciembre 8, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/\",\"name\":\"L\\u00edder de CDU sugiere m\\u00e1s medidas contra Rusia por asesinato en Berl\\u00edn | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 8 dic (dpa) - La l\\u00edder de la Uni\\u00f3n Cristiana Democr\\u00e1tica (CDU), Annegret Kramp-Karrenbauer, sugiri\\u00f3 tomar nuevas medidas contra Rusia, tras el presunto asesinato por encargo de un georgiano en Berl\\u00edn, inform\\u00f3 hoy el dominical \\\"Bild am Sonntag\\\". \\\"Nosotros, en el Gobierno alem\\u00e1n, tendremos que discutir y tomar decisiones sobre otras medidas\\\", dijo la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/berlin-76509_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#mainImage\",\"width\":960,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\\\/#mainImage\"},\"datePublished\":\"2019-12-08T23:17:24+01:00\",\"dateModified\":\"2019-12-08T23:17:24+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn | Cand\u00e1s 365","description":"Berl\u00edn, 8 dic (dpa) - La l\u00edder de la Uni\u00f3n Cristiana Democr\u00e1tica (CDU), Annegret Kramp-Karrenbauer, sugiri\u00f3 tomar nuevas medidas contra Rusia, tras el presunto asesinato por encargo de un georgiano en Berl\u00edn, inform\u00f3 hoy el dominical \"Bild am Sonntag\". \"Nosotros, en el Gobierno alem\u00e1n, tendremos que discutir y tomar decisiones sobre otras medidas\", dijo la","canonical_url":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#listItem","name":"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#listItem","position":3,"name":"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#newsarticle","name":"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn | Cand\u00e1s 365","headline":"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","width":960,"height":720},"datePublished":"2019-12-08T23:17:24+01:00","dateModified":"2019-12-08T23:17:24+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el diciembre 8, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#webpage","url":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/","name":"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn | Cand\u00e1s 365","description":"Berl\u00edn, 8 dic (dpa) - La l\u00edder de la Uni\u00f3n Cristiana Democr\u00e1tica (CDU), Annegret Kramp-Karrenbauer, sugiri\u00f3 tomar nuevas medidas contra Rusia, tras el presunto asesinato por encargo de un georgiano en Berl\u00edn, inform\u00f3 hoy el dominical \"Bild am Sonntag\". \"Nosotros, en el Gobierno alem\u00e1n, tendremos que discutir y tomar decisiones sobre otras medidas\", dijo la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#mainImage","width":960,"height":720},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/#mainImage"},"datePublished":"2019-12-08T23:17:24+01:00","dateModified":"2019-12-08T23:17:24+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn | Cand\u00e1s 365","og:description":"Berl\u00edn, 8 dic (dpa) - La l\u00edder de la Uni\u00f3n Cristiana Democr\u00e1tica (CDU), Annegret Kramp-Karrenbauer, sugiri\u00f3 tomar nuevas medidas contra Rusia, tras el presunto asesinato por encargo de un georgiano en Berl\u00edn, inform\u00f3 hoy el dominical &quot;Bild am Sonntag&quot;. &quot;Nosotros, en el Gobierno alem\u00e1n, tendremos que discutir y tomar decisiones sobre otras medidas&quot;, dijo la","og:url":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","og:image:width":960,"og:image:height":720,"article:published_time":"2019-12-08T23:17:24+00:00","article:modified_time":"2019-12-08T23:17:24+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 8 dic (dpa) - La l\u00edder de la Uni\u00f3n Cristiana Democr\u00e1tica (CDU), Annegret Kramp-Karrenbauer, sugiri\u00f3 tomar nuevas medidas contra Rusia, tras el presunto asesinato por encargo de un georgiano en Berl\u00edn, inform\u00f3 hoy el dominical &quot;Bild am Sonntag&quot;. &quot;Nosotros, en el Gobierno alem\u00e1n, tendremos que discutir y tomar decisiones sobre otras medidas&quot;, dijo la","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"134330","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-25 10:56:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:49:35","updated":"2026-05-25 10:56:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tL\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"L\u00edder de CDU sugiere m\u00e1s medidas contra Rusia por asesinato en Berl\u00edn","link":"https:\/\/candas365.es\/noticias\/lider-de-cdu-sugiere-mas-medidas-contra-rusia-por-asesinato-en-berlin\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/134330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=134330"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/134330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/98518"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=134330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=134330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=134330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}