{"id":132059,"date":"2019-10-27T16:47:30","date_gmt":"2019-10-27T16:47:30","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=132059"},"modified":"2019-10-27T16:54:23","modified_gmt":"2019-10-27T16:54:23","slug":"derrota-del-candas-cf-el-colloto-gana-2-a-0","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/","title":{"rendered":"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-15439\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/la-mata-360x198.jpg\" alt=\"\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/la-mata-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/la-mata-650x357.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/la-mata-150x82.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/la-mata-450x247.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/la-mata-655x360.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/la-mata-696x385.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/la-mata-764x420.jpg 764w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/09\/la-mata.jpg 766w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El <strong>Cand\u00e1s CF<\/strong> ha sumado una <strong>nueva derrota<\/strong> en la <strong>d\u00e9cima jornada de la Preferente asturiana<\/strong>, los de La Mata visitaban a SD Colloto en un partido que se disputo en la ma\u00f1ana de hoy domingo, <strong>resultado final 2 a 0<\/strong> para los locales que se adelantaban en el marcador en el 19 del primer tiempo y que en el minuto 29 marcaban el segundo y definitivo tanto del partido.<\/p>\n<p><strong>El Cand\u00e1s CF ha sumado 9 puntos en diez encuentros<\/strong> y vive situado en la parte baja de la tabla, con tres victorias en su casillero, siete derrotas y es el <strong>tercer equipo menos goleador de la categor\u00eda con siete tantos anotados<\/strong>, hasta la fecha ha visto como el bal\u00f3n ha traspasado sus redes en 18 ocasiones, un balance nada positivo para <em>un proyecto deportivo que \u201cilusionaba\u201d a los aficionados a principio de temporada<\/em> pero que se ha ido desinflando, adem\u00e1s el Cand\u00e1s CF ha visto como<strong> Ra\u00fal Gonz\u00e1lez abandonaba el club hace una semana<\/strong>, el ya ex t\u00e9cnico del Cand\u00e1s CF era el \u201creferente\u201d y piedra angular de un proyecto \u201cmuy atractivo\u201d presentado por la directiva del club.<\/p>\n<p>El <strong>Cand\u00e1s CF volver\u00e1 a jugar fuera de casa la pr\u00f3xima jornada<\/strong>, el rival ser\u00e1 el <strong>Podes CF,<\/strong> el partido comenzar\u00e1 <strong>a las 15,45 horas del domingo en Builla<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cand\u00e1s CF ha sumado una nueva derrota en la d\u00e9cima jornada de la Preferente asturiana, los de La Mata visitaban a SD Colloto en un partido que se disputo en la ma\u00f1ana de hoy domingo, resultado final 2 a 0 para los locales que se adelantaban en el marcador en el 19 del primer<\/p>\n","protected":false},"author":1,"featured_media":98026,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319,316],"tags":[],"class_list":{"0":"post-132059","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deporte","8":"category-destacadas"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Cand\u00e1s CF ha sumado una nueva derrota en la d\u00e9cima jornada de la Preferente asturiana, los de La Mata visitaban a SD Colloto en un partido que se disputo en la ma\u00f1ana de hoy domingo, resultado final 2 a 0 para los locales que se adelantaban en el marcador en el 19 del primer\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"deporte,destacadas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0 | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Cand\u00e1s CF ha sumado una nueva derrota en la d\u00e9cima jornada de la Preferente asturiana, los de La Mata visitaban a SD Colloto en un partido que se disputo en la ma\u00f1ana de hoy domingo, resultado final 2 a 0 para los locales que se adelantaban en el marcador en el 19 del primer\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"643\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-10-27T16:47:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-10-27T16:54:23+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0 | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Cand\u00e1s CF ha sumado una nueva derrota en la d\u00e9cima jornada de la Preferente asturiana, los de La Mata visitaban a SD Colloto en un partido que se disputo en la ma\u00f1ana de hoy domingo, resultado final 2 a 0 para los locales que se adelantaban en el marcador en el 19 del primer\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/destacadas\\\/#listItem\",\"name\":\"Destacadas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/destacadas\\\/#listItem\",\"position\":2,\"name\":\"Destacadas\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/destacadas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#listItem\",\"name\":\"Derrota del Cand\\u00e1s CF: El Colloto gana 2 a 0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#listItem\",\"position\":3,\"name\":\"Derrota del Cand\\u00e1s CF: El Colloto gana 2 a 0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/destacadas\\\/#listItem\",\"name\":\"Destacadas\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#newsarticle\",\"name\":\"Derrota del Cand\\u00e1s CF: El Colloto gana 2 a 0 | Cand\\u00e1s 365\",\"headline\":\"Derrota del Cand\\u00e1s CF: El Colloto gana 2 a 0\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/football-1406106_960_720-1.jpg\",\"width\":960,\"height\":643},\"datePublished\":\"2019-10-27T16:47:30+01:00\",\"dateModified\":\"2019-10-27T16:54:23+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#webpage\"},\"articleSection\":\"Deporte, Destacadas\",\"dateline\":\"Publicado el octubre 27, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/\",\"name\":\"Derrota del Cand\\u00e1s CF: El Colloto gana 2 a 0 | Cand\\u00e1s 365\",\"description\":\"El Cand\\u00e1s CF ha sumado una nueva derrota en la d\\u00e9cima jornada de la Preferente asturiana, los de La Mata visitaban a SD Colloto en un partido que se disputo en la ma\\u00f1ana de hoy domingo, resultado final 2 a 0 para los locales que se adelantaban en el marcador en el 19 del primer\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/football-1406106_960_720-1.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#mainImage\",\"width\":960,\"height\":643},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/derrota-del-candas-cf-el-colloto-gana-2-a-0\\\/#mainImage\"},\"datePublished\":\"2019-10-27T16:47:30+01:00\",\"dateModified\":\"2019-10-27T16:54:23+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0 | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0 | Cand\u00e1s 365","description":"El Cand\u00e1s CF ha sumado una nueva derrota en la d\u00e9cima jornada de la Preferente asturiana, los de La Mata visitaban a SD Colloto en un partido que se disputo en la ma\u00f1ana de hoy domingo, resultado final 2 a 0 para los locales que se adelantaban en el marcador en el 19 del primer","canonical_url":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/","robots":"max-image-preview:large","keywords":"deporte,destacadas","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/destacadas\/#listItem","name":"Destacadas"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/destacadas\/#listItem","position":2,"name":"Destacadas","item":"https:\/\/candas365.es\/noticias\/category\/destacadas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#listItem","name":"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#listItem","position":3,"name":"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/destacadas\/#listItem","name":"Destacadas"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#newsarticle","name":"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0 | Cand\u00e1s 365","headline":"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1.jpg","width":960,"height":643},"datePublished":"2019-10-27T16:47:30+01:00","dateModified":"2019-10-27T16:54:23+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#webpage"},"articleSection":"Deporte, Destacadas","dateline":"Publicado el octubre 27, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/496a8e03d0c493ede1718b7934145dbdf8d89be1036b0eec9544e1094c9de390?s=96&d=mm&r=g","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#webpage","url":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/","name":"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0 | Cand\u00e1s 365","description":"El Cand\u00e1s CF ha sumado una nueva derrota en la d\u00e9cima jornada de la Preferente asturiana, los de La Mata visitaban a SD Colloto en un partido que se disputo en la ma\u00f1ana de hoy domingo, resultado final 2 a 0 para los locales que se adelantaban en el marcador en el 19 del primer","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1.jpg","@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#mainImage","width":960,"height":643},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/#mainImage"},"datePublished":"2019-10-27T16:47:30+01:00","dateModified":"2019-10-27T16:54:23+01:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0 | Cand\u00e1s 365","og:description":"El Cand\u00e1s CF ha sumado una nueva derrota en la d\u00e9cima jornada de la Preferente asturiana, los de La Mata visitaban a SD Colloto en un partido que se disputo en la ma\u00f1ana de hoy domingo, resultado final 2 a 0 para los locales que se adelantaban en el marcador en el 19 del primer","og:url":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1.jpg","og:image:width":960,"og:image:height":643,"article:published_time":"2019-10-27T16:47:30+00:00","article:modified_time":"2019-10-27T16:54:23+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0 | Cand\u00e1s 365","twitter:description":"El Cand\u00e1s CF ha sumado una nueva derrota en la d\u00e9cima jornada de la Preferente asturiana, los de La Mata visitaban a SD Colloto en un partido que se disputo en la ma\u00f1ana de hoy domingo, resultado final 2 a 0 para los locales que se adelantaban en el marcador en el 19 del primer","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/football-1406106_960_720-1.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"132059","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2025-08-30 16:25:12","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:51:12","updated":"2025-08-30 16:25:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/destacadas\/\" title=\"Destacadas\">Destacadas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDerrota del Cand\u00e1s CF: El Colloto gana 2 a 0\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Destacadas","link":"https:\/\/candas365.es\/noticias\/category\/destacadas\/"},{"label":"Derrota del Cand\u00e1s CF: El Colloto gana 2 a 0","link":"https:\/\/candas365.es\/noticias\/derrota-del-candas-cf-el-colloto-gana-2-a-0\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/132059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=132059"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/132059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/98026"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=132059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=132059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=132059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}