{"id":129242,"date":"2019-08-31T23:20:33","date_gmt":"2019-08-31T23:20:33","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=129242"},"modified":"2019-08-31T23:20:33","modified_gmt":"2019-08-31T23:20:33","slug":"merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/","title":{"rendered":"Merkel y Steinmeier, preocupados por los incendios en el Amazonas"},"content":{"rendered":"<p>Berl\u00edn, 31 ago (dpa) &#8211; El presidente de Alemania, Frank-Walter Steinmeier, manifest\u00f3 hoy su preocupaci\u00f3n por los incendios que devastan la selva del Amazonas, al tiempo que la canciller Angela Merkel le ofreci\u00f3 al presidente brasile\u00f1o, Jair Bolsonaro, colaboraci\u00f3n para proteger la regi\u00f3n amaz\u00f3nica. <\/p>\n<p>Merkel dialog\u00f3 telef\u00f3nicamente con Bolsonaro en la noche del viernes, seg\u00fan inform\u00f3 un portavoz gubernamental.<\/p>\n<p>La jefa de Gobierno destac\u00f3 en la comunicaci\u00f3n su voluntad de cooperar con Brasil en la protecci\u00f3n del Amazonas, indic\u00f3 el portavoz, quien se\u00f1al\u00f3 que ambos l\u00edderes dialogaron adem\u00e1s sobre la situaci\u00f3n en Venezuela.<\/p>\n<p>En tanto, el presidente de Alemania urgi\u00f3 a brindar una mejor protecci\u00f3n a los bosques. <\/p>\n<p>Steinmeier debati\u00f3 sobre temas del futuro con el astronauta Alexander Gerst y la investigadora polar Antje Boetius en la fiesta de los ciudadanos en el castillo de Bellevue en Berl\u00edn, sede de la Jefatura de Estado. <\/p>\n<p>\u00abTenemos que hacer nuestra parte para que la tala del bosque deje de ser atractiva\u00bb, inst\u00f3 el mandatario ante una interrupci\u00f3n del p\u00fablico.<\/p>\n<p>Miles de visitantes aprovecharon el d\u00eda de puertas abiertas para pasear por el jard\u00edn de Bellevue. Seg\u00fan estimaciones policiales, se esperaba la asistencia de unas 15.000 personas. Gerst ya hab\u00eda participado el a\u00f1o pasado en el evento, pero en esa oportunidad a trav\u00e9s de una videollamada desde la estaci\u00f3n espacial ISS. <\/p>\n<p>En Brasil se registran actualmente los incendios m\u00e1s graves de los \u00faltimos a\u00f1os. Desde principios de a\u00f1o, se han contabilizado m\u00e1s de 87.000 incendios en el pa\u00eds sudamericano, un 76 por ciento m\u00e1s que en el mismo per\u00edodo del a\u00f1o pasado.<\/p>\n<p>Sin embargo, seg\u00fan la agencia espacial estadounidense NASA, el n\u00famero de incendios sigue estando aproximadamente en l\u00ednea con la media de los \u00faltimos 15 a\u00f1os. Entre 2002 y 2007, as\u00ed como en 2010, hubo muchos m\u00e1s incendios.<\/p>\n<p>En el marco del impacto que generaron los devastadores incendios y en vista de la controvertida pol\u00edtica ambiental de Bolsonaro, se ha puesto en debate el sentido de la continuidad del Fondo de la Amazon\u00eda que re\u00fane fondos internacionales de ayuda.<\/p>\n<p>Este fondo es financiado principalmente por Noruega y, en una proporci\u00f3n mucho menor, tambi\u00e9n por Alemania. Con estos recursos se financian proyectos de protecci\u00f3n ambiental, reforestaci\u00f3n y desarrollo sustentable para la regi\u00f3n del Amazonas. <\/p>\n<p>Noruega fue el \u00faltimo pa\u00eds que detuvo sus pagos. La ministra de Medio Ambiente de Alemania, Svenja Schulze, anunci\u00f3 que congelar\u00eda las contribuciones de su cartera. La participaci\u00f3n de Alemania en el Fondo de la Amazon\u00eda a trav\u00e9s del Ministerio alem\u00e1n de Desarrollo no se ha visto afectada hasta ahora.<\/p>\n<p>Bolsonaro ha condicionado recientemente la aceptaci\u00f3n de una oferta de ayuda de los pa\u00edses del G7. El presidente brasile\u00f1o acusa a los pa\u00edses industrializados ricos de ignorar la soberan\u00eda de su pa\u00eds y de vigilar los recursos minerales de la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 31 ago (dpa) &#8211; El presidente de Alemania, Frank-Walter Steinmeier, manifest\u00f3 hoy su preocupaci\u00f3n por los incendios que devastan la selva del Amazonas, al tiempo que la canciller Angela Merkel le ofreci\u00f3 al presidente brasile\u00f1o, Jair Bolsonaro, colaboraci\u00f3n para proteger la regi\u00f3n amaz\u00f3nica. Merkel dialog\u00f3 telef\u00f3nicamente con Bolsonaro en la noche del viernes, seg\u00fan<\/p>\n","protected":false},"author":1,"featured_media":128975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-129242","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 31 ago (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, manifest\u00f3 hoy su preocupaci\u00f3n por los incendios que devastan la selva del Amazonas, al tiempo que la canciller Angela Merkel le ofreci\u00f3 al presidente brasile\u00f1o, Jair Bolsonaro, colaboraci\u00f3n para proteger la regi\u00f3n amaz\u00f3nica. Merkel dialog\u00f3 telef\u00f3nicamente con Bolsonaro en la noche del viernes, seg\u00fan\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Merkel y Steinmeier, preocupados por los incendios en el Amazonas | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 31 ago (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, manifest\u00f3 hoy su preocupaci\u00f3n por los incendios que devastan la selva del Amazonas, al tiempo que la canciller Angela Merkel le ofreci\u00f3 al presidente brasile\u00f1o, Jair Bolsonaro, colaboraci\u00f3n para proteger la regi\u00f3n amaz\u00f3nica. Merkel dialog\u00f3 telef\u00f3nicamente con Bolsonaro en la noche del viernes, seg\u00fan\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/newspapers-3488861_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/newspapers-3488861_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-08-31T23:20:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-08-31T23:20:33+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Merkel y Steinmeier, preocupados por los incendios en el Amazonas | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 31 ago (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, manifest\u00f3 hoy su preocupaci\u00f3n por los incendios que devastan la selva del Amazonas, al tiempo que la canciller Angela Merkel le ofreci\u00f3 al presidente brasile\u00f1o, Jair Bolsonaro, colaboraci\u00f3n para proteger la regi\u00f3n amaz\u00f3nica. Merkel dialog\u00f3 telef\u00f3nicamente con Bolsonaro en la noche del viernes, seg\u00fan\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/newspapers-3488861_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#listItem\",\"name\":\"Merkel y Steinmeier, preocupados por los incendios en el Amazonas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#listItem\",\"position\":3,\"name\":\"Merkel y Steinmeier, preocupados por los incendios en el Amazonas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#newsarticle\",\"name\":\"Merkel y Steinmeier, preocupados por los incendios en el Amazonas | Cand\\u00e1s 365\",\"headline\":\"Merkel y Steinmeier, preocupados por los incendios en el Amazonas\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/newspapers-3488861_960_720.jpg\",\"width\":960,\"height\":640},\"datePublished\":\"2019-08-31T23:20:33+02:00\",\"dateModified\":\"2019-08-31T23:20:33+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el agosto 31, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/\",\"name\":\"Merkel y Steinmeier, preocupados por los incendios en el Amazonas | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 31 ago (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, manifest\\u00f3 hoy su preocupaci\\u00f3n por los incendios que devastan la selva del Amazonas, al tiempo que la canciller Angela Merkel le ofreci\\u00f3 al presidente brasile\\u00f1o, Jair Bolsonaro, colaboraci\\u00f3n para proteger la regi\\u00f3n amaz\\u00f3nica. Merkel dialog\\u00f3 telef\\u00f3nicamente con Bolsonaro en la noche del viernes, seg\\u00fan\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/newspapers-3488861_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\\\/#mainImage\"},\"datePublished\":\"2019-08-31T23:20:33+02:00\",\"dateModified\":\"2019-08-31T23:20:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Merkel y Steinmeier, preocupados por los incendios en el Amazonas | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Merkel y Steinmeier, preocupados por los incendios en el Amazonas | Cand\u00e1s 365","description":"Berl\u00edn, 31 ago (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, manifest\u00f3 hoy su preocupaci\u00f3n por los incendios que devastan la selva del Amazonas, al tiempo que la canciller Angela Merkel le ofreci\u00f3 al presidente brasile\u00f1o, Jair Bolsonaro, colaboraci\u00f3n para proteger la regi\u00f3n amaz\u00f3nica. Merkel dialog\u00f3 telef\u00f3nicamente con Bolsonaro en la noche del viernes, seg\u00fan","canonical_url":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#listItem","name":"Merkel y Steinmeier, preocupados por los incendios en el Amazonas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#listItem","position":3,"name":"Merkel y Steinmeier, preocupados por los incendios en el Amazonas","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#newsarticle","name":"Merkel y Steinmeier, preocupados por los incendios en el Amazonas | Cand\u00e1s 365","headline":"Merkel y Steinmeier, preocupados por los incendios en el Amazonas","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/newspapers-3488861_960_720.jpg","width":960,"height":640},"datePublished":"2019-08-31T23:20:33+02:00","dateModified":"2019-08-31T23:20:33+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el agosto 31, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#webpage","url":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/","name":"Merkel y Steinmeier, preocupados por los incendios en el Amazonas | Cand\u00e1s 365","description":"Berl\u00edn, 31 ago (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, manifest\u00f3 hoy su preocupaci\u00f3n por los incendios que devastan la selva del Amazonas, al tiempo que la canciller Angela Merkel le ofreci\u00f3 al presidente brasile\u00f1o, Jair Bolsonaro, colaboraci\u00f3n para proteger la regi\u00f3n amaz\u00f3nica. Merkel dialog\u00f3 telef\u00f3nicamente con Bolsonaro en la noche del viernes, seg\u00fan","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/newspapers-3488861_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/#mainImage"},"datePublished":"2019-08-31T23:20:33+02:00","dateModified":"2019-08-31T23:20:33+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Merkel y Steinmeier, preocupados por los incendios en el Amazonas | Cand\u00e1s 365","og:description":"Berl\u00edn, 31 ago (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, manifest\u00f3 hoy su preocupaci\u00f3n por los incendios que devastan la selva del Amazonas, al tiempo que la canciller Angela Merkel le ofreci\u00f3 al presidente brasile\u00f1o, Jair Bolsonaro, colaboraci\u00f3n para proteger la regi\u00f3n amaz\u00f3nica. Merkel dialog\u00f3 telef\u00f3nicamente con Bolsonaro en la noche del viernes, seg\u00fan","og:url":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/newspapers-3488861_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/newspapers-3488861_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2019-08-31T23:20:33+00:00","article:modified_time":"2019-08-31T23:20:33+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Merkel y Steinmeier, preocupados por los incendios en el Amazonas | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 31 ago (dpa) - El presidente de Alemania, Frank-Walter Steinmeier, manifest\u00f3 hoy su preocupaci\u00f3n por los incendios que devastan la selva del Amazonas, al tiempo que la canciller Angela Merkel le ofreci\u00f3 al presidente brasile\u00f1o, Jair Bolsonaro, colaboraci\u00f3n para proteger la regi\u00f3n amaz\u00f3nica. Merkel dialog\u00f3 telef\u00f3nicamente con Bolsonaro en la noche del viernes, seg\u00fan","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/newspapers-3488861_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"129242","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-24 21:06:22","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:53:15","updated":"2026-05-24 21:06:22","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMerkel y Steinmeier, preocupados por los incendios en el Amazonas\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Merkel y Steinmeier, preocupados por los incendios en el Amazonas","link":"https:\/\/candas365.es\/noticias\/merkel-y-steinmeier-preocupados-por-los-incendios-en-el-amazonas\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/129242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=129242"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/129242\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/128975"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=129242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=129242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=129242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}