{"id":129240,"date":"2019-08-31T23:19:37","date_gmt":"2019-08-31T23:19:37","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=129240"},"modified":"2019-08-31T23:19:37","modified_gmt":"2019-08-31T23:19:37","slug":"obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/","title":{"rendered":"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-129201\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720-360x152.jpg\" alt=\"\" width=\"360\" height=\"152\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720-360x152.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720-768x325.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720-655x277.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720-696x294.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Berl\u00edn, 31 ago (dpa) &#8211; Obipos cat\u00f3licos alemanes y polacos llamaron hoy a no poner en riesgo la reconciliaci\u00f3n, al recordar de forma conjunta la invasi\u00f3n hace 80 a\u00f1os de Alemania a Polonia que dio inicio a la Segunda Guerra Mundial.<\/p>\n<p>En una declaraci\u00f3n distribuida hoy, ambas conferencias episcopales advirtieron de no poner en riesgo la reconciliaci\u00f3n lograda por razones pol\u00edticas, a la vez que instaron a profundizar la unidad de Europa.<\/p>\n<p>\u00abEn el 80 aniversario del comienzo de la guerra recordamos a seis millones de polacos, entre ellos tres millones de jud\u00edos, que fueron v\u00edctimas del criminal sistema nazi. Somos conscientes del dolor que han sufrido las v\u00edctimas y sus familias y que a\u00fan hoy se siente\u00bb, dice la declaraci\u00f3n conjunta.<\/p>\n<p>El documento recuerda asimismo que la guerra \u00abcaus\u00f3 m\u00e1s desgracias y sufrimientos humanos, en particular a causa de las medidas de reasentamiento\u00bb.<\/p>\n<p>\u00abMillones de polacos y luego tambi\u00e9n alemanes se vieron obligados a abandonar sus viviendas y buscar un nuevo hogar\u00bb, se\u00f1ala.<\/p>\n<p>Afirmaron que desde hace tiempo ambas partes recorren el camino de la reconciliaci\u00f3n. \u00abSomos conscientes sin embargo de que los frutos de la reconciliaci\u00f3n deben ser manejados de forma responsable, no deben ser dejados imprudentemente a merced del inter\u00e9s pol\u00edtico\u00bb, sostiene el documento.<\/p>\n<p>\u00abHoy depende de nosotros consolidar y profundizar la unidad de Europa, construida sobre bases cristianas, a pesar de las diferencias hist\u00f3ricas entre naciones y Estados individuales\u00bb, insta el comunicado conjunto.<\/p>\n<p>La relaci\u00f3n entre Alemania y Polonia se ha enfriado en los \u00faltimos a\u00f1os desde que el Gobierno conservador nacional asumi\u00f3 el cargo en Varsovia.<\/p>\n<p>En la actualidad hay nuevas disputas, ya que Varsovia reclama reparaciones que Berl\u00edn rechaza a la vista de los logros alcanzados y acuerdos anteriores. Adem\u00e1s, Varsovia est\u00e1 en desacuerdo con la Comisi\u00f3n Europea en Bruselas, especialmente en la discusi\u00f3n sobre la admisi\u00f3n de refugiados y cuestiones sobre el Estado de Derecho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 31 ago (dpa) &#8211; Obipos cat\u00f3licos alemanes y polacos llamaron hoy a no poner en riesgo la reconciliaci\u00f3n, al recordar de forma conjunta la invasi\u00f3n hace 80 a\u00f1os de Alemania a Polonia que dio inicio a la Segunda Guerra Mundial. En una declaraci\u00f3n distribuida hoy, ambas conferencias episcopales advirtieron de no poner en riesgo<\/p>\n","protected":false},"author":1,"featured_media":129201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-129240","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 31 ago (dpa) - Obipos cat\u00f3licos alemanes y polacos llamaron hoy a no poner en riesgo la reconciliaci\u00f3n, al recordar de forma conjunta la invasi\u00f3n hace 80 a\u00f1os de Alemania a Polonia que dio inicio a la Segunda Guerra Mundial. En una declaraci\u00f3n distribuida hoy, ambas conferencias episcopales advirtieron de no poner en riesgo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 31 ago (dpa) - Obipos cat\u00f3licos alemanes y polacos llamaron hoy a no poner en riesgo la reconciliaci\u00f3n, al recordar de forma conjunta la invasi\u00f3n hace 80 a\u00f1os de Alemania a Polonia que dio inicio a la Segunda Guerra Mundial. En una declaraci\u00f3n distribuida hoy, ambas conferencias episcopales advirtieron de no poner en riesgo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-08-31T23:19:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-08-31T23:19:37+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 31 ago (dpa) - Obipos cat\u00f3licos alemanes y polacos llamaron hoy a no poner en riesgo la reconciliaci\u00f3n, al recordar de forma conjunta la invasi\u00f3n hace 80 a\u00f1os de Alemania a Polonia que dio inicio a la Segunda Guerra Mundial. En una declaraci\u00f3n distribuida hoy, ambas conferencias episcopales advirtieron de no poner en riesgo\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#listItem\",\"name\":\"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#listItem\",\"position\":3,\"name\":\"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#newsarticle\",\"name\":\"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\\u00f3n | Cand\\u00e1s 365\",\"headline\":\"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/krakow-966774_960_720.jpg\",\"width\":960,\"height\":406},\"datePublished\":\"2019-08-31T23:19:37+02:00\",\"dateModified\":\"2019-08-31T23:19:37+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el agosto 31, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/\",\"name\":\"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\\u00f3n | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 31 ago (dpa) - Obipos cat\\u00f3licos alemanes y polacos llamaron hoy a no poner en riesgo la reconciliaci\\u00f3n, al recordar de forma conjunta la invasi\\u00f3n hace 80 a\\u00f1os de Alemania a Polonia que dio inicio a la Segunda Guerra Mundial. En una declaraci\\u00f3n distribuida hoy, ambas conferencias episcopales advirtieron de no poner en riesgo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/krakow-966774_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#mainImage\",\"width\":960,\"height\":406},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\\\/#mainImage\"},\"datePublished\":\"2019-08-31T23:19:37+02:00\",\"dateModified\":\"2019-08-31T23:19:37+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n | Cand\u00e1s 365","description":"Berl\u00edn, 31 ago (dpa) - Obipos cat\u00f3licos alemanes y polacos llamaron hoy a no poner en riesgo la reconciliaci\u00f3n, al recordar de forma conjunta la invasi\u00f3n hace 80 a\u00f1os de Alemania a Polonia que dio inicio a la Segunda Guerra Mundial. En una declaraci\u00f3n distribuida hoy, ambas conferencias episcopales advirtieron de no poner en riesgo","canonical_url":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#listItem","name":"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#listItem","position":3,"name":"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#newsarticle","name":"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n | Cand\u00e1s 365","headline":"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720.jpg","width":960,"height":406},"datePublished":"2019-08-31T23:19:37+02:00","dateModified":"2019-08-31T23:19:37+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el agosto 31, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#webpage","url":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/","name":"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n | Cand\u00e1s 365","description":"Berl\u00edn, 31 ago (dpa) - Obipos cat\u00f3licos alemanes y polacos llamaron hoy a no poner en riesgo la reconciliaci\u00f3n, al recordar de forma conjunta la invasi\u00f3n hace 80 a\u00f1os de Alemania a Polonia que dio inicio a la Segunda Guerra Mundial. En una declaraci\u00f3n distribuida hoy, ambas conferencias episcopales advirtieron de no poner en riesgo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#mainImage","width":960,"height":406},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/#mainImage"},"datePublished":"2019-08-31T23:19:37+02:00","dateModified":"2019-08-31T23:19:37+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n | Cand\u00e1s 365","og:description":"Berl\u00edn, 31 ago (dpa) - Obipos cat\u00f3licos alemanes y polacos llamaron hoy a no poner en riesgo la reconciliaci\u00f3n, al recordar de forma conjunta la invasi\u00f3n hace 80 a\u00f1os de Alemania a Polonia que dio inicio a la Segunda Guerra Mundial. En una declaraci\u00f3n distribuida hoy, ambas conferencias episcopales advirtieron de no poner en riesgo","og:url":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720.jpg","og:image:width":960,"og:image:height":406,"article:published_time":"2019-08-31T23:19:37+00:00","article:modified_time":"2019-08-31T23:19:37+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 31 ago (dpa) - Obipos cat\u00f3licos alemanes y polacos llamaron hoy a no poner en riesgo la reconciliaci\u00f3n, al recordar de forma conjunta la invasi\u00f3n hace 80 a\u00f1os de Alemania a Polonia que dio inicio a la Segunda Guerra Mundial. En una declaraci\u00f3n distribuida hoy, ambas conferencias episcopales advirtieron de no poner en riesgo","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/krakow-966774_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"129240","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-24 21:06:21","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:53:15","updated":"2026-05-24 21:06:21","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tObispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Obispos alemanes y polacos piden no poner en peligro la reconciliaci\u00f3n","link":"https:\/\/candas365.es\/noticias\/obispos-alemanes-y-polacos-piden-no-poner-en-peligro-la-reconciliacion\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/129240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=129240"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/129240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/129201"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=129240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=129240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=129240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}