{"id":129238,"date":"2019-08-31T23:18:11","date_gmt":"2019-08-31T23:18:11","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=129238"},"modified":"2019-08-31T23:18:11","modified_gmt":"2019-08-31T23:18:11","slug":"doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/","title":{"rendered":"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-14622\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/merkel-360x198.jpg\" alt=\"\" width=\"360\" height=\"198\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/merkel-360x198.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/merkel-650x357.jpg 650w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/merkel-150x82.jpg 150w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/merkel-450x247.jpg 450w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2015\/08\/merkel.jpg 655w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>Leipzig (Alemania), 31 oct (dpa) &#8211; La canciller alemana, Angela Merkel, recibi\u00f3 hoy el t\u00edtulo de doctora \u00abhonoris causa\u00bb de la Universidad de Comercio de Leipzig en reconocimiento a su estilo de liderazgo pol\u00edtico.<\/p>\n<p>En el discurso de agradecimiento, la pol\u00edtica democristiana, que dirige los destinos de Alemania desde 2005, hizo un alegato a favor de la b\u00fasqueda de consensos. \u00abSin concesiones, una sociedad no puede mantenerse unida\u00bb, destac\u00f3.<\/p>\n<p>Merkel acumula ya 17 doctorados \u00abhonoris causa\u00bb, entre ellos uno de la Universidad de Harvard y tres de universidades de Israel. La pol\u00edtica germana, de 65 a\u00f1os, es doctora en f\u00edsica.<\/p>\n<p>La ex directora del Fondo Monetario Internacional y pr\u00f3xima presidenta del Banco Central Europeo, Christine Lagarde, elogi\u00f3 a Merkel en el discurso laudatorio.<\/p>\n<p>\u00abLa canciller Merkel ha influido en millones de mujeres en todo el mundo. Yo puedo dar cuenta de ello porque soy una de esas mujeres\u00bb, dijo la pol\u00edtica francesa.<\/p>\n<p>Lagarde cont\u00f3 que era ministra en Francia cuando Merkel asumi\u00f3 la jefatura de gobierno de Alemania. \u00abFue una inspiraci\u00f3n para m\u00ed. Ella no lo sabe pero lo fue\u00bb.<\/p>\n<p>Asimismo indic\u00f3 que el estilo de Merkel se caracteriza por cuatro \u00abd\u00bb: diplomacia, diligencia, determinaci\u00f3n y deber, elementos con los que imprimi\u00f3 su sello a la pol\u00edtica europea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leipzig (Alemania), 31 oct (dpa) &#8211; La canciller alemana, Angela Merkel, recibi\u00f3 hoy el t\u00edtulo de doctora \u00abhonoris causa\u00bb de la Universidad de Comercio de Leipzig en reconocimiento a su estilo de liderazgo pol\u00edtico. En el discurso de agradecimiento, la pol\u00edtica democristiana, que dirige los destinos de Alemania desde 2005, hizo un alegato a favor<\/p>\n","protected":false},"author":1,"featured_media":98518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-129238","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Leipzig (Alemania), 31 oct (dpa) - La canciller alemana, Angela Merkel, recibi\u00f3 hoy el t\u00edtulo de doctora &quot;honoris causa&quot; de la Universidad de Comercio de Leipzig en reconocimiento a su estilo de liderazgo pol\u00edtico. En el discurso de agradecimiento, la pol\u00edtica democristiana, que dirige los destinos de Alemania desde 2005, hizo un alegato a favor\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Leipzig (Alemania), 31 oct (dpa) - La canciller alemana, Angela Merkel, recibi\u00f3 hoy el t\u00edtulo de doctora &quot;honoris causa&quot; de la Universidad de Comercio de Leipzig en reconocimiento a su estilo de liderazgo pol\u00edtico. En el discurso de agradecimiento, la pol\u00edtica democristiana, que dirige los destinos de Alemania desde 2005, hizo un alegato a favor\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-08-31T23:18:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-08-31T23:18:11+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Leipzig (Alemania), 31 oct (dpa) - La canciller alemana, Angela Merkel, recibi\u00f3 hoy el t\u00edtulo de doctora &quot;honoris causa&quot; de la Universidad de Comercio de Leipzig en reconocimiento a su estilo de liderazgo pol\u00edtico. En el discurso de agradecimiento, la pol\u00edtica democristiana, que dirige los destinos de Alemania desde 2005, hizo un alegato a favor\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#listItem\",\"name\":\"Doctorado honor\\u00edfico para Merkel por su estilo de liderazgo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#listItem\",\"position\":3,\"name\":\"Doctorado honor\\u00edfico para Merkel por su estilo de liderazgo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#newsarticle\",\"name\":\"Doctorado honor\\u00edfico para Merkel por su estilo de liderazgo | Cand\\u00e1s 365\",\"headline\":\"Doctorado honor\\u00edfico para Merkel por su estilo de liderazgo\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/berlin-76509_960_720.jpg\",\"width\":960,\"height\":720},\"datePublished\":\"2019-08-31T23:18:11+02:00\",\"dateModified\":\"2019-08-31T23:18:11+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el agosto 31, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/\",\"name\":\"Doctorado honor\\u00edfico para Merkel por su estilo de liderazgo | Cand\\u00e1s 365\",\"description\":\"Leipzig (Alemania), 31 oct (dpa) - La canciller alemana, Angela Merkel, recibi\\u00f3 hoy el t\\u00edtulo de doctora \\\"honoris causa\\\" de la Universidad de Comercio de Leipzig en reconocimiento a su estilo de liderazgo pol\\u00edtico. En el discurso de agradecimiento, la pol\\u00edtica democristiana, que dirige los destinos de Alemania desde 2005, hizo un alegato a favor\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/berlin-76509_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#mainImage\",\"width\":960,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\\\/#mainImage\"},\"datePublished\":\"2019-08-31T23:18:11+02:00\",\"dateModified\":\"2019-08-31T23:18:11+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Doctorado honor\u00edfico para Merkel por su estilo de liderazgo | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo | Cand\u00e1s 365","description":"Leipzig (Alemania), 31 oct (dpa) - La canciller alemana, Angela Merkel, recibi\u00f3 hoy el t\u00edtulo de doctora \"honoris causa\" de la Universidad de Comercio de Leipzig en reconocimiento a su estilo de liderazgo pol\u00edtico. En el discurso de agradecimiento, la pol\u00edtica democristiana, que dirige los destinos de Alemania desde 2005, hizo un alegato a favor","canonical_url":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#listItem","name":"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#listItem","position":3,"name":"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#newsarticle","name":"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo | Cand\u00e1s 365","headline":"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","width":960,"height":720},"datePublished":"2019-08-31T23:18:11+02:00","dateModified":"2019-08-31T23:18:11+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el agosto 31, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#webpage","url":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/","name":"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo | Cand\u00e1s 365","description":"Leipzig (Alemania), 31 oct (dpa) - La canciller alemana, Angela Merkel, recibi\u00f3 hoy el t\u00edtulo de doctora \"honoris causa\" de la Universidad de Comercio de Leipzig en reconocimiento a su estilo de liderazgo pol\u00edtico. En el discurso de agradecimiento, la pol\u00edtica democristiana, que dirige los destinos de Alemania desde 2005, hizo un alegato a favor","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#mainImage","width":960,"height":720},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/#mainImage"},"datePublished":"2019-08-31T23:18:11+02:00","dateModified":"2019-08-31T23:18:11+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo | Cand\u00e1s 365","og:description":"Leipzig (Alemania), 31 oct (dpa) - La canciller alemana, Angela Merkel, recibi\u00f3 hoy el t\u00edtulo de doctora &quot;honoris causa&quot; de la Universidad de Comercio de Leipzig en reconocimiento a su estilo de liderazgo pol\u00edtico. En el discurso de agradecimiento, la pol\u00edtica democristiana, que dirige los destinos de Alemania desde 2005, hizo un alegato a favor","og:url":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","og:image:width":960,"og:image:height":720,"article:published_time":"2019-08-31T23:18:11+00:00","article:modified_time":"2019-08-31T23:18:11+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo | Cand\u00e1s 365","twitter:description":"Leipzig (Alemania), 31 oct (dpa) - La canciller alemana, Angela Merkel, recibi\u00f3 hoy el t\u00edtulo de doctora &quot;honoris causa&quot; de la Universidad de Comercio de Leipzig en reconocimiento a su estilo de liderazgo pol\u00edtico. En el discurso de agradecimiento, la pol\u00edtica democristiana, que dirige los destinos de Alemania desde 2005, hizo un alegato a favor","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"129238","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-24 21:06:20","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:53:15","updated":"2026-05-24 21:06:20","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tDoctorado honor\u00edfico para Merkel por su estilo de liderazgo\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Doctorado honor\u00edfico para Merkel por su estilo de liderazgo","link":"https:\/\/candas365.es\/noticias\/doctorado-honorifico-para-merkel-por-su-estilo-de-liderazgo\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/129238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=129238"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/129238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/98518"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=129238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=129238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=129238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}