{"id":129167,"date":"2019-08-31T00:50:16","date_gmt":"2019-08-31T00:50:16","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=129167"},"modified":"2019-08-31T00:50:16","modified_gmt":"2019-08-31T00:50:16","slug":"la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/","title":{"rendered":"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial"},"content":{"rendered":"<figure id=\"attachment_129168\" aria-describedby=\"caption-attachment-129168\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-129168\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa-360x211.jpg\" alt=\"\" width=\"360\" height=\"211\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa-360x211.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa-768x449.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa-655x383.jpg 655w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa-696x407.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa-718x420.jpg 718w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa.jpg 944w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-129168\" class=\"wp-caption-text\">Foto: Marc M\u00fcller\/dpa<\/figcaption><\/figure>\n<p>Berl\u00edn, 29 ago (dpa) &#8211; Miles de familias en Alemania contin\u00faan buscando allegados desaparecidos durante la Segunda Guerra Mundial, seg\u00fan un informe presentado hoy por la Cruz Roja Alemana (DRK).<\/p>\n<p>Seg\u00fan los datos suministrados por el servicio de la Cruz Roja para personas en busca de familiares perdidos se recibieron 4.778 consultas s\u00f3lo de enero a julio de este a\u00f1o.<\/p>\n<p>\u00abEl final de la Segunda Guerra Mundial fue hace 74 a\u00f1os, pero el inter\u00e9s de muchas familias germanas por la suerte de sus familiares desaparecidos sigue siendo incre\u00edble\u00bb, dijo la presidenta de la Cruz Roja Alemana, Gerda Hasselfeldt, con motivo del D\u00eda Internacional de las Personas Desaparecidas, a celebrar el 30 de agosto.<\/p>\n<p>En 2018, la DRK registr\u00f3 8.939 solicitudes de este tipo. Hasselfeldt dijo que la Cruz Roja estima que para finales de este a\u00f1o habr\u00e1 un total de 9.000 consultas.<\/p>\n<p>El servicio de b\u00fasqueda de la DRK s\u00f3lo pudo localizar a los familiares desaparecidos en una cuarta parte de los casos. En estos casos pudieron proporcionar al menos el lugar y la fecha de la muerte de la persona buscada.<\/p>\n<p>\u00abMuchas de las generaciones mayores quieren claridad al final de sus vidas sobre lo que realmente le sucedi\u00f3 a su padre o hermanos en ese entonces\u00bb, dijo Hasselfeld.<\/p>\n<p>\u00abPero la generaci\u00f3n m\u00e1s joven tambi\u00e9n est\u00e1 mostrando gran inter\u00e9s en el tema. Para los j\u00f3venes ya se trata del destino de sus bisabuelos\u00bb, agreg\u00f3.<\/p>\n<p>Seg\u00fan estimaciones, la Segunda Guerra Mundial se cobr\u00f3 al menos 55 millones de vidas en Europa y Asia, muchas de ellas v\u00edctimas civiles.<\/p>\n<p>Con m\u00e1s de 26 millones de muertos, la Uni\u00f3n Sovi\u00e9tica sufri\u00f3 las mayores p\u00e9rdidas.<\/p>\n<p>Por su parte, Alemania contabiliz\u00f3 alrededor de 6,3 millones de muertos, incluidos casi 5,2 millones de soldados. Entre las v\u00edctimas se encuentran tambi\u00e9n unos seis millones de jud\u00edos asesinados por los nazis.<\/p>\n<p>La Cruz Roja Alemana tambi\u00e9n tiene solicitudes relacionadas con el presente. El a\u00f1o pasado hubo alrededor de 2.300 consultas de refugiados en busca de familiares. Los principales pa\u00edses de origen son Afganist\u00e1n, Somalia, Irak y Siria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 29 ago (dpa) &#8211; Miles de familias en Alemania contin\u00faan buscando allegados desaparecidos durante la Segunda Guerra Mundial, seg\u00fan un informe presentado hoy por la Cruz Roja Alemana (DRK). Seg\u00fan los datos suministrados por el servicio de la Cruz Roja para personas en busca de familiares perdidos se recibieron 4.778 consultas s\u00f3lo de enero<\/p>\n","protected":false},"author":1,"featured_media":129168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-129167","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 29 ago (dpa) - Miles de familias en Alemania contin\u00faan buscando allegados desaparecidos durante la Segunda Guerra Mundial, seg\u00fan un informe presentado hoy por la Cruz Roja Alemana (DRK). Seg\u00fan los datos suministrados por el servicio de la Cruz Roja para personas en busca de familiares perdidos se recibieron 4.778 consultas s\u00f3lo de enero\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 29 ago (dpa) - Miles de familias en Alemania contin\u00faan buscando allegados desaparecidos durante la Segunda Guerra Mundial, seg\u00fan un informe presentado hoy por la Cruz Roja Alemana (DRK). Seg\u00fan los datos suministrados por el servicio de la Cruz Roja para personas en busca de familiares perdidos se recibieron 4.778 consultas s\u00f3lo de enero\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"944\" \/>\n\t\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-08-31T00:50:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-08-31T00:50:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 29 ago (dpa) - Miles de familias en Alemania contin\u00faan buscando allegados desaparecidos durante la Segunda Guerra Mundial, seg\u00fan un informe presentado hoy por la Cruz Roja Alemana (DRK). Seg\u00fan los datos suministrados por el servicio de la Cruz Roja para personas en busca de familiares perdidos se recibieron 4.778 consultas s\u00f3lo de enero\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@candas365\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#listItem\",\"name\":\"La Cruz Roja Alemana a\\u00fan busca desaparecidos de la Segunda Guerra Mundial\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#listItem\",\"position\":3,\"name\":\"La Cruz Roja Alemana a\\u00fan busca desaparecidos de la Segunda Guerra Mundial\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#newsarticle\",\"name\":\"La Cruz Roja Alemana a\\u00fan busca desaparecidos de la Segunda Guerra Mundial | Cand\\u00e1s 365\",\"headline\":\"La Cruz Roja Alemana a\\u00fan busca desaparecidos de la Segunda Guerra Mundial\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Busqueda-desaparecidos-2GM-dpa.jpg\",\"width\":944,\"height\":552,\"caption\":\"Foto: Marc M\\u00fcller\\\/dpa\"},\"datePublished\":\"2019-08-31T00:50:16+02:00\",\"dateModified\":\"2019-08-31T00:50:16+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el agosto 31, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/candas365\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/\",\"name\":\"La Cruz Roja Alemana a\\u00fan busca desaparecidos de la Segunda Guerra Mundial | Cand\\u00e1s 365\",\"description\":\"Berl\\u00edn, 29 ago (dpa) - Miles de familias en Alemania contin\\u00faan buscando allegados desaparecidos durante la Segunda Guerra Mundial, seg\\u00fan un informe presentado hoy por la Cruz Roja Alemana (DRK). Seg\\u00fan los datos suministrados por el servicio de la Cruz Roja para personas en busca de familiares perdidos se recibieron 4.778 consultas s\\u00f3lo de enero\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Busqueda-desaparecidos-2GM-dpa.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#mainImage\",\"width\":944,\"height\":552,\"caption\":\"Foto: Marc M\\u00fcller\\\/dpa\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\\\/#mainImage\"},\"datePublished\":\"2019-08-31T00:50:16+02:00\",\"dateModified\":\"2019-08-31T00:50:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial | Cand\u00e1s 365","description":"Berl\u00edn, 29 ago (dpa) - Miles de familias en Alemania contin\u00faan buscando allegados desaparecidos durante la Segunda Guerra Mundial, seg\u00fan un informe presentado hoy por la Cruz Roja Alemana (DRK). Seg\u00fan los datos suministrados por el servicio de la Cruz Roja para personas en busca de familiares perdidos se recibieron 4.778 consultas s\u00f3lo de enero","canonical_url":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#listItem","name":"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#listItem","position":3,"name":"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#newsarticle","name":"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial | Cand\u00e1s 365","headline":"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa.jpg","width":944,"height":552,"caption":"Foto: Marc M\u00fcller\/dpa"},"datePublished":"2019-08-31T00:50:16+02:00","dateModified":"2019-08-31T00:50:16+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el agosto 31, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/candas365","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#webpage","url":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/","name":"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial | Cand\u00e1s 365","description":"Berl\u00edn, 29 ago (dpa) - Miles de familias en Alemania contin\u00faan buscando allegados desaparecidos durante la Segunda Guerra Mundial, seg\u00fan un informe presentado hoy por la Cruz Roja Alemana (DRK). Seg\u00fan los datos suministrados por el servicio de la Cruz Roja para personas en busca de familiares perdidos se recibieron 4.778 consultas s\u00f3lo de enero","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa.jpg","@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#mainImage","width":944,"height":552,"caption":"Foto: Marc M\u00fcller\/dpa"},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/#mainImage"},"datePublished":"2019-08-31T00:50:16+02:00","dateModified":"2019-08-31T00:50:16+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial | Cand\u00e1s 365","og:description":"Berl\u00edn, 29 ago (dpa) - Miles de familias en Alemania contin\u00faan buscando allegados desaparecidos durante la Segunda Guerra Mundial, seg\u00fan un informe presentado hoy por la Cruz Roja Alemana (DRK). Seg\u00fan los datos suministrados por el servicio de la Cruz Roja para personas en busca de familiares perdidos se recibieron 4.778 consultas s\u00f3lo de enero","og:url":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa.jpg","og:image:width":944,"og:image:height":552,"article:published_time":"2019-08-31T00:50:16+00:00","article:modified_time":"2019-08-31T00:50:16+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/Nachofdezber","twitter:card":"summary_large_image","twitter:site":"@candas365","twitter:title":"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial | Cand\u00e1s 365","twitter:description":"Berl\u00edn, 29 ago (dpa) - Miles de familias en Alemania contin\u00faan buscando allegados desaparecidos durante la Segunda Guerra Mundial, seg\u00fan un informe presentado hoy por la Cruz Roja Alemana (DRK). Seg\u00fan los datos suministrados por el servicio de la Cruz Roja para personas en busca de familiares perdidos se recibieron 4.778 consultas s\u00f3lo de enero","twitter:creator":"@candas365","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2019\/08\/Busqueda-desaparecidos-2GM-dpa.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"129167","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-24 20:54:22","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:53:15","updated":"2026-05-24 20:54:22","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"La Cruz Roja Alemana a\u00fan busca desaparecidos de la Segunda Guerra Mundial","link":"https:\/\/candas365.es\/noticias\/la-cruz-roja-alemana-aun-busca-desaparecidos-de-la-segunda-guerra-mundial\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/129167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=129167"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/129167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/129168"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=129167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=129167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=129167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}