{"id":126521,"date":"2019-07-16T11:44:53","date_gmt":"2019-07-16T11:44:53","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=126521"},"modified":"2019-07-16T11:44:53","modified_gmt":"2019-07-16T11:44:53","slug":"espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/","title":{"rendered":"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-96671\" src=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720-360x270.jpg\" alt=\"\" width=\"360\" height=\"270\" srcset=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720-360x270.jpg 360w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720-768x576.jpg 768w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720-640x480.jpg 640w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720-80x60.jpg 80w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720-265x198.jpg 265w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720-696x522.jpg 696w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720-560x420.jpg 560w, https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720.jpg 960w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>El Gobierno de Espa\u00f1a desea trasladar sus m\u00e1s sinceras condolencias a los familiares de las v\u00edctimas, as\u00ed como sus deseos de una pronta recuperaci\u00f3n para los heridos del atentado del pasado viernes, en un hotel en la ciudad somal\u00ed de Kismayo.<\/p>\n<p>El Ejecutivo expresa su solidaridad con el pueblo somal\u00ed y con el resto de los pa\u00edses cuyos ciudadanos han fallecido en otra muestra m\u00e1s de que el horror de la barbarie terrorista no conoce fronteras.<\/p>\n<p>Espa\u00f1a, junto con el resto de la comunidad internacional y de las organizaciones internacionales presentes en Somalia, se reafirma en trasladar su apoyo a las autoridades somal\u00edes en la lucha contra el terrorismo y en sus esfuerzos en la b\u00fasqueda de la paz y la estabilidad en todo el pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Espa\u00f1a desea trasladar sus m\u00e1s sinceras condolencias a los familiares de las v\u00edctimas, as\u00ed como sus deseos de una pronta recuperaci\u00f3n para los heridos del atentado del pasado viernes, en un hotel en la ciudad somal\u00ed de Kismayo. El Ejecutivo expresa su solidaridad con el pueblo somal\u00ed y con el resto de<\/p>\n","protected":false},"author":1,"featured_media":96671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-126521","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Gobierno de Espa\u00f1a desea trasladar sus m\u00e1s sinceras condolencias a los familiares de las v\u00edctimas, as\u00ed como sus deseos de una pronta recuperaci\u00f3n para los heridos del atentado del pasado viernes, en un hotel en la ciudad somal\u00ed de Kismayo. El Ejecutivo expresa su solidaridad con el pueblo somal\u00ed y con el resto de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"El Gobierno de Espa\u00f1a desea trasladar sus m\u00e1s sinceras condolencias a los familiares de las v\u00edctimas, as\u00ed como sus deseos de una pronta recuperaci\u00f3n para los heridos del atentado del pasado viernes, en un hotel en la ciudad somal\u00ed de Kismayo. El Ejecutivo expresa su solidaridad con el pueblo somal\u00ed y con el resto de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-07-16T11:44:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-07-16T11:44:53+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Gobierno de Espa\u00f1a desea trasladar sus m\u00e1s sinceras condolencias a los familiares de las v\u00edctimas, as\u00ed como sus deseos de una pronta recuperaci\u00f3n para los heridos del atentado del pasado viernes, en un hotel en la ciudad somal\u00ed de Kismayo. El Ejecutivo expresa su solidaridad con el pueblo somal\u00ed y con el resto de\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#listItem\",\"name\":\"Espa\\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#listItem\",\"position\":3,\"name\":\"Espa\\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#newsarticle\",\"name\":\"Espa\\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia | Cand\\u00e1s 365\",\"headline\":\"Espa\\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/spain-379535_960_720.jpg\",\"width\":960,\"height\":720},\"datePublished\":\"2019-07-16T11:44:53+02:00\",\"dateModified\":\"2019-07-16T11:44:53+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el julio 16, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/\",\"name\":\"Espa\\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia | Cand\\u00e1s 365\",\"description\":\"El Gobierno de Espa\\u00f1a desea trasladar sus m\\u00e1s sinceras condolencias a los familiares de las v\\u00edctimas, as\\u00ed como sus deseos de una pronta recuperaci\\u00f3n para los heridos del atentado del pasado viernes, en un hotel en la ciudad somal\\u00ed de Kismayo. El Ejecutivo expresa su solidaridad con el pueblo somal\\u00ed y con el resto de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/spain-379535_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#mainImage\",\"width\":960,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\\\/#mainImage\"},\"datePublished\":\"2019-07-16T11:44:53+02:00\",\"dateModified\":\"2019-07-16T11:44:53+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia | Cand\u00e1s 365","description":"El Gobierno de Espa\u00f1a desea trasladar sus m\u00e1s sinceras condolencias a los familiares de las v\u00edctimas, as\u00ed como sus deseos de una pronta recuperaci\u00f3n para los heridos del atentado del pasado viernes, en un hotel en la ciudad somal\u00ed de Kismayo. El Ejecutivo expresa su solidaridad con el pueblo somal\u00ed y con el resto de","canonical_url":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#listItem","name":"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#listItem","position":3,"name":"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#newsarticle","name":"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia | Cand\u00e1s 365","headline":"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720.jpg","width":960,"height":720},"datePublished":"2019-07-16T11:44:53+02:00","dateModified":"2019-07-16T11:44:53+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el julio 16, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#webpage","url":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/","name":"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia | Cand\u00e1s 365","description":"El Gobierno de Espa\u00f1a desea trasladar sus m\u00e1s sinceras condolencias a los familiares de las v\u00edctimas, as\u00ed como sus deseos de una pronta recuperaci\u00f3n para los heridos del atentado del pasado viernes, en un hotel en la ciudad somal\u00ed de Kismayo. El Ejecutivo expresa su solidaridad con el pueblo somal\u00ed y con el resto de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#mainImage","width":960,"height":720},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/#mainImage"},"datePublished":"2019-07-16T11:44:53+02:00","dateModified":"2019-07-16T11:44:53+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia | Cand\u00e1s 365","og:description":"El Gobierno de Espa\u00f1a desea trasladar sus m\u00e1s sinceras condolencias a los familiares de las v\u00edctimas, as\u00ed como sus deseos de una pronta recuperaci\u00f3n para los heridos del atentado del pasado viernes, en un hotel en la ciudad somal\u00ed de Kismayo. El Ejecutivo expresa su solidaridad con el pueblo somal\u00ed y con el resto de","og:url":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720.jpg","og:image:width":960,"og:image:height":720,"article:published_time":"2019-07-16T11:44:53+00:00","article:modified_time":"2019-07-16T11:44:53+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia | Cand\u00e1s 365","twitter:description":"El Gobierno de Espa\u00f1a desea trasladar sus m\u00e1s sinceras condolencias a los familiares de las v\u00edctimas, as\u00ed como sus deseos de una pronta recuperaci\u00f3n para los heridos del atentado del pasado viernes, en un hotel en la ciudad somal\u00ed de Kismayo. El Ejecutivo expresa su solidaridad con el pueblo somal\u00ed y con el resto de","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/05\/spain-379535_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"126521","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-24 14:00:24","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:54:52","updated":"2026-05-24 14:00:24"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tEspa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Espa\u00f1a condena el atentado perpetrado por Al Shabaab en el sur de Somalia","link":"https:\/\/candas365.es\/noticias\/espana-condena-el-atentado-perpetrado-por-al-shabaab-en-el-sur-de-somalia\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=126521"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/96671"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=126521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=126521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=126521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}