{"id":126457,"date":"2019-07-14T22:19:25","date_gmt":"2019-07-14T22:19:25","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=126457"},"modified":"2019-07-14T22:19:25","modified_gmt":"2019-07-14T22:19:25","slug":"merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/","title":{"rendered":"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds"},"content":{"rendered":"<p>Par\u00eds, 14 jul (dpa) &#8211; La canciller alemana, Angela Merkel, agradeci\u00f3 la invitaci\u00f3n del presidente franc\u00e9s, Emmanuel Macron, a participar hoy en los festejos del aniversario de la Toma de la Bastilla en Par\u00eds.<\/p>\n<p>\u00abEs un gran gesto hacia la pol\u00edtica europea de Defensa\u00bb, dijo la mandataria germana, quien asisti\u00f3 a los desfiles como invitada de honor junto con los l\u00edderes de B\u00e9lgica, Estonia, Finlandia, Portugal y Holanda.<\/p>\n<p>La jefa alemana de Gobierno dijo que se sent\u00eda tambi\u00e9n honrada por el hecho de que soldados alemanes participaran en los desfiles.<\/p>\n<p>Francia, Alemania, el Reino Unido, Espa\u00f1a y otros pa\u00edses de la Uni\u00f3n Europea pusieron en marcha el a\u00f1o pasado una nueva cooperaci\u00f3n militar.<\/p>\n<p>La llamada Iniciativa Europea de Intervenci\u00f3n tiene por objeto facilitar una reacci\u00f3n militar m\u00e1s r\u00e1pida en situaciones de crisis mediante una cooperaci\u00f3n mucho m\u00e1s estrecha entre los estados mayores. Sin embargo, esto no implica inicialmente una fuerza de intervenci\u00f3n conjunta.<\/p>\n<p>En junio Alemania, Francia y Espa\u00f1a sellaron un proyecto de miles de millones de d\u00f3lares para el desarrollo de un avi\u00f3n de combate conjunto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par\u00eds, 14 jul (dpa) &#8211; La canciller alemana, Angela Merkel, agradeci\u00f3 la invitaci\u00f3n del presidente franc\u00e9s, Emmanuel Macron, a participar hoy en los festejos del aniversario de la Toma de la Bastilla en Par\u00eds. \u00abEs un gran gesto hacia la pol\u00edtica europea de Defensa\u00bb, dijo la mandataria germana, quien asisti\u00f3 a los desfiles como invitada<\/p>\n","protected":false},"author":1,"featured_media":107557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-126457","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Par\u00eds, 14 jul (dpa) - La canciller alemana, Angela Merkel, agradeci\u00f3 la invitaci\u00f3n del presidente franc\u00e9s, Emmanuel Macron, a participar hoy en los festejos del aniversario de la Toma de la Bastilla en Par\u00eds. &quot;Es un gran gesto hacia la pol\u00edtica europea de Defensa&quot;, dijo la mandataria germana, quien asisti\u00f3 a los desfiles como invitada\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Par\u00eds, 14 jul (dpa) - La canciller alemana, Angela Merkel, agradeci\u00f3 la invitaci\u00f3n del presidente franc\u00e9s, Emmanuel Macron, a participar hoy en los festejos del aniversario de la Toma de la Bastilla en Par\u00eds. &quot;Es un gran gesto hacia la pol\u00edtica europea de Defensa&quot;, dijo la mandataria germana, quien asisti\u00f3 a los desfiles como invitada\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/10\/technology-785742_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/10\/technology-785742_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-07-14T22:19:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-07-14T22:19:25+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Par\u00eds, 14 jul (dpa) - La canciller alemana, Angela Merkel, agradeci\u00f3 la invitaci\u00f3n del presidente franc\u00e9s, Emmanuel Macron, a participar hoy en los festejos del aniversario de la Toma de la Bastilla en Par\u00eds. &quot;Es un gran gesto hacia la pol\u00edtica europea de Defensa&quot;, dijo la mandataria germana, quien asisti\u00f3 a los desfiles como invitada\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/10\/technology-785742_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#listItem\",\"name\":\"Merkel asiste al aniversario de la Toma de la Bastilla en Par\\u00eds\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#listItem\",\"position\":3,\"name\":\"Merkel asiste al aniversario de la Toma de la Bastilla en Par\\u00eds\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#newsarticle\",\"name\":\"Merkel asiste al aniversario de la Toma de la Bastilla en Par\\u00eds | Cand\\u00e1s 365\",\"headline\":\"Merkel asiste al aniversario de la Toma de la Bastilla en Par\\u00eds\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/technology-785742_960_720.jpg\",\"width\":960,\"height\":640},\"datePublished\":\"2019-07-14T22:19:25+02:00\",\"dateModified\":\"2019-07-14T22:19:25+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el julio 14, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/\",\"name\":\"Merkel asiste al aniversario de la Toma de la Bastilla en Par\\u00eds | Cand\\u00e1s 365\",\"description\":\"Par\\u00eds, 14 jul (dpa) - La canciller alemana, Angela Merkel, agradeci\\u00f3 la invitaci\\u00f3n del presidente franc\\u00e9s, Emmanuel Macron, a participar hoy en los festejos del aniversario de la Toma de la Bastilla en Par\\u00eds. \\\"Es un gran gesto hacia la pol\\u00edtica europea de Defensa\\\", dijo la mandataria germana, quien asisti\\u00f3 a los desfiles como invitada\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/technology-785742_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\\\/#mainImage\"},\"datePublished\":\"2019-07-14T22:19:25+02:00\",\"dateModified\":\"2019-07-14T22:19:25+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds | Cand\u00e1s 365","description":"Par\u00eds, 14 jul (dpa) - La canciller alemana, Angela Merkel, agradeci\u00f3 la invitaci\u00f3n del presidente franc\u00e9s, Emmanuel Macron, a participar hoy en los festejos del aniversario de la Toma de la Bastilla en Par\u00eds. \"Es un gran gesto hacia la pol\u00edtica europea de Defensa\", dijo la mandataria germana, quien asisti\u00f3 a los desfiles como invitada","canonical_url":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#listItem","name":"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#listItem","position":3,"name":"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#newsarticle","name":"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds | Cand\u00e1s 365","headline":"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/10\/technology-785742_960_720.jpg","width":960,"height":640},"datePublished":"2019-07-14T22:19:25+02:00","dateModified":"2019-07-14T22:19:25+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el julio 14, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#webpage","url":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/","name":"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds | Cand\u00e1s 365","description":"Par\u00eds, 14 jul (dpa) - La canciller alemana, Angela Merkel, agradeci\u00f3 la invitaci\u00f3n del presidente franc\u00e9s, Emmanuel Macron, a participar hoy en los festejos del aniversario de la Toma de la Bastilla en Par\u00eds. \"Es un gran gesto hacia la pol\u00edtica europea de Defensa\", dijo la mandataria germana, quien asisti\u00f3 a los desfiles como invitada","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/10\/technology-785742_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/#mainImage"},"datePublished":"2019-07-14T22:19:25+02:00","dateModified":"2019-07-14T22:19:25+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds | Cand\u00e1s 365","og:description":"Par\u00eds, 14 jul (dpa) - La canciller alemana, Angela Merkel, agradeci\u00f3 la invitaci\u00f3n del presidente franc\u00e9s, Emmanuel Macron, a participar hoy en los festejos del aniversario de la Toma de la Bastilla en Par\u00eds. &quot;Es un gran gesto hacia la pol\u00edtica europea de Defensa&quot;, dijo la mandataria germana, quien asisti\u00f3 a los desfiles como invitada","og:url":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/10\/technology-785742_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/10\/technology-785742_960_720.jpg","og:image:width":960,"og:image:height":640,"article:published_time":"2019-07-14T22:19:25+00:00","article:modified_time":"2019-07-14T22:19:25+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds | Cand\u00e1s 365","twitter:description":"Par\u00eds, 14 jul (dpa) - La canciller alemana, Angela Merkel, agradeci\u00f3 la invitaci\u00f3n del presidente franc\u00e9s, Emmanuel Macron, a participar hoy en los festejos del aniversario de la Toma de la Bastilla en Par\u00eds. &quot;Es un gran gesto hacia la pol\u00edtica europea de Defensa&quot;, dijo la mandataria germana, quien asisti\u00f3 a los desfiles como invitada","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/10\/technology-785742_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"126457","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-24 13:48:45","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:54:59","updated":"2026-05-24 13:48:45"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tMerkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Merkel asiste al aniversario de la Toma de la Bastilla en Par\u00eds","link":"https:\/\/candas365.es\/noticias\/merkel-asiste-al-aniversario-de-la-toma-de-la-bastilla-en-paris\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=126457"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/107557"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=126457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=126457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=126457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}