{"id":126412,"date":"2019-07-13T23:02:56","date_gmt":"2019-07-13T23:02:56","guid":{"rendered":"http:\/\/candas365.es\/noticias\/?p=126412"},"modified":"2019-07-13T23:02:56","modified_gmt":"2019-07-13T23:02:56","slug":"angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando","status":"publish","type":"post","link":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/","title":{"rendered":"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d"},"content":{"rendered":"<p>Berlin (dpa) &#8211; La canciller alemana, Angela Merkel, llam\u00f3 hoy a sus compatriotas a oponerse al extremismo de derecha en ocasi\u00f3n de cumplirse el <strong>75 aniversario del fallido atentado de militares alemanes contra el dictador Adolf Hitler<\/strong>.<\/p>\n<p>La mandataria dijo en su mensaje semanal por video que el 20 de julio es una fecha que recuerda a todos los que se opusieron al r\u00e9gimen nacionalsocialista.<\/p>\n<p>\u00abHoy nosotros tambi\u00e9n estamos obligados a oponernos a todas las tendencias que quieran destruir la democracia\u00bb, destac\u00f3.<\/p>\n<p>El coronel <strong>Claus Schenk von Stauffenberg<\/strong> intent\u00f3 acabar con la vida de Adolf Hitler el 20 de julio de 1944 al colocar una bomba debajo del escritorio del l\u00edder nacionalsocialista.<\/p>\n<p><strong>El intento fracas\u00f3 y Hitler sobrevivi\u00f3 ligeramente herido.<\/strong> Stauffenberg y sus c\u00f3mplices fueron ejecutados. Un total de 200 c\u00f3mplices fueron v\u00edctimas de la justicia nazi.<\/p>\n<p>Merkel sostuvo que aquellos oficiales son un ejemplo para Alemania, \u00abporque demostraron que escucharon la voz de su conciencia, y al hacerlo se inscribieron en la historia de Alemania, una historia que de otro modo estar\u00eda determinada por la oscuridad del nacionalsocialismo\u00bb.<\/p>\n<p>Asimismo recalc\u00f3 la importancia de aquella sublevaci\u00f3n para la democracia alemana. \u00abNuestra Ley Fundamental tal vez no podr\u00eda haber nacido sin tales actos. Hoy podemos construir sobre el valor de estas personas\u00bb.<\/p>\n<p>Merkel advirti\u00f3 que el n\u00famero de extremistas de derecha en Alemania est\u00e1 aumentando. Mencion\u00f3 tambi\u00e9n en este contexto el asesinato en junio del presidente del distrito de Kassel, Walter L\u00fcbcke, del que es sospechoso un ultraderechista y pidi\u00f3 respaldo a quienes asumen responsabilidad pol\u00edtica.<\/p>\n<p>\u00ab\u00a1Aqu\u00ed necesitamos una se\u00f1al clara de todos! Todos est\u00e1n invitados a trabajar en nuestra sociedad para asegurar que la democracia sea fuerte, que la sociedad civil sea fuerte y que no tengan cabida en ella los extremistas de derecha\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berlin (dpa) &#8211; La canciller alemana, Angela Merkel, llam\u00f3 hoy a sus compatriotas a oponerse al extremismo de derecha en ocasi\u00f3n de cumplirse el 75 aniversario del fallido atentado de militares alemanes contra el dictador Adolf Hitler. La mandataria dijo en su mensaje semanal por video que el 20 de julio es una fecha que<\/p>\n","protected":false},"author":1,"featured_media":98518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[343],"tags":[],"class_list":["post-126412","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berlin (dpa) - La canciller alemana, Angela Merkel, llam\u00f3 hoy a sus compatriotas a oponerse al extremismo de derecha en ocasi\u00f3n de cumplirse el 75 aniversario del fallido atentado de militares alemanes contra el dictador Adolf Hitler. La mandataria dijo en su mensaje semanal por video que el 20 de julio es una fecha que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Cand\u00e1s 365\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-32230408-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"354F3CDFB2DA171B47FBE9ABF1F88D5\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d | Cand\u00e1s 365\" \/>\n\t\t<meta property=\"og:description\" content=\"Berlin (dpa) - La canciller alemana, Angela Merkel, llam\u00f3 hoy a sus compatriotas a oponerse al extremismo de derecha en ocasi\u00f3n de cumplirse el 75 aniversario del fallido atentado de militares alemanes contra el dictador Adolf Hitler. La mandataria dijo en su mensaje semanal por video que el 20 de julio es una fecha que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-07-13T23:02:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-07-13T23:02:56+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nachofdezber\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/carrenoactualidad\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@NabercoDigital\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d | Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berlin (dpa) - La canciller alemana, Angela Merkel, llam\u00f3 hoy a sus compatriotas a oponerse al extremismo de derecha en ocasi\u00f3n de cumplirse el 75 aniversario del fallido atentado de militares alemanes contra el dictador Adolf Hitler. La mandataria dijo en su mensaje semanal por video que el 20 de julio es una fecha que\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@nbasturias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Cand\u00e1s 365\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#listItem\",\"name\":\"Angela Merkel: \\u201cEl n\\u00famero de extremistas de derecha est\\u00e1 aumentando\\u201d\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#listItem\",\"position\":3,\"name\":\"Angela Merkel: \\u201cEl n\\u00famero de extremistas de derecha est\\u00e1 aumentando\\u201d\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#newsarticle\",\"name\":\"Angela Merkel: \\u201cEl n\\u00famero de extremistas de derecha est\\u00e1 aumentando\\u201d | Cand\\u00e1s 365\",\"headline\":\"Angela Merkel: \\u201cEl n\\u00famero de extremistas de derecha est\\u00e1 aumentando\\u201d\",\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/berlin-76509_960_720.jpg\",\"width\":960,\"height\":720},\"datePublished\":\"2019-07-13T23:02:56+02:00\",\"dateModified\":\"2019-07-13T23:02:56+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#webpage\"},\"articleSection\":\"Actualidad\",\"dateline\":\"Publicado el julio 13, 2019.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\",\"name\":\"Cand\\u00e1s 365\",\"description\":\"Cand\\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"email\":\"info@candas365.es\",\"telephone\":\"+34652131393\",\"foundingDate\":\"2012-06-10\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Candas-365-Redes.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#organizationLogo\",\"width\":1152,\"height\":864,\"caption\":\"Cand\\u00e1s 365 Redes\"},\"image\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nachofdezber\",\"https:\\\/\\\/x.com\\\/NabercoDigital\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4, san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"Cand\\u00e1s 365\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#authorImage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-eyevuvEl_400x400-96x96.jpg\",\"width\":96,\"height\":96,\"caption\":\"Cand\\u00e1s 365\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/carrenoactualidad\",\"https:\\\/\\\/twitter.com\\\/nbasturias\",\"https:\\\/\\\/www.instagram.com\\\/nachofdezber\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#webpage\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/\",\"name\":\"Angela Merkel: \\u201cEl n\\u00famero de extremistas de derecha est\\u00e1 aumentando\\u201d | Cand\\u00e1s 365\",\"description\":\"Berlin (dpa) - La canciller alemana, Angela Merkel, llam\\u00f3 hoy a sus compatriotas a oponerse al extremismo de derecha en ocasi\\u00f3n de cumplirse el 75 aniversario del fallido atentado de militares alemanes contra el dictador Adolf Hitler. La mandataria dijo en su mensaje semanal por video que el 20 de julio es una fecha que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/berlin-76509_960_720.jpg\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#mainImage\",\"width\":960,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\\\/#mainImage\"},\"datePublished\":\"2019-07-13T23:02:56+02:00\",\"dateModified\":\"2019-07-13T23:02:56+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/\",\"name\":\"Cand\\u00e1s 365\",\"alternateName\":\"Cand\\u00e1s 365 Noticias\",\"description\":\"Actualidad desde Carre\\u00f1o para el mundo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/candas365.es\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d | Cand\u00e1s 365<\/title>\n\n","aioseo_head_json":{"title":"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d | Cand\u00e1s 365","description":"Berlin (dpa) - La canciller alemana, Angela Merkel, llam\u00f3 hoy a sus compatriotas a oponerse al extremismo de derecha en ocasi\u00f3n de cumplirse el 75 aniversario del fallido atentado de militares alemanes contra el dictador Adolf Hitler. La mandataria dijo en su mensaje semanal por video que el 20 de julio es una fecha que","canonical_url":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-32230408-1","msvalidate.01":"354F3CDFB2DA171B47FBE9ABF1F88D5","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/candas365.es\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/candas365.es\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#listItem","name":"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d"},"previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#listItem","position":3,"name":"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d","previousItem":{"@type":"ListItem","@id":"https:\/\/candas365.es\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"NewsArticle","@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#newsarticle","name":"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d | Cand\u00e1s 365","headline":"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d","author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","width":960,"height":720},"datePublished":"2019-07-13T23:02:56+02:00","dateModified":"2019-07-13T23:02:56+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#webpage"},"isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#webpage"},"articleSection":"Actualidad","dateline":"Publicado el julio 13, 2019."},{"@type":"Organization","@id":"https:\/\/candas365.es\/noticias\/#organization","name":"Cand\u00e1s 365","description":"Cand\u00e1s 365 es un diario digital independiente, fundado en 2012, con base en Asturias. Informamos con rigor sobre actualidad, sociedad, cultura y ocio, con una mirada local y global.","url":"https:\/\/candas365.es\/noticias\/","email":"info@candas365.es","telephone":"+34652131393","foundingDate":"2012-06-10","logo":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2024\/09\/Candas-365-Redes.jpg","@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#organizationLogo","width":1152,"height":864,"caption":"Cand\u00e1s 365 Redes"},"image":{"@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Nachofdezber","https:\/\/x.com\/NabercoDigital","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/candas365.es\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4, san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author","url":"https:\/\/candas365.es\/noticias\/author\/admin\/","name":"Cand\u00e1s 365","image":{"@type":"ImageObject","@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#authorImage","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2026\/07\/cropped-eyevuvEl_400x400-96x96.jpg","width":96,"height":96,"caption":"Cand\u00e1s 365"},"sameAs":["https:\/\/www.facebook.com\/carrenoactualidad","https:\/\/twitter.com\/nbasturias","https:\/\/www.instagram.com\/nachofdezber\/","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"]},{"@type":"WebPage","@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#webpage","url":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/","name":"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d | Cand\u00e1s 365","description":"Berlin (dpa) - La canciller alemana, Angela Merkel, llam\u00f3 hoy a sus compatriotas a oponerse al extremismo de derecha en ocasi\u00f3n de cumplirse el 75 aniversario del fallido atentado de militares alemanes contra el dictador Adolf Hitler. La mandataria dijo en su mensaje semanal por video que el 20 de julio es una fecha que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/candas365.es\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#breadcrumblist"},"author":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/candas365.es\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#mainImage","width":960,"height":720},"primaryImageOfPage":{"@id":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/#mainImage"},"datePublished":"2019-07-13T23:02:56+02:00","dateModified":"2019-07-13T23:02:56+02:00"},{"@type":"WebSite","@id":"https:\/\/candas365.es\/noticias\/#website","url":"https:\/\/candas365.es\/noticias\/","name":"Cand\u00e1s 365","alternateName":"Cand\u00e1s 365 Noticias","description":"Actualidad desde Carre\u00f1o para el mundo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/candas365.es\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Cand\u00e1s 365","og:type":"article","og:title":"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d | Cand\u00e1s 365","og:description":"Berlin (dpa) - La canciller alemana, Angela Merkel, llam\u00f3 hoy a sus compatriotas a oponerse al extremismo de derecha en ocasi\u00f3n de cumplirse el 75 aniversario del fallido atentado de militares alemanes contra el dictador Adolf Hitler. La mandataria dijo en su mensaje semanal por video que el 20 de julio es una fecha que","og:url":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/","og:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","og:image:secure_url":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","og:image:width":960,"og:image:height":720,"article:published_time":"2019-07-13T23:02:56+00:00","article:modified_time":"2019-07-13T23:02:56+00:00","article:publisher":"https:\/\/www.facebook.com\/Nachofdezber","article:author":"https:\/\/www.facebook.com\/carrenoactualidad","twitter:card":"summary_large_image","twitter:site":"@NabercoDigital","twitter:title":"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d | Cand\u00e1s 365","twitter:description":"Berlin (dpa) - La canciller alemana, Angela Merkel, llam\u00f3 hoy a sus compatriotas a oponerse al extremismo de derecha en ocasi\u00f3n de cumplirse el 75 aniversario del fallido atentado de militares alemanes contra el dictador Adolf Hitler. La mandataria dijo en su mensaje semanal por video que el 20 de julio es una fecha que","twitter:creator":"@nbasturias","twitter:image":"https:\/\/candas365.es\/noticias\/wp-content\/uploads\/2018\/06\/berlin-76509_960_720.jpg","twitter:label1":"Escrito por","twitter:data1":"Cand\u00e1s 365","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"126412","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-24 13:40:39","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2020-12-21 10:54:59","updated":"2026-05-24 13:40:39"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/candas365.es\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&ndash;<\/span><span class=\"aioseo-breadcrumb\">\n\tAngela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/candas365.es\/noticias"},{"label":"Actualidad","link":"https:\/\/candas365.es\/noticias\/category\/actualidad\/"},{"label":"Angela Merkel: \u201cEl n\u00famero de extremistas de derecha est\u00e1 aumentando\u201d","link":"https:\/\/candas365.es\/noticias\/angela-merkel-el-numero-de-extremistas-de-derecha-esta-aumentando\/"}],"_links":{"self":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/comments?post=126412"}],"version-history":[{"count":0,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/posts\/126412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media\/98518"}],"wp:attachment":[{"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/media?parent=126412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/categories?post=126412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candas365.es\/noticias\/wp-json\/wp\/v2\/tags?post=126412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}